{"id":10501,"date":"2016-02-05T07:29:46","date_gmt":"2016-02-05T12:29:46","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/dives-in-misericordia\/"},"modified":"2016-02-05T07:29:46","modified_gmt":"2016-02-05T12:29:46","slug":"dives-in-misericordia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/dives-in-misericordia\/","title":{"rendered":"DIVES IN MISERICORDIA"},"content":{"rendered":"<p>[072][970]<br \/>\n   Enc\u00ed\u00adclica de Juan Pablo II del Primer domingo de Adviento, 30 de Noviembre de 1980.<\/p>\n<p>   Invitaci\u00f3n a descubrir en Cristo el rostro del Padre, que es misericordioso y nos ofrece su consolaci\u00f3n.<\/p>\n<p>   Resume ideas hermosas en torno a la Misericordia de Dios para con los hombres pecadores.<\/p>\n<p>      1. Quien me ve a m\u00ed\u00ad, ve al Padre.<\/p>\n<p>      2. Mensaje mesi\u00e1nico.<\/p>\n<p>      3. El Antiguo Testamento.<\/p>\n<p>      4. La par\u00e1bola del Hijo pr\u00f3digo.<\/p>\n<p>      5. Misterio Pascual.<\/p>\n<p>      6. Misericordia en cada generaci\u00f3n.<\/p>\n<p>      7. La misericordia en la Iglesia.<\/p>\n<p>      8. Oraci\u00f3n de la Iglesia en hoy.<\/p>\n<p>   Interesante texto para una catequesis sobre la idea de Dios amoroso y misericordioso con los pecadores, con los d\u00e9biles.<\/p>\n<p>   Presenta a la Iglesia como mensajera de misericordia en un mundo duro con los desheredados.<\/p>\n<p>Pedro Chico Gonz\u00e1lez, Diccionario de Catequesis y Pedagog\u00ed\u00ada Religiosa, Editorial Bru\u00f1o, Lima, Per\u00fa 2006<\/p>\n<p><b>Fuente: Diccionario de Catequesis y Pedagog\u00eda Religiosa<\/b><\/p>\n<p>El 30 de noviembre de 1980, el Papa Juan Pablo II, casi reci\u00e9n estrenado su Pontificado, publica la Enc\u00ed\u00adclia \u00abDives in Misericordia\u00bb (Rico en misericordia) .<\/p>\n<p>Es un extenso documento dividido en ocho grandes apartados o cap\u00ed\u00adtulos.<\/p>\n<p>En sustancia, trata de poner de relieve el rostro revelado del Dios cristiano como misericordioso. La misma encarnaci\u00f3n s\u00f3lo tuvo sentido desde la misericordia entra\u00f1able.<\/p>\n<p>El maestro y modelo de lo que es la misericordia divina es Jesucristo, tanto en su ense\u00f1anza como en su obrar. En este sentido es paradigm\u00e1tica la par\u00e1bola del Padre Misericordioso y el Hijo pr\u00f3digo.<\/p>\n<p>El misterio pascual, contemplado desde la misericordia de Dios, nos habla de un amor m\u00e1s fuerte que la misma muerte y mucho m\u00e1s fuerte que el pecado.<\/p>\n<p>Mar\u00ed\u00ada puede ser denominada tambi\u00e9n como Madre de la misericordia, y la Iglesia, de generaci\u00f3n en generaci\u00f3n, debe ser testigo y profeta de la misericordia de Dios con los hombres y de los hombres entre s\u00ed\u00ad. Por eso es necesario que la Iglesia pida con insistencia la misericordia divina para poder practicarla y para que sea una realidad de cada hombre y de la humanidad en su conjunto.<\/p>\n<p>BIBL. &#8211; JUAN PABLO II, Enc\u00ed\u00adclicas, Edibesa, Madrid 1995.<\/p>\n<p>Ra\u00fal Berzosa Mart\u00ed\u00adnez<\/p>\n<p>Vicente M\u00c2\u00aa Pedrosa &#8211; Jes\u00fas Sastre &#8211; Ra\u00fal Berzosa (Directores), Diccionario de Pastoral y Evangelizaci\u00f3n, Diccionarios \u00abMC\u00bb, Editorial Monte Carmelo, Burgos, 2001<\/p>\n<p><b>Fuente: Diccionario de Pastoral y Evangelizaci\u00f3n<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[072][970] Enc\u00ed\u00adclica de Juan Pablo II del Primer domingo de Adviento, 30 de Noviembre de 1980. Invitaci\u00f3n a descubrir en Cristo el rostro del Padre, que es misericordioso y nos ofrece su consolaci\u00f3n. Resume ideas hermosas en torno a la Misericordia de Dios para con los hombres pecadores. 1. Quien me ve a m\u00ed\u00ad, ve &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/dives-in-misericordia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDIVES IN MISERICORDIA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-10501","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/10501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=10501"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/10501\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=10501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=10501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=10501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}