{"id":10510,"date":"2016-02-05T07:30:03","date_gmt":"2016-02-05T12:30:03","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/doce-los\/"},"modified":"2016-02-05T07:30:03","modified_gmt":"2016-02-05T12:30:03","slug":"doce-los","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/doce-los\/","title":{"rendered":"DOCE. LOS"},"content":{"rendered":"<p>[016]<\/p>\n<p>    Expresi\u00f3n evang\u00e9lica que alude la conciencia de elecci\u00f3n de los Ap\u00f3stoles en n\u00famero de Doce entre los diversos disc\u00ed\u00adpulos que tuvo Jes\u00fas.<\/p>\n<p>    El n\u00famero de \u00abdoce\u00bb aparece citado con significaci\u00f3n singular 63 veces en el Nuevo Testamento. De ellas, 30 se refieren a \u00ablos doce\u00bb. En los cuatro Evangelios se reflerja la conciencia de que eran doce los elegidos (Mt. 10.2; Mc. 3.14; Lc. 6.13; Jn 6.70) y queda patente.<\/p>\n<p>    Y cinco veces m\u00e1s en los Hechos se alude a \u00ablos Doce\u00bb. Tan claro lo ten\u00ed\u00adan los seguidores de Jes\u00fas que los Hechos relatan c\u00f3mo la primera medida despu\u00e9s de la resurrecci\u00f3n fue designar al sustituto del traidor (Hech. 1.26) pues \u00absu puesto\u00bb hab\u00ed\u00ada que darlo a otro digno de la misi\u00f3n encomendada por Jes\u00fas.<\/p>\n<p>    Es interesante realizar con los educandos alg\u00fan trabajo que de la conciencia del Apostolado de los doce, pues ellos son el fundamento de la autoridad entregada por Cristo a la Iglesia.<\/p>\n<p>    El ver qu\u00e9 significa esa autoridad es un ejercicio hermoso recogiendo los textos en que se alude a ellos y comentar el contexto sacando el com\u00fan denominador de todos ellos. Entonces se entiende conceptos asociados a la autoridad eclesial como \u00abservir\u00bb, \u00abpredicar\u00bb, \u00abcaminar\u00bb, \u00abayudar\u00bb, \u00abfortalecer en la fe a los dem\u00e1s\u00bb.<\/p>\n<p>Pedro Chico Gonz\u00e1lez, Diccionario de Catequesis y Pedagog\u00ed\u00ada Religiosa, Editorial Bru\u00f1o, Lima, Per\u00fa 2006<\/p>\n<p><b>Fuente: Diccionario de Catequesis y Pedagog\u00eda Religiosa<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[016] Expresi\u00f3n evang\u00e9lica que alude la conciencia de elecci\u00f3n de los Ap\u00f3stoles en n\u00famero de Doce entre los diversos disc\u00ed\u00adpulos que tuvo Jes\u00fas. El n\u00famero de \u00abdoce\u00bb aparece citado con significaci\u00f3n singular 63 veces en el Nuevo Testamento. De ellas, 30 se refieren a \u00ablos doce\u00bb. En los cuatro Evangelios se reflerja la conciencia de &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/doce-los\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDOCE. LOS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-10510","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/10510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=10510"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/10510\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=10510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=10510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=10510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}