{"id":10532,"date":"2016-02-05T07:30:42","date_gmt":"2016-02-05T12:30:42","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/donacion\/"},"modified":"2016-02-05T07:30:42","modified_gmt":"2016-02-05T12:30:42","slug":"donacion","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/donacion\/","title":{"rendered":"DONACION"},"content":{"rendered":"<p>[324]<\/p>\n<p>    Es el acto de entrega de un bien o derecho a una persona o comunidad. Religiosamente la donaci\u00f3n es una aportaci\u00f3n que en ocasiones se puede hacer para obras buenas o de piedad. Cuando esto se realiza se colabora en la tarea de la Iglesia y esa donaci\u00f3n es una acci\u00f3n religiosa de singular valor.<\/p>\n<p>    A los cristianos hay que educarlos para que aporten sus dones para el bien de la Iglesia y de los dem\u00e1s cristianos.<\/p>\n<p>Pedro Chico Gonz\u00e1lez, Diccionario de Catequesis y Pedagog\u00ed\u00ada Religiosa, Editorial Bru\u00f1o, Lima, Per\u00fa 2006<\/p>\n<p><b>Fuente: Diccionario de Catequesis y Pedagog\u00eda Religiosa<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[324] Es el acto de entrega de un bien o derecho a una persona o comunidad. Religiosamente la donaci\u00f3n es una aportaci\u00f3n que en ocasiones se puede hacer para obras buenas o de piedad. Cuando esto se realiza se colabora en la tarea de la Iglesia y esa donaci\u00f3n es una acci\u00f3n religiosa de singular &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/donacion\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDONACION\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-10532","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/10532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=10532"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/10532\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=10532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=10532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=10532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}