{"id":14474,"date":"2016-02-05T09:32:24","date_gmt":"2016-02-05T14:32:24","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/virrey\/"},"modified":"2016-02-05T09:32:24","modified_gmt":"2016-02-05T14:32:24","slug":"virrey","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/virrey\/","title":{"rendered":"VIRREY"},"content":{"rendered":"<p>[801]<br \/>\n  Cargo o funci\u00f3n social deshacer las veces del rey en actividades de representaci\u00f3n o de gobierno. Como cargo surgi\u00f3 en el Reino de Arag\u00f3n a finales del siglo XV, denominando as\u00ed\u00ad a los representantes reales de Sicilia y de Cerde\u00f1a. Luego se extendi\u00f3 a otros lugares de la pen\u00ed\u00adnsula con los Reyes Cat\u00f3licos. Cobr\u00f3 una significaci\u00f3n especial y resonancia social al denominar as\u00ed\u00ad a los gobernadores colocados por los Austrias.<\/p>\n<p>    Los virreinatos europeos, de Espa\u00f1a y de Sicilia y N\u00e1poles, fueron los primeros. Pero los americanos (Del Pata, de Nueva Espa\u00f1a, de Nueva Granada) fueron los m\u00e1s poderosos, hasta actuar los virreyes como verdaderos reyes locales, debido a la distancia de los soberanos espa\u00f1oles. Los cargos virreinales de Europa duraron hasta comienzos del XVIII y los americanos resistieron hasta el siglo XIX.<\/p>\n<p>Pedro Chico Gonz\u00e1lez, Diccionario de Catequesis y Pedagog\u00ed\u00ada Religiosa, Editorial Bru\u00f1o, Lima, Per\u00fa 2006<\/p>\n<p><b>Fuente: Diccionario de Catequesis y Pedagog\u00eda Religiosa<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[801] Cargo o funci\u00f3n social deshacer las veces del rey en actividades de representaci\u00f3n o de gobierno. Como cargo surgi\u00f3 en el Reino de Arag\u00f3n a finales del siglo XV, denominando as\u00ed\u00ad a los representantes reales de Sicilia y de Cerde\u00f1a. Luego se extendi\u00f3 a otros lugares de la pen\u00ed\u00adnsula con los Reyes Cat\u00f3licos. Cobr\u00f3 &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/virrey\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abVIRREY\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-14474","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/14474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=14474"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/14474\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=14474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=14474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=14474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}