{"id":14476,"date":"2016-02-05T09:32:27","date_gmt":"2016-02-05T14:32:27","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/virtudes\/"},"modified":"2016-02-05T09:32:27","modified_gmt":"2016-02-05T14:32:27","slug":"virtudes","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/virtudes\/","title":{"rendered":"VIRTUD\/ES"},"content":{"rendered":"<p>[320]<\/p>\n<p>    Etimol\u00f3gicamente (virtus) virtud significa fuerza, energ\u00ed\u00ada, cualidad de var\u00f3n (vir). En catequesis el tema de la \u00abvirtud\u00bb es muy general, pero importante. Y el de las virtudes es ambicioso y prolijo, pero concreto.  Ambos son prioritarios.<\/p>\n<p>    1. Vida y virtud<br \/>\n    El terreno pr\u00e1ctico, concreto y din\u00e1mico de las virtudes orienta la acci\u00f3n del catequista hacia la adquisici\u00f3n de las formas convenientes de obrar.<\/p>\n<p>    Educar en las virtudes es fundamental para la formaci\u00f3n de la conciencia y de la inteligencia.<\/p>\n<p>     1.1. Significado catequ\u00ed\u00adstico.<\/p>\n<p>     El catequista tiene que reflexionar con frecuencia en c\u00f3mo hacer para que sus catequizandos se inicien en el \u00abbuen comportamiento\u00bb, entendiendo por tal el que se ajusta a las exigencias del Evangelio. Y esto significa que tiene que animar a sus catequizandos a practicar las virtudes cristianas.<\/p>\n<p>    Basta que una virtud fundamental, la justicia, la sinceridad, la austeridad, por ejemplo, no funcione en una persona, para que toda su vida espiritual se resquebraje y se debilite. Y basta que un vicio se adue\u00f1e de un hombre, la mentira, la lujuria, la soberbia, para que toda su conducta se aleje del Evangelio.<\/p>\n<p>    La virtud en el cristiano no es s\u00f3lo la conducta honrada por imperativo de la propia conciencia, por honradez. Es sobre todo imitaci\u00f3n del modelo que es Jes\u00fas y respuesta libre el mandato que dio a sus seguidores: \u00abSed perfectos como vuestro Padre celestial es perfecto\u00bb. (Mt. 5.48)<\/p>\n<p>    Es lo que han hechos todos los santos, comenzando por sus Ap\u00f3stoles que recogieron y transmitieron a los dem\u00e1s creyentes su mensaje de amor.<\/p>\n<p>    Con todo, el catequista debe recordar que la moral cristiana es m\u00e1s positiva que negativa. Se cuida m\u00e1s de promover las virtudes que de fustigar los vicios.<\/p>\n<p>    Mira m\u00e1s a educar en el bien que a prevenir el mal, a pesar de que determinadas actitudes o corrientes cristianas rigoristas han pretendido lo contrario, por el prejuicio de que la naturaleza humana est\u00e1 da\u00f1ada por el pecado (iluminismo, jansenismo, pesimismo) y han pretendido m\u00e1s prevenir el mal que abrir la mente y el coraz\u00f3n del hombre a la pr\u00e1ctica del bien.<\/p>\n<p>    Pero, sin caer en el optimismo desmesurado, en el naturalismo, el catequista debe tender m\u00e1s a se\u00f1alar a sus catequizandos los caminos hacia el bien. Para ello se precisa energ\u00ed\u00ada, valor, fuerza y lucha. Y esto es la virtud.<\/p>\n<p>    1.2. Disposiciones<br \/>\n    Esta actitud implica determinadas disposiciones en el catequista:<\/p>\n<p>   &#8211; Si la conciencia se halla bien orientada, se lucha m\u00e1s contra el pecado, contra el vicio, contra las desviaciones, ense\u00f1anza a hacer el bien que adoptando actitudes defensivas contra el mal.<\/p>\n<p>   &#8211; Si la Iglesia dedica m\u00e1s tiempo y esfuerzo a defenderse del error que a predicar la verdad, no cumple el mandato de Jes\u00fas de \u00abpredicar el mensaje de salvaci\u00f3n a todas las naciones\u00bb. El Salvador la fund\u00f3 y env\u00ed\u00ado al mundo para anunciar el bien, el Evangelio, no para condenar el mal.<\/p>\n<p>   &#8211; Si el catequista gasta sus energ\u00ed\u00adas en prevenir contra el mal y no en despertar el deseo de hacer el bien, su catequesis se moraliza (se hace \u00e9tica) y se \u00abdesenvangeliza\u00bb, (pierde fuerza kerigm\u00e1tica). Entonces queda debilitada y se desgasta m\u00e1s bien pronto que tarde.<\/p>\n<p>    2. Naturaleza de la virtud<br \/>\n    La virtud en esencia es el h\u00e1bito bueno, del mismo modo que el vicio es el h\u00e1bito malo. El h\u00e1bito es la repetici\u00f3n de actos, lo que significa que es tendencia, costumbre, propensi\u00f3n que se adquiere a repetir lo mismo siempre que una vez se realiza.<\/p>\n<p>    La virtud, en s\u00ed\u00ad misma considerada, es una cualidad natural que se adquiere por la repetici\u00f3n de actos. Y por eso tiene tanta importancia en educaci\u00f3n, pues el educador debe lograr que, mediante esa repetici\u00f3n, se desarrollen las virtudes fundamentales de la vida cristiana.<\/p>\n<p>    Blas Pascal (1623-1662) dec\u00ed\u00ada \u00abLa virtud de un hombre no se mide por los esfuerzos que hace en ocasiones especiales, sino por la conducta ordinaria de la vida cotidiana\u00bb. (Pensamientos 29)<\/p>\n<p>    Las virtudes son los instrumentos o cauces con los que se consigue la virtud. La virtud es perfecci\u00f3n estable del mismo modo que las virtudes son instrumentos parciales.<\/p>\n<p>    Es evidente que los cristianos no pueden obrar en aspectos o terrenos de la fe y de la gracia por las solas fuerzas de la naturaleza o por los meros argumentos de la raz\u00f3n. S\u00f3lo si miran las cosas y los hechos a la luz del mensaje y de la vida de Cristo, su ideal se eleva a lo sobrenatural.<\/p>\n<p>    Ellos necesitan vivir con dinamismos m\u00e1s profundos en su obrar.<\/p>\n<p>    San Gregorio de Nisa (335-394) dec\u00ed\u00ada: \u00abEl objetivo de una vida virtuosa para el cristiano consiste en llegar a ser semejante a Dios. Ese debe ser su ideal\u00bb.<\/p>\n<p>    Y San Agust\u00ed\u00adn (354-431) recordaba: \u00abVivir bien no es otra cosa que amar a Dios con todo el coraz\u00f3n, con toda el alma y en todas las acciones. Quien est\u00e1 vigilante para no dejarse sorprender por la astucia y el enga\u00f1o, se halla siempre en disposici\u00f3n de hacer lo que dios quiere y ninguna desgracia puede perjudicarle o destruirle. La cumbre de nuestra vida es el amor. Este es nuestro fin. Para conseguirlo corremos y cuando lo conseguimos reposamos\u00bb<br \/>\n    3. Tipos de virtudes<br \/>\n    En la tradici\u00f3n asc\u00e9tica cristiana se suelen dividir las virtudes en teologales y morales, en sobrenaturales y en naturales, en divinas y humanas.<\/p>\n<p>    Las primeras son las que Dios nos concede en germen por su misma gracia y nosotros desarrollamos por nuestra fidelidad a sus invitaciones y en funci\u00f3n de nuestra aceptaci\u00f3n libre. Por eso las denominamos teologales, pues tienen a Dios por principio y por objeto.<\/p>\n<p>    3.1. Virtudes teologales[321]<br \/>\n    Estas virtudes teologales son regalos divinos que se nos infunden en el alma y nosotros desarrollamos poco a poco en la vida, actuando con buena voluntad y tambi\u00e9n respondiendo a las ayudas externas que recibimos, entre las cuales la educaci\u00f3n es la principal.<\/p>\n<p>   Estas virtudes, recogiendo la expresi\u00f3n de S. Pablo a los Corintios (1. Cor. 13. 13) son la caridad, la fe y la esperanza.<br \/>\n  *  La Caridad es la mayor gracia divina que recibimos del mismo Dios. No s\u00f3lo es un don el amor a Dios, sino que se desarrolla en el mismo hecho de amar a los hombres como hijos de Dios.<br \/>\n  *  La Fe es el gran don que se recibe gratuitamente de Dios y consiste en la adhesi\u00f3n plena a la Palabra divina.<br \/>\n  *  La Esperanza es la actitud de confianza que Dios nos inspira en virtud de sus gestos interminables de misericordia y seg\u00fan las promesas de salvaci\u00f3n que nos ha hecho.<\/p>\n<p>    3.2. Las virtudes morales[325]<\/p>\n<p>     Las virtudes morales son cualidades que nosotros desarrollamos por la repetici\u00f3n de actos buenos que constituyen su objeto. Las solemos llamar \u00e9ticas o morales.<\/p>\n<p>     Algunos autores antiguos, como Sto. Tom\u00e1s, las denominan cardinales, por ser ejes (cardo, gozne, en lat\u00ed\u00adn) de otras muchas que se construyen en torno a ellas y las desarrollan de alguna forma.<\/p>\n<p>    3.2.1. Opiniones y clasificaciones<br \/>\n    Se las considera en cuatro formas, ejes o grupos: prudencia, justicia, fortaleza y templanza.<\/p>\n<p>   En muchas de las explicaciones de estas cuatro virtudes, los comentaristas antiguos son tributarios de los maestros griegos de la Filosof\u00ed\u00ada, sobre todo de Plat\u00f3n y de Arist\u00f3teles.<\/p>\n<p>    Plat\u00f3n (La Rep\u00fablica. 4) habla de las cuatro virtudes que engendran otras, que son cardinales&#8230;: la prudencia, o sabidur\u00ed\u00ada pr\u00e1ctica, que es propia de la inteligencia; de fortaleza, o valent\u00ed\u00ada y coraje, propia del a voluntad; de la templanza, o austeridad de vida, que es propia del cuerpo; y de la justicia, o equilibrio, que implica la armon\u00ed\u00ada entre las otras tres<br \/>\n    Arist\u00f3teles, en la \u00abEtica a Nicom\u00e1co\u00bb (2.6), habla de la virtud como \u00abh\u00e1bito o forma de ser\u00bb&#8230;. como \u00abcualidad que depende de nuestra voluntad, pero regulada por la raz\u00f3n y que se sit\u00faa en un justo medio entre extremos\u00bb. Para \u00e9l hay dos formas de virtudes \u00abno\u00e9ticas\u00bb y dos \u00ab\u00e9ticas\u00bb: son no\u00e9ticas o te\u00f3ricas \u00abla prudencia y la justicia\u00bb: y son \u00e9ticas o pr\u00e1cticas \u00abla templanza y la fortaleza\u00bb.<\/p>\n<p>    Los romanos como Cicer\u00f3n, S\u00e9neca, Plotino, m\u00e1s tarde, seguir\u00ed\u00adan insistiendo en el valor de la virtud como forma de ordenar la vida de los hombres, individual y colectivamente considerados.<\/p>\n<p>    Los cristianos recoger\u00e1n de los grandes pensadores antiguos muchas de las formas de hablar de la virtud y de las virtudes.<\/p>\n<p>    San Agust\u00ed\u00adn entiende la virtud como \u00abordo amoris\u00bb, como ordenaci\u00f3n del amor hacia objetos concretos (De Civitas Dei 15. 22)&#8230; Es un h\u00e1bito del alma que sigue los cauces de la moderaci\u00f3n y de la rectitud.<\/p>\n<p>    Y Sto. Tom\u00e1s dir\u00e1 que la virtud es \u00abh\u00e1bito del alma que nos lleva hacia el bien, del mismo modo que el vicio es un h\u00e1bito que nos lleva al mal (Summa Th. 2. 2. q. 55)<\/p>\n<p>    En todos ellos hay coincidencia en reclamar la acci\u00f3n humana, unas veces libre y otras alentadas desde el exterior, en su consecuci\u00f3n. Adquirimos las virtudes con nuestro esfuerzo Y las poseemos todas ellas interrelacionadas de alguna forma.<\/p>\n<p>    3.2.2. Las cuatro virtudes<br \/>\n    Por eso a las b\u00e1sicas las denominamos cardinales, porque se convierten en ejes o fundamentos de otras muchas. Estas son las antes nombradas.<\/p>\n<p>     La Prudencia es la actitud reflexiva que nos facilita el discernimiento entre el bien y el mal.<\/p>\n<p>     La Justicia equivale a la llamada de nuestra conciencia a respetar al pr\u00f3jimo y ofrecer a cada uno lo que le corresponde.<\/p>\n<p>     La Fortaleza equivale a la energ\u00ed\u00ada de nuestro esp\u00ed\u00adritu y coraz\u00f3n para vencer el mal.<\/p>\n<p>    Y la Templanza es la moderaci\u00f3n en las inclinaciones sensoriales que sometemos a la justa raz\u00f3n.<\/p>\n<p>    Cualquiera de estas virtudes se puede considerar como regalos divinos para conseguir la vida cristiana y el comportamiento digno que Dios espera de nosotros.<\/p>\n<p>    4. Las virtudes y la vida<br \/>\n    Nuestra pertenencia a la familia humana, y tambi\u00e9n a la Comunidad de fe y de vida cristiana que es la Iglesia, reclama de nosotros una dimensi\u00f3n solidaria a nuestra manera de pensar y de actuar.<\/p>\n<p>    Las virtudes y los valores, los ideales y los criterios morales, las actitudes y los actos buenos, tienen siempre car\u00e1cter comunitario, incluso los que se hacen de la forma m\u00e1s secreta y personal.<\/p>\n<p>    Los hombres vivimos en relaci\u00f3n con los dem\u00e1s y los cristianos somos adem\u00e1s miembros del Cuerpo M\u00ed\u00adstico de Jes\u00fas. Todo lo bueno y lo malo que hacemos posee resonancia comunitaria. Tenemos que ser sensibles a esta dimensi\u00f3n de solidaridad y de vivencia moral compartida. Ella har\u00e1 nuestra conciencia m\u00e1s eclesial.<\/p>\n<p>    Son hermosas las recomendaciones sobre el a vida virtuosa que San Pablo ofrece a su disc\u00ed\u00adpulo Timoteo: \u00abHuye de los excesos juveniles, lucha por llevar vida de rectitud, de fe, de amor, de paz en uni\u00f3n con los que invocan sinceramente al Se\u00f1or. Evita las controversias in\u00fatiles e incorrectas que s\u00f3lo engendran altercados. Quien sirve al Se\u00f1or no debe ser pendenciero. Debe ser amable con todos, buen educador y sufrido\u00bb.<\/p>\n<p>   (2 Tim. 2. 20-24)<\/p>\n<p>     5. Virtudes teologales<br \/>\n    Son las que tienen a Dios por objeto, por centro, por motor: para creen en el, la fe, mucho m\u00e1s que la credulidad; para esperar en El, la esperanza, muy superior a la espera; y para amarle totalmente, la caridad, muy diferente de la filantrop\u00ed\u00ada y de la simpat\u00ed\u00ada.<\/p>\n<p>    5.1. La caridad<br \/>\n    La m\u00e1s excelente y sublime es la caridad. Es la m\u00e1s \u00abteol\u00f3gica\u00bb, la m\u00e1s centrada en El. \u00abEs la virtud teologal por la cual amamos a Dios sobre todas las cosas por El mismo, y a nuestro pr\u00f3jimo como a nosotros mismos por amor de Dios\u00bb. (Catec. de la Iglesia Cat\u00f3lica).<\/p>\n<p>    Esa referencia a Dios es el factor fundamental en el concepto cristiano de caridad, virtud sobrenatural que no une a Dios y que exige el amor humano. Precisamente por ese amor a Dios, el amor al hombre no se reduce a simpat\u00ed\u00ada, a compasi\u00f3n o a simple afecto. Si ella el amor humano no pasa de simple filantrop\u00ed\u00ada.<\/p>\n<p>    Fue la cualidad m\u00e1s reclamada por Jes\u00fas para sus seguidores. El proclam\u00f3 que el amor es el mandamiento principal de la Ley: \u00abEl amor a Dios y el amor al pr\u00f3jimo, que es un mismo amor\u00bb (Mt. 22. 37). Y les dio un s\u00f3lo mandamiento: \u00abAmaos los unos a los otros como yo os he amado, y en eso conocer\u00e1n que sois mis disc\u00ed\u00adpulos\u00bb. (Jn. 13. 34)<\/p>\n<p>    Son 143 las veces que aparece en el  N.T el verbo \u00abagapeo\u00bb, amar, y 117 la forma concreta de \u00abagap\u00e9\u00bb. Y son 75 las formas de \u00abfileo\u00bb, tambi\u00e9n expresi\u00f3n del amor o entrega al otro.<\/p>\n<p>    La caridad con el pr\u00f3jimo es la se\u00f1al distintiva del cristiano. Es la que autentifica el amor a Dios: \u00abQuien dice que ama a Dios, a quien no ve, y no ama a su pr\u00f3jimo, a quien ve, ese tal es un mentiroso.\u00bb (1 Jn. 14,20).<\/p>\n<p>    5.2. La Fe[322]<br \/>\n    Es la virtud del hombre inteligente que acoge el mensaje divino y lo asume como reflejo y expresi\u00f3n del mismo Dios. Es la actitud que se asume ante el misterio incomprensible, el cual se acepta por la misma autoridad de Dios. Es una virtud radical y su objeto es la persona la palabra o la voluntad de Dios.<br \/>\n  * La fe humana implica un objeto humano: creer en una persona o en una ense\u00f1anza de hombre. Supone acogida, adhesi\u00f3n y permanencia.<br \/>\n  *  La fe divina, sin embargo, implica un objeto superior: Dios y su mensaje, Cristo que es Dios encarnado y sus ense\u00f1anzas, el Esp\u00ed\u00adritu Santo que act\u00faa en el alma y la transforma.<\/p>\n<p>    Los te\u00f3logos cristianos resaltan el car\u00e1cter existencial absoluto de la fe, para distinguirla as\u00ed\u00ad del concepto de creencia.<\/p>\n<p>    El alma de la fe, como virtud teologal, es la adhesi\u00f3n a la misma persona de Cristo, que es divina. Por eso el cristianismo no implica s\u00f3lo la fe o aceptaci\u00f3n de lo que dice Jes\u00fas, sino la acogida de su misma persona divina. Los cristianos no creemos \u00aba\u00bb Jes\u00fas, sino creemos \u00aben\u00bb Jes\u00fas. Por eso llamamos a Jes\u00fas \u00abVerbo\u00bb, Logos, Palabra divina encarnada. No hacemos diferencia esencial entre su ser y su decir.<\/p>\n<p>    La fe es virtud misteriosa que Dios regala al hombre cuando y como quiere. Es muy superior a la creencia, que es actitud humana de aceptaci\u00f3n y acogida en funci\u00f3n del sentido de la inteligencia y de la bondad divina. Y desde luego es muy superior a la credulidad, que es la aceptaci\u00f3n ingenua de lo que se oye o se encuentra.<\/p>\n<p>    La fe abarca la creencia, est\u00e1 lejos del a credulidad. Pero se diferencia esencialmente ambas.<\/p>\n<p>    Todo el Nuevo Testamento, de los evangelistas y de las Cartas, sobre todo de Santiago y de S. Pablo, est\u00e1 aludiendo continuamente a la importancia de la fe como acogida del mensaje de Cristo. Por ejemplo en la Carta a los Hebreos (11, 1) la fe se proclama como \u00abel fundamento de las cosas que se esperan y un convencimiento de las cosas que no se ven\u00bb.<\/p>\n<p>    La palabra griega que se emplea es preferentemente \u00abpistis\u00bb, que significa el acto de dar la confianza de uno. Las 242 veces que aparece en los libros del Nuevo Testamento y las 274 que se usa en su forma verbal \u00abpisteuo\u00bb o en diversos compuestos, significan el concepto radical de acogida o adhesi\u00f3n de un mensaje divino es el alma del t\u00e9rmino.<\/p>\n<p>    La idea hebrea arcaica de la fe, como confianza y confianza, queda superada en el Nuevo Testamento con el concepto de gracia divina, de uni\u00f3n con Dios, de acogida de sus palabras. En Teolog\u00ed\u00ada cristiana se ha de distinguir entre el elemento subjetivo de la fe, que implica la acci\u00f3n sobrenatural de Dios en el alma humana, y el componente objetivo de la fe, que se caracteriza por reunir un conjunto de verdades en lo que denominanos credos, en las definiciones de los concilios de la Iglesia y, en especial, en la Biblia.<\/p>\n<p>    5.3. La Esperanza<br \/>\n    Es la virtud teologal que lleva al individuo a poner absoluta confianza en Dios y en su proyecto de salvaci\u00f3n de la humanidad. La esperanza no es una actitud est\u00e1tica, no es la simple espera, sino algo din\u00e1mico: lo que lleva a colaborar de forma activa con el plan de salvaci\u00f3n y transformaci\u00f3n del mundo.<\/p>\n<p>    Las 86 veces que aparece el t\u00e9rmino de esperanza, en forma de verbo \u00abelpidso\u00bb o como sustantivo \u00abelpis\u00bb, alude a la situaci\u00f3n de quien conf\u00ed\u00ada en alguien superior. Es la esperanza, la confianza puesta en Dios.<\/p>\n<p>    La esperanza cristiana, como virtud teol\u00f3gica, tiene a Dios por centro y ello compromete en el mundo. Por eso es virtud que engendra deseo de mejora, compromiso de acci\u00f3n, af\u00e1n de aumentar la paz, la justicia y el bien en el mundo, en el cual se desea instalar el Reino anunciado por Jes\u00fas y esperado por sus seguidores en la otra vida y en \u00e9sta.<\/p>\n<p>    Es conveniente caer en la cuenta de que, en esencia, la esperanza como virtud cristiana no es pac\u00ed\u00adfica y resignada espera a que llegue el Reino de Dios en el otro mundo. No mira s\u00f3lo al m\u00e1s all\u00e1, sino que hace al que la posee consciente de que lo que Dios espera de nosotros en el m\u00e1s ac\u00e1 es la lucha contra el mal y el trabajo esforzado para establecer el bien.<\/p>\n<p>     Se debe, pues, superar el mero concepto de esperanza como confianza en la salvaci\u00f3n en el mundo que vendr\u00e1.<\/p>\n<p>     Esto es muy importante en la formaci\u00f3n cristiana de la conciencia, pues durante mucho tiempo se ha pensado que la religi\u00f3n consuela e inhibe. Los adversarios del cristianismo, como Marx (religi\u00f3n, sobretodo cristiana, el opio del pueblo), Nietzsche (religi\u00f3n destrucci\u00f3n del hombre fuerte y libre), Fueuerbach (religi\u00f3n opresi\u00f3n de la inteligencia), han explotado esta perspectiva parcial y falsa.<\/p>\n<p>     La religi\u00f3n reclama caridad comprometida, esperanza din\u00e1mica y fe luchadora. Son pues virtudes que se manifiestan en las obras de la vida. Si esta dimensi\u00f3n no se entiende y se convierte en programas de educaci\u00f3n comprometida y comprometedora no hay formaci\u00f3n cristiana verdadera y duradera.<\/p>\n<p>    6. Virtudes morales<br \/>\n    Las virtudes morales est\u00e1n m\u00e1s centradas en el hombre en cuanto ser libre que las adquiere con la repetici\u00f3n de actos buenos. Reclaman un programa intenso de actos buenos, libres, repetidos, ordenados y graduados, que vayan haci\u00e9ndolas penetrar hasta el fondo de la persona y convirti\u00e9ndolas en h\u00e1bitos firmes, que eso son las virtudes.<\/p>\n<p>    6.1. Prudencia.[327]<br \/>\n    Es la virtud del sentido com\u00fan, cuya base es la inteligencia. Se identifica con la sabidur\u00ed\u00ada: 76 veces en la ra\u00ed\u00adz de sof\u00ed\u00ada (sabidur\u00ed\u00ada), 37 en la de fronesis (discreci\u00f3n), 35 en la de synhiemi (pensamiento reflexivo). Aparece el t\u00e9rmino en m\u00faltiples contextos sem\u00e1nticos y conceptuales a lo largo de todo el Nuevo Testamento.<\/p>\n<p>    Pero la sabidur\u00ed\u00ada llevada a la vida de cada d\u00ed\u00ada, el sentido com\u00fan, la habilidad, para moverse en el mundo es la que esconde la fuerza, la virtud, cristiana<br \/>\n    En cualquiera de las acepciones en que recojamos la idea, la prudencia refleja la serenidad en la mente, la capacidad para desenvolverse en el mundo, la discreci\u00f3n para relacionarse y la habilidad para situarse.<\/p>\n<p>    Es una virtud recomendada por el mismo Jes\u00fas: \u00abSed prudentes como serpientes\u00bb (Mt 10.16). \u00abSiervo fiel y prudente\u00bb (Mt. 24. 24). \u00abV\u00ed\u00adrgenes prudentes\u00bb (Mt. 25. 8)&#8230; \u00abEl que pone por obra mis palabras es prudente&#8230;\u00bb (Mt 10.16)<\/p>\n<p>    La prudencia tiene sus mejores manifestaciones en la serenidad en los juicios, en la agudeza en las previsiones, en la acomodaci\u00f3n a los recursos y a los cambios, en la serenidad en las decisiones, en la moderaci\u00f3n y en la estabilidad en las opciones.<\/p>\n<p>    6.2. Fortaleza.[326]<br \/>\n    Es la virtud que nos hace enfrentarnos con decisi\u00f3n a las diversas circunstancias de la vida. En el Nuevo Testamento se identifica con el valor, la decisi\u00f3n y la energ\u00ed\u00ada, la capacidad de persuadir, la decisi\u00f3n, la audacia, el atrevimiento.<\/p>\n<p>    En todo caso es la cualidad que le hace al hombre enfrentarse sin cobard\u00ed\u00ada y sin debilidad con las adversidades y con los enemigos. Eso supone que desarrolla confianza en Dios y humildad ante s\u00ed\u00ad mismo, que se abre a los dem\u00e1s sin temor y no se acobarda por los obst\u00e1culos. Se presenta a Cristo como el modelo de fortaleza, de valent\u00ed\u00ada y de decisi\u00f3n. Por eso la fortaleza cristiana alcanza la plenitud en el martirio, es decir en la capacidad de dar testimonio de la propia fe al precio de la propia vida, como aconteci\u00f3 con el mismo Jes\u00fas.<\/p>\n<p>    No cabe duda de que la catequesis de la fortaleza supone una decisiva actuaci\u00f3n del educador de la fe. Se prepara a los actos de fortaleza con la paciencia en las adversidades, con el optimismo en los juicios de valor, con el cultivo de la alegr\u00ed\u00ada y con la resignaci\u00f3n serena en los fracasos cuando llegan.<\/p>\n<p>     6.3. Templanza<\/p>\n<p>     Es la virtud que facilita la vida superior y la superaci\u00f3n de las inclinaciones materiales de hombre. Tiene que ver con la renuncia, con la austeridad, con la penitencia, con el trabajo, con el esfuerzo, con la sobriedad, con el dominio de si mismo.<\/p>\n<p>      El cristiano es un caminante en la vida y su ideal no est\u00e1 en aprovecharse del presente, sino en prepararse para el porvenir. Por eso el Evangelio insiste en la penitencia y en la pobreza como caminos de la salvaci\u00f3n y se rechaza el abuso de los bienes de esta vida como peligro de empobrecimiento moral y espiritual de los seguidoresde Jes\u00fas.<\/p>\n<p>     6.4. Justicia<\/p>\n<p>     Es la constante y perpetua voluntad de dar a cada uno lo que le corresponde. Es una actitud radical de la persona humana que se traduce en honradez, en sinceridad, en respeto, en apertura y en comprensi\u00f3n con todos los hombres.<\/p>\n<p>    6.4.1. Rasgos evang\u00e9licos<br \/>\n    En el mensaje de Jes\u00fas, que es lo mismo que decir en lo m\u00e1s profundo y vivo de su doctrina, la justicia se presente como eje y fundamento de la fidelidad a Dios.<\/p>\n<p>    La frecuencia con que aparece el termino justicia (dikaiosine, dikaios) en los escritos del Nuevo Testamento (228 en forma positiva, justo, justicia, justificar; y 71 en referencia negativa, injusto, injusticia) indica la importancia que tiene la idea en los autores.<\/p>\n<p>    Posee un doble sentido: por una parte, la participaci\u00f3n en la pureza de Dios reflejada en la conducta de los hombres; y por otra, recoge la amistad divina lograda despu\u00e9s de la destrucci\u00f3n del pecado.<\/p>\n<p>    No es extra\u00f1o que Jes\u00fas aluda continuamente al ideal de la justicia como verdadero distintivo de los que se hallan cerca del Reino de Dios que El ha venido a anunciar al mundo. A sus seguidores les recomienda: \u00abBuscad primero de todo el Reino de Dios y su justicia y todo lo dem\u00e1s os vendr\u00e1 por a\u00f1adidura\u00bb. (Mt 6. 33)<\/p>\n<p>    Y a todos bendice con el deseo de que lleguen a ser due\u00f1os de la justicia, triunfando en sus vidas: \u00abBienaventurados los que tienen hambre y sed de justicia, porque ver\u00e1n sus deseos satisfechos y bienaventurados los que sufren persecuci\u00f3n por la justicia, porque suyo es el Reino de los cielos\u00bb (Mt 5. 6-10).<\/p>\n<p>    La justicia es ante todo una actitud del coraz\u00f3n que refleja el amor divino al mundo y se traduce en respuesta de obras honestas. No es un c\u00f3digo de conducta, pues las normas de poco sirven si no nacen del coraz\u00f3n. Las obras son justas s\u00f3lo si proceden de un coraz\u00f3n que las hace tales. De lo contrario, pueden ser mera apariencia.<\/p>\n<p>    Tambi\u00e9n en esta limpieza interior insiste el mensaje de Jes\u00fas, sobre todo al mirar a su alrededor y ver tantos hombres que fingen justicia sin tenerla en su interior: \u00abMirad que si vuestro justicia no es mayor que la que muestran los escribas y fariseos, no entrar\u00e9is en el Reino de los cielos\u00bb   (Mt. 5. 20)<br \/>\n  Las virtudes. De Rafael<br \/>\n    6.4.2. Obras de la justicia<br \/>\n    El sentido de justicia que Jes\u00fas muestra en sus palabras es verdaderamente comprometedor para quienes quieren vivir en armon\u00ed\u00ada con sus ense\u00f1anzas.<\/p>\n<p>    Por una parte mira a Dios, que es la fuente de toda justicia y reclama que el hombre se comporte en su presencia como El quiere. Por otra parte ofrece una profunda referencia a los hombres, a los cuales hay que tratar como Dios espera y como el ser imagen suya reclama.<\/p>\n<p>    Jes\u00fas explica su sentido de la justicia con la par\u00e1bola del criado inicuo, a quien el amo perdon\u00f3 la gran deuda que ten\u00ed\u00ada de diez mil talentos: \u00abNo teniendo con qu\u00e9 pagar, mand\u00f3 que le vendieran a \u00e9l, a su mujer, a sus hijos y a todas su cosas. Cay\u00f3 de rodillas y le dec\u00ed\u00ada: \u00abTen paciencia conmigo, que todo te lo pagar\u00e9\u00bb. Compadecido, el amo se lo perdon\u00f3 todo.<\/p>\n<p>    Al salir, se encontr\u00f3 con un compa\u00f1ero que le deb\u00ed\u00ada cien denarios. Le agarr\u00f3 por el cuello y le dijo: \u00abP\u00e1game lo que me debes\u00bb. Y \u00e9l le dec\u00ed\u00ada: \u00abTen paciencia conmigo, que yo te lo pagar\u00e9\u00bb. Pero no quiso y le meti\u00f3 en prisi\u00f3n hasta que liquid\u00f3 la deuda\u00bb   (Mat.18. 23-34)<\/p>\n<p>     En la ense\u00f1anza de esta par\u00e1bola de Jes\u00fas, el sentido de justicia es mucho m\u00e1s profundo que el mero zanjar las deudas. Llega a las actitudes del coraz\u00f3n, rechaza la dureza en el trato m\u00e1s all\u00e1 de las razones, abarca a la totalidad de la vida, compromete a la benevolencia y al agradecimiento.<\/p>\n<p>    No es extra\u00f1o que Jes\u00fas ponga en boca del amo la profunda explicaci\u00f3n de la actitud injusta: \u00abSiervo malvado, \u00bfno era justo que t\u00fa perdonaras a tu compa\u00f1ero como yo te perdon\u00e9 a ti?\u00bb<br \/>\n    La justicia de los hombres y entre los hombres posee siempre un reflejo, un eco y una imitaci\u00f3n de la misma Justicia de Dios, que los hombres tienen que imitar.<\/p>\n<p>    6.4.3. Tipos y formas<br \/>\n    La extensi\u00f3n de la justicia llega a todos los terrenos y momentos de la vida humana. Es un modo de ser y no s\u00f3lo un estilo de obrar. Por lo tanto, compromete a toda la personalidad en la ordenaci\u00f3n de los comportamientos en relaci\u00f3n consigo mismo y con los dem\u00e1s.<\/p>\n<p>    Por eso, siempre se ha hablado de la justicia en la moral cristiana aludiendo a sus diversos modos o manifestaciones.<\/p>\n<p>   &#8211; Es justicia legal la que impulsa al hombre cristiano a cumplir la ley, tanto divina como humana, por ser reflejo de la voluntad de Dios.<\/p>\n<p>   &#8211; Es justicia distributiva la que lleva a la conciencia a asumir, en la comunidad a la que se pertenece, las dedicaciones, impuestos o servicios, que reclama la igualdad y la proporcionalidad debida en las relaciones colectivas.<\/p>\n<p>   &#8211; Es justicia conmutativa la que mueve a cada persona a dar a los dem\u00e1s todo lo que les corresponde y a tratar a todos con la misma medida y sin discriminaciones, dando equilibrio y paz a las relaciones interpersonales.<\/p>\n<p>   &#8211; Es justicia personal la virtud de la mente y de la voluntad que arrastra hacia el cumplimiento del deber, como respuesta al reclamo de la propia conciencia.<\/p>\n<p>   &#8211; Y hablamos de justicia social cuando se manifiesta en sistemas y estilos de relaci\u00f3n colectiva, que mueven a asegurar y afirmar el equilibrio en la sociedad, a partir del cumplimiento de los deberes por parte de cada miembro de ella.<\/p>\n<p>    Todos estos tipos o modos de justicia se hilvanan en valores comunes de orden, de equidad, de dependencia de la voluntad de Dios. Todos aluden a la ley que est\u00e1 escrita en los corazones y se convierte en norma de acci\u00f3n pues algo nos dice en nuestro interior c\u00f3mo se debe actuar y en qu\u00e9 nos debemos vigilar para no alejarnos de Dios.<\/p>\n<p>    San Pablo escrib\u00ed\u00ada: \u00abNo son justos los que conocen la ley, sino los que la llevan a su cumplimiento\u00bb  (Rom 2. 12)<\/p>\n<p>    6.4.5. Las injusticias<br \/>\n    Tendremos que recordar tambi\u00e9n que la justicia reclama una preparaci\u00f3n de la mente y del coraz\u00f3n para hacerse realidad en la vida y no quedarse en mera forma de hablar.<\/p>\n<p>    S\u00f3lo quien ordena sus criterios y desarrolla sus h\u00e1bitos de comportamiento en conformidad con sus exigencias, puede llamarse justo. Por eso la formaci\u00f3n de la mente y la educaci\u00f3n de la voluntad en actitudes de justicia reclaman tiempo y deseos de conseguirlo.<\/p>\n<p>      Por una parte se requiere evitar las injusticias, o situaciones que lesionan los derechos de los dem\u00e1s. El lenguaje m\u00e1s frecuente de esas lesiones es el de la discriminaci\u00f3n, la cual puede ser de muchos tipos:  &#8211; Discriminaci\u00f3n racial es cuando unos grupos se imponen a otros y les consideran de inferior dignidad o les oprimen con imposiciones.<\/p>\n<p>  &#8211; Discriminaci\u00f3n sexual es la que implica infravaloraci\u00f3n de un sexo, ordinariamente el femenino, con actitudes prepotentes e irracionales.<\/p>\n<p>  &#8211; Discriminaci\u00f3n cultural, pol\u00ed\u00adtica, econ\u00f3mica, religiosa, etc. son diversas formas que atentan a la radical igualdad de los hombres, que es un postulado \u00ed\u00adntimo de la raz\u00f3n y de la naturaleza.<\/p>\n<p>    Cualquiera de estas discriminaciones perturba la ley de Dios, para quien todos los hombres son iguales. Aunque en el mundo encontramos muchas injusticias, el cristiano no puede resignarse a ella y debe luchar contra su imperio.<\/p>\n<p>     La mejor manera de hacerlo es fomentar la igualdad y el respeto, la paz y la bondad, la honradez y la solidaridad. A todo esto se denomina justicia en el sentido m\u00e1s preciso de la palabra.<\/p>\n<p>    Esta justicia adquiere expresi\u00f3n concreta en el Derecho positivo, que es la expresi\u00f3n del deseo de esa justicia como forma de vida social. En la sociedad la justicia se persigue por medio del ordenamiento jur\u00ed\u00addico que tiende a promover la dignidad, la libertad, la igualdad y el pluralismo. Se se\u00f1ala este orden ya que son valores que expresan la justicia.<\/p>\n<p>    Sin embargo la justicia de la colectividad s\u00f3lo es posible cuando cada miembro de ella ha sido formado en la justicia y ha conseguido ordenar su vida en conformidad con ella. Por eso tiene tanta importancia la educaci\u00f3n en la justicia en un sentido muy general, pero tambi\u00e9n en clave evang\u00e9lica.<\/p>\n<p>    6.5. Catequesis de la justicia<br \/>\n    La educaci\u00f3n en la justicia cristiana es una de las urgencias de la catequesis en todos los tiempos, pero sobre todo en los momentos y en los ambientes en que m\u00e1s se puede alterar la vida justa seg\u00fan el cristianismo<br \/>\n    Por eso, en los tiempos actuales, en que predomina en el mundo la injusta distribuci\u00f3n de los bienes y de las oportunidades, el catequista debe hacer lo posible por tomar como prioritaria este tipo de educaci\u00f3n.<\/p>\n<p>    Es exigencia del Evangelio y es reclamo de la Iglesia en los tiempos actuales, que ha llamado la atenci\u00f3n por medio del Concilio Vaticano II, de los Papas del siglo XX y de la misma sensibilidad de los creyentes que advierten las deficiencias sociales y los abusos frecuentes.<\/p>\n<p>    El catequista debe buscar planes adecuados a cada edad, siempre consciente de que es una forma especialmente querida por el Se\u00f1or, que se present\u00f3 ante los hombres como profeta que reclamaba la justicia en el mundo y la caridad cuando la justicia no fuera suficiente.<\/p>\n<p>    Trabajar por la justicia y no s\u00f3lo luchar contra la injusticia es lo que diferencia al cristiano positivo del mero portavoz de reivindicaciones humanas y sociales, que con frecuencia se queda en un l\u00ed\u00adder social o pol\u00ed\u00adtico.<\/p>\n<p>    San Pablo, que tantas veces habla de la justicia fundamentada en Cristo, nos recuerda que es el amor a Jes\u00fas el que nos lleva a ser justos con los hijos de Dios. \u00abEl hombre no se justifica por las obras de la ley, sino por la fe en Jesucristo. Por eso ponemos nuestra confianza en Cristo, con el fin de obtener de Dios la plena justificaci\u00f3n por El.\u00bb (Gal 2. 16-18). (Ver justificaci\u00f3n)<\/p>\n<p>Pedro Chico Gonz\u00e1lez, Diccionario de Catequesis y Pedagog\u00ed\u00ada Religiosa, Editorial Bru\u00f1o, Lima, Per\u00fa 2006<\/p>\n<p><b>Fuente: Diccionario de Catequesis y Pedagog\u00eda Religiosa<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[320] Etimol\u00f3gicamente (virtus) virtud significa fuerza, energ\u00ed\u00ada, cualidad de var\u00f3n (vir). En catequesis el tema de la \u00abvirtud\u00bb es muy general, pero importante. Y el de las virtudes es ambicioso y prolijo, pero concreto. Ambos son prioritarios. 1. Vida y virtud El terreno pr\u00e1ctico, concreto y din\u00e1mico de las virtudes orienta la acci\u00f3n del catequista &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/virtudes\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abVIRTUD\/ES\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-14476","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/14476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=14476"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/14476\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=14476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=14476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=14476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}