{"id":14478,"date":"2016-02-05T09:32:31","date_gmt":"2016-02-05T14:32:31","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/visigodos\/"},"modified":"2016-02-05T09:32:31","modified_gmt":"2016-02-05T14:32:31","slug":"visigodos","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/visigodos\/","title":{"rendered":"VISIGODOS"},"content":{"rendered":"<p>[933]<br \/>\n  Pueblo b\u00e1rbaro que construy\u00f3 el m\u00e1s importante de los reinos del sur de Europa, una vez que fue arrinconado en la pen\u00ed\u00adnsula ib\u00e9rica, aunque su dominio llego a ser tan amplio que llegaba desde Dalmacia a los terrenos del Ebro. El nombre indicaba ya que eran los godos del Oeste (en alem\u00e1n, west, oeste).<\/p>\n<p>    Comenz\u00f3 su expansi\u00f3n en el siglo IV, pero en el VI se organiz\u00f3 en Hispania, a donde penetr\u00f3 en el 416, con consentimiento de Roma, de cuyo imperio los visigodos eran federados. Incluso fueron llamados para luchar contra los otros b\u00e1rbaros (suevos, v\u00e1ndalos y alanos). Terminaron dominando la situaci\u00f3n y la capital de su reino se coloc\u00f3 en Toledo, desde donde domin\u00f3 hasta el 711, a\u00f1o en el que se produjo la invasi\u00f3n mahometana y el reino desapareci\u00f3.<\/p>\n<p>    El principal rey visigodo fue Leovigildo (568-586) que extendi\u00f3 su dominio hasta la B\u00e9tica. Religiosamente eran arrianos, por influencia cristiana adquirida en Oriente. Su hijo Hermenegildo, gobernante en la B\u00e9tica fue quien pretendi\u00f3 sustituirlo por la dependencia de Roma. Se sublev\u00f3 (579), pero muri\u00f3 al ser apresado. Su otro hijo Recaredo en el III Concilio de Toledo (589).<\/p>\n<p>    Las leyes promulgadas por Recesvinto  en el Liber Iudiciorum (654) unificaron jur\u00ed\u00addicamente a godos e hispanorromanos. El gobierno qued\u00f3 mediatizado por los concilios de Toledo, el IV de los cuales (633) hizo la monarqu\u00ed\u00ada hereditaria, naciendo una corte animada por los nobles (conde, duques, marqueses) que aceleraron la destrucci\u00f3n del reino con sus rivalidades y a veces traiciones. El \u00faltimo rey visigodo, Rodrigo, fue derrotado y muerto por los musulmanes en la batalla de Guadalete (711) y con \u00e9l desapareci\u00f3 el reino de Toledo.<\/p>\n<p>    La mezcla entre el poder pol\u00ed\u00adtico y el religioso fue un rasgo negativo de este reino. La Iglesia foment\u00f3 la cultura casi en exclusiva. La figura sobresaliente fue la del Obispo de Sevilla, San Isidoro  autor de las Etimolog\u00ed\u00adas y de otros muchos escritos.<\/p>\n<p>Pedro Chico Gonz\u00e1lez, Diccionario de Catequesis y Pedagog\u00ed\u00ada Religiosa, Editorial Bru\u00f1o, Lima, Per\u00fa 2006<\/p>\n<p><b>Fuente: Diccionario de Catequesis y Pedagog\u00eda Religiosa<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[933] Pueblo b\u00e1rbaro que construy\u00f3 el m\u00e1s importante de los reinos del sur de Europa, una vez que fue arrinconado en la pen\u00ed\u00adnsula ib\u00e9rica, aunque su dominio llego a ser tan amplio que llegaba desde Dalmacia a los terrenos del Ebro. El nombre indicaba ya que eran los godos del Oeste (en alem\u00e1n, west, oeste). &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/visigodos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abVISIGODOS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-14478","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/14478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=14478"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/14478\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=14478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=14478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=14478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}