{"id":18216,"date":"2016-02-05T11:45:23","date_gmt":"2016-02-05T16:45:23","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/luz-ii\/"},"modified":"2016-02-05T11:45:23","modified_gmt":"2016-02-05T16:45:23","slug":"luz-ii","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/luz-ii\/","title":{"rendered":"LUZ, II"},"content":{"rendered":"<p>(Almendro).<\/p>\n<p>1. Antiguo nombre de la ciudad de Betel, que debieron darle los cananeos. Jacob puso por nombre Betel (que significa \u2020\u0153Casa de Dios\u2020\u009d) al lugar donde recibi\u00f3 una revelaci\u00f3n divina por medio de un sue\u00f1o; era el mismo lugar donde tiempo atr\u00e1s Abrah\u00e1n hab\u00ed\u00ada acampado. (G\u00e9 28:16-19; 35:6.) Se ha identificado el pueblo de Luz con las ruinas de Beit\u00ed\u00adn, a unos 17 Km. al N. de Jerusal\u00e9n. Parece que con el tiempo el nombre Betel sustituy\u00f3 al de Luz, al menos para cuando se produjo la conquista israelita de Cana\u00e1n. (Jue 1:22.) La redacci\u00f3n de Josu\u00e9 16:2 en algunas versiones (BR; Mod; Val, 1960, y otras), que dicen que los l\u00ed\u00admites del territorio de Efra\u00ed\u00adn sal\u00ed\u00adan \u2020\u02dcde Bet-el a Luz\u2020\u2122, ha llevado a algunos a pensar que se trataba de lugares diferentes. Sin embargo, otras traducciones relacionan ambos nombres como si se tratase de un mismo lugar, por ejemplo: \u2020\u0153de B\u00e9tel, Luz, [&#8230;]\u2020\u009d (NC); \u2020\u0153de Betel-Luz\u2020\u009d (SA); \u2020\u0153de Betel, es decir, Luz\u2020\u009d (VP), y \u2020\u0153de Betel, que pertenece a Luz\u2020\u009d (NM). Despu\u00e9s del primer cap\u00ed\u00adtulo del libro de los Jueces no se vuelve a emplear el nombre Luz en el texto b\u00ed\u00adblico. (V\u00e9ase BETEL n\u00fam. 1.)<br \/>\nEl t\u00e9rmino hebreo (luz) que corresponde al nombre del pueblo se emplea tambi\u00e9n en G\u00e9nesis 30:37 con referencia a las varas de almendro que us\u00f3 Jacob.<\/p>\n<p>2. Nombre de una ciudad edificada en \u2020\u0153la tierra de los hititas\u2020\u009d por un hombre de Betel (Luz) que ayud\u00f3 a los israelitas de la casa de Jos\u00e9 a derribar la ciudad. Como ocurri\u00f3 con Rahab y su familia, a este hombre y a los suyos se les dej\u00f3 ir sanos y salvos, pero, a diferencia de Rahab, no se interes\u00f3 en permanecer con los israelitas, sino que se fue a la tierra de los hititas y edific\u00f3 all\u00ed\u00ad la ciudad que llam\u00f3 Luz, seguramente en memoria de su ciudad natal, todo lo cual parece indicar que no ayud\u00f3 a los israelitas movido por temor y aprecio genuino por Jehov\u00e1 el Dios de Israel. El hecho de que la Biblia no mencione su nombre indica que no se le da ning\u00fan reconocimiento, a diferencia del caso de Rahab. (Jue 1:23-26.) Hay quienes consideran que probablemente el nombre de aquella ciudad por lo menos est\u00e1 reflejado en el de las ruinas de el-Louaize, a unos 20 Km. al ESE. de Sid\u00f3n.<\/p>\n<p><b>Fuente: Diccionario de la Biblia<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Almendro). 1. Antiguo nombre de la ciudad de Betel, que debieron darle los cananeos. Jacob puso por nombre Betel (que significa \u2020\u0153Casa de Dios\u2020\u009d) al lugar donde recibi\u00f3 una revelaci\u00f3n divina por medio de un sue\u00f1o; era el mismo lugar donde tiempo atr\u00e1s Abrah\u00e1n hab\u00ed\u00ada acampado. (G\u00e9 28:16-19; 35:6.) Se ha identificado el pueblo de &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/luz-ii\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLUZ, II\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-18216","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/18216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=18216"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/18216\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=18216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=18216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=18216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}