{"id":22241,"date":"2016-02-05T15:16:08","date_gmt":"2016-02-05T20:16:08","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/celesiria\/"},"modified":"2016-02-05T15:16:08","modified_gmt":"2016-02-05T20:16:08","slug":"celesiria","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/celesiria\/","title":{"rendered":"CELESIRIA"},"content":{"rendered":"<p><p style='text-align:justify;'><span lang=ES style=''>(gr. <\/span><span style=''>koil&#275; syria<\/span><span lang=ES style=''>, \u2018Siria hueca\u2019), 1 Esdras 2.17, etc.; 2 Mac. 3.5, etc., el valle que se encuentra entre el L\u00edbano y la cadena del Antil\u00edbano, la moderna El-Biqa (cf. <\/span><span style=''>biq\u2019a&#7791; \u2019&#257;wen<\/span><span lang=ES style=''>, \u201cel valle de Av\u00e9n\u201d, Am. 1.5). Como regi\u00f3n pol\u00edtica bajo los imperios tolemaida y sel\u00e9ucida frecuentemente comprende una zona m\u00e1s amplia, a veces llegando hasta Damasco en el N e incluyendo Fenicia al O o Judea al S. Desde el 312 hasta el 198 a.C. form\u00f3 parte del imperio tolemaida, pero se rindi\u00f3 a los Sel\u00e9ucidas como consecuencia de la batalla de Pani\u00f3n en el \u00faltimo a\u00f1o mencionado. Celesiria fue una divisi\u00f3n administrativa de la provincia de Siria despu\u00e9s de la ocupaci\u00f3n romana (64 a.C.). Herodes fue designado prefecto militar de Celesiria por Sexto C\u00e9sar en 47 a.C. y nuevamente por Casio en 43 a.C.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal align=right style='text-align:right;line-height:normal'><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><etiqueta id=\"#_ftn394\" name=\"_ftnref394\" title=\"\"><span lang=ES style='font-size:10.0pt; ;color:green'>F.F.B.<\/span><\/etiqueta><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><\/p>\n<p style='text-align:justify;'>Douglas, J. (2000). Nuevo diccionario Biblico : Primera Edicion. Miami: Sociedades B\u00edblicas Unidas.<\/p>\n<\/p>\n<p><b>Fuente: Nuevo Diccionario B\u00edblico<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(gr. koil&#275; syria, \u2018Siria hueca\u2019), 1 Esdras 2.17, etc.; 2 Mac. 3.5, etc., el valle que se encuentra entre el L\u00edbano y la cadena del Antil\u00edbano, la moderna El-Biqa (cf. biq\u2019a&#7791; \u2019&#257;wen, \u201cel valle de Av\u00e9n\u201d, Am. 1.5). Como regi\u00f3n pol\u00edtica bajo los imperios tolemaida y sel\u00e9ucida frecuentemente comprende una zona m\u00e1s amplia, a veces &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/celesiria\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCELESIRIA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-22241","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/22241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=22241"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/22241\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=22241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=22241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=22241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}