{"id":22256,"date":"2016-02-05T15:16:40","date_gmt":"2016-02-05T20:16:40","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/cronologia-del-nuevo-testamento\/"},"modified":"2016-02-05T15:16:40","modified_gmt":"2016-02-05T20:16:40","slug":"cronologia-del-nuevo-testamento","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/cronologia-del-nuevo-testamento\/","title":{"rendered":"CRONOLOGIA DEL NUEVO TESTAMENTO"},"content":{"rendered":"<p><p style='text-align:justify;'><span lang=ES style=''>(V\u00e9anse Tabla \u201cCronolog\u00eda: Antiguo y Nuevo Testamentos\u201d) Los cristianos primitivos demostraron poco inter\u00e9s en las cronolog\u00edas. La escasez de datos en los escritos del <etiqueta id=\"#_ftn983\" name=\"_ftnref983\" title=\"\">NT y la falta de certeza en cuanto a la interpretaci\u00f3n de la mayor parte de los datos de que se dispone hacen que la cuesti\u00f3n de la cronolog\u00eda del NT resulte bastante espinosa. Adem\u00e1s, se trata de una cuesti\u00f3n inconclusa, ya todav\u00eda pueden aparecer aclara<\/etiqueta>ciones de fuentes insospechadas. En la actualidad, en la mayor\u00eda de los casos, apenas se pueden tener en cuenta ciertas probabilidades y determinar hacia qu\u00e9 lado se inclina la balanza.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><b><span lang=ES style=''>I. Cronolog\u00eda de la vida de Jes\u00fas<\/span><\/b><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><i><span lang=ES style=''>a. Su nacimiento<\/span><\/i><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><span lang=ES style=''>El nacimiento de Jes\u00fas ocurri\u00f3 antes de la muerte de Herodes el Grande (Mt. 2.1; Lc. 1.5), por lo tanto a m\u00e1s tardar en el a\u00f1o 4 a.C. (<etiqueta id=\"#_ftn984\" name=\"_ftnref984\" title=\"\">Jos., <\/etiqueta><etiqueta id=\"#_ftn985\" name=\"_ftnref985\" title=\"\">Ant. 17. 191; 14. 389, 487).<\/etiqueta><\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Seg\u00fan Lc. 2.1\u20137, el nacimiento de Jes\u00fas se produjo en el momento en que se realizaba un empadronamiento, cuando Cirenio era gobernador de la Siria. Ahora bien, Cirenio no pudo haber gobernado la Siria sino despu\u00e9s de su consulado en el a\u00f1o 12 a.C. y Josefo no menciona, ni tampoco los historiadores romanos, que lo haya hecho durante el intervalo 11\u20134 a.C. Pero fue gobernador de la Siria en el a\u00f1o 6\/7 d.C., y en ese entonces efectu\u00f3 el empadronamiento de Judea que provoc\u00f3 el alzamiento de Judas el Galileo (Jos., <i>Ant.<\/i> 18. 1ss). Esto llev\u00f3 a algunos a pensar que en Lc. 2.2 el empadronamiento llevado a cabo cuando naci\u00f3 Jes\u00fas se ha confundido con este empadronamiento posterior y m\u00e1s conocido. Sin embargo, es posible que *Cirenio haya gobernado la Siria desde el a\u00f1o 11 a.C. hasta la llegada de Ticio como su gobernador en el 9 a.C. (as\u00ed, <etiqueta id=\"#_ftn986\" name=\"_ftnref986\" title=\"\">p. ej., Marsh, <\/etiqueta><i>Founding of the Roman Empire<\/i>, pp. 246, <etiqueta id=\"#_ftn987\" name=\"_ftnref987\" title=\"\">n. 1), y que Augusto haya decidido efectuar un empadronamiento despu\u00e9s de consultar a Herodes cuando este lo visit\u00f3 en el a\u00f1o 12 a.C. De ah\u00ed que el nacimiento de Jes\u00fas puede haber sucedido en el a\u00f1o 11 a.C. Las tentativas para deter<\/etiqueta>minar el mes y el d\u00eda no han dado resultados positivos.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>El cometa Halley que se vio en el a\u00f1o 12 a.C. fue un espect\u00e1culo fulgurante, perfectamente adecuado para ser heraldo de aquel que habr\u00eda de ser la luz del mundo. Pero en la antig\u00fcedad, la aparici\u00f3n de cometas generalmente se consideraba como presagio de desgracias. La conclusi\u00f3n a que lleg\u00f3 el astronomo italiano Argentieri, de que esta estrella fue la que gui\u00f3 a los magos, est\u00e1 basada en dos suposiciones discutibles: que Jes\u00fas naci\u00f3 en domingo, y que fue un 25 de diciembre.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Aceptando que la palabra traducida \u201cestrella\u201d en Mt. 2 se refiere a una sola estrella, los que adhieren a la conocida teor\u00eda de la conjunci\u00f3n Saturno-J\u00fapiter respecto a la estrella de los magos se han separado en dos escuelas; una de ellas sostiene que la estrella de Israel fue Saturno (as\u00ed Gerhardt, <i>Das Stern de Messias<\/i>), y la otra que fue J\u00fapiter (as\u00ed Voigt, <i>Die Geschichte Jesu und die Astrologie<\/i>). Pero parecer\u00eda improbable que la conjunci\u00f3n de estos dos planetas pudiera haber significado para los astr\u00f3logos orientales el nacimiento de un rey.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><i><span lang=ES style=''>b. El comienzo de su ministerio<\/span><\/i><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><span lang=ES style=''>Entre el nacimiento de Jes\u00fas y el comienzo de su ministerio hubo un per\u00edodo \u201ccomo de treinta a\u00f1os\u201d (Lc. 3.23). Pero el comienzo a que se hace referencia all\u00ed podr\u00eda no ser el de su ministerio, y se desconoce qu\u00e9 amplitud puede abarcar el vocablo \u201ccomo\u201d. La afirmaci\u00f3n de que \u201ca\u00fan no tienes cincuenta a\u00f1os\u201d (Jn. 8.57) sugiere que durante su ministerio Jes\u00fas estar\u00eda en los cuarenta; seg\u00fan Ireneo, entre los \u201cancianos\u201d de Asia circulaba una tradici\u00f3n en ese sentido. No obstante, la observaci\u00f3n de los jud\u00edos puede referirse a la edad lev\u00edtica para el retiro del servicio activo en el tabern\u00e1culo (Nm. 4.3). Es como si le dijeran a Jes\u00fas, \u201csi todav\u00eda est\u00e1s, como lo sostienes, al servicio de Dios, no puedes tener ni siquiera 50 a\u00f1os de edad\u201d.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Jes\u00fas comenz\u00f3 su ministerio despu\u00e9s de que lo hiciera Juan el Bautista, por lo tanto no antes del decimoquinto a\u00f1o del reinado de Tiberio (Lc. 3.1). Por razones muy valederas actualmente se descarta en general la idea de que ese a\u00f1o se calcule a partir del momento en que Tiberio pas\u00f3 a ser corregente con Augusto. Dado que Augusto muri\u00f3 el 19 de agosto del 14, el 2\u00ba a\u00f1o del reinado de Tiberio empez\u00f3 el 1 de oct. del 14 seg\u00fan el calendario sirio, el 1 de Nis\u00e1n del a\u00f1o 15 seg\u00fan el calendario jud\u00edo. En consecuencia, en Lc. 3.1 el a\u00f1o decimoquinto de su reinado significa ya sea el 27 (1 de oct.)-28, o el 28 (1 de Nis\u00e1n)-29. Lo m\u00e1s probable es que sea la segunda alternativa, por cuanto aqu\u00ed Lucas aparentemente utiliza una fuente derivada de un c\u00edrculo vinculado con el Bautista, y en muchos escritos antiguos, tanto paganos como jud\u00edos y cristianos, el decimoquinto a\u00f1o de Tiberio comprende parte del a\u00f1o 29.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>En Lc. 3.21 se indica que transcurri\u00f3 alg\u00fan tiempo entre el llamado del Bautista y el bautismo de Jes\u00fas, aunque no se puede precisar cu\u00e1nto. Al bautismo de Jes\u00fas siguieron los 40 d\u00edas en el desierto, el llamado de los primeros disc\u00edpulos, las bodas de Can\u00e1, y una breve estada en Capernaum. Posteriormente a estos acontecimientos, que ocuparon por lo menos dos meses, Jes\u00fas se dirigi\u00f3 a Jerusal\u00e9n para participar de la primera pascua de su ministerio (Jn. 2.13). Podr\u00eda parecer que la fecha est\u00e1 dada por la aseveraci\u00f3n de los jud\u00edos de que \u201cen cuarenta y seis a\u00f1os fue edificado este templo\u201d (Jn. 2.20), juntamente con la observacion de Jos., <i>Ant.<\/i> 15. 380, de que Herodes en el a\u00f1o 18 de su reinado (20\/19 a.C.) \u201cse dispuso a edificar\u201d dicho templo. No obstante, reuni\u00f3 muchos materiales antes de comenzar la edificaci\u00f3n, y el tiempo utilizado en estas tareas puede no estar incluido en los 46 a\u00f1os. Adem\u00e1s, la afirmaci\u00f3n de los jud\u00edos significa, quiz\u00e1s, que la construcci\u00f3n ya hab\u00eda sido terminada con anterioridad a esta pascua.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><i><span lang=ES style=''>c. El final de su ministerio<\/span><\/i><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><span lang=ES style=''>Jes\u00fas fue crucificado cuando Poncio Pilato era procurador de Judea (los cuatro evangelios, T\u00e1cito, Anales 15. 44, y posiblemente Jos., Ant. 18. 63s), por lo tanto en alguno de los a\u00f1os 26\u201336. Se han hecho varios intentos de determinar cu\u00e1l de ellos es el m\u00e1s probable.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-top:0cm;margin-right:0cm;margin-bottom:0cm; margin-left:18.0pt;margin-bottom:.0001pt;text-indent:-18.0pt;line-height:normal'><span lang=ES style=''>(i)<\/span><span style=''>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/span><span lang=ES style=''> De Lc. 13.1 y 23.12 puede inferirse que Pilato ya hab\u00eda sido procurador por alg\u00fan tiempo antes de la crucifixi\u00f3n, y que por lo tanto dif\u00edcilmente pudo haber sucedido en fecha tan temprana como lo ser\u00eda el a\u00f1o 26 o el 27.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-top:0cm;margin-right:0cm;margin-bottom:0cm; margin-left:18.0pt;margin-bottom:.0001pt;text-indent:-18.0pt;line-height:normal'><span lang=ES style=''>(ii)<\/span><span style=''>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/span><span lang=ES style=''> En muchos documentos primitivos la crucifixi\u00f3n se asigna al consulado de los G\u00e9mini, <etiqueta id=\"#_ftn988\" name=\"_ftnref988\" title=\"\">e. d. al a\u00f1o 29. P<\/etiqueta>ero esta fecha de ninguna manera se aceptaba en forma general en la iglesia primitiva; y no existen pruebas, como algunos piensan, de que se trata de una tradici\u00f3n fidedigna. Los escritores que la citan, de los cuales Tertuliano (ca. 200 d.C.) es el m\u00e1s antiguo, pertenecen en general al occidente latino. El 25 de marzo, la fecha-mes de la crucifixi\u00f3n dada por Hip\u00f3lito, Tertuliano, y muchos otros, fue un viernes en el a\u00f1o 29; pero la crucifixi\u00f3n se llev\u00f3 a cabo en el momento de la luna llena pascual, y en el 29 esa luna apareci\u00f3 casi seguramente en abril.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-top:0cm;margin-right:0cm;margin-bottom:0cm; margin-left:18.0pt;margin-bottom:.0001pt;text-indent:-18.0pt;line-height:normal'><span lang=ES style=''>(iii)<\/span><span style=''>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/span><span lang=ES style=''> Cuando Pilato fue procurador ofendi\u00f3 a los jud\u00edos cuando coloc\u00f3 escudos votivos en el palacio en Jerusal\u00e9n. Herodes Antipas particip\u00f3 en forma prominente en el env\u00edo a Tiberio de una petici\u00f3n por la que se solicitaba la remoci\u00f3n de los mismos. Esto, seg\u00fan algunos entendidos, explica la enemistad mencionada en Lc. 23.12. Tiberio accedi\u00f3 al pedido, y esta actitud, seg\u00fan los mismos entendidos, no la pudo haber asumido mientras estuvo bajo la influencia de su confidente Sejano, enemigo ac\u00e9rrimo de los jud\u00edos. Se llega, pues, a la conclusi\u00f3n de que la crucifixi\u00f3n debe de haberse llevado a cabo despu\u00e9s de la muerte de Sejano acaecida en octubre del a\u00f1o 31, y por ello no antes del a\u00f1o 32. Pero la enemistad pudo haber sido motivada igualmente por la matanza mencionada en Lc. 13.1, o debido a alguna disputa ante la cual la historia ha guardado silencio.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-top:0cm;margin-right:0cm;margin-bottom:0cm; margin-left:18.0pt;margin-bottom:.0001pt;text-indent:-18.0pt;line-height:normal'><span lang=ES style=''>(iv)<\/span><span style=''>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/span><span lang=ES style=''> Keim, en su <i>Jesus of Nazareth<\/i>, 2, pp. 379ss, fija \u201cel gran a\u00f1o en la historia del mundo\u201d en dependencia de la afirmaci\u00f3n de Josefo (Ant. 18. 116) de que la derrota de Antipas por Aretas en el a\u00f1o 36 fue considerada por algunos como \u201cde Dios, y eso con toda justicia, como castigo por lo que hizo contra Juan, a quien llamaban el Bautista\u201d. Keim llega a la conclusi\u00f3n de que la ejecuci\u00f3n de Juan debe de haber acontecido tan s\u00f3lo dos a\u00f1os antes, en el 34, y la crucifixi\u00f3n en el 35. Pero el castigo no siempre sigue inmediatamente a la perpetraci\u00f3n del crimen; y si bien el origen de la hostilidad entre Antipas y Aretas bien puede haber sido el hecho de que el primero se divorci\u00f3 de la hija del segundo, hay indicaciones en Josefo de que hubo un intervalo entre el divorcio y la guerra del a\u00f1o 36.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-top:0cm;margin-right:0cm;margin-bottom:0cm; margin-left:18.0pt;margin-bottom:.0001pt;text-indent:-18.0pt;line-height:normal'><span lang=ES style=''>(v)<\/span><span style=''>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/span><span lang=ES style=''> De los esfuerzos realizados para determinar el a\u00f1o de la crucifixi\u00f3n, el m\u00e1s fruct\u00edfero es el que se ha llevado a cabo mediante la ayuda de la astronom\u00eda. Seg\u00fan los cuatro evangelios la crucifixi\u00f3n se llev\u00f3 a cabo en viernes; pero mientras que en los sin\u00f3pticos ese viernes fue el 15 de Nis\u00e1n, en Juan es el 14 de Nis\u00e1n. Por lo tanto, el problema que tiene que resolverse con la ayuda de la astronom\u00eda es el de determinar en cu\u00e1l de los a\u00f1os 26\u201336 el 14 y el 15 de Nis\u00e1n cayeron en viernes. Pero teniendo en cuenta que en la \u00e9poca del NT el mes jud\u00edo era lunar y que el momento de su comienzo se determinaba por la observaci\u00f3n de la luna nueva, el problema consiste b\u00e1sicamente en determinar cu\u00e1ndo se torn\u00f3 visible la luna nueva. Despu\u00e9s de estudiar este problema, Fotheringham y Schoch han arribado cada uno a una f\u00f3rmula por aplicaci\u00f3n de la cual encuentran que el 15 de Nis\u00e1n cay\u00f3 en viernes \u00fanicamente en el a\u00f1o 27, y el 14 de Nis\u00e1n \u00fanicamente en los a\u00f1os 30 y 33. Ya que el a\u00f1o de la crucifixi\u00f3n no puede ser de ninguna manera el 27, la elecci\u00f3n se reduce a escoger entre el 30 (7 de abril) y el 33 (3 de abril).<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>En la cronolog\u00eda sin\u00f3ptica de la semana de la pasi\u00f3n se asignan al 15 de Nis\u00e1n acontecimientos muy improbables para ese d\u00eda de santa convocaci\u00f3n. La cronolog\u00eda de Juan para esa semana ciertamente parecer\u00eda ser de por s\u00ed la m\u00e1s probable, y hasta por lo menos los comienzos del ss. III evidentemente era la m\u00e1s generalmente aceptada en todos los \u00e1mbitos de la iglesia. Los intentos realizados para armonizar los evangelios en lo que se refiere a esta cuesti\u00f3n no han obtenido asentimiento general, y las discusiones tocantes al problema prosiguen. No obstante, es digno de notar que los c\u00e1lculos de los astr\u00f3nomos no se\u00f1alan, para la crucifixi\u00f3n, un a\u00f1o que pueda aceptarse por otras razones en el que el 14 de Nis\u00e1n fuera jueves.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><i><span lang=ES style=''>d. La duraci\u00f3n de su ministerio<\/span><\/i><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><span lang=ES style=''>Es m\u00e1s importante conocer cu\u00e1l fue la duraci\u00f3n del ministerio de Jes\u00fas que saber cu\u00e1ndo comenz\u00f3 o cu\u00e1ndo termin\u00f3. Existen tres teor\u00edas principales respecto a su duraci\u00f3n.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-top:0cm;margin-right:0cm;margin-bottom:0cm; margin-left:18.0pt;margin-bottom:.0001pt;text-indent:-18.0pt;line-height:normal'><span lang=ES style=''>(i)<\/span><span style=''>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/span><i><span lang=ES style=''>La teor\u00eda de que dur\u00f3 un a\u00f1o<\/span><\/i><span lang=ES style=''>. Los primeros en apoyar esta teor\u00eda consideraban que era una convincente confirmaci\u00f3n de la misma el hecho de que Jes\u00fas se hab\u00eda adjudicado a s\u00ed mismo el pasaje de Isa\u00edas que profetiza sobre \u201cel a\u00f1o agradable del Se\u00f1or\u201d (Is. 61.2; Lc. 4.19). Esta teor\u00eda tuvo amplia aceptaci\u00f3n durante el per\u00edodo anteniceno, y en el ss. XVII se renov\u00f3 el inter\u00e9s en ella. Entre los trabajos importantes que la exponen se encuentran los de van Bebber, <i>Zur Chronologie des Lebens Jesu<\/i>, 1898, y Belser en <i>Biblische Zeitschrift<\/i> 1, 1903; 2, 1904.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-top:0cm;margin-right:0cm;margin-bottom:0cm; margin-left:18.0pt;margin-bottom:.0001pt;text-indent:-18.0pt;line-height:normal'><span lang=ES style=''>(ii)<\/span><span style=''>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/span><i><span lang=ES style=''>La teor\u00eda de que dur\u00f3 dos a\u00f1os<\/span><\/i><span lang=ES style=' '>. Los que apoyan esta teor\u00eda, entre los cuales uno de los primeros fue Apolinario de Laodicea, sostienen que en el intervalo entre el bautismo de Jes\u00fas y su crucifixi\u00f3n, las \u00fanicas pascuas fueron las tres que se mencionan expl\u00edcitamente en Jn. (2.13; 6.4; 11.55). Si bien en la Edad Media apenas si tuvo alguna aceptaci\u00f3n esta teor\u00eda, en la actualidad es aceptada por muchos.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-top:0cm;margin-right:0cm;margin-bottom:0cm; margin-left:18.0pt;margin-bottom:.0001pt;text-indent:-18.0pt;line-height:normal'><span lang=ES style=''>(iii)<\/span><span style=''>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/span><i><span lang=ES style=''>La teor\u00eda de que dur\u00f3 tres a\u00f1os<\/span><\/i><span lang=ES style=' '>. El primer defensor de esta teor\u00eda de quien se tiene noticia fue Melit\u00f3n de Sardis, pero su amplia aceptaci\u00f3n en \u00e9pocas posnicenas y durante toda la Edad Media debe atribuirse mayormente a la influencia de Eusebio, quien rechaz\u00f3 la interpretaci\u00f3n literal del vocablo \u201ca\u00f1o\u201d en la frase \u201cel a\u00f1o agradable del Se\u00f1or\u201d, y demostr\u00f3 en forma convincente que solamente un ministerio de tres a\u00f1os enteros pod\u00eda satisfacer las exigencias del cuarto evangelio. En la actualidad esta teor\u00eda tiene tambi\u00e9n muchos sostenedores.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Debido a la pascua de Jn. 6.4, vers\u00edculo que goza de excelente autoridad en los manuscritos, debe rechazarse la teor\u00eda de un solo a\u00f1o. Para que pueda decidirse entre las teor\u00edas de los dos y los tres a\u00f1os, el intervalo entre las pascuas de Juan 2.13 y 6.4 debe someterse a un cuidadoso examen.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Dado que ordinariamente transcurr\u00edan seis meses entre la \u00e9poca de la siembra y la de la siega, las palabras \u201caun faltan cuatro meses para que llegue la siega\u201d (Jn. 4.35) no pueden constituir un dicho en forma de proverbio, sino que deben relacionarse con las circunstancias imperantes en la \u00e9poca en que fueron pronunciadas. Por lo tanto, el regreso de Jes\u00fas a Galilea que se menciona en Jn. 4.43 debe de haberse producido en invierno. El que la fiesta innominada de Jn. 5.1 fuese Purim, como lo han sostenido muchos de los que apoyan la teor\u00eda de los dos a\u00f1os, siguiendo a Kepler, es improbable. La fiesta de Purim se celebraba en febrero\/marzo, y por consiguiente poco tiempo despu\u00e9s del regreso de Jes\u00fas. Pero las palabras \u201cdespu\u00e9s de estas cosas\u201d (Jn. 5.1) indican que hubo un intervalo bastante prolongado entre su regreso y su posterior visita a Jerusal\u00e9n. Es m\u00e1s probable que la fiesta innominada fuese la pascua siguiente, en marzo\/abril, o el d\u00eda de Pentecost\u00e9s o la fiesta de los tabern\u00e1culos siguientes. Algunos sostenedores de la teor\u00eda de los dos a\u00f1os, aunque aceptan que puede haber sido la pascua siguiente, la equiparan con la pascua de Jn. 6.4, sosteniendo algunos que \u201cestaba cerca\u201d significa \u201cacababa de pasar\u201d, y otros que Jn. 6 debe leerse inmediatamente antes de Jn. 5. Pero el \u201cestaba cerca\u201d de Jn. 6.4 no puede significar \u201cacababa de pasar\u201d, puesto que, como es evidente por las palabras \u201cdespu\u00e9s de esto\u201d en Jn. 6.1, hubo un intervalo bastante largo entre los acontecimientos de Jn. 5 y los de Jn. 6. Adem\u00e1s, no existen pruebas textuales que abonen la propuesta de modificar el orden de los cap\u00edtulos. Parecer\u00eda, en consecuencia, que hubo una pascua entre las de Jn. 2.13 y 6.4, y que, por lo tanto, la duraci\u00f3n del ministerio de Jes\u00fas fue realmente de tres a\u00f1os completos.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>De acuerdo a la primera de las teor\u00edas ya mencionadas, la primera y la \u00faltima pascuas del ministerio de Jes\u00fas fueron la del 29 y la del 30; de acuerdo a la segunda, la del 28 y la del 30; de acuerdo a la tercera, la del 30 y la del 33.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><b><span lang=ES style=''>II. Cronolog\u00eda de la era apost\u00f3lica<\/span><\/b><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><i><span lang=ES style=''>a. Desde Pentecost\u00e9s hasta la conversi\u00f3n de Pablo<\/span><\/i><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><span lang=ES style=''>Cuando, tres a\u00f1os despu\u00e9s de su conversi\u00f3n (G\u00e1. 1.18), Pablo logr\u00f3 escapar de Damasco, un funcionario del lugar, \u201cgobernador de la provincia del rey Aretas guardaba la ciudad de los damascenos\u201d para prenderlo (2 Co. 11.32). Seg\u00fan algunos, este funcionario era el jeque de una banda de \u00e1rabes, s\u00fabditos de Aretas, acampados fuera de los muros de la ciudad. Pero cuando Pablo se refiere a \u00e9l da la impresi\u00f3n de que se trataba de un funcionario que actuaba dentro de la ciudad. Seg\u00fan otros, la ciudad de Damasco estaba bajo el control directo de la administraci\u00f3n romana, y este funcionario era el representante de la comunidad \u00e1rabe residente en ella (cf. el etnarca o gobernador de los jud\u00edos en la ciudad de Alejandr\u00eda, Jos., Ant. 14. 117). Pero este representante no hubiese tenido autoridad para guardar la ciudad. Por lo tanto en esa \u00e9poca Aretas estaba aparentemente en posesi\u00f3n de Damasco, y el indicado funcionario ser\u00eda en realidad su virrey. Se han encontrado monedas cuya acu\u00f1aci\u00f3n demuestra que Damasco estuvo en poder de Roma hasta el a\u00f1o 33. Cuando, en el a\u00f1o 37, Vitelio, gobernador de Siria, se lanz\u00f3 contra Aretas, se dirigi\u00f3, no a Damasco, sino en direcci\u00f3n al <etiqueta id=\"#_ftn989\" name=\"_ftnref989\" title=\"\">S, hacia Petra, 1o cual no hubiera hecho salvo qu<\/etiqueta>e Damasco todav\u00eda estuviese en poder de los romanos. Aretas, que muri\u00f3 en el a\u00f1o 40, debe de haber obtenido posesi\u00f3n de Damasco entre el 37 y el 40, y la conversi\u00f3n de Pablo debe considerarse como acaecida entre el 34 y el 37.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>No existen indicaciones claras de que el intervalo bajo consideraci\u00f3n haya sido prolongado. El apedreamiento de Esteban, seg\u00fan insisten algunos, fue un hecho ilegal que los jud\u00edos no se hubieran atrevido a cometer siendo Pilato procurador, y en consecuencia la fecha de este hecho no pudo haber sido anterior al a\u00f1o 36. Pero nadie puede decir cu\u00e1ndo no han de estallar tales brotes de fanatismo. Otros han observado que antes de la conversi\u00f3n de Pablo el cristianismo ya se hab\u00eda extendido hasta Damasco, pero aparentemente todav\u00eda no hab\u00eda comunidades cristianas organizadas fuera de Jerusal\u00e9n. Es muy posible que el cristianismo haya avanzado r\u00e1pidamente en esos primeros d\u00edas pentecostales; y si bien una tradici\u00f3n preservada en Ireneo y en la <i>Ascensi\u00f3n de Isa\u00edas<\/i>, en el sentido de que este intervalo dur\u00f3 18 meses, puede ser de valor muy relativo, la conversi\u00f3n de Pablo parecer\u00eda m\u00e1s probable en el 34 \u00f3 35 que en el 36 \u00f3 37.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><i><span lang=ES style=''>b. Desde la primera visita de Pablo a Jerusal\u00e9n posterior a su conversi\u00f3n hasta la visita de socorro en el per\u00edodo de hambre<\/span><\/i><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><span lang=ES style=''>En el a\u00f1o 37 \u00f3 38 Pablo hizo una visita a Jerusal\u00e9n por primera vez desde su conversi\u00f3n, se qued\u00f3 all\u00ed durante 15 d\u00edas, y luego parti\u00f3 a Siria y Cilicia, donde permaneci\u00f3 hasta recibir una invitaci\u00f3n de Bernab\u00e9 para ir a prestarle ayuda en Antioqu\u00eda. Un a\u00f1o m\u00e1s tarde los dos hicieron juntos la visita de socorro a Jerusal\u00e9n que se menciona en Hch. 11.29s y 12.25.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Dado que en Hch. 12.1\u201324 Lucas interrumpe el relato de esta visita a fin de completar la historia de la iglesia de Jerusal\u00e9n hasta ese momento, se desprende que la fecha que le asigna es posterior a la muerte de Agripa I. Seg\u00fan datos de Josefo este rey falleci\u00f3 en el 44, posiblemente antes del 1 de Nis\u00e1n. La persecuci\u00f3n de la iglesia, que llev\u00f3 a cabo en \u00e9poca pascual, puede haber ocurrido en el a\u00f1o 43, pero quiz\u00e1s no antes, ya que aparentemente no hubo un per\u00edodo prolongado entre dicha persecuci\u00f3n y la muerte de Agripa.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>El hambre profetizada por Agabo sobrevino en Judea mientras gobernaba all\u00ed el procurador Tiberio Alejandro (46\u201348). Las condiciones adversas llegaron a su punto culminante en el a\u00f1o que sigui\u00f3 al de la p\u00e9rdida de la cosecha, e inmediatamente antes de que se recogiese la nueva cosecha. Fue justamente en ese momento que Helena, reina de Adiabena, lleg\u00f3 a Jerusal\u00e9n trayendo trigo de Egipto para sus habitantes. Como se descubre al examinar los papiros de la \u00e9poca, hubo hambre en Egipto en la segunda mitad del a\u00f1o 45. Los servidores de la reina Helena no habr\u00e1n, pues, encontrado all\u00ed trigo hasta despu\u00e9s de la cosecha del a\u00f1o 46. Por lo tanto, la mala cosecha en Palestina habr\u00e1 ocurrido en el a\u00f1o 46 \u00f3 47. La ofrenda que se levant\u00f3 en Antioqu\u00eda probablemente s\u00f3lo se remiti\u00f3 cuando los creyentes en Judea empezaron a sentir la necesidad de ese socorro, por consiguiente hacia fines del 45 \u00f3 46. La primera de estas fechas resulta la m\u00e1s aceptable porque permite acomodar dentro del per\u00edodo ciertos acontecimientos subsiguientes, y ha de preferirse.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><i><span lang=ES style=''>c. El primer viaje misionero<\/span><\/i><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><span lang=ES style=''>Despu\u00e9s de regresar a Antioqu\u00eda, muy pronto, probablemente a principios del a\u00f1o 46, Pablo y Bernab\u00e9 comenzaron el primer viaje misionero. Navegando hasta Salamina en Chipre, atravesaron la isla hasta Pafos, donde se encontraron con el proc\u00f3nsul Sergio Paulo. No hay seguridad de que se trate del mismo Sergio Paulo que cita Plinio en su Historia Nateralis. Existe en Roma una inscripci\u00f3n que menciona a un tal L. Sergio Paulo que fue guardi\u00e1n del T\u00edber durante el reinado de Claudio, pero no se sabe si posteriormente fue gobernador de Chipre. Una inscripci\u00f3n descubierta en la localidad de Soloi en Chipre termina con la fecha \u201ca\u00f1o 13, mes Demarcusio 25\u201d, pero tiene un agregado que dice lo siguiente: \u201cTambi\u00e9n modific\u00f3 [el Apolonio de la inscripci\u00f3n] el senado cuando Paulo era proc\u00f3nsul. \u201cEste Paulo posiblemente sea el de Hechos, pero quiz\u00e1s Apolonio no haya modificado el senado en el a\u00f1o 23; adem\u00e1s, lo que en realidad significa \u201ca\u00f1o 13\u201d no est\u00e1 muy claro. Ya que otra inscripci\u00f3n indica que el a\u00f1o en que Paulo fue proc\u00f3nsul no fue ni el 51 ni el 52 no es posible determinar con mucha precisi\u00f3n, sobre la base de las informaciones que proveen las inscripciones hasta el momento, cu\u00e1l fue el a\u00f1o.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>A medida que avanzaban hacia el <etiqueta id=\"#_ftn990\" name=\"_ftnref990\" title=\"\">O desde Salamina, los misioneros probablemente predicaron en las ciudades por las que fueron pasando. As\u00ed habr\u00e1n llegado a Pafos para el oto\u00f1o y, cruzando el mar hasta Perge, habr\u00e1n comenzado su obra misionera en Pisidia y Licaonia antes de que empezara <\/etiqueta>el invierno. Como parecer\u00eda que 12 meses ser\u00eda tiempo suficiente para completar esta parte de su obra, el regreso a Antioqu\u00eda podr\u00eda fijarse en el oto\u00f1o del 47.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><i><span lang=ES style=''>d. El concilio apost\u00f3lico<\/span><\/i><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><span lang=ES style=''>A principios del a\u00f1o 48, 14 a\u00f1os despu\u00e9s de su conversi\u00f3n, Pablo juntamente con Bernab\u00e9 asistieron al concilio apost\u00f3lico de Hch. 15.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Algunos entienden que este concilio y la conferencia de G\u00e1. 2.1\u201310 son la misma cosa, y opinan que la objeci\u00f3n de que en G\u00e1latas Pablo no puede haber omitido la visita a Jerusal\u00e9n de Hch. 11.30 carece de valor, ya que atribuye la visita de G\u00e1. 1.18 a un motivo, y a un motivo distinto la de G\u00e1. 2.1. Para demostrar que era \u201cap\u00f3stol, no de hombres ni por hombre\u201d afirma que no tuvo ning\u00fan contacto con los ap\u00f3stoles hasta tres a\u00f1os despu\u00e9s de su conversi\u00f3n. Su prop\u00f3sito al mencionar una visita posterior a Jerusal\u00e9n es el de asegurar a los g\u00e1latas que su apostolado a los gentiles hab\u00eda sido reconocido por los dirigentes de la iglesia. (* <span style='text-transform:uppercase'>Concilio de Jerusal\u00e9n;<\/span> <span style='text-transform:uppercase'>G\u00e1latas, Ep\u00edstola a los<\/span> )<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Algunos ubican la visita de Hch. 11.30 antes de la persecuci\u00f3n de la iglesia por parte de Agripa y sostienen que el concilio de Hch. 15 (= G\u00e1. 2.1\u201310) se realiz\u00f3 entonces. Pero cronol\u00f3gicamente esto es dif\u00edcil porque en ese caso la fecha de la conversi\u00f3n de Pablo no podr\u00eda ser posterior al a\u00f1o 30. Otros sostienen que el concilio se llev\u00f3 a cabo despu\u00e9s del primer viaje misionero, pero que fue en esa oportunidad, y no antes, que la ofrenda levantada en Antioqu\u00eda para el alivio de los creyentes afectados por el hambre fue llevada a Jerusal\u00e9n. Se presume que Lucas contaba con dos descripciones de esta visita, una originada en Antioqu\u00eda y otra en Jerusal\u00e9n, atribuy\u00e9ndolas err\u00f3neamente a visitas diferentes. J. Knox, en su <i>Chapters in a Life of Paul <\/i>(1954), no solamente condens\u00f3 en un solo per\u00edodo (40\u201351) toda la actividad evangel\u00edstica de Pablo, sino que coloc\u00f3 al concilio apost\u00f3lico despu\u00e9s de ella. Sin embargo, su revisi\u00f3n radical de la cronolog\u00eda de Pablo no ha merecido aceptaci\u00f3n general.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><i><span lang=ES style=''>e. El segundo viaje misionero<\/span><\/i><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><span lang=ES style=''>Seg\u00fan parece, Pablo inici\u00f3 su segundo viaje hacia fines de la primavera del a\u00f1o 48. Despu\u00e9s de visitar las iglesias en Siria y Cilicia, y las que ya hab\u00edan sido fundadas en Asia Menor, se introdujo en un nuevo campo de labor, \u201cla regi\u00f3n de Frigia y Galacia\u201d (Hch. 16.6). No se relata nada acerca de su obra misionera all\u00ed. Sin embargo, sus labores deben de haber incluido la constituci\u00f3n de las iglesias a las cuales fue m\u00e1s tarde dirigida la Ep\u00edstola a los G\u00e1latas, si es que estas iglesias (de acuerdo al criterio sustentado en todas partes hasta el ss. XIX) se encontraban en Galacia en el sentido etnogr\u00e1fico. La constituci\u00f3n de dichas iglesias puede haberlo tenido ocupado hasta principios del 49. La misi\u00f3n posterior en Macedonia y Acaya concluy\u00f3 poco despu\u00e9s del episodio relacionado con Gali\u00f3n (Hch. 18.12\u201317), cuyo fechamiento, con la ayuda de una inscripci\u00f3n, puede fijarse dentro de l\u00edmites bastante precisos. En esa inscripci\u00f3n, un rescrito de Claudio a los de Delfos fechado en su \u201c26\u00aa aclamaci\u00f3n imperatoria\u201d, se menciona a Gali\u00f3n como proc\u00f3nsul. Las inscripciones (CIL 3. 476 y 6. 1256) demuestran que Claudio fue aclamado por vigesimotercera vez en una fecha posterior al 25 de enero del 51 y por vigesimos\u00e9ptima vez antes del 1 de agosto del 52. De esto se desprende que muy probablemente fue aclamado por vigesimosexta vez en la primera mitad del a\u00f1o 52, y que, por consiguiente, el rescrito fue escrito en esa misma fecha tambi\u00e9n. Pero con anterioridad a esto Gali\u00f3n hab\u00eda investigado la cuesti\u00f3n de l\u00edmites sobre la que trata, y hab\u00eda mantenido correspondencia con Claudio al respecto. Por lo tanto el rescrito debe corresponder a la segunda mitad del a\u00f1o en que Gali\u00f3n actu\u00f3 como proc\u00f3nsul, a\u00f1o que debe de haber comenzado en el verano del 51. Hch. 18.12 indica que Gali\u00f3n hab\u00eda ocupado su cargo por alg\u00fan tiempo antes de que los jud\u00edos iniciaran su movimiento contra Pablo, pero es improbable que hayan esperado m\u00e1s que un par de meses. Como Pablo hab\u00eda pasado 18 meses en Corinto con anterioridad a este episodio, debe de haber llegado all\u00ed a principios del a\u00f1o 50; y como despu\u00e9s de esto se qued\u00f3 en Corinto \u201cmuchos d\u00edas (Hch. 18.18), expresi\u00f3n que aqu\u00ed no puede significar m\u00e1s que uno o dos meses, quiz\u00e1s haya regresado a Siria antes del invierno del 51\/52.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Al llegar a Corinto Pablo encontr\u00f3 a Aquila y Priscila, que hab\u00edan llegado poco antes de Roma, porque Claudio hab\u00eda ordenado que todos los jud\u00edos saliesen de la ciudad. Seg\u00fan Orosio, esta orden de expulsi\u00f3n se promulg\u00f3 en el noveno a\u00f1o del gobierno de Claudio, o sea el 49 (25 de enero) -50. Aunque no existe ninguna certeza acerca del origen de la fecha dada por Orosio, puede tener buen fundamento. Concuerda bien con la conclusi\u00f3n de que Pablo lleg\u00f3 a Corinto a principios del 50.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><i><span lang=ES style=''>f. Desde el comienzo del tercer viaje misionero de Pablo hasta su llegada a Roma<\/span><\/i><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><span lang=ES style=''>Es dif\u00edcil que el tercer viaje de Pablo haya comenzado antes del a\u00f1o 52; y teniendo en cuenta que inclu\u00eda una estada de tres a\u00f1os en \u00c9feso (Hch. 20.31), y tres meses pasados en Grecia (Hch. 20.3), debe considerarse su finalizaci\u00f3n no antes del 55. Por lo tanto, la llegada de Festo como procurador en lugar de F\u00e9lix dos a\u00f1os m\u00e1s tarde (Hch. 24.27) debe fijarse en el a\u00f1o 57, y no antes. Como el sucesor de Festo se encontraba en Palestina en la \u00e9poca de la fiesta de los tabern\u00e1culos del 62 (Jos., <etiqueta id=\"#_ftn991\" name=\"_ftnref991\" title=\"\"><span style='text-transform:uppercase'>GJ<\/span><\/etiqueta> 6. 300ss), Festo, que muri\u00f3 mientras ejerc\u00eda sus funciones, debe haber llegado a m\u00e1s tardar para el a\u00f1o 61. De estos a\u00f1os posibles, 57\u201361, la mayor\u00eda de los entendidos rechaza los a\u00f1os 57 y 58, por considerarlos demasiado tempranos, y, eligiendo el a\u00f1o 59 \u00f3 60, estima que Pablo debe de haber llegado a Roma en el 60 \u00f3 61.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Pero, mientras fue procurador, Festo permiti\u00f3 que una embajada llevara una petici\u00f3n a Roma, la que fue concedida \u201cpara complacer a Popea, esposa de Ner\u00f3n\u201d (Jos., <i>Ant.<\/i> 20. 195). Como Ner\u00f3n se cas\u00f3 con Popea en mayo del 62, es posible que Festo todav\u00eda viviera en abril. Una nueva moneda provincial acu\u00f1ada y puesta en circulaci\u00f3n en Judea en 59 d.C. (la \u00faltima antes de la rebeli\u00f3n del 66) quiz\u00e1s indique que asumi\u00f3 sus funciones ese a\u00f1o.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>El motivo del regreso de Pablo de Corinto a Siria quiz\u00e1s haya sido una enfermedad, y es posible que no haya comenzado su tercer viaje hasta el a\u00f1o 53. Al regresar a la regi\u00f3n de Frigia y Galacia entr\u00f3 por esta \u00faltima (Hch. 18.23) en esta oportunidad y, despu\u00e9s de lo que seg\u00fan Hch. 19.1 parece haber sido una misi\u00f3n bastante amplia en la regi\u00f3n central de Asia Menor, lleg\u00f3 a \u00c9feso, probablemente en el oto\u00f1o del 54. En el 57, despu\u00e9s del tumulto que hubo all\u00ed, parti\u00f3 a Troas. Cruz\u00f3 a Europa a comienzos del 58, se encontr\u00f3 con Tito, quien lo tranquiliz\u00f3 con respecto a la iglesia en Corinto. Luego continu\u00f3 trabajando en Macedonia y Acaya, y posiblemente en Il\u00edrico (Ro. 15.19), y volvi\u00f3 a Jerusal\u00e9n en el 59. En el 61, despu\u00e9s de pasar dos a\u00f1os en la c\u00e1rcel de Cesarea, apel\u00f3 a C\u00e9sar, y en el oto\u00f1o (Hch. 27.9) se embarc\u00f3 para Roma, arribando a dicha ciudad en el 62. Observando que, seg\u00fan Josefo, al volver a Roma F\u00e9lix pudo evitar el castigo por su mal comportamiento en Palestina gracias a la intervenci\u00f3n de su hermano Palas, \u201cquien en ese entonces era tenido en la mayor estima por \u00e9l (Ner\u00f3n)\u201d y que, seg\u00fan T\u00e1cito, Ner\u00f3n relev\u00f3 a Palas de su puesto a poco de ascender, observando tambi\u00e9n que en la <i>Cr\u00f3nica <\/i>de Eusebio (versi\u00f3n hieron\u00edmica) la llegada de Festo en calidad de procurador se registra en el segundo a\u00f1o de Ner\u00f3n y considerando el per\u00edodo de dos a\u00f1os de Hch. 24.27 como el del desempe\u00f1o de F\u00e9lix como procurador, ciertos entendidos sostienen que Festo sucedi\u00f3 a F\u00e9lix en el 55 \u00f3 56. Las objeciones a esta cronolog\u00eda \u201cantedatada\u201d son: que apenas deja lugar para los acontecimientos relacionados con el tercer viaje de Pablo, que supone la interpretaci\u00f3n menos natural del Hch. 24.27 y que Josefo mismo ubica los acontecimientos del per\u00edodo en que F\u00e9lix fue procurador en el reinado de Ner\u00f3n.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><i><span lang=ES style=''>g. Desde el arribo de Pablo a Roma hasta el final de la era apost\u00f3lica<\/span><\/i><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;line-height: normal'><span lang=ES style=''>Durante por lo menos dos a\u00f1os, e. d. hasta el 64, a\u00f1o de las persecuciones de Ner\u00f3n, Pablo permaneci\u00f3 en Roma como prisionero. Acerca de lo que le sucedi\u00f3 luego, nada se sabe con certeza.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Pedro fue librado milagrosamente de las manos de Agripa (Hch. 12.3ss). Posteriormente concurri\u00f3 al concilio apost\u00f3lico, y m\u00e1s tarde aun visit\u00f3 Antioqu\u00eda (G\u00e1. 2.11ss). La referencia que se hace en (1 Co. 1.12) a la existencia en Corinto de un partido favorable a Cefas no ofrece ninguna prueba fehaciente de que Pedro haya visitado esa ciudad. Hay suficientes pruebas de que en alg\u00fan momento estuvo en Roma, pero en cuanto a su asociaci\u00f3n con esa ciudad, solamente lo referente a su martirio puede aceptarse como razonablemente seguro.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Jacobo, el hermano del Se\u00f1or, muri\u00f3 apedreado en el a\u00f1o 62, seg\u00fan Jos., <i>Ant.<\/i> 20. 200, pasaje que, sin embargo, podr\u00eda ser una interpolaci\u00f3n. Poco antes de la guerra de los jud\u00edos (66\u201370) los cristianos de Jerusal\u00e9n huyeron a Pela. En cuanto a las persecuciones que pudiera haber habido contra los cristianos durante el reinado de Domiciano (81\u201396) aparentemente fueron consecuencia de enemistades personales, o de la furia popular, y no de la acci\u00f3n de las autoridades. Existen escasas pruebas de que el ap\u00f3stol Juan haya sufrido el martirio juntamente con su hermano Jacobo (Hch. 12.2). El que haya sobrevivido hasta el \u00e9poca de Trajano, como lo atestigua Ireneo (<etiqueta id=\"#_ftn992\" name=\"_ftnref992\" title=\"\"><i>Adv. Haer.<\/i><\/etiqueta> 2. 22. 5) es mucho m\u00e1s probable. Su muerte (ca. 100) marca el final de la era apost\u00f3lica.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Para la dataci\u00f3n de los libros del NT, v\u00e9anse los art\u00edculos sobre los libros correspondientes.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=';text-transform:uppercase'>Bibliograf\u00eda.<\/span><span lang=ES style=''> \u00b0J Finegan, <i>Manual de cronolog\u00eda b\u00edblica<\/i>, 1975; M. Join-Lambert, \u201cCronolog\u00eda biblica\u201d, <etiqueta id=\"#_ftn993\" name=\"_ftnref993\" title=\"\"><i>\u00b0EBDM<\/i><\/etiqueta>, t(t). II, cols. 660\u2013682; A. Robert, A. Feuillet, <i>Introducci\u00f3n a la Biblia<\/i>, 1970, t(t). Il; W. Marxsem, <i>Introducci\u00f3n al Nuevo Testamento<\/i>, 1983.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Ginzel, <i>Hanedbuch der mathematischen und technischen Chronologie<\/i>, 1906\u201314; Cavaignac, <i>Chronologie<\/i>, 1925; J. Finegan, <i>Handbook of Biblical Chronology<\/i>, 1964; U. Holzmeister, <i>Chronologia Vitae Christi<\/i>, 1933; J. K. Fotheringham, \u201cThe Evidence of Astronorny and Technical Chronology for the Date of the Crucifixion\u201d en <etiqueta id=\"#_ftn994\" name=\"_ftnref994\" title=\"\"><i>JTS<\/i><\/etiqueta>, 35, 1934, 146ss; E. F. Sutcliffe, <i>A Two Year Public Ministry<\/i>, 1938; G. Ogg, <i>The Chronology of the Public Ministry of Jesus<\/i>, 1940; <i>The Chronology of the Life of Paul<\/i>, 1968; L. Girard, <i>Le Cadre chronologique du Minist\u00e8re de J\u00e9sus<\/i>, 1953; A. Jaubert, <i>La Date de la C\u00e8ne<\/i>, 1957; D. Plooij, <i>De Chronologie van het Leven van Paulus<\/i>, 1918; U. Holzmeister, <i>Historia Aetatis Novi Testamenti<\/i>, 1938; J. Dupont, <i>Les Probl\u00e8mes du Livre des Actes<\/i>, 1950; G. B. Caird, <i>The Apostolic Age<\/i>, 1955, ap\u00e9ndice A; J. J. Gunther, Paul, <i>Messenger and Exile<\/i>: <i>A Study in the Chronology of his Life and Letters<\/i>, 1972; J. A. T. Robinson, <i>Redating the New Testament<\/i>, 1976.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal align=right style='text-align:right;line-height:normal'><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><etiqueta id=\"#_ftn995\" name=\"_ftnref995\" title=\"\"><span lang=ES style='font-size:10.0pt; ;color:green'>G.O.<\/span><\/etiqueta><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><\/p>\n<p style='text-align:justify;'>Douglas, J. (2000). Nuevo diccionario Biblico : Primera Edicion. Miami: Sociedades B\u00edblicas Unidas.<\/p>\n<\/p>\n<p><b>Fuente: Nuevo Diccionario B\u00edblico<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(V\u00e9anse Tabla \u201cCronolog\u00eda: Antiguo y Nuevo Testamentos\u201d) Los cristianos primitivos demostraron poco inter\u00e9s en las cronolog\u00edas. La escasez de datos en los escritos del NT y la falta de certeza en cuanto a la interpretaci\u00f3n de la mayor parte de los datos de que se dispone hacen que la cuesti\u00f3n de la cronolog\u00eda del NT &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/cronologia-del-nuevo-testamento\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCRONOLOGIA DEL NUEVO TESTAMENTO\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-22256","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/22256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=22256"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/22256\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=22256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=22256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=22256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}