{"id":22341,"date":"2016-02-05T15:19:39","date_gmt":"2016-02-05T20:19:39","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/necedad-insensatez\/"},"modified":"2016-02-05T15:19:39","modified_gmt":"2016-02-05T20:19:39","slug":"necedad-insensatez","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/necedad-insensatez\/","title":{"rendered":"NECEDAD, INSENSATEZ"},"content":{"rendered":"<p><p style='text-align:justify;'><span lang=ES style=''>Si bien en el AT la necedad es a veces simplemente fatuidad (p. ej. Pr. 10.14; 14.15; 18.13, en este \u00faltimo caso justamente \u201cfatuidad\u201d en <\/span><span lang=ES style='font-size:10.0pt;;color:green; text-transform:uppercase'>\u00b0vrv2<\/span><span lang=ES style=' '>), generalmente envuelve culpabilidad: desprecio para con la verdad y la disciplina divinas (Pr. 1.7). De aqu\u00ed surge que aun el hombre \u201csimple\u201d o cr\u00e9dulo (<\/span><span style=' '>pe&#7791;&#305;&#770;<\/span><span lang=ES style=''>) no es s\u00f3lo \u201cfalto de entendimiento\u201d (Pr. 7.7ss), sino que est\u00e1 fatalmente descarriado (Pr. 1.32). Debe hacer una elecci\u00f3n moral y espiritual, y no s\u00f3lo un esfuerzo mental (Pr. 9.1\u20136, 13\u201318; Sal. 19.7). De la misma manera, el \u201cnecio\u201d (para el que existen diversos t\u00e9rminos virtualmente intercambiables, principalmente <\/span><span style=''>k<sup>e<\/sup>s&#305;&#770;l<\/span><span lang=ES style=''>, <\/span><span style=''>&#722;<sup>e<\/sup>w&#305;&#770;l<\/span><span lang=ES style=''>, <\/span><span style=''>s&#257;&#7733;&#257;l<\/span><span lang=ES style=''>), es t\u00edpicamente el que, como Sa\u00fal, se ha \u201cportado como un necio\u201d (1 S. 26.21, <\/span><etiqueta id=\"#_ftn131\" name=\"_ftnref131\" title=\"\"><span lang=ES style='font-size:10.0pt; ;color:green;text-transform:uppercase'>\u00b0vp<\/span><\/etiqueta><span lang=ES style=''>) y ha cerrado su mente a Dios (p. ej. Sal. 94.8ss; Pr. 27.22; Jer. 5.21). La necedad m\u00e1s empedernida es la del \u201cburlador\u201d (<\/span><span style=' '>l&#275;&#7779;<\/span><span lang=ES style=''>, p. ej. Pr. 1.22; 14.6; 24.9) y la del incr\u00e9dulo agresivo, llamado <\/span><span style=' '>n&#257;&#7687;&#257;l<\/span><span lang=ES style=''> (1 S. 25.25; Sal. 14.1; Is. 32.5s).<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>La advertencia de Cristo en cuanto a estigmatizar de \u201cnecio\u201d a otro (moros, Mt. 5.22) presupone estas connotaciones espirituales y morales (v\u00e9ase <etiqueta id=\"#_ftn132\" name=\"_ftnref132\" title=\"\">Arndt para otras explicacio<\/etiqueta>nes). En 1 Co. 1.25, 27 Pablo emplea el t\u00e9rmino (<\/span><span style=''>m&#333;ros<\/span><span lang=ES style=''>, \u2018insensatez\u2019) utilizado por los incr\u00e9dulos en su evaluaci\u00f3n err\u00f3nea de los prop\u00f3sitos de Dios. La necedad del hombre a veces puede residir en su incapacidad para percibir los problemas (p. ej. Lc. 11.40; 1 Co. 15.36, <\/span><span style=''>afr&#333;n<\/span><span lang=ES style=''>), pero m\u00e1s posiblemente en el haber hecho una elecci\u00f3n indigna (p. ej. Lc. 12.20, <\/span><span style=''>afr&#333;n<\/span><span lang=ES style=''>; Ro. 1.21, <\/span><span style=''>asynetos<\/span><span lang=ES style=''>; G\u00e1. 3.1, 3, <\/span><span style=''>ano&#275;tos<\/span><span lang=ES style=''>; Mt. 7.26, <\/span><span style=''>m&#333;ros<\/span><span lang=ES style=''>).<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal align=right style='text-align:right;line-height:normal'><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><etiqueta id=\"#_ftn133\" name=\"_ftnref133\" title=\"\"><span lang=ES style='font-size:10.0pt; ;color:green'>D.A.H.<\/span><\/etiqueta><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><span lang=ES style=''>, <\/span><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><etiqueta id=\"#_ftn134\" name=\"_ftnref134\" title=\"\"><span lang=ES style='font-size:10.0pt;;color:green'>F.D.K.<\/span><\/etiqueta><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><\/p>\n<p style='text-align:justify;'>Douglas, J. (2000). Nuevo diccionario Biblico : Primera Edicion. Miami: Sociedades B\u00edblicas Unidas.<\/p>\n<\/p>\n<p><b>Fuente: Nuevo Diccionario B\u00edblico<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si bien en el AT la necedad es a veces simplemente fatuidad (p. ej. Pr. 10.14; 14.15; 18.13, en este \u00faltimo caso justamente \u201cfatuidad\u201d en \u00b0vrv2), generalmente envuelve culpabilidad: desprecio para con la verdad y la disciplina divinas (Pr. 1.7). De aqu\u00ed surge que aun el hombre \u201csimple\u201d o cr\u00e9dulo (pe&#7791;&#305;&#770;) no es s\u00f3lo \u201cfalto &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/necedad-insensatez\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abNECEDAD, INSENSATEZ\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-22341","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/22341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=22341"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/22341\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=22341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=22341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=22341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}