{"id":22345,"date":"2016-02-05T15:19:51","date_gmt":"2016-02-05T20:19:51","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/nodriza-ama\/"},"modified":"2016-02-05T15:19:51","modified_gmt":"2016-02-05T20:19:51","slug":"nodriza-ama","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/nodriza-ama\/","title":{"rendered":"NODRIZA, AMA"},"content":{"rendered":"<p><p style='text-align:justify;'><span lang=ES style=''>\u201cAma\u201d o \u201cnodriza\u201d, pueden significar en las <etiqueta id=\"#_ftn271\" name=\"_ftnref271\" title=\"\">vss. b\u00edblicas \u201cama de leche\u201d y traducen el heb. <\/etiqueta><\/span><span style=''>m\u00eaneqe&#7791;<\/span><span lang=ES style=''>, que se emplea para D\u00e9bora (Gn. 24.59), la madre de Mois\u00e9s (Ex. 2.7), y la nodriza del peque\u00f1o Jo\u00e1s (2 R. 11.2; 2 Cr. 22.11). En el Cercano Oriente usualmente se da el pecho a los ni\u00f1os hasta los dos a\u00f1os de edad, y a menudo la nodriza permanece con la familia como sierva de confianza, como en el caso de D\u00e9bora (Gn. 35.8). Se emplea la misma palabra en sentido figurado para las reinas que se ocupar\u00e1n del pueblo de Dios en el glorioso futuro (Is. 49.23). Pablo compara su cuidado por los creyentes con el de una nodriza (gr. <\/span><span style=''>trofos<\/span><span lang=ES style=''>) por sus propios hijos (1 Ts. 2.7).<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>En sentido m\u00e1s general de alguien que se ocupa de los ni\u00f1os, la voz \u201cnodriza\u201d (o \u201caya\u201d) es traducci\u00f3n del heb. <\/span><span style=''>&#722;&#333;mene&#7791;<\/span><span lang=ES style=''>; por ejemplo, Noem\u00ed (Rt. 4.16) y la nodriza de Mefi-boset cuando ten\u00eda cinco a\u00f1os (2 S. 4.4). La forma masculina de esta voz heb., <\/span><span style=''>&#722;&#333;m&#275;n<\/span><span lang=ES style=''>, que se traduce \u201cnodriza\u201d (<\/span><span lang=ES style='font-size:10.0pt;; color:green;text-transform:uppercase'>\u00b0nbe<\/span><span lang=ES style=''>, <\/span><span lang=ES style='font-size:10.0pt;;color:green; text-transform:uppercase'>\u00b0vm<\/span><span lang=ES style=' '>, <\/span><span lang=ES style='font-size: 10.0pt;;color:green;text-transform:uppercase'>\u00b0bj<\/span><span lang=ES style=''> ); \u201cama\u201d (<\/span><span lang=ES style='font-size:10.0pt;; color:green;text-transform:uppercase'>\u00b0sba<\/span><span lang=ES style=''> ); \u201cla que cr\u00eda al que mama\u201d (<\/span><span lang=ES style='font-size:10.0pt;; color:green;text-transform:uppercase'>\u00b0vrv2<\/span><span lang=ES style=''>), se emplea en forma figurada para el cuidado que tuvo Mois\u00e9s por los israelitas (Nm. 11.12), y para los reyes que servir\u00e1n al pueblo de Dios (Is. 49.23, <\/span><span lang=ES style='font-size:10.0pt;;color:green; text-transform:uppercase'>\u00b0vrv2<\/span><span lang=ES style=' '> \u201cayo\u201d). Cf. Hch. 13.18, <\/span><etiqueta id=\"#_ftn272\" name=\"_ftnref272\" title=\"\"><span lang=ES style='font-size:10.0pt; ;color:green;text-transform:uppercase'>\u00b0ba<\/span><\/etiqueta><span lang=ES style=''> mg.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=';text-transform:uppercase'>Bibliograf\u00eda.<\/span><span lang=ES style=''> C. Wau, \u201cNodriza\u201d, <i>\u00b0EBDM<\/i>, t(t). V, cols. 538\u2013539; R. de Vaux, <i>Instituciones del Antiguo Testamento<\/i>, 1985, pp. 80, 86.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>H. Granquist, <i>Birth and Childhood among the Arabs<\/i>, 1947, pp. 107\u2013117, 246\u2013252; <etiqueta id=\"#_ftn273\" name=\"_ftnref273\" title=\"\"><i>RAC<\/i><\/etiqueta>, I, pp. 383\u2013385.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal align=right style='text-align:right;line-height:normal'><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><etiqueta id=\"#_ftn274\" name=\"_ftnref274\" title=\"\"><span lang=ES style='font-size:10.0pt; ;color:green'>J.T.<\/span><\/etiqueta><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><\/p>\n<p style='text-align:justify;'>Douglas, J. (2000). Nuevo diccionario Biblico : Primera Edicion. Miami: Sociedades B\u00edblicas Unidas.<\/p>\n<\/p>\n<p><b>Fuente: Nuevo Diccionario B\u00edblico<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cAma\u201d o \u201cnodriza\u201d, pueden significar en las vss. b\u00edblicas \u201cama de leche\u201d y traducen el heb. m\u00eaneqe&#7791;, que se emplea para D\u00e9bora (Gn. 24.59), la madre de Mois\u00e9s (Ex. 2.7), y la nodriza del peque\u00f1o Jo\u00e1s (2 R. 11.2; 2 Cr. 22.11). En el Cercano Oriente usualmente se da el pecho a los ni\u00f1os hasta &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/nodriza-ama\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abNODRIZA, AMA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-22345","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/22345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=22345"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/22345\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=22345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=22345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=22345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}