{"id":22353,"date":"2016-02-05T15:20:07","date_gmt":"2016-02-05T20:20:07","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/padrenuestro-el\/"},"modified":"2016-02-05T15:20:07","modified_gmt":"2016-02-05T20:20:07","slug":"padrenuestro-el","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/padrenuestro-el\/","title":{"rendered":"PADRENUESTRO, EL"},"content":{"rendered":"<p><p style='text-align:justify;'><span lang=ES style=''>La oraci\u00f3n que nuestro Se\u00f1or ense\u00f1\u00f3 a sus disc\u00edpulos como la plegaria modelo que deb\u00edan usar regularmente. En Mt. 6.9\u201313 aparece como parte integrante del Serm\u00f3n del monte. Pero en Lc. 11.2\u20134 la da nuestro Se\u00f1or en circunstancias diferentes. Es probable que haya repetido esta oraci\u00f3n en diferentes oportunidades, dado que era su intenci\u00f3n que sirviera de modelo para todos sus disc\u00edpulos en todas las ocasiones.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>En Mt. 6.9\u201313 aparece como oraci\u00f3n ejemplar que cumple todos los requisitos que \u00e9l mismo hab\u00eda puesto como condici\u00f3n esencial de la oraci\u00f3n verdadera: \u201cOrar\u00e9is as\u00ed\u201d, dijo (<etiqueta id=\"#_ftn102\" name=\"_ftnref102\" title=\"\">v. 9). De este modo continuaba ense\u00f1ando a sus disc\u00edpulos <\/etiqueta><i>c\u00f3mo<\/i> ten\u00edan que orar. Despu\u00e9s de haberles advertido que no deb\u00edan orar como los hip\u00f3critas (v. 5), ni usando vanas repeticiones, como los gentiles (v. 7), les ense\u00f1\u00f3 cu\u00e1l era el tipo de oraci\u00f3n que resultaba aceptable ante Dios. Pero en Lc. 11.1\u20134, en respuesta al pedido de un disc\u00edpulo, esta vez les dice la oraci\u00f3n, no s\u00f3lo como ejemplo de una plegaria que se ajusta a sus ense\u00f1anzas, sino como una oraci\u00f3n concreta que deben elevar sus seguidores: \u201cCuando or\u00e9is, decid \u2026\u201d (v. 2).<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>En Lc. 11.2\u20134 la oraci\u00f3n aparece en forma m\u00e1s breve que en Mt. 6.9\u201313: \u201cPadre nuestro que est\u00e1s en los cielos, santificado sea tu nombre. Venga tu reino. H\u00e1gase tu voluntad, como en el cielo, as\u00ed tambi\u00e9n en la tierra. El pan nuestro de cada d\u00eda d\u00e1noslo hoy. Y perd\u00f3nanos nuestras deudas, como tambi\u00e9n nosotros perdonamos a nuestros deudores. Y no nos metas en tentaci\u00f3n, mas l\u00edbranos del mal\u201d.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>La forma breve probablemente representa la extensi\u00f3n que le dio Jes\u00fas cuando la compuso originalmente: la forma de tratamiento sencilla \u201cPadre\u201d corresponde a \u201cAbba\u201d, que \u00e9l mismo empleaba (<etiqueta id=\"#_ftn103\" name=\"_ftnref103\" title=\"\">cf. Mr. 14.36), y que los primitivos cristianos usaron siguiendo su ejemplo (cf. Ro. 8.15; G\u00e1. 4.6). El texto ampliado de Mateo ha sido adoptado para el uso lit\u00fargico cristiano, habi\u00e9ndose tomado la f\u00f3rmula \u201cPadre nuestro que est\u00e1s en los cielos\u201d del us<\/etiqueta>o en la sinagoga. Aqu\u00ed consideraremos el texto completo de Mateo.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Es obvio que nuestro Se\u00f1or haya dicho la plegaria en arameo originalmente. Para la \u00e9poca en que Mateo y Lucas escribieron sus evangelios, sin embargo, es natural que los cristianos hayan usado la oraci\u00f3n en griego tambi\u00e9n. Esto probablemente explica por qu\u00e9 Mt. 6 y Lc. 11 en general concuerdan en el lenguaje empleado, y ambos usan el t\u00e9rmino \u00fanico <\/span><span style=''>epiousios<\/span><span lang=ES style=''> (traducido \u201ccada d\u00eda\u201d) en la oraci\u00f3n.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Por medio de la introducci\u00f3n\u2014\u201cPadre nuestro que est\u00e1s en los cielos\u201d\u2014se nos ense\u00f1a la actitud y el esp\u00edritu correctos en los que debemos orar a Dios. Al dirigirnos a \u00e9l como \u201cPadre nuestro\u201d lo hacemos en esp\u00edritu de amor y fe, como aquel que est\u00e1 cerca de nosotros en perfecto amor y gracia. Por medio de las palabras \u201cque est\u00e1s en los cielos\u201d damos expresi\u00f3n a nuestra santa reverencia por \u00e9l, que es el todopoderoso Rey de cuanto existe. Las palabras introductorias de la plegaria tambi\u00e9n nos recuerdan el hecho de que todos los creyentes cristianos somos uno en \u00e9l, ya que debemos orar dirigi\u00e9ndonos a \u00e9l como Padre <i>nuestro<\/i>\u201d. Una vez que el coraz\u00f3n del creyente est\u00e1 bien preparado por la invocaci\u00f3n, las primeras peticiones se relacionan con la gloria y los prop\u00f3sitos divinos de nuestro Padre celestial. \u201cSantificado sea (<\/span><span style=''>hagiasth&#275;to<\/span><span lang=ES style=''>) tu nombre\u201d, es una oraci\u00f3n en la que pedimos a Dios que nos permita, a los que oramos, y a todos los hombres, reconocerlo y honrarlo. Su nombre, <etiqueta id=\"#_ftn104\" name=\"_ftnref104\" title=\"\">e. d. \u00e9l mismo en su autorrevelaci\u00f3n, se ha de reconocer como santo; y \u00e9l debe recibir <\/etiqueta>todo el honor y la gloria debidas al que en perfecci\u00f3n nos ama y es nuestro santo y omnipotente Creador. (* <span style='text-transform:uppercase'>Dios, Nombres de<\/span>). La petici\u00f3n \u201cVenga tu reino\u201d, puede usarse, en general, como s\u00faplica para que se extienda el divino dominio (<\/span><span style='font-family: \"Charis SIL\"'>basileia<\/span><span lang=ES style=''>) de Dios \u201caqu\u00ed y ahora\u201d (en la era actual), tanto en el coraz\u00f3n de los individuos como en el mundo en general. Principalmente, sin embargo, esta oraci\u00f3n tiene sentido escatol\u00f3gico. Es una s\u00faplica para que se establezca \u201ccon poder\u201d el dominio real y soberano de Dios (Mr. 9.1) con la gloriosa aparici\u00f3n del Hijo del Hombre (* <span style='text-transform:uppercase'>Reino de Dios<\/span>).<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>La tercera petici\u00f3n \u201cH\u00e1gase tu voluntad, como en el cielo, as\u00ed tambi\u00e9n en la tierra\u201d, que no figura en el texto aut\u00e9ntico de Lc. 11.2, es pr\u00e1cticamente una ampliaci\u00f3n de la petici\u00f3n previa. En el cielo, donde todos aceptan en forma gozosa e incondicional el dominio de Dios, tambi\u00e9n se obedece en forma espont\u00e1nea y gozosa su voluntad. Es por esto que los creyentes deben orar para que todos sobre la tierra tambi\u00e9n obedezcan a Dios en la misma forma, especialmente en su propia vida. Esta petici\u00f3n se refiere en forma parcial a la \u00e9poca actual, pero abre perspectivas a la era en la que toda rodilla se doblar\u00e1 ante el Rey de reyes y los poderes de las tinieblas ser\u00e1n finalmente destruidos. Dios ser\u00e1, entonces, todo en todos y su voluntad reinar\u00e1 en forma suprema (1 Co. 15.25\u201328). Los tres imperativos <\/span><span style=''>hagiasth&#275;t&#333;<\/span><span lang=ES style=''> (\u2018santificado sea\u2019), <\/span><span style=''>elthat&#333;<\/span><span lang=ES style=''> (\u2018venga\u2019) y <\/span><span style=''>gen&#275;th&#275;t&#333;<\/span><span lang=ES style=''> (\u2018h\u00e1gase\u2019) son todos aor\u00edsticos y se refieren a la consumaci\u00f3n final.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Una vez centradas las tres primeras peticiones en la glorificaci\u00f3n de Dios, las tres siguientes se refieren al bienestar f\u00edsico y espiritual de los creyentes.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>De este modo, los creyentes deben orar expresamente por la ayuda y la bendici\u00f3n de Dios para todos los aspectos de la vida en este mundo. Por medio de la petici\u00f3n \u201cEl pan nuestro de cada d\u00eda, d\u00e1noslo hoy\u201d solicitamos a Dios, nuestro Padre celestial, que nos conceda las necesidades f\u00edsicas de la vida. La palabra \u201cpan\u201d resume aqu\u00ed todo lo que realmente necesitamos para nuestra existencia terrenal. En vista de las peticiones antedichas, se trata de una s\u00faplica en la que pedimos a Dios que continuamente nos supla las necesidades materiales de la vida, de modo que podamos asi santificar m\u00e1s efectivamente su nombre, obrar para la venida de su reino, y hacer su voluntad en la tierra. De este modo, nuestra plegaria por el sost\u00e9n diario no tiene sentido ego\u00edsta, ni es una oraci\u00f3n para satisfacer el lujo material, sino una oraci\u00f3n en la que confesamos nuestra total dependencia de Dios, y por la que miramos a \u00e9l con fe para poder vivir de acuerdo con su voluntad.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>La voz <etiqueta id=\"#_ftn105\" name=\"_ftnref105\" title=\"\">gr. <\/etiqueta><\/span><span style=''>epiousios<\/span><span lang=ES style=''>, traducida \u201cde cada d\u00eda\u201d, s\u00f3lo aparece en Mt. 6.11 y Lc. 11.3 y (seg\u00fan se dice) en un solo papiro (que lamentablemente ya no existe), en el que parecer\u00eda que la forma neutra plural <\/span><span style=''>epiousia<\/span><span lang=ES style=''> significaba \u201craciones diarias\u201d. Aunque todav\u00eda no se ha podido establecer definitivamente la derivaci\u00f3n etimol\u00f3gica correcta, y algunos prefieren traducir \u201cpara el pr\u00f3ximo d\u00eda\u201d o \u201clo que es necesario o suficiente\u201d, la traducci\u00f3n \u201cde cada d\u00eda\u201d parece ser apropiada. La traducci\u00f3n \u201dpan supersustancial\u201d se remonta a los d\u00edas de Jer\u00f3nimo, como si la referencia aqu\u00ed fuera a Jes\u00fas como el verdadero pan de vida. J. Jeremias relaciona esta petici\u00f3n con el \u00e9nfasis escatol\u00f3gico de sus predecesoras, como si la referencia fuera a \u201ccomer pan en el reino de Dios\u201d (cf. Lc. 14.15). Pero en el contexto, lo que se quiere expresar es la provisi\u00f3n constante de lo que realmente se necesita y es adecuado para nosotros d\u00eda tras d\u00eda en el campo de la existencia f\u00edsica, material.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>La petici\u00f3n que sigue, \u201cy perd\u00f3nanos nuestras deudas, como tambi\u00e9n nosotros perdonamos a nuestros deudores\u201d, es tanto una plegaria como una confesi\u00f3n. Porque el que ora por el perd\u00f3n, al mismo tiempo admite que ha pecado y es culpable. En Lc. 11.4 la petici\u00f3n aparece as\u00ed: \u201cY perd\u00f3nanos nuestros pecados, porque tambi\u00e9n nosotros perdonamos a todos los que nos deben\u201d. La voz gr. <\/span><span style=''>hamartias<\/span><span lang=ES style=''>, traducida aqu\u00ed \u201cpecados\u201d, tiene el significado primario de \u201cerrar el blanco\u201d, o sea \u201cactuar incorrectamente\u201d y \u201cviolar la ley de Dios\u201d. En Mt. 6.12 <\/span><span style=''>ofeil&#275;mata<\/span><span lang=ES style=''> (\u201cdeudas\u201d) preserva la expresi\u00f3n idiom\u00e1tica <etiqueta id=\"#_ftn106\" name=\"_ftnref106\" title=\"\">arm. en la que el t\u00e9rmino para \u201cdeuda\u201d (<\/etiqueta><\/span><span style=''>&#7717;\u00f4&#7687;\u00e2<\/span><span lang=ES style=''>) tambi\u00e9n se emplea en el mismo sentido de \u201cpecado\u201d. Al pecar entramos en deuda moral y espiritual con nuestro Padre y Creador, que tiene total autoridad sobre nuestra vida. Por lo tanto, en esta petici\u00f3n humildemente le rogamos por la remisi\u00f3n de nuestras deudas, en vista de que nosotros mismos nunca podemos ganarnos el perd\u00f3n.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Las palabras \u201ccomo tambi\u00e9n nosotros [<\/span><span style=''>h&#333;s kai h&#275;meis<\/span><span lang=ES style=''>, \u2018en la misma forma en que tambi\u00e9n nosotros\u2019] hemos perdonado [aoristo] a nuestros deudores\u201d (Mt. 6.12) y \u201cporque tambi\u00e9n nosotros perdonamos [presente de indicativo] a todos los que nos deben\u201d (Lc. 11.4), no significan que debemos pedir perd\u00f3n <i>debido a que<\/i> hemos perdonado a los que han pecado contra nosotros. S\u00f3lo a trav\u00e9s de la gracia podemos recibir perd\u00f3n. Pero a fin de orar a Dios con sinceridad y sin hipocres\u00eda pidiendo que nos perdone, debemos liberarnos de todo esp\u00edritu de odio y venganza. S\u00f3lo cuando Dios nos ha dado la gracia para perdonar verdaderamente a los que han pecado contra nosotros podemos formular una sincera plegaria de perd\u00f3n. Nuestro Se\u00f1or lo consider\u00f3 de tal importancia que lo reiter\u00f3 en Mt. 6.14\u201315 (cf. Mt. 18.23\u201335; Mr. 11.25).<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>La petici\u00f3n final en Lc. 11.4 dice: \u201cY no nos metas en tentaci\u00f3n.\u201d En Mt. 6.13 las palabras \u201cmas l\u00edbranos del mal\u201d (<\/span><etiqueta id=\"#_ftn107\" name=\"_ftnref107\" title=\"\"><span lang=ES style='font-size:10.0pt; ;color:green;text-transform:uppercase'>\u00b0ba<\/span><\/etiqueta><span lang=ES style=''> <etiqueta id=\"#_ftn108\" name=\"_ftnref108\" title=\"\">mg \u201cdel maligno\u201d) siguen a continuaci\u00f3n. Estas palabras adicionales hacen que la petici\u00f3n sea de apli<\/etiqueta>caci\u00f3n general. Los que sinceramente oran para que se les perdone sus pecados desean poder no pecar nuevamente. Es apropiado, por lo tanto, que esta petici\u00f3n siga a la anterior. Dios nunca tienta a nadie para que haga el mal (Stg. 1.13), pero controla las circunstancias de nuestras vidas. En esta oraci\u00f3n confesamos humildemente que estamos predispuestos al pecado, y por lo tanto le suplicamos que no permita que nos encontremos en situaciones o condiciones que entra\u00f1en una gran tentaci\u00f3n a pecar. Como elaboraci\u00f3n posterior de este aspecto siguen las palabras \u201cmas l\u00edbranos del mal\u201d (\u201cdel maligno\u201d), e. d. esc\u00fadanos, prot\u00e9genos, gu\u00e1rdanos (<\/span><span style=''>rhyesthai<\/span><span lang=ES style=''>) de los ataques del diablo (<\/span><span style=''>tou pon&#275;rou<\/span><span lang=ES style=''>). Esta petici\u00f3n final, aunque se aplica a todos los d\u00edas de nuestra vida, hace una clara alusi\u00f3n a la consumaci\u00f3n, en la que nuestro Se\u00f1or terminar\u00e1 con todo lo malo, y establecer\u00e1 su reino eterno de justicia y santidad.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Esto nos lleva a considerar que en el marco del ministerio de Jes\u00fas esta petici\u00f3n ten\u00eda una nota escatol\u00f3gica. La traducci\u00f3n de <\/span><etiqueta id=\"#_ftn109\" name=\"_ftnref109\" title=\"\"><span lang=ES style='font-size:10.0pt;;color:green; text-transform:uppercase'>\u00b0nbe<\/span><\/etiqueta><span lang=ES style=' '>, \u201cy no nos dejes caer en la prueba\u201d (v\u00e9ase <etiqueta id=\"#_ftn110\" name=\"_ftnref110\" title=\"\">tamb. <\/etiqueta><\/span><etiqueta id=\"#_ftn111\" name=\"_ftnref111\" title=\"\"><span lang=ES style='font-size:10.0pt; ;color:green;text-transform:uppercase'>\u00b0vrv3<\/span><\/etiqueta><span lang=ES style=''> mg) lo indica, aunque muy cr\u00edpticamente. La prueba mencionada es la prueba crucial de la fe de los disc\u00edpulos que, sin el poder divino, resultar\u00eda demasiado intensa para resistir exitosamente. La forma que adopta esa prueba puede verse en Getseman\u00ed (la prueba final para Jes\u00fas mismo tamb.). La exhortaci\u00f3n a los disc\u00edpulos: \u201cVelad y orad, para que no entr\u00e9is en tentaci\u00f3n\u201d (Mr. 14.38) posiblemente significa: \u201cManteneos despiertos, y rogad para que no fall\u00e9is en la prueba\u201d. Esto sugiere que la petici\u00f3n en el Padrenuestro quiere decir: \u201cHaz que no fallemos en la prueba\u201d (cf. C. C. Torrey, <i>The Four Gospels<\/i>, 1933, pp. 292). Y actualmente, adem\u00e1s de la petici\u00f3n general de ser librados de la tentaci\u00f3n, los cristianos pueden usar esta petici\u00f3n como oraci\u00f3n para que la gracia y el poder de Dios eviten que fallen cuando su fe se vea amenazada por una prueba suprema.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>En algunos <etiqueta id=\"#_ftn112\" name=\"_ftnref112\" title=\"\">ms(s). antiguos, y en otros posteriores, de Mt. 6.13 aparece una doxolog\u00eda. En <\/etiqueta><\/span><etiqueta id=\"#_ftn113\" name=\"_ftnref113\" title=\"\"><span lang=ES style='font-size:10.0pt;;color:green; text-transform:uppercase'>\u00b0vrv2<\/span><\/etiqueta><span lang=ES style=' '> la tenemos as\u00ed: \u201cPorque tuyo es el reino, y el poder, y la gloria, por todos los siglos. Am\u00e9n.\u201d Aunque algunos de los ms(s). m\u00e1s autorizados no tienen esta doxolog\u00eda, la iglesia cristiana la ha usado desde las \u00e9pocas m\u00e1s primitivas (cf. la <\/span><span style=''>Didaj\u00e9<\/span><span lang=ES style=''> y el texto occ.), y por cierto que es un final muy adecuado y digno para el Padrenuestro. Sin embargo, por el hecho de que los vv. 14 y 15 siguen naturalmente a los vv. 12 y 13a, resulta evidente que no pertenece al texto original de Mateo.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Bien dijo alguien que el Padrenuestro es el mensaje de Jes\u00fas sobre el reino de Dios resumido en forma de plegaria. Es la oraci\u00f3n que todos los cristianos deben ofrecer regularmente a Dios a fin de poder vivir como hijos suyos en forma crecientemente cabal, hasta el d\u00eda en que se establezca perfectamente su soberan\u00eda.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Corresponde hacer notar que nuestro Se\u00f1or (cuando ense\u00f1aba a los disc\u00edpulos esta oraci\u00f3n) no dijo: \u201c<i>debemos<\/i> orar\u201d, sino \u201c<i>orad <\/i>(vosotros)\u201d. El Padrenuestro es la oraci\u00f3n que \u00e9l ense\u00f1\u00f3, y no la que usaba \u00e9l. Aparentemente nunca utiliz\u00f3 la expresi\u00f3n \u201cPadre nuestro\u201d en forma tal que incluyese a sus disc\u00edpulos junto con \u00e9l (cf. Jn. 20.17, \u201cmi Padre y\u2026 vuestro Padre\u201d); tampoco tenemos indicio de que alguna vez haya sentido la necesidad de pedir perd\u00f3n para s\u00ed mismo.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>Si bien las peticiones individuales en el Padrenuestro tienen sus paralelos en diversos contextos de la literatura religiosa judia, no encontramos nada comparable a esta oraci\u00f3n en su conjunto. El Padreouestro es \u00fanico, y no ha sido superado hasta el d\u00eda de hoy: en pocas palabras re\u00fane todos los elementos esenciales de la verdadera plegaria.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=';text-transform:uppercase'>Bibliograf\u00eda.<\/span><span lang=ES style=''> Jeremias, <i>Palabras de Jes\u00fas, el Padrenuestro<\/i>, 1970; K. Barth, <i>La oraci\u00f3n<\/i>, 1968; S. Canclini, <i>La oraci\u00f3n que nos ense\u00f1aron nuestros padres<\/i>, 1977; M. Lutero, <i>Padrenuestro<\/i>, 1939; S. Sabugal, <i>El Padrenuestro en la interpretaci\u00f3n catequ\u00e9tica antigua y moderna<\/i>, 1982.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>J. Jeremias, <i>The Lord\u2019s Prayer<\/i>, 1964 (reimpreso en <i>The Prayers of Jesus<\/i>, 1967, pp. 82\u2013107); E. Lohmeyer, <i>The Lord\u2019s Prayer<\/i>, 1965; T. W. Manson, \u201cThe Lord\u2019s Prayer\u201d, <etiqueta id=\"#_ftn114\" name=\"_ftnref114\" title=\"\"><i>BJRL<\/i><\/etiqueta> 38, 1955\u20136, pp. 99\u2013113, 436\u2013448; B. M. Metzger, \u201cHow Many Times does <\/span><span style=' '>epiousios<\/span><span lang=ES style=' '> occur outside the Lord\u2019s Prayer?\u201d en <i>Historical and Literary Studies<\/i>, 1968, pp. 64ss; comentarios sobre Mateo y Lucas.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal align=right style='text-align:right;line-height:normal'><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><etiqueta id=\"#_ftn115\" name=\"_ftnref115\" title=\"\"><span lang=ES style='font-size:10.0pt; ;color:green'>J.N.G.<\/span><\/etiqueta><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><span lang=ES style=''>, <\/span><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><etiqueta id=\"#_ftn116\" name=\"_ftnref116\" title=\"\"><span lang=ES style='font-size:10.0pt;;color:green'>F.F.B.<\/span><\/etiqueta><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><\/p>\n<p style='text-align:justify;'>Douglas, J. (2000). Nuevo diccionario Biblico : Primera Edicion. Miami: Sociedades B\u00edblicas Unidas.<\/p>\n<\/p>\n<p><b>Fuente: Nuevo Diccionario B\u00edblico<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La oraci\u00f3n que nuestro Se\u00f1or ense\u00f1\u00f3 a sus disc\u00edpulos como la plegaria modelo que deb\u00edan usar regularmente. En Mt. 6.9\u201313 aparece como parte integrante del Serm\u00f3n del monte. Pero en Lc. 11.2\u20134 la da nuestro Se\u00f1or en circunstancias diferentes. Es probable que haya repetido esta oraci\u00f3n en diferentes oportunidades, dado que era su intenci\u00f3n que &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/padrenuestro-el\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abPADRENUESTRO, EL\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-22353","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/22353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=22353"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/22353\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=22353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=22353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=22353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}