{"id":31677,"date":"2016-09-30T03:21:05","date_gmt":"2016-09-30T08:21:05","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/g4052\/"},"modified":"2016-09-30T03:21:05","modified_gmt":"2016-09-30T08:21:05","slug":"g4052","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/g4052\/","title":{"rendered":"G4052"},"content":{"rendered":"<p>Diccionario Strong<\/p>\n<p>\u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03b5\u03cd\u03c9<\/p>\n<p>perisse\u00fao<\/p>\n<p>de G4053; superabundar (en cantidad o calidad), haber en exceso, ser superfluo; tambi\u00e9n (transitivamente) hacer superabundar o sobresalir: abundancia, abundar, aumentar, crecer.<\/p>\n<p>&#8212;-<\/p>\n<p>Diccionario Tuggy<\/p>\n<p>\u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03b5\u03cd\u03c9.(imperf. \u1f10\u03c0\u03b5\u03c1\u03af\u03c3\u03c3\u03b5\u03c5\u03bf\u03bd; tiempo futuro  \u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03b5\u03cd\u03c3\u03c9; 1 tiempo aoristo   \u1f10\u03c0\u03b5\u03c1\u03af\u03c3\u03c3\u03b5\u03c5\u03c3\u03b1). Sobrar, abundar, ser m\u00e1s que suficiente, desbordar, aumentar, aventajar, sobresalir, tener de sobra, estar en mejor posici\u00f3n. A.T. \u05d9\u05b8\u05ea\u05b7\u05e8  ni. 1Sa 2:36. \u05d9\u05d5\u05b9\u05ea\u05b5\u05e8 ; Ecl 3:19. \u05de\u05b7\u05e8\u05b0\u05d1\u05bc\u05b4\u05d9\u05ea , 1Sa 2:33. N.T. <\/p>\n<p>A) intransitivo Hacer abundar o aumentar, proveer en abundancia : Mat 13:12; Mat 25:29; Luc 15:17; 2Co 4:15; 2Co 9:8; Efe 1:8; 1Ts 3:12. <\/p>\n<p>B) intrans. Sobrar, abundar, ser m\u00e1s que suficiente, desbordar, aumentar, aventajar, sobresalir, tener de sobra, estar en mejor posici\u00f3n : Mat 5:20; Mat 14:20; Mat 15:37; Luc 9:17; Luc 12:15; Luc 21:4; Jua 6:12-13; Hch 16:5; Rom 3:7; Rom 5:15; Rom 15:13; 1Co 8:8; 1Co 14:12; 1Co 15:58; 2Co 1:5; 2Co 3:9; 2Co 8:2; 2Co 8:7; 2Co 9:8; 2Co 9:12; Flp 1:9; Flp 1:26; Flp 4:12; Flp 4:18; Col 2:7; 1Ts 4:1; 1Ts 4:10.<\/p>\n<p>&#8212;-<\/p>\n<p>Diccionario Swanson<\/p>\n<p>(Swanson 4355)<\/p>\n<p>\u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03b5\u03cd\u03c9 (perisseu\u014d): vb.; \u2261 Strong 4052; TDNT 6.58-1. LN 59.52 tener abundancia, abundar (2Co 1:5); 2. LN 59.54 proveer en abundancia (Efe 1:8); 3. LN 57.24 tener m\u00e1s que suficiente (Luc 15:17); 4. LN 78.31 excesivo, mucha cantidad (Mat 5:20); 5. LN 78.32 causar que haya m\u00e1s (1Ts 3:12); 6. LN 65.47 tener mayor ventaja (1Co 8:8) <\/p>\n<p>&#8212;-<\/p>\n<p>Diccionario Vine NT<\/p>\n<p>perisseuo (\u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03b5\u03cd\u03c9, G4052), estar sobre y por encima, por encima de una cierta cantidad o medida, abundar, exceder. Se traduce \u00absobreabunde\u00bb en 2Co 4:15; \u00abhizo sobreabundar\u00bb en Efe 1:8. V\u00e9ase ABUNDAR bajo ABUNDANCIA, B, N\u00ba 1, y tambi\u00e9n AUMENTAR, CRECER, MAYOR, QUEDAR, SOBRAR, TENER ABUNDANCIA.<\/p>\n<p>perisseuo (\u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03b5\u03cd\u03c9, G4052), relacionado con A, N\u00ba 2 y 3. Se usa intransitivamente: (a) de exceder una cierta cantidad o medida, sobrar, quedar, de los fragmentos despu\u00e9s de alimentar a la multitud (Luc 9:17; Jua 6:12-13, cf. perisseuma); de existir en abundancia, como de la riqueza (Luc 12:15; Luc 21:4); de los alimentos (Luc 15:17). En este sentido se utiliza tambi\u00e9n de la consolaci\u00f3n (2Co 1:5); del efecto de una ofrenda enviada para suplir las necesidades de los santos (2Co 9:12); de la gloria o gozo (Flp 1:26); de lo que viene o cae como parte de una persona en gran medida, como de la gracia de Dios y el don por la gracia de Cristo (Rom 5:15); de los sufrimientos de Cristo (2Co 1:5).<\/p>\n<p>(b) redundar en, o resultar abundantemente para algo, como con respecto a los efectos liberales de la pobreza (2Co 8:2); en Rom 3:7 argumentativamente, de los efectos de la verdad de Dios, en cuanto a si la fidelidad de Dios llega a quedar m\u00e1s patente y si su gloria aumenta debido a la infidelidad del hombre; del aumento num\u00e9rico (Hch 16:5).<\/p>\n<p>(c) ser abundantemente suplido, abundar en algo, como beneficios materiales (Luc 12:15; Flp 4:18); en cuanto a dones espirituales (1Co 14:12), o ser preeminente, sobresalir, ser moralmente mejor, en lo que respecta a participar de ciertas viandas (1Co 8:8 : \u00abseremos m\u00e1s\u00bb); abundar en esperanza (Rom 15:13); la obra del Se\u00f1or (1Co 15:58); fe y gracia (2Co 8:7); acci\u00f3n de gracias (Col 2:7); andar de forma que agrade a Dios (Flp 1:9; 1Ts 4:1, 1Ts 4:10); de la justicia (Mat 5:20); del evangelio, en cuanto a ministraci\u00f3n de justicia (2Co 3:9 : \u00ababundar\u00e1\u00bb).<\/p>\n<p>Se utiliza transitivamente, en el sentido de hacer abundar, p.ej., proveer a una persona ricamente, de forma que tenga abundancia como de verdad espiritual (Mat 13:12); del uso recto de lo que Dios nos ha confiado (Mat 25:29). del poder de Dios en dar gracia (2Co 9:8; Efe 1:8); de hacer abundante o de hacer sobresalir, en cuanto a los efectos de la gracia en relaci\u00f3n con la acci\u00f3n de gracias (2Co 4:15); de su poder para hacernos abundar en amor (1Ts 3:12). V\u00e9anse AUMENTAR, CRECER ( SER M\u00c1S ), MAYOR (SER MAYOR), SOBRAR, SOBREABUNDAR, TENER ABUNDANCIA.\u00b6<\/p>\n<p>perisseuo (\u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03b5\u03cd\u03c9, G4052), v\u00e9anse ABUNDAR, AUMENTAR. Se traduce \u00abcreciendo\u00bb en 1Co 15:58.<\/p>\n<p>perisseuo (\u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03b5\u03cd\u03c9, G4052), estar por encima de (una cantidad), de ah\u00ed, sobrar. Se traduce \u00abtendr\u00e1 m\u00e1s\u00bb (Mat 13:12; Mat 25:29); v\u00e9ase ABUNDAR bajo ABUNDANCIA, B, N\u00ba 1, etc. <\/p>\n<p>perisseuo (\u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03b5\u03cd\u03c9, G4052), estar encima y m\u00e1s all\u00e1, abundar. Se traduce \u00abaumentaban\u00bb en Hch 16:5, de las iglesias. V\u00e9ase ABUNDAR, B, N\u00ba 1, etc.<\/p>\n<p>perisseuo (\u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03b5\u03cd\u03c9, G4052), abundar, estar por encima, sobrar, quedar. Se traduce \u00abque han quedado\u00bb en Jua 6:12 (RV: \u00abque sobraron\u00bb); V\u00e9ase ABUNDAR bajo ABUNDANCIA, B, N\u00ba 1, y tambi\u00e9n SOBRAR, etc.<\/p>\n<p>perisseuo (\u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03b5\u03cd\u03c9, G4052), v\u00e9ase ABUNDANCIA, B. Se traduce con la frase verbal \u00abtener abundancia\u00bb en Luc 15:17, Flp 4:12, dos veces; Flp 4:18. <\/p>\n<p>perisseuo (\u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03b5\u03cd\u03c9, G4052), abundar, estar sobre y por encima. Se traduce con el verbo sobrar en Mat 14:20; Mat 15:37; Mar 12:44; Luc 9:17; Luc 21:4; Jua 6:12-13; v\u00e9ase ABUNDAR, B, N\u00ba 1, etc.<\/p>\n<p>Fuente: Varios Autores<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diccionario Strong \u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03b5\u03cd\u03c9 perisse\u00fao de G4053; superabundar (en cantidad o calidad), haber en exceso, ser superfluo; tambi\u00e9n (transitivamente) hacer superabundar o sobresalir: abundancia, abundar, aumentar, crecer. &#8212;- Diccionario Tuggy \u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03b5\u03cd\u03c9.(imperf. \u1f10\u03c0\u03b5\u03c1\u03af\u03c3\u03c3\u03b5\u03c5\u03bf\u03bd; tiempo futuro \u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03b5\u03cd\u03c3\u03c9; 1 tiempo aoristo \u1f10\u03c0\u03b5\u03c1\u03af\u03c3\u03c3\u03b5\u03c5\u03c3\u03b1). Sobrar, abundar, ser m\u00e1s que suficiente, desbordar, aumentar, aventajar, sobresalir, tener de sobra, estar en mejor posici\u00f3n. &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/g4052\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abG4052\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31677","post","type-post","status-publish","format-standard","hentry","category-enciclopedia"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/31677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=31677"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/31677\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=31677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=31677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=31677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}