{"id":31731,"date":"2016-09-30T03:21:14","date_gmt":"2016-09-30T08:21:14","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/g4100\/"},"modified":"2016-09-30T03:21:14","modified_gmt":"2016-09-30T08:21:14","slug":"g4100","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/g4100\/","title":{"rendered":"G4100"},"content":{"rendered":"<p>Diccionario Strong<\/p>\n<p>\u03c0\u03b9\u03c3\u03c4\u03b5\u03cd\u03c9<\/p>\n<p>piste\u00fao<\/p>\n<p>de G4102; tener fe (en, o con respecto a, persona o cosa), i.e. cr\u00e9dito; por implicaci\u00f3n confiar (espec\u00edficamente a Cristo el bienestar espiritual de uno): encomendar, fiar, guardar, confiar, creer, creyente.<\/p>\n<p>&#8212;-<\/p>\n<p>Diccionario Tuggy<\/p>\n<p>\u03c0\u03b9\u03c3\u03c4\u03b5\u03cd\u03c9.(imperf. \u1f10\u03c0\u03af\u03c3\u03c4\u03b5\u03c5\u03bf\u03bd; tiempo futuro  \u03c0\u03b9\u03c3\u03c4\u03b5\u03cd\u03c3\u03c9; 1 tiempo aoristo   \u1f10\u03c0\u03af\u03c3\u03c4\u03b5\u03c5\u03c3\u03b1; 1 tiempo aoristo   voz pasiva \u1f10\u03c0\u03b9\u03c3\u03c4\u03b5\u03cd\u03b8\u03b7\u03bd; tiempo perfecto \u03c0\u03b5\u03c0\u03af\u03c3\u03c4\u03b5\u03c5\u03ba\u03b1; tiempo perfecto voz pasiva \u03c0\u03b5\u03c0\u03af\u03c3\u03c4\u03b5\u03c5\u03bc\u03b1\u03b9). Creer, tener fe, tener confianza, confiar. A.T. \u05d0\u05b8\u05de\u05b7\u05df  ni. G\u00e9n 42:20. Casi siempre \u05d0\u05b8\u05de\u05b7\u05df  hi., G\u00e9n 15:6. \u05d0\u05b2\u05de\u05b7\u05df  aph., Dan 6:24(Dan 6:23). \u05e9\u05c1\u05b8\u05de\u05b7\u05e2 , Jer 25:8. N.T., Mat 8:13; Mat 18:6; Mar 1:15; Mar 11:23; Luc 1:20; Luc 20:5; Luc 24:25; Jua 1:12; Jua 2:22; Jua 5:38; Jua 8:24; Jua 11:26; Jua 14:11; Hch 4:4; Hch 9:26; Hch 11:17; Hch 15:11; Hch 19:2; Rom 4:3; Rom 4:18; Rom 6:8; Rom 9:33; Rom 14:2; 1Co 9:17; 1Co 13:7; G\u00e1l 2:7; G\u00e1l 3:22; Efe 1:13; 1Ts 2:4; 1Ts 4:14; 2Ts 1:10; 1Ti 1:16; Tit 1:3; Tit 3:8; Heb 11:6; Stg 2:23; 1Pe 2:7; 1Jn 4:16.<\/p>\n<p>&#8212;-<\/p>\n<p>Diccionario Swanson<\/p>\n<p>(Swanson 4409)<\/p>\n<p>\u03c0\u03b9\u03c3\u03c4\u03b5\u03cd\u03c9 (pisteu\u014d): vb.; \u2261 DBLHebr 586; Strong 4100; TDNT 6.174-1. LN 31.35 considerar cierto, creer, con la implicaci\u00f3n de confianza (Mat 24:23; Luc 1:20; 1Co 11:18; Stg 2:19; Mar 16:13-14 v.l.); 2. LN 31.85 confiar, fe, creer hasta el punto de confiar totalmente (Mat 18:6; Rom 4:3; 1Pe 2:6; Mar 16:17 v.l.); 3. LN 31.102 tener la fe cristiana, hacerse creyente del Evangelio (Hch 4:32; Rom 1:16; Mar 16:16 v.l.); 4. LN 35.50 confiar, poner algo bajo el cuidado de otro (Rom 3:2; G\u00e1l 2:7; 1Ts 2:4; 1Ti 1:11; Tit 1:3) <\/p>\n<p>&#8212;-<\/p>\n<p>Diccionario Vine NT<\/p>\n<p>pisteuo (\u03c0\u03b9\u03c3\u03c4\u03b5\u03cd\u03c9, G4100), confiar; o, en la voz pasiva, serle encomendado. Se traduce as\u00ed en Luc 16:11; en 1Ti 1:11 y en Tit 1:3 se traduce con el verbo \u00abencomendar\u00bb. V\u00e9anse CREER, CREYENTE, ENCOMENDAR, FIAR.<\/p>\n<p>Nota: El nombre pepoithesis se traduce en Flp 3:4 como verbo, \u00abde qu\u00e9 confiar\u00bb (VHA: \u00abyo ten\u00eda confianza\u00bb). V\u00e9ase B, N\u00ba 1. <\/p>\n<p>pisteuo (\u03c0\u03b9\u03c3\u03c4\u03b5\u03cd\u03c9, G4100), creer. Se traduce \u00abse fiaba\u00bb en Jua 2:24; v\u00e9ase CREER, y tambi\u00e9n CONFIAR, ENCOMENDAR. <\/p>\n<p>pisteuo (\u03c0\u03b9\u03c3\u03c4\u03b5\u03cd\u03c9, G4100), significa confiar, encomendar a (Luc 16:11 : \u00abconfiar\u00e1\u00bb; 1Ti 1:11 : \u00abme fue encomendada\u00bb); v\u00e9anse CONFIAR, CREER, etc.<\/p>\n<p>pisteuo (\u03c0\u03b9\u03c3\u03c4\u03b5\u03c5\u03c9, G4100), creer, tambi\u00e9n ser persuadido de, y por ello fiarse de, confiar. Significa, en este sentido de la palabra, apoyarse en, no una mera creencia. Se halla con gran frecuencia en los escritos del ap\u00f3stol Juan, especialmente en su Evangelio. No usa el nombre (v\u00e9anse pistis, en FE). En cuanto a la primera utilizaci\u00f3n del verbo, v\u00e9ase Jua 1:50. De los escritores de los Evangelios, Mateo usa el verbo en diez ocasiones, Marcos diez, Lucas nueve, Juan noventa y nueve. En Hch 5:14 se traduce el participio presente del verbo como \u00abcreyentes\u00bb. V\u00e9anse CONFIAR, CREYENTE, ENCOMENDAR, FIAR.<\/p>\n<p>Fuente: Varios Autores<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diccionario Strong \u03c0\u03b9\u03c3\u03c4\u03b5\u03cd\u03c9 piste\u00fao de G4102; tener fe (en, o con respecto a, persona o cosa), i.e. cr\u00e9dito; por implicaci\u00f3n confiar (espec\u00edficamente a Cristo el bienestar espiritual de uno): encomendar, fiar, guardar, confiar, creer, creyente. &#8212;- Diccionario Tuggy \u03c0\u03b9\u03c3\u03c4\u03b5\u03cd\u03c9.(imperf. \u1f10\u03c0\u03af\u03c3\u03c4\u03b5\u03c5\u03bf\u03bd; tiempo futuro \u03c0\u03b9\u03c3\u03c4\u03b5\u03cd\u03c3\u03c9; 1 tiempo aoristo \u1f10\u03c0\u03af\u03c3\u03c4\u03b5\u03c5\u03c3\u03b1; 1 tiempo aoristo voz pasiva \u1f10\u03c0\u03b9\u03c3\u03c4\u03b5\u03cd\u03b8\u03b7\u03bd; tiempo perfecto &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/g4100\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abG4100\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31731","post","type-post","status-publish","format-standard","hentry","category-enciclopedia"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/31731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=31731"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/31731\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=31731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=31731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=31731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}