{"id":3316,"date":"2016-02-04T23:48:00","date_gmt":"2016-02-05T04:48:00","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/nefeg\/"},"modified":"2016-02-04T23:48:00","modified_gmt":"2016-02-05T04:48:00","slug":"nefeg","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/nefeg\/","title":{"rendered":"NEFEG"},"content":{"rendered":"<p>Nefeg    (heb. Nefeg, tal vez \u00abrenuevo\u00bb o \u00abperezoso\u00bb).  1.  Levita coatita de la casa de Izar y hermano del rebelde Cor\u00e9 (Exo 6:21; cf Num 16:1).  2.  Hijo de David que naci\u00f3 en Jerusal\u00e9n (2Sa 5:15; 1Ch 3:7; 14:6).<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Evang\u00e9lico<\/b><\/p>\n<p>(brote, reto\u00f1o).<br \/>\n1.  Un hijo de Izjar (Exo 6:21).<br \/>\n2.  Un hijo de David (2 Samuel 5:15: 1Ch 3:7; 1Ch 14:6).<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Mundo Hispano<\/b><\/p>\n<p>(Jactancioso). Nombre de personas del AT.<\/p>\n<p>1.     Personaje en la descendencia de Lev\u00ed\u00ad. Era hijo de Izhar (Exo 6:21).<\/p>\n<p>.     Hijo de David. Uno \u2020\u0153de los que le nacieron en Jerusal\u00e9n\u2020\u009d (2Sa 5:15; 1Cr 3:7; 1Cr 14:6).<\/p>\n<p><b>Fuente: Diccionario de la Biblia Cristiano<\/b><\/p>\n<p>1. Hijo de Izhar y hermano de Cor\u00e9 y Zicr\u00ed\u00ad. Pertenec\u00ed\u00ada a la tribu de Lev\u00ed\u00ad, y era primo de Mois\u00e9s y Aar\u00f3n. (Ex 6:16, 18, 20, 21.)<\/p>\n<p>2. Uno de los hijos que le nacieron al rey David en Jerusal\u00e9n. (2Sa 5:13-15; 1Cr 3:5, 7; 14:3-6.)<\/p>\n<p><b>Fuente: Diccionario de la Biblia<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nefeg (heb. Nefeg, tal vez \u00abrenuevo\u00bb o \u00abperezoso\u00bb). 1. Levita coatita de la casa de Izar y hermano del rebelde Cor\u00e9 (Exo 6:21; cf Num 16:1). 2. Hijo de David que naci\u00f3 en Jerusal\u00e9n (2Sa 5:15; 1Ch 3:7; 14:6). Fuente: Diccionario B\u00edblico Evang\u00e9lico (brote, reto\u00f1o). 1. Un hijo de Izjar (Exo 6:21). 2. Un hijo &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/nefeg\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abNEFEG\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3316","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/3316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=3316"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/3316\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=3316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=3316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=3316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}