{"id":34397,"date":"2016-09-30T03:28:35","date_gmt":"2016-09-30T08:28:35","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/g926\/"},"modified":"2016-09-30T03:28:35","modified_gmt":"2016-09-30T08:28:35","slug":"g926","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/g926\/","title":{"rendered":"G926"},"content":{"rendered":"<p>Diccionario Strong<\/p>\n<p>\u03b2\u03b1\u03c1\u03cd\u03c2<\/p>\n<p>bar\u00fas<\/p>\n<p>de lo mismo que G922; pesado, i.e. (fig) cargoso, grave: grave, gravoso, lo m\u00e1s importante, duro, pesado, rapaz.<\/p>\n<p>&#8212;-<\/p>\n<p>Diccionario Tuggy<\/p>\n<p>\u03b2\u03b1\u03c1\u03cd\u03c2, \u03b5\u1fd6\u03b1, \u03cd. Pesado, dif\u00edcil, duro, de peso, abrumado, feroz, severo. A.T. \u05d9\u05b7\u05e7\u05bc\u05b4\u05d9\u05e8 , Dan 2:11. \u05db\u05bc\u05b8\u05d1\u05b5\u05d3  \u00c9xo 17:12. \u05db\u05bc\u05b9\u05d1\u05b6\u05d3 , Pro 27:3. \u05db\u05bc\u05b8\u05d1\u05b5\u05d3  qal. Jue 20:34. \u05db\u05bc\u05b8\u05d1\u05b5\u05d3  hi., 2Cr 25:19. \u05db\u05bc\u05b7\u05d1\u05bc\u05b4\u05d9\u05e8 , Job 15:10. \u05e2\u05b8\u05e6\u05d5\u05bc\u05dd , Sal 34:18(Sal 35:18). \u05e8\u05b8\u05e2\u05b7\u05e2 , G\u00e9n 48:17. N.T. <\/p>\n<p>A) literal    Pesado : Mat 23:4. <\/p>\n<p>B) figurativo     <\/p>\n<p>1) Duro, dif\u00edcil de cumplir : 2Co 10:10; 1Jn 5:3. <\/p>\n<p>2) Cruel, feroz : Hch 20:29. <\/p>\n<p>3) De peso, importante, grave : Mat 23:23; Hch 25:7.<\/p>\n<p>&#8212;-<\/p>\n<p>Diccionario Swanson<\/p>\n<p>(Swanson 987)<\/p>\n<p>\u03b2\u03b1\u03c1\u03cd\u03c2 (barys), \u03b5\u1fd6\u03b1 (eia), \u03cd (y): adj.; \u2261 DBLHebr 3877, 3878; Strong 926; TDNT 1.556-1. LN 86.1 pesado, de gran peso (Mat 23:4; Hch 25:7; 2Co 10:10+); 2. LN 22.30 gravoso, preocupante, dificultoso (1Jn 5:3+); 3. LN 65.55 importante (Mat 23:23+); 4. LN 20.7 rapaz, salvaje (Hch 20:29+) <\/p>\n<p>&#8212;-<\/p>\n<p>Diccionario Vine NT<\/p>\n<p>barus (\u03b2\u03b1\u03c1\u03cd\u03c2, G926), denota pesado, gravoso. En el NT se usa siempre metaf\u00f3ricamente. Se traduce \u00abpesadas\u00bb en Mat 23:4, de las ordenanzas de los fariseos; con el grado comparativo: \u00ablo m\u00e1s importante\u00bb (Mat 23:23), de los detalles de la ley de Dios; \u00abrapaces\u00bb, metaf\u00f3rica mente, de lobos (Hch 20:29); de acusaciones: \u00abgraves\u00bb; negativamente, de los mandamientos de Dios ( 1Jn 5:3 : \u00abno son gravosos\u00bb para el que los cumple); en 2Co 10:10 : \u00abduras\u00bb, de las cartas de Pablo. V\u00e9anse DURO, GRAVOSO, IMPORTANTE, PESADO, RAPAZ.\u00b6 <\/p>\n<p>barus (\u03b2\u03b1\u03c1\u03cd\u03c2, G926), pesado. Se traduce as\u00ed en Mat 23:4 : \u00abcargas pesadas\u00bb. V\u00e9ase GRAVE, y tambi\u00e9n DURO bajo DUREZA, B, N\u00ba 2, etc. <\/p>\n<p>barus (\u03b2\u03b1\u03c1\u03cd\u03c2, G926), denota pesado, gravoso. Se utiliza en sentido metaf\u00f3rico, de lobos \u00abrapaces\u00bb (Hch 20:29). V\u00e9ase GRAVE, y tambi\u00e9n DURO, GRAVOSO, IMPORTANTE, PENOSO, PESADO.\u00b6<\/p>\n<p>barus (\u03b2\u03b1\u03c1\u03cd\u03c2, G926), pesado; relacionado con bareo, cargar, y baros, carga. Significa pesado, y as\u00ed se traduce en Mat 23:4 : \u00abcargas pesadas\u00bb. En Mat 23:23 se usa en grado comparativo en plural neutro: \u00ablo m\u00e1s importante de la ley\u00bb. V\u00e9anse DURO, GRAVE, PESADO, RAPAZ . <\/p>\n<p>barus (\u03b2\u03b1\u03c1\u03cd\u03c2, G926), pesado. Se traduce \u00abduras\u00bb en 2Co 10:10, de las cartas de Pablo. V\u00e9anse GRAVE, GRAVOSO, IMPORTANTE, PESADO, RAPAZ.<\/p>\n<p>barus (\u03b2\u03b1\u03c1\u03cd\u03c2, G926), v\u00e9ase GRAVE. Se traduce \u00abpenosos\u00bb, en sentido negativo, de los mandamientos del Se\u00f1or ( 1Jn 5:3; RV: \u00absus mandamientos no son penosos\u00bb; RVR: \u00abgravosos\u00bb). V\u00e9anse GRAVOSO, A, N\u00ba 2, DURO, IMPORTANTE, PESADO, RAPAZ.<\/p>\n<p>Fuente: Varios Autores<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diccionario Strong \u03b2\u03b1\u03c1\u03cd\u03c2 bar\u00fas de lo mismo que G922; pesado, i.e. (fig) cargoso, grave: grave, gravoso, lo m\u00e1s importante, duro, pesado, rapaz. &#8212;- Diccionario Tuggy \u03b2\u03b1\u03c1\u03cd\u03c2, \u03b5\u1fd6\u03b1, \u03cd. Pesado, dif\u00edcil, duro, de peso, abrumado, feroz, severo. A.T. \u05d9\u05b7\u05e7\u05bc\u05b4\u05d9\u05e8 , Dan 2:11. \u05db\u05bc\u05b8\u05d1\u05b5\u05d3 \u00c9xo 17:12. \u05db\u05bc\u05b9\u05d1\u05b6\u05d3 , Pro 27:3. \u05db\u05bc\u05b8\u05d1\u05b5\u05d3 qal. Jue 20:34. \u05db\u05bc\u05b8\u05d1\u05b5\u05d3 hi., 2Cr &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/g926\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abG926\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-34397","post","type-post","status-publish","format-standard","hentry","category-enciclopedia"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/34397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=34397"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/34397\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=34397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=34397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=34397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}