{"id":40456,"date":"2016-09-30T03:53:53","date_gmt":"2016-09-30T08:53:53","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/h5475\/"},"modified":"2016-09-30T03:53:53","modified_gmt":"2016-09-30T08:53:53","slug":"h5475","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/h5475\/","title":{"rendered":"H5475"},"content":{"rendered":"<p>Diccionario Strong<\/p>\n<p>\u05e1\u05d5\u05d9\u05d3<\/p>\n<p>sod<\/p>\n<p>de H3245; sesi\u00f3n, i.e. compa\u00f1\u00eda de personas (en deliberaci\u00f3n estrecha); por impl. intimidad, consulta, secreto: compa\u00f1\u00eda, comunicar, comuni\u00f3n, congregaci\u00f3n, consejo, consultar, entrar, favor, \u00edntimo, reuni\u00f3n, (consejo) secreto.<\/p>\n<p>&#8212;-<\/p>\n<p>Diccionario Ch\u00e1vez<\/p>\n<p>\u05e1\u05d5\u05b9\u05d3<\/p>\n<p>1) Secreto, conversaci\u00f3n \u00edntima (Am\u00f3 3:7; Sal. 55:15\/Sal 55:14).<\/p>\n<p>2) Consejo formado por un grupo de confidentes (G\u00e9n 49:6). \u2014 Suf. \u05e1\u05d5\u05b9\u05d3\u05d5\u05b9, \u05e1\u05b9\u05d3\u05b8\u05dd.<\/p>\n<p>&#8212;-<\/p>\n<p>Diccionario Vine AT<\/p>\n<p>s\u00f4d (\u05e1\u05d5\u05d9\u05d3, H5475), \u00abplanes secretos o confidenciales; comunicaci\u00f3n secreta o confidencial, consejo, secreto; reuni\u00f3n; c\u00edrculo\u00bb. Este sustantivo aparece 21 veces en hebreo b\u00edblico.<\/p>\n<p>En primer lugar, S\u00f4d quiere decir \u00abcomunicaci\u00f3n confidencial\u00bb: \u00abEsc\u00f3ndeme del consejo secreto de los malhechores\u00bb (Sal 64:2 RVA). En Pro 15:22 el vocablo se refiere a planes que se hacen en privado antes de cont\u00e1rselos a otros: \u00abLos pensamientos son frustrados [\u00abfracasan\u00bb NVI] donde no hay consejo; mas en la multitud de consejeros se afirman [\u00abprosperan\u00bb NVI]\u00bb. A veces el t\u00e9rmino solo se refiere a algo dicho que deber\u00eda haberse mantenido en confidencia: \u00abDiscute tu causa con tu pr\u00f3jimo y no des a conocer el secreto de otro\u00bb (Pro 25:9 RVA).<\/p>\n<p>En segundo lugar,el vocablo representa un grupo de amigos \u00edntimos con los que se comparte un asunto confidencial: \u00abEn su consejo no entre mi alma,[de Sime\u00f3n y Lev\u00ed] ni mi esp\u00edritu se junte en su compa\u00f1\u00eda\u00bb (G\u00e9n 49:6 : primera aparici\u00f3n del vocablo). Jer 6:11 habla de la \u00abreuni\u00f3n de los j\u00f3venes [informal pero que comparten asuntos confidenciales] igualmente\u00bb. Y \u00abJuntos comunic\u00e1bamos dulcemente los secretos\u00bb es estar en un grupo donde todos comparten y se regocijan en lo que se hace y\/o se discute (Sal 55:14).<\/p>\n<p>Fuente: Varios Autores<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diccionario Strong \u05e1\u05d5\u05d9\u05d3 sod de H3245; sesi\u00f3n, i.e. compa\u00f1\u00eda de personas (en deliberaci\u00f3n estrecha); por impl. intimidad, consulta, secreto: compa\u00f1\u00eda, comunicar, comuni\u00f3n, congregaci\u00f3n, consejo, consultar, entrar, favor, \u00edntimo, reuni\u00f3n, (consejo) secreto. &#8212;- Diccionario Ch\u00e1vez \u05e1\u05d5\u05b9\u05d3 1) Secreto, conversaci\u00f3n \u00edntima (Am\u00f3 3:7; Sal. 55:15\/Sal 55:14). 2) Consejo formado por un grupo de confidentes (G\u00e9n 49:6). \u2014 &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/h5475\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abH5475\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-40456","post","type-post","status-publish","format-standard","hentry","category-enciclopedia"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/40456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=40456"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/40456\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=40456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=40456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=40456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}