{"id":40609,"date":"2016-09-30T03:54:46","date_gmt":"2016-09-30T08:54:46","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/h5612\/"},"modified":"2016-09-30T03:54:46","modified_gmt":"2016-09-30T08:54:46","slug":"h5612","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/h5612\/","title":{"rendered":"H5612"},"content":{"rendered":"<p>Diccionario Strong<\/p>\n<p>\u05e1\u05b5\u05e4\u05b6\u05e8<\/p>\n<p>s\u00e9fer<\/p>\n<p>o (femenino) \u05e1\u05b4\u05e4\u05b0\u05e8\u05b8\u05d4 sifr\u00e1 (Sal 56:8 [9]); de H5608; propiamente escrito (el arte o documento); por impl. libro: carta, libro.<\/p>\n<p>&#8212;-<\/p>\n<p>Diccionario Ch\u00e1vez<\/p>\n<p>\u05e1\u05b5\u05e4\u05b6\u05e8<\/p>\n<p>1) Pergamino, l\u00e1mina de piel preparada para escribir en ella (Jer 36:2; Sal. 40:8\/Sal 40:7).<\/p>\n<p>2) Carta (2Sa 11:14).<\/p>\n<p>3) Libro:<\/p>\n<p>s\u00e9fer jaz\u00f3n Nah\u00fam = libro de la visi\u00f3n de Nah\u00fam (Nah 1:1). \u2014 yod\u00e9a ha-s\u00e9fer = conocedor del libro, es decir, que sabe leer (Isa 29:11). \u2014 Suf. \u05e1\u05b4\u05e4\u05b0\u05e8\u05b0\u05da\u05b8, \u05e1\u05b4\u05e4\u05b0\u05e8\u05b4\u05d9; Pl. \u05e1\u05b0\u05e4\u05b8\u05e8\u05b4\u05d9\u05dd.<\/p>\n<p>&#8212;-<\/p>\n<p>Diccionario Vine AT<\/p>\n<p>seper (\u05e1\u05b5\u05e4\u05b6\u05e8, H5612), \u00ablibro; tablilla\u00bb. Este nombre se encuentra en ac\u00e1dico, fenicio y arameo (incluyendo en la Biblia) y en todos los per\u00edodos del hebreo b\u00edblico. Aparece 187 veces en el Antiguo Testamento. Se refiere b\u00e1sicamente a un objeto sobre el que se escribe alguna informaci\u00f3n. As\u00ed, en \u00c9xo 17:14, \u00abJehovah dijo a Mois\u00e9s: \u00abEscribe esto en un libro como memorial\u00bb\u00bb (RVA). En Isa 30:8 seper representa una tabla. En G\u00e9n 5:1 (primer caso b\u00edblico del vocablo) quiere decir un objeto (tal vez una tablilla) sobre el que se ha registrado algo: \u00abEste es el libro de las generaciones de Ad\u00e1n\u00bb. Este documento escrito puede ser un resumen de la Ley divina (\u00c9xo 24:7). Durante la monarqu\u00eda, seper adquiri\u00f3 la acepci\u00f3n de \u00abcarta\u00bb (2Sa 11:14). M\u00e1s adelante significar\u00eda un decreto escrito por un rey para distribuirse en todo su imperio (Est 1:22). Por regla general, el vocablo significa \u00ablibro\u00bb (\u00c9xo 32:32), o sea, un registro completo de cualquier informaci\u00f3n que se desea preservar con exactitud. A menudo, el t\u00e9rmino puede referirse a la manera en que un pueblo escribe, a su lengua escrita o caracteres (Isa 29:11). <\/p>\n<p>seper (\u05e1\u05b6\u05e4\u05b6\u05e8, H5612), \u00ablibro; documento; escritura\u00bb. Seper parece ser prestado del t\u00e9rmino ac\u00e1dico sipru (\u00abmensaje escrito, documento\u00bb). El vocablo aparece 187 veces en el Antiguo Testamento hebreo, y el primer caso est\u00e1 en G\u00e9n 5:1 : \u00abEste es el libro de los descendientes de Ad\u00e1n: Cuando Dios cre\u00f3 al hombre, lo hizo a semejanza de Dios\u00bb (RVA). A excepci\u00f3n de Deuteronomio (11 veces), hay muy pocos ejemplos del t\u00e9rmino en el Pentateuco. Es m\u00e1s frecuente en los libros hist\u00f3ricos tard\u00edos (Reyes 60 veces, pero en Cr\u00f3nicas 24 veces; cf. Ester 11 veces y Nehem\u00edas 9 veces).<\/p>\n<p>La traducci\u00f3n m\u00e1s com\u00fan de seper es \u00ablibro\u00bb. Un manuscrito se escribe (\u00c9xo 32:32; Deu 17:18) y se sella (Isa 29:11) para que lo lea el destinatario (2Re 22:16). El sentido de seper es semejante al de \u00abrollo o pergamino\u00bb (megillah): \u00abEntra t\u00fa pues, y lee de este rollo que escribiste de mi boca, las palabras de Jehov\u00e1 a los o\u00eddos del pueblo, en la casa de Jehov\u00e1, el d\u00eda del ayuno; y las leer\u00e1s tambi\u00e9n a o\u00eddos de todos los de Jud\u00e1 que vienen de sus ciudades\u00bb (Jer 36:6). Seper est\u00e1 tambi\u00e9n estrechamente relacionado con sipra (\u00ablibro\u00bb; Sal 56:8).<\/p>\n<p>Se mencionan muchos \u00ablibros\u00bb en el Antiguo Testamento: el \u00ablibro\u00bb de memorias (Mal 3:16), \u00ablibro\u00bb de la vida (Sal 69:28), \u00ablibro\u00bb de Jaser (Jos 10:13), \u00ablibro\u00bb de las generaciones (G\u00e9n 5:1),\u00ablibro\u00bb del Se\u00f1or, \u00ablibro\u00bb de las cr\u00f3nicas de los reyes de Israel y Jud\u00e1, y las anotaciones del \u00ablibro\u00bb de los reyes (2Cr 24:27). Los profetas escribieron \u00ablibros\u00bb mientras vivieron. La profec\u00eda de Nahum comienza con la siguiente introducci\u00f3n: \u00abLa profec\u00eda acerca de N\u00ednive. Libro de la visi\u00f3n de Nah\u00fam, de Elc\u00f3s\u00bb (2Cr 1:1 RVA).<\/p>\n<p>Jerem\u00edas escribi\u00f3 varios \u00ablibros\u00bb adem\u00e1s de su carta a los cautivos. Escribi\u00f3 un libro sobre los desastres que caer\u00edan sobre Jerusal\u00e9n, pero el \u00ablibro\u00bb lo destruy\u00f3 el rey Joacim (Jerem\u00edas 36). En este contexto aprendemos algo del proceso de escribir un \u00ablibro\u00bb. Jerem\u00edas dict\u00f3 a Baruc, quien escribi\u00f3 con tinta sobre el rollo (2Cr 36:18). Baruc llev\u00f3 el libro a los jud\u00edos que fueron al templo a ayunar. Cuando confiscaron y quemaron el \u00ablibro\u00bb, Jerem\u00edas escribi\u00f3 en otro rollo un \u00ablibro\u00bb con una fuerte condenaci\u00f3n a Joacim y su familia: \u00abEntonces Jerem\u00edas tom\u00f3 otro rollo y lo dio al escriba Baruc hijo de Ner\u00edas. Este escribi\u00f3 en \u00e9l, al dictado de Jerem\u00edas, todas las cosas del libro que Joacim rey de Jud\u00e1 hab\u00eda quemado en el fuego; y adem\u00e1s, fueron a\u00f1adidas muchas otras palabras semejantes\u00bb (Jer 36:32).<\/p>\n<p>Ezequiel recibi\u00f3 la orden de comer un \u00ablibro\u00bb (Eze 2:8; Eze 3:1) como un acto simb\u00f3lico del juicio de Dios sobre Jud\u00e1 y su restauraci\u00f3n.<\/p>\n<p>Seper puede tambi\u00e9n significar \u00abcarta\u00bb. El profeta Jerem\u00edas escribi\u00f3 una carta a los cautivos en Babilonia, indicando que deb\u00edan acomodarse, pues permanecer\u00edan all\u00ed 70 a\u00f1os: \u00abEstas son las palabras de la carta que el profeta Jerem\u00edas envi\u00f3 de Jerusal\u00e9n al resto de los ancianos de la cautividad, a los sacerdotes, a los profetas y a todo el pueblo, que Nabucodonosor hab\u00eda llevado cautivo de Jerusal\u00e9n a Babilonia\u00bb (Jer 29:1 RVA).<\/p>\n<p>Es variado el contenido de un seper. Podr\u00eda contener una orden escrita, una comisi\u00f3n, una solicitud o un decreto, como en la siguiente cita: \u00abMardoqueo escribi\u00f3 las cartas [seper] en el nombre del rey Asuero, las sell\u00f3 con el anillo del rey y las envi\u00f3 por medio de mensajeros a caballo, que cabalgaban los veloces corceles de las caballerizas reales\u00bb (Est 8:10 RVA). Si divorciaba a su mujer, un hombre le presentaba un documento legal conocido como seper de divorcio (Deu 24:1). Aqu\u00ed seper significa \u00abcertificado\u00bbo \u00abdocumento legal\u00bb.A algunos otros documentos legales tambi\u00e9n se les podria llamar seper. Como documento legal, el seper pod\u00eda publicarse o bien esconderse hasta un tiempo m\u00e1s apropiado: \u00abAs\u00ed ha dicho Jehov\u00e1 de los Ej\u00e9rcitos, Dios de Israel: Toma estos documentos (el documento de compra sellado y la copia abierta), y ponlos en una vasija de cer\u00e1mica para que se conserven por mucho tiempo\u00bb (Jer 32:14 RVA).<\/p>\n<p>La Septuaginta ofrece las siguientes traducciones: biblion (\u00abrollo\u00bb) y gramma (\u00abcarta; documento; escritura; libro\u00bb).<\/p>\n<p>Fuente: Varios Autores<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diccionario Strong \u05e1\u05b5\u05e4\u05b6\u05e8 s\u00e9fer o (femenino) \u05e1\u05b4\u05e4\u05b0\u05e8\u05b8\u05d4 sifr\u00e1 (Sal 56:8 [9]); de H5608; propiamente escrito (el arte o documento); por impl. libro: carta, libro. &#8212;- Diccionario Ch\u00e1vez \u05e1\u05b5\u05e4\u05b6\u05e8 1) Pergamino, l\u00e1mina de piel preparada para escribir en ella (Jer 36:2; Sal. 40:8\/Sal 40:7). 2) Carta (2Sa 11:14). 3) Libro: s\u00e9fer jaz\u00f3n Nah\u00fam = libro de &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/h5612\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abH5612\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-40609","post","type-post","status-publish","format-standard","hentry","category-enciclopedia"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/40609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=40609"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/40609\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=40609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=40609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=40609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}