{"id":4506,"date":"2016-02-05T00:28:55","date_gmt":"2016-02-05T05:28:55","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/zohar\/"},"modified":"2016-02-05T00:28:55","modified_gmt":"2016-02-05T05:28:55","slug":"zohar","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/zohar\/","title":{"rendered":"ZOHAR"},"content":{"rendered":"<p>Zohar    (heb.  Tsojar, \u00abrojo amarillento\u00bb o \u00abblancura\u00bb; nombre que tambi\u00e9n aparece el algunas inscripciones sudar.).  1.  Heteo cuyo hijo Efr\u00f3n le vendi\u00f3 a Abrah\u00e1n la cueva de Macpela (Gen 23:8; 25:8, 9).  2.  Hijo de Sime\u00f3n y antepasado de una familia tribal (Gen 46:10; Exo 6:15).  El nombre Zera que aparece en Num 26:13 y 1Ch 4:24 aparentemente es el de la misma persona que en los otros pasajes figura como Zohar; la diferencia de escritura se deber\u00ed\u00ada a la transposici\u00f3n del equivalente espa\u00f1ol de las letras hebreas j y r. V\u00e9ase Zera 4.<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Evang\u00e9lico<\/b><\/p>\n<p>1.  Un hitita noble, padre de Efr\u00f3n, a quien Abraham compr\u00f3 el campo de Macpela donde sepult\u00f3 en una cueva el cuerpo de Sara (Gen 23:8; Gen 25:9).<br \/>\n2.  Un hijo de Sime\u00f3n (Gen 46:10; Exo 6:15). Tambi\u00e9n es llamado S\u00e9raj (Num 26:13; 1Ch 4:24).<br \/>\n3.  Un hombre de Jud\u00e1 (1Ch 4:7).<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Mundo Hispano<\/b><\/p>\n<p>Nombre de personas del AT.<\/p>\n<p>1.     Personaje heteo. Padre de \u2020\u00a2Efr\u00f3n, el que vendi\u00f3 a Abraham la heredad de Macpela (Gen 23:8).<\/p>\n<p>.     Uno de los hijos de Sime\u00f3n (Gen 46:10; Exo 6:15). = \u2020\u00a2Zera (Num 26:13).<\/p>\n<p><b>Fuente: Diccionario de la Biblia Cristiano<\/b><\/p>\n<p>tip, BIOG HOMB HOAT<\/p>\n<p>ver, ZERA<\/p>\n<p>vet, (a) Padre de Efr\u00e9n heteo (Gn. 33:8.) (b) Hijo de Sime\u00f3n (Gn. 46:10). Llamado Zera en Nm. 26:13. (V\u00e9ase ZERA, c.)<\/p>\n<p><b>Fuente: Nuevo Diccionario B\u00edblico Ilustrado<\/b><\/p>\n<p>1. Hitita cuyo hijo, Efr\u00f3n, vendi\u00f3 a Abrah\u00e1n la cueva de Macpel\u00e1. (G\u00e9 23:7-9; 25:9.)<\/p>\n<p>2. Quinto hijo de Sime\u00f3n mencionado por nombre y fundador de una familia de su tribu; figuraba entre los 70 miembros de la casa de Jacob que \u2020\u0153entraron en Egipto\u2020\u009d. (G\u00e9 46:8, 10, 27; Ex 6:15.) Otras referencias a \u00e9l lo llaman Z\u00e9rah. (N\u00fa 26:13; 1Cr 4:24.)<\/p>\n<p><b>Fuente: Diccionario de la Biblia<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zohar (heb. Tsojar, \u00abrojo amarillento\u00bb o \u00abblancura\u00bb; nombre que tambi\u00e9n aparece el algunas inscripciones sudar.). 1. Heteo cuyo hijo Efr\u00f3n le vendi\u00f3 a Abrah\u00e1n la cueva de Macpela (Gen 23:8; 25:8, 9). 2. Hijo de Sime\u00f3n y antepasado de una familia tribal (Gen 46:10; Exo 6:15). El nombre Zera que aparece en Num 26:13 y &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/zohar\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abZOHAR\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4506","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/4506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=4506"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/4506\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=4506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=4506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=4506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}