{"id":4514,"date":"2016-02-05T00:29:36","date_gmt":"2016-02-05T05:29:36","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/zorro\/"},"modified":"2016-02-05T00:29:36","modified_gmt":"2016-02-05T05:29:36","slug":"zorro","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/zorro\/","title":{"rendered":"ZORRO"},"content":{"rendered":"<p>Zorro\/a    (heb. sh\u00fb&#8217;\u00e2l; gr. alop&#8217;x).  La palabra hebrea parece referirse claramente al chacal,* como por ejemplo en Jdg 15:4, de donde se puede inferir que los animales que caz\u00f3 Sans\u00f3n corr\u00ed\u00adan en grupos.  Los chacales, a diferencia de las zorras, a menudo andan en manada, y a Sans\u00f3n sin duda le habr\u00e1 costado mucho menos cazar 300 chacales que 300 zorras.  En Psa 63: 10 la RVR ha traducido correctamente la palabra hebrea por chacales, ya que las zorras no se alimentan de carro\u00f1a.  La descripci\u00f3n de animales que vagan por el desierto o en medio de las ruinas, y que destruyen las vi\u00f1as (Lam 5:18; Eze 13:4; Son 2:15), se podr\u00ed\u00ada aplicar tanto a zorras como a chacales.  En Palestina hay 2 clases de zorros: una variedad peque\u00f1a en el sur y una variedad m\u00e1s grande en el norte. Jes\u00fas mencion\u00f3 las guaridas de las zorras (Mat 8:20; Luk 9:59) y compar\u00f3 a Herodes Antipas con una astuta zorra (Luk 13:32).<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Evang\u00e9lico<\/b><\/p>\n<p>g\u00e9nero de mam\u00ed\u00adferos carniceros, de la familia de los c\u00e1nidos, de extremidades cortas, orejas empinadas, pelaje pardorrojizo y vientre grisoso,  cola peluda, cabeza ancha, hocico puntiagudo. Es depredadora, se alimenta de frutas, Ct 2, 15, aves y peque\u00f1os mam\u00ed\u00adferos. Habita en guaridas, Mt 8,  20; Lc 9, 58; merodea en lugares desolados, Lm 5, 18. Sans\u00f3n para abrasar las mieses de los filisteos, se vali\u00f3 de trescientas zorras Jc 15, 4-5. La z. por su astucia es mencionada en la Escritura figuradamente y as\u00ed\u00ad Cristo llama zorro a Herodes Antipas Lc 13, 32; es posible que en la Biblia se confunda con el chacal, Ez 13, 4, o tambi\u00e9n el c\u00e1nido.<\/p>\n<p>Diccionario B\u00ed\u00adblico Digital, Grupo C Service &#038; Design Ltda., Colombia, 2003<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Digital<\/b><\/p>\n<p>ver ANIMALES<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Mundo Hispano<\/b><\/p>\n<p>[911]<br \/>\n   Animal de la especie de los c\u00e1nidos y del g\u00e9nero vulpes. Simb\u00f3licamente alude al hombre que disimula su situaci\u00f3n para obtener ventaja, que enga\u00f1a con astucia o que simula necesidad con doblez con m\u00e1s o menos habilidad y eficacia.<\/p>\n<p>    Con todo, esta interpretaci\u00f3n, como todas las zoom\u00f3rficas, han variado con el tiempo. En las citas b\u00ed\u00adblicas en que se alude a esta especie el t\u00e9rmino tiene otro sentido. As\u00ed\u00ad, como cuando Jes\u00fas indica respecto de Herodes \u00abDecidle a ese zorro que a\u00fan no es llegado mi tiempo\u00bb (Lc. 13.32), se hace alusi\u00f3n al car\u00e1cter dependiente del rey, que es como \u00abpobre hombre\u00bb, hombre sin poder, al igual de \u00e9l mismo cuando se compara con las \u00abraposas del campo que no tienen d\u00f3nde reclinar la cabeza\u00bb (Mt. 8.20; Lc. 9.58)<\/p>\n<p>Pedro Chico Gonz\u00e1lez, Diccionario de Catequesis y Pedagog\u00ed\u00ada Religiosa, Editorial Bru\u00f1o, Lima, Per\u00fa 2006<\/p>\n<p><b>Fuente: Diccionario de Catequesis y Pedagog\u00eda Religiosa<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zorro\/a (heb. sh\u00fb&#8217;\u00e2l; gr. alop&#8217;x). La palabra hebrea parece referirse claramente al chacal,* como por ejemplo en Jdg 15:4, de donde se puede inferir que los animales que caz\u00f3 Sans\u00f3n corr\u00ed\u00adan en grupos. Los chacales, a diferencia de las zorras, a menudo andan en manada, y a Sans\u00f3n sin duda le habr\u00e1 costado mucho menos &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/zorro\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abZORRO\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4514","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/4514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=4514"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/4514\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=4514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=4514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=4514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}