{"id":4601,"date":"2016-02-05T00:32:37","date_gmt":"2016-02-05T05:32:37","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/ajitofel\/"},"modified":"2016-02-05T00:32:37","modified_gmt":"2016-02-05T05:32:37","slug":"ajitofel","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/ajitofel\/","title":{"rendered":"AJITOFEL"},"content":{"rendered":"<p>de la ciudad de Guil\u00f3, consejero de David 2 S 15, 12. Conspirador que se uni\u00f3 al levantamiento de Absal\u00f3n contra su propio  padre, el rey David, 2 S 15-31. En esta sublevaci\u00f3n A. aconsejaba a Absal\u00f3n 2 S 16, 23. Sin embargo, Absal\u00f3n despreci\u00f3 la idea propuesta por A. para atacar y matar a David, prefiriendo el consejo de Jusay, esp\u00ed\u00ada del rey, por lo cual A. volvi\u00f3 a su ciudad y se ahorc\u00f3 2 S 17.<\/p>\n<p>Diccionario B\u00ed\u00adblico Digital, Grupo C Service &#038; Design Ltda., Colombia, 2003<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Digital<\/b><\/p>\n<p>(heb., \u2020\u2122ahithophel, hermano de necedad). Consejero de David que se sum\u00f3 a la conspiraci\u00f3n de Absal\u00f3n y uno de los principales responsables de la rebeli\u00f3n (2Sa 15:12). Con su proverbial sabidur\u00ed\u00ada (2Sa 16:23) inst\u00f3 a Absal\u00f3n a perseguir a David inmediatamente, hiriendo al rey mientras todav\u00ed\u00ada estaba cansado y desprotegido. Ajitofel, al ver rechazado su consejo en favor del de Husai, supo que la de Absal\u00f3n era una causa perdida; se fue a su casa y se ahorc\u00f3 (2Sa 17:1-23).<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Mundo Hispano<\/b><\/p>\n<p><p style=\"text-align: justify;\">Ajit\u00f3fel fue un h\u00e1bil y honrado consejero del rey David, qui\u00e9n se uni\u00f3 a la rebeli\u00f3n de Absal\u00f3n. El rey se vio muy afectado por esta deserci\u00f3n. Oyendo que el hombre cuya palabra hab\u00eda confiado como \u201cor\u00e1culo de Dios\u201d estaba aconsejando a su enemigo, el rey or\u00f3 al Se\u00f1or para que \u201ctornara in\u00fatiles los consejos de Ajit\u00f3fel\u201d.\n<\/p>\n<p style=\"text-align: justify;\">Algunos han visto en los Salmos 55(54),13-15 y 41(40),10, reflexiones de David sobre este desleal amigo. Fue con el consejo de Ajit\u00f3fel que Absal\u00f3n tom\u00f3 posesi\u00f3n del harem de su padre, cortando toda esperanza de reconciliaci\u00f3n. Entendiendo la necesidad de en\u00e9rgicas medidas, Ajit\u00f3fel aconsej\u00f3 a Absal\u00f3n para que 12,000 hombres fueran enviados a Jerusal\u00e9n en persecuci\u00f3n del rey, y se ofreci\u00f3 a conducirlos \u00e9l mismo. Jusay un amigo secreto de David, anul\u00f3 este prop\u00f3sito. Acto seguido, Ajit\u00f3fel se retir\u00f3 orgullosamente a su ciudad de Guil\u00f3, una vez en su casa puso todo en regla y se ahorc\u00f3. (Ver 2 Sam. 15,12; 17,23; 1 Cr\u00f3n. 27,33)   Podr\u00eda parecer por una asociaci\u00f3n de 2 Sam. 23,34 y 11,3, que Ajit\u00f3fel fue el abuelo de Betsab\u00e9, y se ha sugerido, como una explicaci\u00f3n de su conducta hacia David, que \u00e9l guardaba un secreto rencor hacia el rey por la forma como \u00e9l hab\u00eda tratado a Betsab\u00e9 y a su primer esposo, el desafortunado Ur\u00edas. \u00c9ste, u otro motivo de ambici\u00f3n, podr\u00eda estar relacionado con el altanero car\u00e1cter de Ajit\u00f3fel.  John Dryden ha usado este nombre en el t\u00edtulo de su famosa s\u00e1tira contra el partido protestante, \u201cAbsal\u00f3n y Ajit\u00f3fel\u201d.\n<\/p>\n<p style=\"text-align: justify;\">\n<b>Fuente:<\/b>   Reilly, Wendell. \u00abAchitopel.\u00bb The Catholic Encyclopedia. Vol. 1. New York: Robert Appleton Company, 1907.  19 Dec. 2011, <br \/>http:\/\/www.newadvent.org\/cathen\/01102e.htm\n<\/p>\n<p style=\"text-align: justify;\">Traducido por Nydia Isabel Chavarr\u00eda P\u00e9rez de Rayo.  rc\n<\/p>\n<\/p>\n<p><b>Fuente: Enciclopedia Cat\u00f3lica<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>de la ciudad de Guil\u00f3, consejero de David 2 S 15, 12. Conspirador que se uni\u00f3 al levantamiento de Absal\u00f3n contra su propio padre, el rey David, 2 S 15-31. En esta sublevaci\u00f3n A. aconsejaba a Absal\u00f3n 2 S 16, 23. Sin embargo, Absal\u00f3n despreci\u00f3 la idea propuesta por A. para atacar y matar a &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/ajitofel\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abAJITOFEL\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4601","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/4601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=4601"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/4601\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=4601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=4601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=4601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}