{"id":4608,"date":"2016-02-05T00:32:49","date_gmt":"2016-02-05T05:32:49","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/akko\/"},"modified":"2016-02-05T00:32:49","modified_gmt":"2016-02-05T05:32:49","slug":"akko","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/akko\/","title":{"rendered":"AKKO"},"content":{"rendered":"<p>importante ciudad costera fundada ca. 1500 a. C., puerto del Mediterr\u00e1neo, cerca de la bah\u00ed\u00ada de Haifa, considerada la puerta de Tierra Santa, en el norte de Palestina. Ciudad que toc\u00f3 en suerte a la tribu de Aser Jos 19, 24-31, pero que no pudo conquistar Jc 1, 31. Conquistada varias veces, por los faraones Tutmosis III, Rams\u00e9s II, como tambi\u00e9n por Alejandro Magno. En la \u00e9poca hel\u00e9nica, bajo el reinado de Tolomeo II Filadelfo, fue Estado semindependiente con el nombre de Tolemaida, en honor del fara\u00f3n, 261 a. C., nombre que conserv\u00f3 hasta la Edad Media.<\/p>\n<p>Esta ciudad tuvo su protagonismo en tiempo de las luchas de los Macabeos  1 M 5, 15; en Tolemaida muere Jonat\u00e1n 1 M 12, 45-48. San Pablo visit\u00f3 Tolemaida en el tercer viaje apost\u00f3lico Hch 21, 7. En la tercera Cruzada, A. fue conquistada por los cruzados, quienes le dieron el nombre de San Juan de Acre. En 1948, Acre fue tomada por el ej\u00e9rcito de Israel en la guerra contra los \u00e1rabes, y desde 1949 forma parte del Estado jud\u00ed\u00ado.<\/p>\n<p>Diccionario B\u00ed\u00adblico Digital, Grupo C Service &#038; Design Ltda., Colombia, 2003<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Digital<\/b><\/p>\n<p>Ciudad portuaria situada en el extremo N. de la ancha bah\u00ed\u00ada de Akk\u00f3 (o Acre). Esta bah\u00ed\u00ada, que tiene forma de luna creciente, est\u00e1 formada por el promontorio del monte Carmelo, que a unos 13 Km. al S. se adentra en el mar Mediterr\u00e1neo.<br \/>\nDurante el tiempo de los jueces, la ciudad cananea se hallaba sobre un mont\u00ed\u00adculo que se ha identificado con Tell-el-Fujjar (Tel `Akko), situado a m\u00e1s o menos un kil\u00f3metro de la bah\u00ed\u00ada y a casi dos de las antiguas murallas, que se encuentran dentro del t\u00e9rmino de la moderna `Akko. Posteriormente, durante la dominaci\u00f3n persa, a partir del siglo VI a. E.C., la ciudad se extendi\u00f3 hacia el sector occidental del territorio, acerc\u00e1ndose as\u00ed\u00ad a la pen\u00ed\u00adnsula que configura el extremo N. de la bah\u00ed\u00ada, y es tambi\u00e9n en esa \u00e9poca cuando se cre\u00f3 un puerto en este lugar. Para el comienzo de la era cristiana la localidad de Akk\u00f3 tambi\u00e9n comprend\u00ed\u00ada la pen\u00ed\u00adnsula, y as\u00ed\u00ad ha permanecido hasta hoy en la ciudad moderna.<br \/>\nAkk\u00f3 estaba a unos 39 Km. al S. de Tiro, y fue el puerto mar\u00ed\u00adtimo m\u00e1s importante de la costa de Palestina, que contaba con pocos puertos, hasta que Herodes el Grande construy\u00f3 diques desde la orilla para formar un puerto artificial en Cesarea. Aunque Akk\u00f3 no reun\u00ed\u00ada tantas ventajas como los puertos fenicios que hab\u00ed\u00ada al N. y no proporcionaba mucho abrigo de los vientos mar\u00ed\u00adtimos, estaba situada estrat\u00e9gicamente cerca del acceso a la rica llanura de Jezreel (Esdrel\u00f3n), y hab\u00ed\u00ada varias rutas comerciales que conectaban este puerto con Galilea, el valle del Jord\u00e1n y otros puntos del E. Por el puerto de Akk\u00f3 se exportaba madera, as\u00ed\u00ad como art\u00ed\u00adculos art\u00ed\u00adsticos y grano.<br \/>\nAkk\u00f3 pertenec\u00ed\u00ada a la divisi\u00f3n territorial asignada a Aser en la Tierra Prometida, pero esta tribu no expuls\u00f3 a los cananeos que entonces la ocupaban. (Jue 1:31, 32.) Aunque solo se la menciona una vez en las Escrituras Hebreas, en los registros extrab\u00ed\u00adblicos se la nombra con m\u00e1s frecuencia. Su nombre aparece varias veces en las tablillas de el-Amarna. Otros registros muestran que la subyugaron los reyes asirios Senaquerib y Asurbanipal. En los libros ap\u00f3crifos se habla de esta ciudad como un centro de resistencia durante la gobernaci\u00f3n de los macabeos. (1 Macabeos 5:15, 22, 55; 12:45-48; 13:12.) Para entonces su nombre hab\u00ed\u00ada sido cambiado a Tolemaida, un nombre al que dio origen Tolomeo II Filadelfo de Egipto.<br \/>\nBajo el emperador Claudio, la ciudad de Tolemaida (Akk\u00f3) lleg\u00f3 a ser una colonia romana, y en los tiempos apost\u00f3licos hubo en ella un grupo de cristianos. Al regreso de su tercera gira misional, Pablo hizo escala en Akk\u00f3 (ya conocida como Tolemaida) y pas\u00f3 el d\u00ed\u00ada visitando a los hermanos antes de continuar su viaje hacia Cesarea y Jerusal\u00e9n. (Hch 21:7.)<br \/>\nLa moderna ciudad de Haifa, situada justo en el extremo opuesto de la bah\u00ed\u00ada, ha eclipsado la importancia de la actual `Akko.<\/p>\n<p>[Fotograf\u00ed\u00ada en la p\u00e1gina 80]<br \/>\nAkk\u00f3 (m\u00e1s tarde conocida como Tolemaida). El ap\u00f3stol Pablo se detuvo en esta ciudad portuaria en su \u00faltimo viaje a Jerusal\u00e9n<\/p>\n<p><b>Fuente: Diccionario de la Biblia<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>importante ciudad costera fundada ca. 1500 a. C., puerto del Mediterr\u00e1neo, cerca de la bah\u00ed\u00ada de Haifa, considerada la puerta de Tierra Santa, en el norte de Palestina. Ciudad que toc\u00f3 en suerte a la tribu de Aser Jos 19, 24-31, pero que no pudo conquistar Jc 1, 31. Conquistada varias veces, por los faraones &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/akko\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abAKKO\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4608","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/4608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=4608"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/4608\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=4608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=4608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=4608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}