{"id":4629,"date":"2016-02-05T00:33:30","date_gmt":"2016-02-05T05:33:30","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/amigo\/"},"modified":"2016-02-05T00:33:30","modified_gmt":"2016-02-05T05:33:30","slug":"amigo","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/amigo\/","title":{"rendered":"AMIGO"},"content":{"rendered":"<p>lat\u00ed\u00adn amicus. La amistad es el cari\u00f1o o afecto entre personas. Con el a. se pueden establecer lazos tan fuertes, que pueden arruinar o ser m\u00e1s poderosos que los familiares Pr 18, 24. Abraham goz\u00f3 de la intimidad divina, y Dios le llama \u2020\u0153mi amigo\u2020\u009d Is 41, 8. Existen en las Sagradas Escrituras ejemplos de amistad, como la de Rut y su suegra Noem\u00ed\u00ad Rt 1,  16-18. La de David y Jonat\u00e1n 1 S 18, 1; 2 S 25-27. La de David y Jusay,  el arquita, 2 S 15, 37 y 16, 16. Las personas de confianza del soberano recib\u00ed\u00adan el t\u00ed\u00adtulo de a., Jusay es llamado \u2020\u0153a. del rey\u2020\u009d 1 Cro 27, 33. Como herencia de la corte persa, exist\u00ed\u00adan \u2020\u0153los amigos del rey\u2020\u009d 1 M 2, 18; 3, 38; 7, 8; 10, 16-20; 11, 27; 14, 39; 15, 28; 2 M 8, 9, a los cuales el monarca encargaba de funciones p\u00fablicas. \u2020\u0153Amigos m\u00ed\u00ados\u2020\u009d, llama Cristo a sus disc\u00ed\u00adpulos Lc 12, 4. Jes\u00fas previene a los ap\u00f3stoles sobre la traici\u00f3n del a.<\/p>\n<p>De causa de su nombre Lc 21  16, como le sucedi\u00f3 a \u00e9l mismo despu\u00e9s con Judas Mt 26, 50; Mc 14, 43; Lc 22, 47-48; Jn 13, 21 y 18, 1-3. A. era,  como actualmente, una f\u00f3rmula de cortes\u00ed\u00ada o la manera corriente para dirigirse a otro Mt 20, 13 y 22, 12; Lc, 14- 10.<\/p>\n<p>Diccionario B\u00ed\u00adblico Digital, Grupo C Service &#038; Design Ltda., Colombia, 2003<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Digital<\/b><\/p>\n<p>Persona con la cual nos une un sentimiento fraterno, de cari\u00f1o y afecto. Cuando la palabra se usa en relaci\u00f3n con un rey generalmente se incluye la idea de consejero, consultor, como en el caso de \u2020\u00a2Ahuzat, a. de Abimelec (Gen 26:26) o \u2020\u0153Husai a. de David\u2020\u009d (2Sa 15:37), o Zabud, a. de Salom\u00f3n (1Re 4:5). La Biblia, especialmente los Proverbios, alaba la amistad, advirtiendo contra las cosas que pueden da\u00f1arla (Pro 6:1; Pro 16:28; Pro 17:9; Pro 19:4, Pro 19:6; Pro 26:19; Pro 27:14). \u2020\u0153A. hay m\u00e1s unido que un hermano\u2020\u009d (Pro 18:24). \u2020\u0153El cordial consejo del a.\u2020\u009d, alegra al hombre (Pro 27:9). Pero no se debe prestar atenci\u00f3n a \u2020\u0153tu a. \u00ed\u00adntimo\u2020\u009d si te invita a pecar (Deu 13:6). Es triste sentir que los a. fallan, como en el caso de Job (Job 12:4; Job 16:20). Es famosa la amistad de David y Jonat\u00e1n (1Sa 18:3), as\u00ed\u00ad como la de \u2020\u00a2Rut y \u2020\u00a2Noem\u00ed\u00ad (Rut 1:16-17). Tal fue la intimidad de Abraham con Dios, que \u00e9ste le llam\u00f3 su a. (Isa 41:8). De igual manera, el Se\u00f1or Jes\u00fas llam\u00f3 a sus disc\u00ed\u00adpulos a. (\u2020\u0153&#8230; porque todas las cosas que o\u00ed\u00ad de mi Padre, os las he dado a conocer\u2020\u009d [Jua 15:15]). La amistad con Dios se obtiene a trav\u00e9s de la obediencia (Jua 15:14).<\/p>\n<p><b>Fuente: Diccionario de la Biblia Cristiano<\/b><\/p>\n<p>vet, El amor rec\u00ed\u00adproco y desinteresado es una de las caracter\u00ed\u00adsticas de la amistad que en la Biblia se nos describe en algunas p\u00e1ginas verdaderamente inmortales, pero que, dado el car\u00e1cter sobrenatural que inspira muchas de las amistades de la Escritura, no pueden ser entendidas solamente en su vertiente psicol\u00f3gica (1 S. 18 ss). Entre los paganos, al amigo se le amaba como a la \u00abmitad de mi alma\u00bb, en decir de Horacio (\u00abanimae dimidium meae\u00bb); pero \u00abel alma de Jonat\u00e1n se apeg\u00f3 a la de David y le am\u00f3 Jonat\u00e1n como a s\u00ed\u00ad mismo&#8230;; le amaba como a su alma, como a su propia vida\u00bb (1 S. 20:17). Por esta amistad tierna y conmovedora el joven David lo arriesga todo y salva la vida del amigo frente al propio padre, Sa\u00fal, que se siente postergado y celoso (1 S. 20:30). Esta amistad es sellada con un pacto y juramento de renovada ayuda (1 S. 20). El libro de los Proverbios y la literatura sapiencial dan consejos sobre la manera de conseguir, seleccionar y tratar a los amigos: elige al amigo entre muchos, ponle a prueba antes de confiarte a \u00e9l, porque nada vale tanto como un buen amigo, que es \u00abel otro t\u00fa\u00bb; ay\u00fadale cuanto puedas y no lo traiciones nunca, porque la traici\u00f3n (bien sea el desamparo, la murmuraci\u00f3n o la revelaci\u00f3n de secretos) no es compatible con la verdadera amistad. Viejo amigo, vino a\u00f1ejo, gozo y gracia que Dios concede a quienes le aman: \u00abFeliz quien encuentra un amigo de verdad.\u00bb La amistad entre los hombres y Dios es posible por medio de Jesucristo (Pr. 13:20; Jn. 3:16; 11:3, 11; Mt. 11:19; Lc. 12:4).<\/p>\n<p><b>Fuente: Nuevo Diccionario B\u00edblico Ilustrado<\/b><\/p>\n<p>La Biblia dice que un verdadero amigo es aquel que se adhiere m\u00e1s estrechamente que un hermano, es constante en su lealtad y amistad, acude en ayuda de su compa\u00f1ero angustiado y lo aconseja con fidelidad. (Pr 18:24; 17:17; 27:6, 9.) Por otra parte, los ricos y los que ofrecen d\u00e1divas tienen muchos amigos que solo est\u00e1n interesados en los beneficios ego\u00ed\u00adstas que se derivan de la amistad. (Pr 14:20; 19:4, 6, 7.) Por ello, Jesucristo aconsej\u00f3 que no se invitase a una cena a amigos que pudieran devolver el favor, sino a personas que no pudiesen hacerlo. (Lu 14:12-14.) El mismo puso el ejemplo en este respecto al ayudar espiritualmente a los despreciados, por lo que se le llam\u00f3 \u2020\u0153amigo de recaudadores de impuestos y pecadores\u2020\u009d (Mt 11:19); no obstante, indic\u00f3 que sus verdaderos amigos eran solo aquellos que obedec\u00ed\u00adan sus mandamientos. Les demostr\u00f3 su amor al entregar su alma en favor suyo y les anim\u00f3 a amarse unos a otros de la misma manera. (Jn 15:12-14.)<br \/>\nAunque los cristianos del primer siglo se refer\u00ed\u00adan a sus compa\u00f1eros creyentes en general como \u2020\u0153amigos\u2020\u009d (3Jn 14), esto no excluye que en la congregaci\u00f3n cristiana alguien est\u00e9 m\u00e1s allegado a ciertas personas, sea por parentesco, por conocerse de tiempo, por antecedentes o intereses similares, por mera compatibilidad de personalidades o por las buenas cualidades cristianas de la otra persona. Jes\u00fas escogi\u00f3 a Pedro, Santiago y Juan debido a algunas de sus cualidades, para que le acompa\u00f1aran en momentos de gran trascendencia, como en la transfiguraci\u00f3n. Es posible que Jes\u00fas, previendo el futuro, los escogiera pensando en las responsabilidades que ten\u00ed\u00ada previstas para ellos en su servicio. (Mr 9:1-10; 14:32, 33; Lu 8:51.)<br \/>\nAunque, al igual que Jes\u00fas, el cristiano manifiesta amor a la humanidad en general, correctamente solo brinda la clase de amor que va unida a la amistad a los que son amigos de Dios, tal como se le hizo ver al rey Jehosafat cuando se le pregunt\u00f3: \u2020\u0153\u00bfEs a los inicuos a quienes se ha de dar ayuda, y es para los que odian a Jehov\u00e1 para quienes debes tener amor?\u2020\u009d. (2Cr 19:2.) Las personas que desean ser amigas del mundo se hacen a s\u00ed\u00ad mismas enemigas de Dios. (Snt 4:4.)<br \/>\nEn el plano humano, la amistad m\u00e1s sobresaliente que se menciona en las Escrituras Hebreas fue la de David y Jonat\u00e1n. A pesar de que Jonat\u00e1n era el heredero natural al trono de su padre Sa\u00fal, no odi\u00f3 a David ni lleg\u00f3 a considerarlo un rival, sino que reconoci\u00f3 que el favor de Jehov\u00e1 descansaba sobre \u00e9l. As\u00ed\u00ad, \u2020\u0153la misma alma de Jonat\u00e1n se lig\u00f3 con el alma de David, y Jonat\u00e1n empez\u00f3 a amarlo como a su propia alma\u2020\u009d. (1Sa 18:1.) Despu\u00e9s de la muerte de Jonat\u00e1n en batalla, David lament\u00f3 en gran manera la p\u00e9rdida de su amigo. Dijo: \u2020\u0153Estoy angustiado por ti, hermano m\u00ed\u00ado, Jonat\u00e1n, muy agradable me fuiste. M\u00e1s maravilloso me fue tu amor que el amor procedente de mujeres\u2020\u009d. (2Sa 1:26.) Esta amistad fue posible porque tanto David como Jonat\u00e1n colocaron la lealtad a Jehov\u00e1 Dios por encima de todo lo dem\u00e1s.<br \/>\nSin embargo, en marcado contraste con esta experiencia y debido a la corrupci\u00f3n moral que predominaba en su d\u00ed\u00ada, el profeta Miqueas se vio obligado a decir: \u2020\u0153No cifren su confianza en un amigo \u00ed\u00adntimo\u2020\u009d. (Miq 7:5.) Jes\u00fas tambi\u00e9n advirti\u00f3 a sus seguidores que personas que en un tiempo manifestar\u00ed\u00adan ser sus amigos se les opondr\u00ed\u00adan y hasta los entregar\u00ed\u00adan a fin de que se les ejecutara. (Lu 21:16; v\u00e9ase AMOR.)<\/p>\n<p>Amigo de Dios. Una de las bendiciones divinas otorgadas a Abrah\u00e1n fue el privilegio y el honor de ser llamado \u2020\u0153amigo [o: amador] de Jehov\u00e1\u2020\u009d. Esto se debi\u00f3 a su fe sobresaliente, de la que hizo m\u00e1xima expresi\u00f3n al estar dispuesto a ofrecer en sacrificio a su hijo Isaac. (Isa 41:8, nota; 2Cr 20:7; Snt 2:21-23; v\u00e9ase DECLARAR JUSTO.)<br \/>\nComo se\u00f1al\u00f3 Jesucristo en su ilustraci\u00f3n sobre el mayordomo injusto, al que emplea debidamente las \u2020\u0153riquezas injustas\u2020\u009d le es posible hacerse amigo de Jehov\u00e1 Dios y de su Hijo, quienes pueden recibir a dicha persona en los \u2020\u0153lugares de habitaci\u00f3n eternos\u2020\u009d. (Lu 16:1-13.) De hecho, Jes\u00fas llam\u00f3 a sus disc\u00ed\u00adpulos: sus amigos, y, por lo tanto, ellos eran tambi\u00e9n los amigos de su Padre. (Jn 15:13-15; 14:21.) Los requisitos para ser un hu\u00e9sped en la tienda de Jehov\u00e1 como uno de sus amigos se registran en el Salmo 15:1-5.<br \/>\nEn contraste, la amistad con el mundo constituye enemistad con Dios. (Snt 4:4; 1Jn 2:15-17.) La humanidad en conjunto est\u00e1 alejada de Dios y en enemistad con El; sin embargo, la reconciliaci\u00f3n es posible, pero solo por medio de Jesucristo y el ministerio de la reconciliaci\u00f3n que Dios ha confiado a los embajadores de su Hijo. La vida eterna ser\u00e1 al fin la posesi\u00f3n exclusiva de los amigos de Dios. (2Co 5:18-20; Rev 21:3, 4; Sl 37:29.)<\/p>\n<p>Amigo (compa\u00f1ero) del rey. Al usar esta expresi\u00f3n, la Biblia no dice que tuviera otra connotaci\u00f3n aparte de la normal, es decir, la de ser un amigo o un compa\u00f1ero, por lo que no describe directamente las funciones espec\u00ed\u00adficas del amigo del rey como t\u00ed\u00adtulo oficial. Sin embargo, bas\u00e1ndose en las costumbres de otras tierras, puede que la expresi\u00f3n designara a un oficial de la corte que fuera confidente, amigo personal y compa\u00f1ero del rey, alguien que a veces ejecutaba \u00f3rdenes confidenciales. (G\u00e9 26:26.)<br \/>\nEntre los dignatarios de la corte de Salom\u00f3n mencionados en 1 Reyes 4:1-6, se hallaban dos hijos de Nat\u00e1n. De uno se dice que \u2020\u0153estaba sobre los comisarios\u2020\u009d, mientras que del otro, Zabud, se dice que era \u2020\u0153amigo del rey\u2020\u009d. Durante el reinado de David, el padre de Salom\u00f3n, Husai el arkita ocup\u00f3 ese puesto; a \u00e9l se le llam\u00f3 \u2020\u0153compa\u00f1ero de David\u2020\u009d. Cuando Absal\u00f3n conspir\u00f3 para conseguir el trono de su padre, Husai regres\u00f3 a Jerusal\u00e9n por petici\u00f3n de David con el objeto de frustrar el consejo de Ahitofel. (2Sa 15:32-37; 16:16-19.)<br \/>\nEntre los antiguos reyes egipcios, el t\u00ed\u00adtulo de \u2020\u0153amigo\u2020\u009d del rey correspond\u00ed\u00ada a diversos rangos. No ten\u00ed\u00ada car\u00e1cter exclusivo alguno, era una simple designaci\u00f3n honor\u00ed\u00adfica para funcionarios cuyos deberes reales se denominaban con otros t\u00ed\u00adtulos. Tambi\u00e9n en el Imperio griego se emple\u00f3 con cierta frecuencia el t\u00ed\u00adtulo \u2020\u0153amigo del rey\u2020\u009d. Antes de tomar decisiones sobre cuestiones relevantes, el rey consultaba a un cuerpo constituido por estos \u2020\u0153amigos\u2020\u009d. El puesto existi\u00f3, as\u00ed\u00ad mismo, en Persia, Arabia y Etiop\u00ed\u00ada.<\/p>\n<p>Amigo del novio. En tiempos antiguos, uno de los conocidos m\u00e1s allegados del novio actuaba como su representante legal y asum\u00ed\u00ada la responsabilidad principal de los preparativos para la boda. A veces preparaba los esponsales con los padres de la novia y le llevaba al padre el precio de esta, as\u00ed\u00ad como regalos para ella. Se le consideraba como aquel que reun\u00ed\u00ada a los novios. La procesi\u00f3n nupcial llegaba a la casa del padre del novio o a la casa del novio, donde se celebraba el banquete de bodas. All\u00ed\u00ad se un\u00ed\u00adan los novios. Cuando el amigo del novio o\u00ed\u00ada a este hablarle a la novia en el banquete, se sent\u00ed\u00ada feliz, pues hab\u00ed\u00ada cumplido con \u00e9xito su deber. (Jn 3:29.)<br \/>\nJuan el Bautista, quien prepar\u00f3 el camino para el Mes\u00ed\u00adas, present\u00f3 los primeros componentes de la \u2020\u0153novia\u2020\u009d a Jesucristo, con quien esta \u2020\u0153novia\u2020\u009d estaba comprometida. (2Co 11:2; Ef 5:22-27; Rev 21:2, 9.) Por consiguiente, Juan estaba en posici\u00f3n de decir: \u2020\u0153Ustedes mismos me dan testimonio de que dije: Yo no soy el Cristo, sino que he sido enviado delante de aquel. El que tiene la novia es el novio. Sin embargo, el amigo del novio, cuando est\u00e1 de pie y lo oye, tiene mucho gozo a causa de la voz del novio. Por eso, este gozo m\u00ed\u00ado se ha hecho pleno\u2020\u009d. As\u00ed\u00ad como el cometido del amigo del novio quedaba cumplido al llegar este momento y \u00e9l ced\u00ed\u00ada su protagonismo, Juan dijo de s\u00ed\u00ad mismo en relaci\u00f3n con Jes\u00fas: \u2020\u0153Aquel tiene que seguir aumentando, pero yo tengo que seguir menguando\u2020\u009d. (Jn 3:27-30.)<br \/>\nEn Mateo 9:15 se hace menci\u00f3n de los \u2020\u0153amigos del novio\u2020\u009d. En este caso se trata de amigos que se unen al cortejo nupcial y a los que se ha invitado a la recepci\u00f3n de bodas.<\/p>\n<p><b>Fuente: Diccionario de la Biblia<\/b><\/p>\n<p>rea> ([&#8216;re , 7453), \u00abamigo; compa\u00f1ero; camarada\u00bb. Este nombre aparece cerca de 187 veces en la Biblia. En 2Sa 13:3 el t\u00e9rmino se refiere a un \u00abamigo\u00bb: \u00abY Amn\u00f3n ten\u00ed\u00ada un amigo que se llamaba Jonadab\u00bb. La misma palabra puede usarse para un marido (Jer 3:20) o un amante (Son 5:16). En otro sentido, rea> puede referirse a cualquier persona con la que uno tiene relaciones rec\u00ed\u00adprocas: \u00abY dijeron cada uno a su compa\u00f1ero: Venid y echemos suertes\u00bb (Joh 1:7). El t\u00e9rmino se halla adem\u00e1s en frases como \u00abunos a otros\u00bb, tal es el caso de Gen 11:3  \u00abY se dijeron unos a otros\u00bb (cf. Gen 31:49). Otros nombres cognados que aparecen con menos frecuencia son re>eh, que significa \u00abamigo\u00bb (unas 5 veces; p. ej. 1Ki 4:5) y re>ah, que se traduce \u00abcompa\u00f1ero o asistente\u00bb (Jdg 11:38; Psa 45:14).<\/p>\n<p><b>Fuente: Diccionario Vine Antiguo Testamento<\/b><\/p>\n<p>etairos (eJtai`ro\u00bb, 2083), compa\u00f1ero, socio. Se usa como t\u00e9rmino bondadoso para dirigirse a alguien en Mat 20:13; 22.12; 26.50. Esta palabra, que expresa camarader\u00ed\u00ada, debe distinguirse del N\u00c2\u00ba 2, que es un t\u00e9rmino cari\u00f1oso. Algunos mss. tienen la palabra en Mat 11:16; los mejores tienen eterois; otros, como la RV y RVR, tienen \u00abcompa\u00f1ero\u00bb. V\u00e9ase COMPA\u00ed\u2018ERO. 2. filos (fivlo\u00bb, 5384), adjetivo, que denota ser amado, querido, o amistoso, pas\u00f3 a ser usado como un nombre: (a) masculino (Mat 11:19; catorce veces en Lucas, con una vez en femenino, 15.9; seis veces en Juan; tres en Hechos; dos en Jam 2:23, \u00abamigo de Dios\u00bb; 4.4: \u00abamigo del mundo\u00bb; 3 Juan 14, dos veces); (b) femenino (Luk 15:9, \u00absus amigas\u00bb).<\/p>\n<p><b>Fuente: Diccionario Vine Nuevo testamento<\/b><\/p>\n<p>1. \u00abEl amigo fiel no tiene precio\u00bb (Eclo 6,15s; 7,18), porque \u00abama en todo tiempo\u00bb (Prov 17,17) y hace la vida deliciosa (Sal 133; Prov 15,17). \u00bfC\u00f3mo ser\u00ed\u00ada posible olvidar la amistad que uni\u00f3 a David y Jonat\u00e1s en un brote espont\u00e1neo (ISa 18,1-4), que dur\u00f3 en la prueba (ISa 19-20), hasta la muerte (2Sa 1,25s) y sobrevivi\u00f3 en la *memoria del coraz\u00f3n (2Sa 9,1; 21,7)?<br \/>\nAhora bien, aunque existen tales amistades, las hay tambi\u00e9n que son ilusorias. \u00bfPor qu\u00e9 tienen tantos amigos los ricos, y tan pocos los pobres, lo enfermos, los perseguidos? (Prov 14,20; cf. Sal 38,12; 55,13s; 88,19; 109,4s; Job 19,19). \u00bfPor qu\u00e9 \u00abel que comparte el pan conmigo levanta contra m\u00ed\u00ad su calca\u00f1ar\u00bb (Sal 41,10)? Estas dolorosas experiencias ense\u00f1an a proceder con lucidez en la elecci\u00f3n de los amigos, tanto que a veces conviene ponerse en guardia (Eclo 6,5-13; 12,8-13,23: 37,1-5). Una amistad, incluso sincera (Job 2,12s), \u00bfno puede ser decepcionante (Job 6,15-30) y hasta arrastrar al mal (Dt 13,7; Eclo 12,14; cf. 2Sa 13,3-15)?<br \/>\nAs\u00ed\u00ad la amistad gana seg\u00fan va envejeciendo: \u00abVino nuevo el amigo nuevo: cuando envejece es cuando se bebe con placer\u00bb (Eclo 9,10); agradece la reprensi\u00f3n sincera (Prov 27, 5s): sobre todo se alimenta del *temor de Dios: \u00abEI que teme al Se\u00f1or encuentra verdaderos amigos, y como fiel es \u00e9l, as\u00ed\u00ad lo ser\u00e1 su amigo\u00bb (Eclo 6.16s). De hecho (cf. *amor), el modelo y la fuente de la verdadera amistad es la amistad que Dios sella con el hombre, con un Abraham (Is 41,8, G\u00e9n 18,17ss), con un Mois\u00e9s (Ex 33,11), con los profetas (Am 3,7).<\/p>\n<p>2. Al enviar a su Hijo entre nosotros se mostr\u00f3 Dios \u00abamigo de los hombres\u00bb (Tit 3,4); y Jes\u00fas lo describi\u00f3 como uno que se deja molestar por el amigo importuno (Lc 11,5-8). Sobre todo, Jes\u00fas dio a esta amistad un rostro de carne: am\u00f3 al joven rico (Mc 10.21), am\u00f3 tiernamente a L\u00e1zaro y, a trav\u00e9s de \u00e9l, a todos los que por la fe deb\u00ed\u00adan resurgir de la tumba con \u00e9l (Jn 11,3. 11.35 ss). Tuvo \u00abcompa\u00f1eros\u00bb que compartieron su existencia (Mc 3,14), pero no todos llegaron a ser sus \u00abamigoso (gr. philos); as\u00ed\u00ad a Judas se le llama todav\u00ed\u00ada compa\u00f1ero (gr. hetairos) (Mt 26,50; cf. 20,13; 22,12), mientras que a los otros acaba Jes\u00fas de declarar: \u00abYa no os llamo *servidores, sino amigos\u00bb (Jn 15,15): han compartido sus pruebas, est\u00e1n prontos a afrontar la noche de la pasi\u00f3n (Lc 22,28s); as\u00ed\u00ad Jes\u00fas los hace participes de los secretos de su Padre (Jn 15,15), como entre amigos. El tipo de amigo de Jes\u00fas, fiel hasta la cruz, es \u00abel disc\u00ed\u00adpulo al que amaba Jes\u00fas\u00bb (Jn 13,23) y al que confi\u00f3 a su propia madre (19,26).<\/p>\n<p>En adelante reinar\u00e1 una amistad perfecta entre estos amigos prontos a dar la vida los unos por los otros, como Jes\u00fas lo hizo por cada uno (Jn 15,12ss). Aun cuando, entre hermanos, esta amistad puede conocer tormentas (Act 15,36-39; 2Tim 4,1014), renace sin cesar; es que sobrepasa la medida com\u00fan de la amistad humana (Mt 5,46) y no conoce ya las barreras que separan a los hombres (G\u00e1l 3,28). Algunos hombres querr\u00e1n romper su amistad con el que se hace disc\u00ed\u00adpulo de Cristo (Lc 21,16), pero \u00e9ste no cesa de ofrecer su amistad a todos, aun a los que se creen sus *enemigos (Rm 12,13-21). -> Amor &#8211; Hermano &#8211; Pr\u00f3jimo.<\/p>\n<p>LEON-DUFOUR, Xavier, Vocabulario de Teolog\u00ed\u00ada B\u00ed\u00adblica, Herder, Barcelona, 2001<\/p>\n<p><b>Fuente: Vocabulario de las Ep\u00edstolas Paulinas<\/b><\/p>\n<p><p style=\"text-align: justify;\">As\u00ed como la palabra inglesa <em>friend<\/em> (amigo) deriva del saj\u00f3n <em>freond<\/em>, que significa \u00abuno amado o liberado\u00bb, la palabra griega equivalente, <em>filos<\/em>, lleva la misma idea en su uso neotestamentario, especialmente en Juan. All\u00ed el amigo es uno que ha sido libertado (Jn. 8:31\u201336) por el conocimiento que Jes\u00fas ha impartido (15:15). De aqu\u00ed en adelante los disc\u00edpulos ya no son esclavos, sino amigos que ahora participan de la gloria de Cristo (17:22).<\/p>\n<p style=\"text-align: justify;\">Es de importancia la frase \u00abamigo de Dios\u00bb, que sirve como t\u00edtulo de distinci\u00f3n (por ejemplo, Abraham en Is. 41:8, adoptado por el cristianismo, como en Stg. 2:23, y por el islam). El juda\u00edsmo confiri\u00f3 este honor a Mois\u00e9s (Ex. 33:11) y a Israel. Fil\u00f3n (<em>Mig.<\/em> 45) incluy\u00f3 en esta categor\u00eda a los profetas, pero en el sentido griego de que todo <em>sofos<\/em> es un \u00abamigo de Dios\u00bb.<\/p>\n<p style=\"text-align: justify;\">Entre los cristianos alejandrinos \u00abamigo de Dios\u00bb se aplicaba a los m\u00e1rtires y monjes, y gradualmente fue adquiriendo una significaci\u00f3n m\u00edstica que se expandi\u00f3 en el misticismo de la Edad Media.<\/p>\n<p style=\"text-align: justify;\">BIBLIOGRAF\u00cdA<\/p>\n<ol style=\"text-align: justify;\" start=\"202\">\n<li>Peterson, \u00abDer Gottesfreund\u00bb, <em><a href=\"#_ftn1\" name=\"_ftnref1\">ZKG<\/a><\/em> (1923), pp. 161\u2013202.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Herman C. Waetjen<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftn2\" name=\"_ftnref2\"><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\"><em>ZKG <\/em><\/a><em>Zeitschrift fuer Kirchengeschichte<\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref2\" name=\"_ftn2\"><\/a>Harrison, E. F., Bromiley, G. W., &amp; Henry, C. F. H. (2006). <em>Diccionario de Teologi\u0301a<\/em> (24). Grand Rapids, MI: Libros Desafi\u0301o.<\/p>\n<\/p>\n<p><b>Fuente: Diccionario de Teolog\u00eda<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>lat\u00ed\u00adn amicus. La amistad es el cari\u00f1o o afecto entre personas. Con el a. se pueden establecer lazos tan fuertes, que pueden arruinar o ser m\u00e1s poderosos que los familiares Pr 18, 24. Abraham goz\u00f3 de la intimidad divina, y Dios le llama \u2020\u0153mi amigo\u2020\u009d Is 41, 8. Existen en las Sagradas Escrituras ejemplos de &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/amigo\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abAMIGO\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4629","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/4629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=4629"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/4629\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=4629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=4629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=4629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}