{"id":4663,"date":"2016-02-05T00:34:34","date_gmt":"2016-02-05T05:34:34","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/arma\/"},"modified":"2016-02-05T00:34:34","modified_gmt":"2016-02-05T05:34:34","slug":"arma","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/arma\/","title":{"rendered":"ARMA"},"content":{"rendered":"<p>Gen 49:5 son hermanos; a de iniquidad sus a<br \/>\n1Sa 17:54 pero las a de \u00e9l las puso en su tienda<br \/>\n2Sa 1:27 \u00a1c\u00f3mo .. han perecido las a de guerra!<br \/>\nJob 20:24 huir\u00e1 de las a de hierro, y el arco<br \/>\nEcc 8:8 no valen a en tal guerra, ni la impiedad<br \/>\nEcc 9:18 mejor es la sabidur\u00eda que las a de guerra<br \/>\nIsa 54:17 ninguna a .. contra ti prosperar\u00e1<br \/>\nJer 21:4 yo vuelvo atr\u00e1s las a de guerra que<br \/>\nLuk 11:22 le quita todas sus a en que confiaba<br \/>\nRom 13:12 tinieblas, y vist\u00e1monos las a de la luz<br \/>\n2Co 6:7 a de justicia a diestra y a siniestra<\/p>\n<hr>\n<p>instrumento que sirve para atacar o defenderse 2 R 11, 8 y 11; 2 Cro 23, 7 y 10; Ne 4, 11 y 17. San Pablo usa figuradamente el plural armas, para referirse al combate espiritual, Rm 13, 12; 2 Co 6, 7 y 10, 4; Ef 6, 11-13.<\/p>\n<p>En la Escritura encontramos armas ofensivas  como el  \u00c2\u00ae arco, la  \u00c2\u00ae espada, la  \u00c2\u00ae honda, la  \u00c2\u00ae lanza, el  \u00c2\u00ae pu\u00f1al, la  \u00c2\u00ae saeta; defensivas, como el  \u00c2\u00ae escudo, la  \u00c2\u00ae coraza, el  \u00c2\u00ae yelmo.<\/p>\n<p>Diccionario B\u00ed\u00adblico Digital, Grupo C Service &#038; Design Ltda., Colombia, 2003<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Digital<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gen 49:5 son hermanos; a de iniquidad sus a 1Sa 17:54 pero las a de \u00e9l las puso en su tienda 2Sa 1:27 \u00a1c\u00f3mo .. han perecido las a de guerra! Job 20:24 huir\u00e1 de las a de hierro, y el arco Ecc 8:8 no valen a en tal guerra, ni la impiedad Ecc 9:18 &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/arma\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abARMA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4663","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/4663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=4663"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/4663\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=4663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=4663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=4663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}