{"id":5898,"date":"2016-02-05T02:11:34","date_gmt":"2016-02-05T07:11:34","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/congregacion\/"},"modified":"2016-02-05T02:11:34","modified_gmt":"2016-02-05T07:11:34","slug":"congregacion","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/congregacion\/","title":{"rendered":"CONGREGACION"},"content":{"rendered":"<p>v. Asamblea, Iglesia, Reuni\u00f3n<br \/>\nLev 4:13 si toda la c de Israel hubiere errado<br \/>\nLev 8:3 re\u00fane toda la c a la puerta del tabern\u00e1culo<br \/>\nNum 14:5 Mois\u00e9s y .. se postraron delante de la c<br \/>\nNum 16:3 toda la c, todos ellos son santos, y en<br \/>\nPsa 7:7 te rodear\u00e1 c de pueblos, y sobre ella<br \/>\nPsa 22:22 anunciar\u00e9 .. en medio de la c te alabar\u00e9<br \/>\nPsa 26:12 en rectitud; en las c bendecir\u00e9 a Jehov\u00e1<br \/>\nPsa 89:7 Dios temible en la gran c de los santos<br \/>\nPsa 107:32 ex\u00e1ltenlo en la c del pueblo, y en la<br \/>\nAct 7:38 aquel Mois\u00e9s que estuvo en la c en el<br \/>\nAct 13:43 despedida la c, muchos de los jud\u00edos<br \/>\n1Co 14:34 vuestras mujeres callen en las c<br \/>\n1Co 14:35 indecoroso que una mujer hable en la c<br \/>\nHeb 2:12 tu nombre, en medio de la c te alabar\u00e9<br \/>\nHeb 12:23 a la c de los primog\u00e9nitos que est\u00e1n<br \/>\nJam 2:2 en vuestra c entra un hombre con anillo<\/p>\n<hr>\n<p>(heb., \u2020\u2122edhah y qahal, gr., ekklesia y synagoge). El pueblo hebreo, considerado en su capacidad colectiva como pueblo de Dios o como una asamblea de personas congregadas para un prop\u00f3sito definido (1Ki 8:65), o reunido para una ocasi\u00f3n festiva (Deu 23:1).<\/p>\n<p>Algunas veces se refiere a una asamblea de todo el pueblo y otras veces a una parte (Exo 12:6, Exo 12:47; Exo 19:7-8; Lev 4:13; Lev 8:4; Num 16:3; Num 25:6; Joe 2:15).<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Mundo Hispano<\/b><\/p>\n<p>T\u00e9rmino que se utiliza para traducir varias palabras hebreas con el sentido de \u2020\u0153reuni\u00f3n\u2020\u009d, o \u2020\u0153asamblea\u2020\u009d, o \u2020\u0153concurrencia\u2020\u009d. Es frecuente el uso en la forma de \u2020\u0153la c. de Israel\u2020\u009d, para referirse al pueblo, que otras veces es mencionado simplemente como \u2020\u0153la c.\u2020\u009d (Exo 12:3; Exo 16:1; Exo 35:4; Lev 4:13; Num 1:2, etc\u00e9tera). \u2020\u0153Entrar a la c. de Jehov\u00e1\u2020\u009d significaba poder participar con plenitud de derechos en los privilegios y beneficios del pueblo de Israel, especialmente en lo referente a la adoraci\u00f3n a Dios en el \u2020\u00a2tabern\u00e1culo o el \u2020\u00a2templo (Deu 23:1-8).<\/p>\n<p>La palabra ekkl\u00ebsia (iglesia), tan usada en el NT, fue introducida por los traductores de la Septuaginta, que la pon\u00ed\u00adan en lugar de la palabra hebrea cajal (congregaci\u00f3n). Por lo tanto, cuando el Se\u00f1or Jes\u00fas us\u00f3 el t\u00e9rmino ekkl\u00ebsia (Mat 16:18; Mat 18:17) el mismo no era desconocido para sus oyentes.<\/p>\n<p><b>Fuente: Diccionario de la Biblia Cristiano<\/b><\/p>\n<p>(V\u00e9anse CONVOCACI\u00ed\u201cN, SINAGOGA, IGLESIA)<\/p>\n<p><b>Fuente: Nuevo Diccionario B\u00edblico Ilustrado<\/b><\/p>\n<p>[266]<br \/>\n Asociaci\u00f3n de personas que establecen v\u00ed\u00adnculos comunes. en lenguaje religioso y eclesial se alude a la asociaci\u00f3n que tiene objetivos religiosos.<\/p>\n<p>    Unas \u00abcongregaciones\u00bb son de car\u00e1cter piadoso y el t\u00e9rmino se usaba con frecuencia desde finales del siglo XIX para aludir a los grupos marianos, eucar\u00ed\u00adsticos, apost\u00f3licos que surg\u00ed\u00adan en parroquias y en centros educativos.<\/p>\n<p>    De manera especial se aplic\u00f3 la denominaci\u00f3n a \u00abInstitutos religiosos\u00bb con car\u00e1cter jur\u00ed\u00addico, ya fueran clericales o laicales, de \u00abderecho\u00bb o autorizaci\u00f3n diocesana o pontificia, masculinos o femeninos. Fueron varios miles las Congregaciones docentes que surgieron, sobre todo en el siglo XIX y XX, para prestar un servicio magn\u00ed\u00adfico a la sociedad y a la Iglesia cuando todav\u00ed\u00ada los Estados no hab\u00ed\u00adan ca\u00ed\u00addo en la cuenta de su deber de instruir a los ciudadanos.<\/p>\n<p>    Ellas prestaron este inapreciable deber de solidaridad humana y de educaci\u00f3n en clave de valores evang\u00e9licos. Lo mismo aconteci\u00f3 con otros campos: el de la asistencia, el de la sanidad, el de las misiones.<\/p>\n<p>    El t\u00e9rmino de \u00abcongregaci\u00f3n\u00bb se aplic\u00f3 a estos grupos ya desde 1610, cuando Federico Borromeo, sucesor de S. Carlos Borromeo en la animaci\u00f3n de la Compa\u00f1\u00ed\u00ada de la Doctrina Cristiana establecida en Mil\u00e1n, redact\u00f3 nuevos estatutos para las casi 750 \u00abcofrad\u00ed\u00adas o compa\u00f1\u00ed\u00adas de la doctrina cristiana\u00bb. En esos estatutos denomin\u00f3 \u00abcongregaci\u00f3n de la Doctrina Cristiana\u00bb a los diversos grupos escolares y parroquiales. El nombre se difundi\u00f3 posteriormente con profusi\u00f3n.<\/p>\n<p>    Tambi\u00e9n se denomin\u00f3 \u00abcongregaci\u00f3n\u00bb ya en el siglo XX, a determinados grupos de gobierno eclesial diocesano y sobretodo romano y pontificio, compuestos de diversidad de miembros entre los permanentes o los eventuales, directivos o simplemente consultores.<\/p>\n<p>Pedro Chico Gonz\u00e1lez, Diccionario de Catequesis y Pedagog\u00ed\u00ada Religiosa, Editorial Bru\u00f1o, Lima, Per\u00fa 2006<\/p>\n<p><b>Fuente: Diccionario de Catequesis y Pedagog\u00eda Religiosa<\/b><\/p>\n<p>Grupo de personas reunido para un prop\u00f3sito o actividad en particular. La palabra hebrea que suele traducirse \u2020\u0153congregaci\u00f3n\u2020\u009d en la Traducci\u00f3n del Nuevo Mundo es qa\u00c2\u00b7h\u00e1l, que viene de una ra\u00ed\u00adz cuyo significado es \u2020\u0153convocar; congregar\u2020\u009d. (N\u00fa 20:8; Dt 4:10.) Se usa frecuentemente con relaci\u00f3n a un cuerpo organizado, y se encuentra en las expresiones \u2020\u0153congregaci\u00f3n de Israel\u2020\u009d (Le 16:17; Jos 8:35; 1Re 8:14), \u2020\u0153congregaci\u00f3n del Dios verdadero\u2020\u009d (Ne 13:1) y \u2020\u0153congregaci\u00f3n de Jehov\u00e1\u2020\u009d. (Dt 23:2, 3; Miq 2:5.) Qa\u00c2\u00b7h\u00e1l designa diferentes tipos de convocatorias humanas: con fines religiosos (Dt 9:10; 18:16; 1Re 8:65; Sl 22:25; 107:32), para tratar asuntos civiles (1Re 12:3) y para la guerra (1Sa 17:47; Eze 16:40). En el libro de Eclesiast\u00e9s se identifica a Salom\u00f3n como \u2020\u0153el congregador\u2020\u009d (heb. qo\u00c2\u00b7h\u00e9\u00c2\u00b7leth). (Ec 1:1, 12.) En su calidad de rey, congreg\u00f3 o reuni\u00f3 al pueblo para la adoraci\u00f3n de Jehov\u00e1. Una ocasi\u00f3n notable fue cuando reuni\u00f3 a sus s\u00fabditos con motivo de la inauguraci\u00f3n del templo de Jerusal\u00e9n. (1Re 8:1-5; 2Cr 5:2-6.)<br \/>\nLa palabra traducida \u2020\u0153congregaci\u00f3n\u2020\u009d en las Escrituras Griegas Cristianas es ek\u00c2\u00b7kle\u00c2\u00b7s\u00ed\u00ad\u00c2\u00b7a, de la que se deriva el vocablo \u2020\u0153iglesia\u2020\u009d. Ek\u00c2\u00b7kle\u00c2\u00b7s\u00ed\u00ad\u00c2\u00b7a viene de dos ra\u00ed\u00adces griegas: ek, que significa \u2020\u0153fuera\u2020\u009d, y ka\u00c2\u00b7l\u00e9\u00c2\u00b7o, que significa \u2020\u0153llamar\u2020\u009d. Por lo tanto, designa a un grupo de personas a las que se ha \u2020\u02dcllamado hacia afuera\u2020\u2122 o se ha convocado, sea oficial o extraoficialmente. Es la palabra que se usa con referencia a la congregaci\u00f3n de Israel en Hechos 7:38 y tambi\u00e9n para aludir a la \u2020\u0153asamblea\u2020\u009d que el platero Demetrio levant\u00f3 contra Pablo y sus compa\u00f1eros en Efeso. (Hch 19:23, 24, 29, 32, 41.) Sin embargo, su uso m\u00e1s frecuente es con relaci\u00f3n a la congregaci\u00f3n cristiana. Se aplica a la congregaci\u00f3n cristiana en general (1Co 12:28); a una congregaci\u00f3n de una ciudad en particular, como Jerusal\u00e9n (Hch 8:1), Antioqu\u00ed\u00ada (Hch 13:1) o Corinto (2Co 1:1), y a un grupo espec\u00ed\u00adfico que se re\u00fane en casa de alguien. (Ro 16:5; Flm 2.) Tambi\u00e9n se mencionan congregaciones cristianas individuales o \u2020\u0153congregaciones de Dios\u2020\u009d. (Hch 15:41; 1Co 11:16.) La mayor\u00ed\u00ada de las versiones espa\u00f1olas utilizan la palabra \u2020\u0153iglesia\u2020\u009d en textos que hablan de la congregaci\u00f3n cristiana, como en 1 Corintios 16:19, pero puesto que muchas personas relacionan el t\u00e9rmino iglesia con un edificio para servicios religiosos m\u00e1s bien que con una congregaci\u00f3n reunida para adorar, esa traducci\u00f3n puede conducir a equ\u00ed\u00advocos.<br \/>\nLa palabra griega ek\u00c2\u00b7kle\u00c2\u00b7s\u00ed\u00ad\u00c2\u00b7a se emplea a veces en la Versi\u00f3n de los Setenta para traducir el vocablo hebreo qa\u00c2\u00b7h\u00e1l, como en el Salmo 22:22 (21:23, LXX). (Comp\u00e1rese con NM, nota.)<\/p>\n<p>La congregaci\u00f3n de Israel. Desde el tiempo de Mois\u00e9s en adelante, las Escrituras llamaron congregaci\u00f3n a la naci\u00f3n de Israel. Jehov\u00e1 dispuso que el gobierno de la congregaci\u00f3n fuese, no democr\u00e1tico, del pueblo, sino teocr\u00e1tico, es decir, de El mismo. Precisamente con ese prop\u00f3sito se introdujo a la naci\u00f3n en el pacto de la Ley. (Ex 19:3-9; 24:6-8.) Puesto que Mois\u00e9s era el mediador de aquel pacto, los israelitas pod\u00ed\u00adan decir: \u2020\u0153Mois\u00e9s nos impuso como mandato una ley, una posesi\u00f3n de la congregaci\u00f3n de Jacob\u2020\u009d (Dt 33:4), aunque Jehov\u00e1 era su Juez, Dador de Estatutos y Rey. (Isa 33:22.) De este modo, la naci\u00f3n era una congregaci\u00f3n de Dios y se la pod\u00ed\u00ada llamar la \u2020\u0153congregaci\u00f3n de Jehov\u00e1\u2020\u009d. (N\u00fa 16:3; 1Cr 28:8.)<br \/>\nA veces qa\u00c2\u00b7h\u00e1l (congregaci\u00f3n) se emplea junto con otra palabra hebrea, `e\u00c2\u00b7dh\u00e1h (asamblea). (Le 4:13; N\u00fa 20:8, 10.) `E\u00c2\u00b7dh\u00e1h viene de una ra\u00ed\u00adz cuyo significado es \u2020\u0153nombrar\u2020\u009d, as\u00ed\u00ad que quiere decir un grupo reunido por nombramiento, y con frecuencia se aplica a la comunidad de Israel, como en la expresi\u00f3n \u2020\u0153asamblea de Israel\u2020\u009d. (Ex 12:3.) Los que constitu\u00ed\u00adan la poblaci\u00f3n hebrea de la naci\u00f3n de Israel compon\u00ed\u00adan la congregaci\u00f3n (qa\u00c2\u00b7h\u00e1l; N\u00fa 15:15), mientras que, al parecer, la asamblea (`e\u00c2\u00b7dh\u00e1h) abarcaba tanto a los israelitas como a los residentes forasteros que viv\u00ed\u00adan con ellos. (Ex 12:19.) Parece ser que a los residentes forasteros circuncisos se les contaba como parte de la congregaci\u00f3n de Israel, en una aplicaci\u00f3n general y extendida de este t\u00e9rmino. (N\u00fa 15:14-16.)<br \/>\nNo obstante, hab\u00ed\u00ada excepciones en cuanto a qui\u00e9nes pod\u00ed\u00adan formar parte de la \u2020\u0153congregaci\u00f3n de Jehov\u00e1\u2020\u009d. Ning\u00fan hombre castrado o que \u2020\u02dctuviera cortado su miembro viril\u2020\u2122 pod\u00ed\u00ada entrar en la congregaci\u00f3n, ni los hijos ileg\u00ed\u00adtimos ni los varones ammonitas ni moabitas pod\u00ed\u00adan formar parte de ella \u2020\u0153hasta la d\u00e9cima generaci\u00f3n\u2020\u009d. Sin embargo, los hijos de los edomitas y de los egipcios de \u2020\u0153la tercera generaci\u00f3n\u2020\u009d pod\u00ed\u00adan \u2020\u0153entrar de por s\u00ed\u00ad en la congregaci\u00f3n de Jehov\u00e1\u2020\u009d. (Dt 23:1-8.) El hecho de que se excluyera \u2020\u0153hasta la d\u00e9cima generaci\u00f3n\u2020\u009d a los hijos de alguien que fuera hijo ileg\u00ed\u00adtimo promov\u00ed\u00ada respeto a la ley de Jehov\u00e1 contra el adulterio. (Ex 20:14.) Y a pesar de que los mutilados sexualmente no pod\u00ed\u00adan integrarse en la \u2020\u0153congregaci\u00f3n de Jehov\u00e1\u2020\u009d, recib\u00ed\u00adan consuelo de las palabras registradas en Isa\u00ed\u00adas 56:1-7. De todas maneras, las personas excluidas de la \u2020\u0153congregaci\u00f3n de Jehov\u00e1\u2020\u009d en el Israel antiguo ten\u00ed\u00adan la posibilidad de llegar a recibir las provisiones y bendiciones que Jehov\u00e1 otorgaba a las personas de las dem\u00e1s naciones. (G\u00e9 22:15-18.)<br \/>\nA aquellos que formaban parte de la congregaci\u00f3n de Israel se les mostraba misericordia si pecaban por error, pero se les ejecutaba en caso de hacer algo malo deliberadamente. (N\u00fa 15:27-31.) Por ejemplo, hab\u00ed\u00ada que cortar de la congregaci\u00f3n y ejecutar a quien rehusase purificarse cuando estaba \u2020\u0153inmundo\u2020\u009d ceremonialmente, comiese de la carne del sacrificio de comuni\u00f3n estando en esa condici\u00f3n, participase de la grasa de las ofrendas o de la sangre o comiese cosas santas mientras estaba inmundo. (N\u00fa 19:20; Le 7:21-27; 17:10, 14; 22:3.) Se deb\u00ed\u00ada ejecutar tambi\u00e9n a aquel que trabajase en s\u00e1bado (Ex 31:14), entregase su prole a M\u00f3lek, se volviera a m\u00e9dium espiritistas y pronosticadores profesionales de sucesos, se entregara a ciertas clases de inmoralidad sexual y a quien no \u2020\u02dcse afligiera\u2020\u2122 en el D\u00ed\u00ada de Expiaci\u00f3n anual. (Le 20:1-6, 17, 18; 23:27-30; v\u00e9anse tambi\u00e9n Ex 30:31-33; Le 17:3, 4, 8, 9; 18:29; 19:5-8.)<br \/>\nLos habitantes de Israel estaban organizados en tribus, familias y casas. El incidente que tuvo que ver con Ac\u00e1n muestra esta organizaci\u00f3n del pueblo, pues en esa ocasi\u00f3n Israel se present\u00f3 primero tribu por tribu, luego familia por familia, m\u00e1s tarde casa por casa y por fin hombre f\u00ed\u00adsicamente capacitado por hombre f\u00ed\u00adsicamente capacitado, hasta que se aisl\u00f3 a Ac\u00e1n como el malhechor. (Jos 7:10-19.)<br \/>\nEn Israel, los \u2020\u0153pr\u00ed\u00adncipes\u2020\u009d sol\u00ed\u00adan actuar en representaci\u00f3n de todo el pueblo. (Esd 10:14.) As\u00ed\u00ad, los \u2020\u0153principales de las tribus\u2020\u009d hicieron sus presentaciones cuando se erigi\u00f3 el tabern\u00e1culo. (N\u00fa 7:1-11.) Los sacerdotes, levitas y \u2020\u0153cabezas del pueblo\u2020\u009d tambi\u00e9n actuaron como representantes de la naci\u00f3n cuando se autentic\u00f3 por sello el \u2020\u0153arreglo fidedigno\u2020\u009d en los d\u00ed\u00adas de Nehem\u00ed\u00adas. (Ne 9:38\u201310:27.) Durante el viaje de los israelitas por el desierto, doscientos cincuenta de los \u2020\u0153principales de la asamblea, los convocados de la reuni\u00f3n, hombres de fama\u2020\u009d, se congregaron con Cor\u00e9, Dat\u00e1n, Abiram y On en contra de Mois\u00e9s y Aar\u00f3n. (N\u00fa 16:1-3.) En conformidad con la instrucci\u00f3n divina, Mois\u00e9s seleccion\u00f3 a 70 ancianos de Israel para que le ayudaran a llevar \u2020\u0153la carga del pueblo\u2020\u009d, demasiado pesada para \u00e9l solo. (N\u00fa 11:16, 17, 24, 25.) En Lev\u00ed\u00adtico 4:15 se habla de \u2020\u0153los ancianos de la asamblea\u2020\u009d; al parecer los ancianos de la naci\u00f3n, sus cabezas, sus jueces y sus oficiales eran los representantes del pueblo. (N\u00fa 1:4, 16; Jos 23:2; 24:1.)<br \/>\nEn el desierto se usaron dos trompetas de plata para convocar a la asamblea y tambi\u00e9n para levantar el campamento. La asamblea se reun\u00ed\u00ada con Mois\u00e9s a la entrada de la tienda de reuni\u00f3n si se tocaban ambas trompetas, pero en caso de que se tocara solo una, no se presentaban m\u00e1s que \u2020\u0153los principales como cabezas de los millares de Israel\u2020\u009d. (N\u00fa 10:1-4.) A veces los reyes convocaron reuniones (1Re 8:5; 2Cr 20:4, 5), y Ezequ\u00ed\u00adas us\u00f3 a corredores para convocar al pueblo a Jerusal\u00e9n con ocasi\u00f3n de la gran celebraci\u00f3n de la Pascua que tuvo lugar en su d\u00ed\u00ada. (2Cr 30:1, 2, 10-13.)<br \/>\nEn tiempos posteriores, el cuerpo judicial conocido como el Sanedr\u00ed\u00adn (compuesto de 71 miembros: el sumo sacerdote y otros 70 hombres principales de la naci\u00f3n, \u2020\u0153la asamblea de los ancianos\u2020\u009d) lleg\u00f3 a concentrar un poder considerable. (Mt 26:59; Lu 22:66.)<br \/>\nDurante el exilio babilonio de los jud\u00ed\u00ados, o poco despu\u00e9s, se generaliz\u00f3 el uso de las sinagogas, edificios donde se congregaban los jud\u00ed\u00ados, y con el tiempo se establecieron en diferentes lugares; Jes\u00fas ense\u00f1\u00f3 en la sinagoga de Nazaret, por ejemplo. (Lu 4:16-21.) Las sinagogas eran, en realidad, escuelas donde se le\u00ed\u00adan y ense\u00f1aban las Escrituras, y donde tambi\u00e9n se oraba y se daba gracias a Dios. (Hch 15:21; v\u00e9ase SINAGOGA.)<br \/>\nLa congregaci\u00f3n de Israel estaba en una posici\u00f3n singular. Mois\u00e9s les record\u00f3: \u2020\u0153Porque t\u00fa eres un pueblo santo a Jehov\u00e1 tu Dios. Es a ti a quien Jehov\u00e1 tu Dios ha escogido para que llegues a ser su pueblo, una propiedad especial, de entre todos los pueblos que est\u00e1n sobre la superficie del suelo\u2020\u009d. (Dt 7:6.) Sin embargo, la congregaci\u00f3n jud\u00ed\u00ada dej\u00f3 de ser la congregaci\u00f3n de Dios, quien la abandon\u00f3 por rechazar a Su propio Hijo. (Hch 4:24-28; 13:23-29; Mt 21:43; 23:37, 38; Lu 19:41-44.)<\/p>\n<p>La congregaci\u00f3n cristiana de Dios. Antes de que se rechazase a la naci\u00f3n jud\u00ed\u00ada y llegase a su fin la posici\u00f3n que hab\u00ed\u00ada gozado como congregaci\u00f3n de Dios, Jesucristo se identific\u00f3 como la \u2020\u0153masa rocosa\u2020\u009d sobre la que edificar\u00ed\u00ada \u2020\u02dcsu congregaci\u00f3n\u2020\u2122. (Mt 16:18.) As\u00ed\u00ad es como entendi\u00f3 Pedro lo que Jes\u00fas le dijo, pues m\u00e1s tarde le identific\u00f3 como la \u2020\u0153piedra\u2020\u009d figurativa que fue rechazada por los hombres, pero \u2020\u0153escogida, preciosa, para con Dios\u2020\u009d, y como la \u2020\u0153piedra angular de fundamento\u2020\u009d en la que se puede ejercer fe sin sufrir desilusi\u00f3n. (1Pe 2:4-6; Sl 118:22; Isa 28:16.) Pablo tambi\u00e9n identific\u00f3 sin ambages a Jesucristo como el fundamento sobre el que se edifica la congregaci\u00f3n cristiana. (Ef 2:19-22; 1Co 3:11.) Adem\u00e1s, dado que pertenece a Jehov\u00e1, es apropiado que se la llame \u2020\u0153la congregaci\u00f3n de Dios\u2020\u009d. (Hch 20:28; G\u00e1l 1:13.)<br \/>\nEsta congregaci\u00f3n cristiana (gr. ek\u00c2\u00b7kle\u00c2\u00b7s\u00ed\u00ad\u00c2\u00b7a), fundada sobre Cristo, tambi\u00e9n lo tiene como cabeza. Por eso se dice: \u2020\u0153El [Dios] tambi\u00e9n sujet\u00f3 todas las cosas debajo de sus pies, y lo hizo cabeza sobre todas las cosas en cuanto a la congregaci\u00f3n, la cual es su cuerpo, la plenitud de aquel que llena todas las cosas en todos\u2020\u009d. (Ef 1:22, 23; v\u00e9ase tambi\u00e9n Col 1:18.)<br \/>\nEn Pentecost\u00e9s de 33 E.C., cuando se derram\u00f3 el esp\u00ed\u00adritu santo sobre los seguidores de Jes\u00fas en Jerusal\u00e9n, la congregaci\u00f3n cristiana de Dios sustituy\u00f3 a la de Israel. Jes\u00fas escogi\u00f3 a los que llegar\u00ed\u00adan a ser los primeros miembros de aquella congregaci\u00f3n poco despu\u00e9s de su bautismo, justo al principio de su ministerio terrestre. (Hch 2:1-4; Jn 1:35-43.) De entre sus primeros seguidores seleccion\u00f3 a los doce ap\u00f3stoles. (Lu 6:12-16.) M\u00e1s tarde, escogi\u00f3 a Saulo de Tarso, quien lleg\u00f3 a ser un \u2020\u0153ap\u00f3stol a las naciones\u2020\u009d. (Hch 9:1-19; Ro 11:13.) Los doce ap\u00f3stoles fieles del Cordero Jesucristo \u2014entre los que hay que contar a Mat\u00ed\u00adas, sustituto de Judas\u2014 constituyen fundamentos secundarios de la congregaci\u00f3n cristiana. (Hch 1:23-26; Rev 21:1, 2, 14.)<br \/>\nA esta congregaci\u00f3n se la llama \u2020\u0153la congregaci\u00f3n de los primog\u00e9nitos que han sido matriculados en los cielos\u2020\u009d, el n\u00famero total de los cuales, bajo Cristo la cabeza, es de 144.000. (Heb 12:23; Rev 7:4.) A estos llamados se les \u2020\u02dccompra de entre la humanidad\u2020\u2122 para llevar a cabo una obra especial aqu\u00ed\u00ad en la Tierra y luego estar con Cristo en los cielos como su novia. Tal como hab\u00ed\u00ada que satisfacer ciertos requisitos para pertenecer a la congregaci\u00f3n hebrea de Dios, tambi\u00e9n hay requisitos que satisfacer para formar parte de la \u2020\u02dccongregaci\u00f3n cristiana de Dios\u2020\u2122. Los que la componen son v\u00ed\u00adrgenes espirituales que van siguiendo al Cordero, Jesucristo, no importa ad\u00f3nde vaya, \u2020\u02dcy no se halla en su boca falsedad; est\u00e1n sin tacha\u2020\u2122. (Rev 14:1-5.)<br \/>\nEs Jehov\u00e1 quien escoge a los que forman parte de la congregaci\u00f3n cristiana. (Ro 8:30; 2Te 2:13.) A los primeros se les llam\u00f3 de la congregaci\u00f3n jud\u00ed\u00ada rechazada, que no hab\u00ed\u00ada aceptado al Hijo de Dios como su Mes\u00ed\u00adas. No obstante, empezando con Cornelio en 36 E.C., tambi\u00e9n se llam\u00f3 a miembros de la congregaci\u00f3n cristiana de entre las dem\u00e1s naciones, de manera que Pablo pudo decir: \u2020\u0153No hay ni jud\u00ed\u00ado ni griego, no hay ni esclavo ni libre, no hay ni var\u00f3n ni hembra; porque todos ustedes son una persona en uni\u00f3n con Cristo Jes\u00fas\u2020\u009d. (G\u00e1l 3:28; Hch 10:34, 35; Ro 10:12; Ef 2:11-16.) Cristo cumpli\u00f3 con el pacto de la Ley, del que Mois\u00e9s hab\u00ed\u00ada sido mediador y que regulaba a la congregaci\u00f3n de Israel, y Jehov\u00e1 Dios lo quit\u00f3 del camino (Mt 5:17; 2Co 3:14; Col 2:13, 14); no obstante, los miembros de la congregaci\u00f3n cristiana de Dios participan de los beneficios del nuevo pacto mediado por Jesucristo, el Mois\u00e9s Mayor. (Mt 26:28; Heb 12:22-24; Hch 3:19-23.) Asimismo, mientras que los sacerdotes y reyes de Israel eran ungidos con aceite (Ex 30:22-30; 2Re 9:6), los que Dios escoge para ser miembros de la congregaci\u00f3n cristiana son ungidos con esp\u00ed\u00adritu santo (2Co 1:21, 22; 1Jn 2:20) y Jehov\u00e1 Dios los adopta como hijos. (Ef 1:5.)<br \/>\nLa congregaci\u00f3n hebrea estaba compuesta b\u00e1sicamente de israelitas naturales. Las personas que componen la congregaci\u00f3n cristiana ungida de Dios son israelitas espirituales y forman las tribus del Israel espiritual. (Rev 7:4-8.) Puesto que la mayor\u00ed\u00ada de los israelitas naturales rechazaron a Jesucristo, \u2020\u0153no todos los que provienen de Israel son realmente \u2020\u02dcIsrael\u2020\u2122\u2020\u009d, es decir, Israel espiritual. (Ro 9:6-9.) Y con respecto a la congregaci\u00f3n cristiana de Dios compuesta de jud\u00ed\u00ados espirituales, Pablo escribi\u00f3: \u2020\u0153No es jud\u00ed\u00ado el que lo es por fuera, ni es la circuncisi\u00f3n la que est\u00e1 afuera en la carne. M\u00e1s bien, es jud\u00ed\u00ado el que lo es por dentro, y su circuncisi\u00f3n es la del coraz\u00f3n por esp\u00ed\u00adritu\u2020\u009d. (Ro 2:28, 29.)<br \/>\nCuando las Escrituras aluden a \u2020\u0153la congregaci\u00f3n\u2020\u009d en sentido general, suelen referirse a los 144.000, los seguidores ungidos de Cristo, sin incluirle a \u00e9l. (Ef 5:32; Heb 12:23, 24.) Sin embargo, en Hebreos 2:12 por inspiraci\u00f3n se aplican a Jesucristo las palabras de David registradas en el Salmo 22:22, lo que hace ver que el t\u00e9rmino \u2020\u0153congregaci\u00f3n\u2020\u009d puede incluir tambi\u00e9n a su cabeza, Jesucristo. Citando parcialmente a David, el escritor de la carta a los Hebreos dijo: \u2020\u0153Porque tanto el que est\u00e1 santificando como los que est\u00e1n siendo santificados, todos emanan de uno solo, y por esta causa \u00e9l no se averg\u00fcenza de llamarlos \u2020\u02dchermanos\u2020\u2122, como dice: \u2020\u02dcDeclarar\u00e9 tu nombre a mis hermanos; en medio de la congregaci\u00f3n te alabar\u00e9 con canci\u00f3n\u2020\u2122\u2020\u009d. (Heb 2:11, 12.) Al igual que David formaba parte de la congregaci\u00f3n de Israel, en medio de la que alababa a Jehov\u00e1, en este caso a Jesucristo se le puede considerar miembro de la congregaci\u00f3n espiritual, pues se llama a los dem\u00e1s sus \u2020\u0153hermanos\u2020\u009d. (Comp\u00e1rese con Mt 25:39, 40.) David perteneci\u00f3 a la congregaci\u00f3n israelita de Jehov\u00e1 Dios, de la que tambi\u00e9n form\u00f3 parte Jesucristo cuando estuvo en la Tierra, predicando en medio de sus miembros. Un resto de esa congregaci\u00f3n lleg\u00f3 a ser parte de la congregaci\u00f3n de Jes\u00fas.<\/p>\n<p>Organizaci\u00f3n de la congregaci\u00f3n cristiana. Aunque se fundaron congregaciones cristianas en distintos lugares, no funcionaban independientemente unas de otras. Todas reconoc\u00ed\u00adan la autoridad del cuerpo gobernante cristiano de Jerusal\u00e9n, que compon\u00ed\u00adan los ap\u00f3stoles y los ancianos de la congregaci\u00f3n de Jerusal\u00e9n, y no hab\u00ed\u00ada ning\u00fan otro cuerpo rival que intentara supervisar la congregaci\u00f3n desde otro lugar. Fue al cuerpo gobernante cristiano fiel del siglo I E.C. a quien se someti\u00f3 la cuesti\u00f3n de la circuncisi\u00f3n, y cuando este, dirigido por el esp\u00ed\u00adritu santo, tom\u00f3 una decisi\u00f3n, todas las congregaciones cristianas la aceptaron y se sometieron a ella de forma voluntaria. (Hch 15:22-31.)<br \/>\nEl cuerpo gobernante de Jerusal\u00e9n envi\u00f3 a representantes viajeros. Por ejemplo, se despach\u00f3 a Pablo y a otros cristianos para que entregaran la mencionada decisi\u00f3n del cuerpo gobernante a las congregaciones: \u2020\u0153Ahora bien, a medida que iban viajando por las ciudades entregaban a los de all\u00ed\u00ad, para que los observaran, los decretos sobre los cuales hab\u00ed\u00adan tomado decisi\u00f3n los ap\u00f3stoles y ancianos que estaban en Jerusal\u00e9n\u2020\u009d. Con respecto a los resultados, se dice: \u2020\u0153Por lo tanto, en realidad, las congregaciones continuaron haci\u00e9ndose firmes en la fe y aumentando en n\u00famero de d\u00ed\u00ada en d\u00ed\u00ada\u2020\u009d. (Hch 16:4, 5.) Cuando alg\u00fan tiempo antes los ap\u00f3stoles que estaban en Jerusal\u00e9n \u2020\u0153oyeron que Samaria hab\u00ed\u00ada aceptado la palabra de Dios, les despacharon a Pedro y a Juan; y estos bajaron y oraron para que recibieran esp\u00ed\u00adritu santo\u2020\u009d. (Hch 8:14, 15.)<br \/>\nLas congregaciones se adhirieron estrechamente a la direcci\u00f3n del cuerpo gobernante cristiano, que supervisaba el nombramiento de ancianos. (Tit 1:1, 5.) Bajo la influencia del esp\u00ed\u00adritu santo, el cuerpo gobernante dirigi\u00f3 el nombramiento de superintendentes y auxiliares \u2014siervos ministeriales\u2014 en todas ellas. Los hombres colocados en esos puestos de confianza y responsabilidad ten\u00ed\u00adan que satisfacer unos requisitos espec\u00ed\u00adficos. (1Ti 3:1-13; Tit 1:5-9.) Los representantes viajeros del cuerpo gobernante, como Pablo, siguieron los pasos de Cristo y pusieron un buen ejemplo a imitar. (1Co 11:1; Flp 4:9.) Todos los que eran pastores espirituales ten\u00ed\u00adan que hacerse \u2020\u0153ejemplos del reba\u00f1o\u2020\u009d (1Pe 5:2, 3), mostrar inter\u00e9s amoroso en los miembros de la congregaci\u00f3n (1Te 2:5-12) y ser verdaderas ayudas para los que padecieran enfermedad espiritual. (G\u00e1l 6:1; Snt 5:13-16; v\u00e9anse ANCIANO; MINISTRO; SUPERINTENDENTE.)<br \/>\nAs\u00ed\u00ad, tal como Jehov\u00e1 organiz\u00f3 a la congregaci\u00f3n de Israel bajo ancianos, cabezas, jueces y oficiales (Jos 23:2), tambi\u00e9n se preocup\u00f3 de que ancianos nombrados a puestos de confianza supervisaran la congregaci\u00f3n cristiana. (Hch 14:23.) Y tal como en ocasiones hubo hombres responsables que actuaron en representaci\u00f3n de toda la congregaci\u00f3n de Israel, como a la hora de tratar asuntos judiciales (Dt 16:18), Dios dispuso que de igual manera toda congregaci\u00f3n cristiana estuviera representada en tales asuntos por hombres responsables colocados en posiciones de autoridad por el esp\u00ed\u00adritu santo. (Hch 20:28; 1Co 5:1-5.) Sin embargo, cuando surg\u00ed\u00adan dificultades personales entre los miembros de la congregaci\u00f3n de Dios, las palabras de Jesucristo registradas en Mateo 18:15-17 (pronunciadas antes de que Dios rechazara a la congregaci\u00f3n jud\u00ed\u00ada y, por lo tanto, en un principio aplicables a ella) sirvieron de base para zanjar o tratar tales problemas.<br \/>\nJehov\u00e1 Dios coloc\u00f3 a los miembros del \u2020\u0153cuerpo\u2020\u009d espiritual \u2020\u0153as\u00ed\u00ad como le agrad\u00f3\u2020\u009d. Pablo escribi\u00f3: \u2020\u0153Dios ha colocado a las personas respectivas en la congregaci\u00f3n: primero, ap\u00f3stoles; segundo, profetas; tercero, maestros; luego obras poderosas; luego dones de curaciones; servicios de ayuda, capacidades directivas, diferentes lenguas\u2020\u009d. No todos llevaban a cabo las mismas funciones, pero todos eran necesarios en la congregaci\u00f3n cristiana. (1Co 12:12-31.) Pablo explic\u00f3 que el que se suministrara a la congregaci\u00f3n cristiana ap\u00f3stoles, profetas, evangelizadores, pastores y maestros era \u2020\u0153con miras al reajuste de los santos, para obra ministerial, para la edificaci\u00f3n del cuerpo de Cristo, hasta que todos logremos alcanzar la unidad en la fe y en el conocimiento exacto del Hijo de Dios, a un hombre hecho, a la medida de estatura que pertenece a la plenitud del Cristo\u2020\u009d. (Ef 4:11-16.)<br \/>\nDios dio sus leyes a la congregaci\u00f3n de Israel y le hizo ver que \u2020\u0153no solo de pan vive el hombre, sino que de toda expresi\u00f3n de la boca de Jehov\u00e1 vive el hombre\u2020\u009d. (Dt 8:1-3.) Jesucristo tambi\u00e9n reconoci\u00f3 que el hombre no viv\u00ed\u00ada solo de pan, \u2020\u0153sino de toda expresi\u00f3n que sale de la boca de Jehov\u00e1\u2020\u009d. (Mt 4:1-4.) De modo que se ha hecho la provisi\u00f3n adecuada para que la congregaci\u00f3n cristiana tenga el alimento espiritual que necesita; Cristo mismo habl\u00f3 del \u2020\u0153esclavo\u2020\u009d mediante el que se dispensar\u00ed\u00ada tal alimento a los \u2020\u0153dom\u00e9sticos\u2020\u009d cristianos. Como parte de su profec\u00ed\u00ada acerca de su presencia y de \u2020\u0153la conclusi\u00f3n del sistema de cosas\u2020\u009d, mostr\u00f3 que cuando el \u2020\u0153amo\u2020\u009d llegara, nombrar\u00ed\u00ada a este \u2020\u0153esclavo fiel y discreto\u2020\u009d \u2020\u0153sobre todos sus bienes\u2020\u009d. (Mt 24:3, 45-47.)<br \/>\nEn la congregaci\u00f3n de Israel eran importantes las reuniones para adorar a Jehov\u00e1 y examinar su ley. (Dt 31:12; Ne 8:1-8.) De igual manera, las reuniones para la adoraci\u00f3n de Jehov\u00e1 y el estudio de las Escrituras son un rasgo esencial de la congregaci\u00f3n cristiana de Dios, por lo que el escritor de la carta a los Hebreos advirti\u00f3 a los receptores de esta que no abandonaran el reunirse. (Heb 10:24, 25.) Con el tiempo los jud\u00ed\u00ados usaron sus sinagogas para leer y ense\u00f1ar las Escrituras, ofrecer oraciones y dar alabanza a Dios. Estas costumbres pasaron a los lugares de reuni\u00f3n cristianos, aunque desprovistas del elemento ritualista que con el tiempo lleg\u00f3 a existir en los servicios de las sinagogas. En la sinagoga no hab\u00ed\u00ada ninguna clase sacerdotal separada, sino que cualquier var\u00f3n jud\u00ed\u00ado devoto pod\u00ed\u00ada participar en la lectura y comentario de las Escrituras. De igual manera, la congregaci\u00f3n cristiana primitiva carec\u00ed\u00ada de la distinci\u00f3n entre clero y legos. Por supuesto, ni en la congregaci\u00f3n ni en la sinagoga pod\u00ed\u00ada la mujer ense\u00f1ar o ejercer autoridad sobre el var\u00f3n. (1Ti 2:11, 12.)<br \/>\nEl mantenimiento del orden apropiado en las reuniones de la congregaci\u00f3n cristiana de Dios estaba de acuerdo con el hecho de que Jehov\u00e1, quien dispuso que los seguidores de Cristo fueran una congregaci\u00f3n, \u2020\u0153no es Dios de desorden, sino de paz\u2020\u009d. Este orden tambi\u00e9n obraba para el completo beneficio espiritual de todos los asistentes. (1Co 14:26-35, 40; v\u00e9ase ASAMBLEA.)<\/p>\n<p><b>Fuente: Diccionario de la Biblia<\/b><\/p>\n<p>>edah (jd;[e , 5712) \u00abcongregaci\u00f3n\u00bb. Etimol\u00f3gicamente, este vocablo significar\u00ed\u00ada una \u00abcongregaci\u00f3n de personas\u00bb reunidas con alg\u00fan prop\u00f3sito. Se asemeja en esto a los t\u00e9rminos griegos synagoge y ekklesia, de los cuales provienen \u00absinagoga\u00bb e \u00abiglesia\u00bb. En uso corriente, >edah se refiere a un \u00abgrupo de personas\u00bb. Aparece 140 veces en el Antiguo Testamento, con mayor frecuencia en el libro de N\u00fameros. Aparece por primera vez en Exo 12:3, donde el t\u00e9rmino es un sin\u00f3nimo de qahal, \u00abasamblea\u00bb. La acepci\u00f3n m\u00e1s generalizada de >edah es \u00abgrupo\u00bb, ya sea de animales (un enjambre de abejas [Jdg 14:8], una manada de toros [Psa 68:30], una bandada de aves [Hos 7:12]) o de personas, por ejemplo de justos (Psa 1:5), malhechores (Psa 22:16) y de naciones (Psa 7:7). Las menciones m\u00e1s frecuentes son de la \u00abcongregaci\u00f3n de Israel\u00bb (9 veces), \u00abla congregaci\u00f3n de los hijos de Israel\u00bb (26 veces), \u00abla congregaci\u00f3n\u00bb (24 veces) o \u00abtoda la congregaci\u00f3n\u00bb (30 veces). Mois\u00e9s coloc\u00f3 a ancianos (Lev 4:15), cabezas de familia (Num 31:26) y pr\u00ed\u00adncipes (Num 16:2; 31.13; 32.2) sobre la \u00abcongregaci\u00f3n\u00bb con el fin de ayudarle con un gobierno justo. La Septuaginta traduce el t\u00e9rmino como synagoge (\u00ablugar de asamblea\u00bb). La rv, en sus varias revisiones, lo traduce como \u00abconcurso\u00bb y \u00abcongregaci\u00f3n\u00bb; otras versiones usan los t\u00e9rminos \u00abasamblea\u00bb (bj, nbe), \u00abcomunidad\u00bb (bla) y \u00abpueblo\u00bb (lvp). mo\u00ed\u2020>ed (d[e\/m , 4150), \u00ablugar acordado de reuni\u00f3n, reuni\u00f3n\u00bb. El nombre mo\u00ed\u2020>ed se encuentra 223 veces en el Antiguo Testamento y en el Pentateuco 160. En orden de frecuencia, aparece 27 veces en los libros hist\u00f3ricos. La palabra mo\u00ed\u2020>ed conserva su significado b\u00e1sico se\u00f1alado, pero var\u00ed\u00ada en lo acordado seg\u00fan el contexto: tiempo y lugar o bien la propia reuni\u00f3n. El uso del t\u00e9rmino en Am\u00f3s 3.3 es revelador: \u00ab\u00bfAndar\u00e1n dos juntos, a menos que se pongan de acuerdo?\u00bb El contexto es ambiguo. No est\u00e1 claro si hay acuerdo sobre tiempo y lugar de reuni\u00f3n, ni si aun se va a realizar. El significado de mo\u00ed\u2020>ed se encuadra dentro del contexto de la religi\u00f3n de Israel. En primer t\u00e9rmino, las fiestas llegaron a conocerse como \u00abfiestas se\u00f1aladas\u00bb o prefijadas. Estas fiestas se establecieron claramente en el Pentateuco. El t\u00e9rmino se refiere a cualquier \u00abfiesta\u00bb o peregrinaje festivo, como la Pascua o la Fiesta de las Primicias (Lev 23:15  ), la Fiesta de los Tabern\u00e1culos (Lev 23:33  ) o el D\u00ed\u00ada de Expiaci\u00f3n (Lev 23:27). Al mismo tiempo, Dios condena a las personas que observan el mo\u00ed\u2020>ed con excesivo ritualismo: \u00abVuestras lunas nuevas y vuestras fiestas se\u00f1aladas las aborrece mi alma; se han vuelto una carga para m\u00ed\u00ad, estoy cansado de soportarlas\u00bb (Isa 1:14 lba). El vocablo mo\u00ed\u2020>ed tambi\u00e9n significa un \u00ablugar determinado\u00bb. Este uso es menos frecuente: \u00abT\u00fa has dicho en tu coraz\u00f3n: Subir\u00e9 al cielo en lo alto; hasta las estrellas de Dios levantar\u00e9 mi trono y me sentar\u00e9 en el monte de la asamblea [mo\u00ed\u2020>ed], en las regiones m\u00e1s distantes del norte\u00bb (Isa 14:13 rva). \u00abPorque yo s\u00e9 que me conduces a la muerte, y a la casa determinada a todo viviente\u00bb (Job 30:23). En ambas acepciones de mo\u00ed\u2020>ed \u00abtiempo fijado\u00bb y \u00ablugar fijado\u00bb, el denominador com\u00fan es la \u00abreuni\u00f3n\u00bb de dos o m\u00e1s personas en determinado lugar y tiempo; de ah\u00ed\u00ad el uso de mo\u00ed\u2020>ed como simple \u00abreuni\u00f3n\u00bb. Sin embargo, la similitud entre los significados de \u00abtiempo fijo\u00bb, \u00ablugar fijo\u00bb y \u00abreuni\u00f3n\u00bb causa verdaderos problemas de traducci\u00f3n en cada contexto. Por ejemplo, \u00abcontra m\u00ed\u00ad convoc\u00f3 una asamblea\u00bb (Lam 1:15 rva), podr\u00ed\u00ada leerse: \u00abHa convocado contra m\u00ed\u00ad un tiempo determinado\u00bb (lba) o \u00abLlam\u00f3 contra m\u00ed\u00ad compa\u00f1\u00ed\u00ada\u00bb (rv). La frase \u00abtabern\u00e1culo de testimonio\u00bb (rv) es una traducci\u00f3n del hebreo <ohel mo\u00ed\u2020>ed (\u00abtabern\u00e1culo de reuni\u00f3n\u00bb rva; \u00abtienda de reuni\u00f3n\u00bb lba). La frase aparece 139 veces, sobre todo en Exodo, Lev\u00ed\u00adtico y N\u00fameros, pocas veces en Deuteronomio. Significa que el Se\u00f1or tiene un \u00ablugar designado\u00bb que representa su presencia y por medio del cual Israel tiene la certeza de que su Dios est\u00e1 con ellos. El hecho de que el espacio se denomin\u00f3 \u00abtienda de reuni\u00f3n\u00bb significa que el Dios de Israel estar\u00ed\u00ada entre su pueblo y que el pueblo se aproximar\u00ed\u00ada a El en un tiempo y espacio \u00abfijado\u00bb (ya>ad) en el Pentateuco. Cuando los traductores se dieron cuenta de que el nombre >edah (\u00abcongregaci\u00f3n\u00bb o \u00abreuni\u00f3n\u00bb) procede de la misma ra\u00ed\u00adz que mo\u00ed\u2020>ed, escogieron la frase \u00abtabern\u00e1culo de reuni\u00f3n\u00bb (Exo 28:43). Los traductores de la Septuaginta enfrentaron una dificultad similar. Notaron la relaci\u00f3n de mo\u00ed\u2020>ed con la ra\u00ed\u00adz >u\u00ed\u2020d (\u00abtestificar\u00bb), por lo que tradujeron la frase <ohel hamo\u00ed\u2020>ed como \u00abtabern\u00e1culo del testimonio\u00bb. Esta frase se acogi\u00f3 en el Nuevo Testamento: \u00abDespu\u00e9s de esto mir\u00e9, y el santuario del tabern\u00e1culo del testimonio fue abierto en el cielo\u00bb (Rev 15:5). De los tres significados, el m\u00e1s fundamental es \u00abtiempo determinado\u00bb. Porque la frase \u00abtienda de reuni\u00f3n\u00bb enfatiza el \u00ablugar de reuni\u00f3n\u00bb. La \u00abreuni\u00f3n\u00bb en s\u00ed\u00ad generalmente se asocia con \u00abtiempo\u00bb y \u00ablugar\u00bb. La Septuaginta contiene las siguientes traducciones de mo\u00ed\u2020>ed: kairos (\u00abtiempo\u00bb), eorte (\u00abfiesta; festival\u00bb). Las traducciones cat\u00f3licas usan: \u00abtienda del encuentro\u00bb (nbe, cf. lvp), \u00abtienda de reuni\u00f3n\u00bb (bj), \u00abtienda de las citas divinas\u00bb (bla).<\/p>\n<p><b>Fuente: Diccionario Vine Antiguo Testamento<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>v. Asamblea, Iglesia, Reuni\u00f3n Lev 4:13 si toda la c de Israel hubiere errado Lev 8:3 re\u00fane toda la c a la puerta del tabern\u00e1culo Num 14:5 Mois\u00e9s y .. se postraron delante de la c Num 16:3 toda la c, todos ellos son santos, y en Psa 7:7 te rodear\u00e1 c de pueblos, y &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/congregacion\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCONGREGACION\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5898","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/5898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=5898"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/5898\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=5898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=5898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=5898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}