{"id":5940,"date":"2016-02-05T02:14:29","date_gmt":"2016-02-05T07:14:29","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/cultivos\/"},"modified":"2016-02-05T02:14:29","modified_gmt":"2016-02-05T07:14:29","slug":"cultivos","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/cultivos\/","title":{"rendered":"CULTIVOS"},"content":{"rendered":"<p>La agricultura era el trasfondo de toda la legislaci\u00f3n de Israel. En la \u00e9poca de la conquista es probable que cada familia haya recibido una porci\u00f3n de tierra, marcada por piedras que no pod\u00ed\u00adan moverse legalmente (Deu 19:14; Deu 27:17; Hos 5:10). En general el suelo de Palestina era f\u00e9rtil. El abonar era casi desconocido. Para mantener la fertilidad del suelo, la ley exig\u00ed\u00ada que las granjas, los vi\u00f1edos y los olivares estuvieran en barbecho el s\u00e9ptimo a\u00f1o (Exo 23:10). En el a\u00f1o del Jubileo los que hab\u00ed\u00adan perdido sus tierras ancestrales las recuperaban. Era necesario formar gradas para poder utilizar el suelo en las colinas. No hac\u00ed\u00ada falta irrigaci\u00f3n ya que hab\u00ed\u00ada suficiente lluvia.<\/p>\n<p>Se araba para preparar el suelo para la siembra en el oto\u00f1o, cuando las lluvias tempranas ablandaban el suelo que se hab\u00ed\u00ada vuelto duro como una piedra con el sol estival. Se hac\u00ed\u00ada con un arado primitivo de madera tirado por bueyes o, si hab\u00ed\u00ada poco suelo, con un azad\u00f3n. Con estos implementos apenas se escarbaba la superficie del suelo, tal vez 8 o 10 cm. Se gradaba poco y probablemente se des conoc\u00ed\u00ada en la \u00e9poca temprana de Palestina.<\/p>\n<p>Se sembraba el grano estival entre fines de enero y fines de febrero.<\/p>\n<p>Generalmente se dispersaba la semilla a mano desde un cesto, pero los granjeros cuidadosos la pon\u00ed\u00adan en surcos y en filas (Isa 28:25). Entre la siembra y la siega los cultivos estaban expuestos a varios peligros:<br \/>\n( 1 )  La falta de lluvia tard\u00ed\u00ada (en marzo y abril),<br \/>\n( 2 )  vientos orientales calurosos y secos (frecuentemente en marzo y abril, Gen 41:6),<br \/>\n( 3 )  granizo (Hageo 2:17),<br \/>\n( 4 )  varios tipos de malezas (ciza\u00f1a, espinas, Jer 12:13; Mat 13:7, Mat 13:25),<br \/>\n( 5 )  plagas de insectos, especialmente el gusano de palmar, el gusano del cancro, la oruga y la langosta (Amo 7:2),<br \/>\n( 6 )  hurtos por cuervos y gorriones (Mat 13:4) y<br \/>\n( 7 )  hongos, especialmente el tiz\u00f3n (Deu 28:22). Cuando se acercaba la \u00e9poca de la cosecha se pon\u00ed\u00adan vigilantes para proteger las cosechas valiosas (Jer 4:17) pero la ley permit\u00ed\u00ada que una persona hambrienta recogiera granos al pasar (Deu 23:25; Mat 12:1).<\/p>\n<p>Se trillaba el grano al aire libre, una costumbre posibilitada por la falta de lluvia en la \u00e9poca de la cosecha (2Ki 13:7). Durante la \u00e9poca de la trilla los cosechadores vigilaban el grano pasando la noche en la era (Rth 3:6). Se aventaba el grano tirando el grano y la paja en el aire con un tenedor o una pala de madera para que el viento se llevara la paja. Generalmente se hac\u00ed\u00ada de noche para aprovechar las brisas nocturnas. Se quemaba la paja o se dejaba que el viento la dispersara. Entonces se cern\u00ed\u00ada el grano (para quitar las piedras y dem\u00e1s impurezas) y se juntaba en pozos o graneros (Luk 12:18).<\/p>\n<p>Del gran n\u00famero de cultivos producidos por los israelitas, el trigo y la cebada eran los m\u00e1s importantes. Tambi\u00e9n cultivaban centeno, mijo, lino y una variedad de hortalizas. Ver AGRICULTURA.<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Mundo Hispano<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La agricultura era el trasfondo de toda la legislaci\u00f3n de Israel. En la \u00e9poca de la conquista es probable que cada familia haya recibido una porci\u00f3n de tierra, marcada por piedras que no pod\u00ed\u00adan moverse legalmente (Deu 19:14; Deu 27:17; Hos 5:10). En general el suelo de Palestina era f\u00e9rtil. El abonar era casi desconocido. &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/cultivos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCULTIVOS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5940","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/5940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=5940"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/5940\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=5940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=5940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=5940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}