{"id":5963,"date":"2016-02-05T02:17:03","date_gmt":"2016-02-05T07:17:03","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/dios-no-conocido\/"},"modified":"2016-02-05T02:17:03","modified_gmt":"2016-02-05T07:17:03","slug":"dios-no-conocido","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/dios-no-conocido\/","title":{"rendered":"DIOS NO CONOCIDO"},"content":{"rendered":"<p>Estas palabras aparecen solo en Act 17:23.<\/p>\n<p>Este probablemente era un altar votivo, levantado por alg\u00fan adorador que no sab\u00ed\u00ada a qu\u00e9 dios agradecer por alg\u00fan beneficio que hab\u00ed\u00ada recibido.<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Mundo Hispano<\/b><\/p>\n<p><p style=\"text-align: justify;\">(Griego <em>agn\u014dstos zeos<\/em>). Esta frase se encuentra s\u00f3lo una vez en el NT, en Hechos 17:23. Como en el griego no existe el art\u00edculo definido, la traducci\u00f3n \u00aba un dios no conocido\u00bb es m\u00e1s exacta que \u00abal dios no conocido\u00bb, como la traduce la <a href=\"#_ftn1\" name=\"_ftnref1\">AV<\/a>. Se ha debatido mucho sobre la fuente exacta de la cual Pablo tom\u00f3 la frase. Pausanias (i, 1, y v, 14, 8) del siglo segundo d.C. y otros despu\u00e9s de \u00e9l mencionaron altares \u00aba dioses no conocidos\u00bb en Atenas y alrededor de ella. Deismann argumenta m\u00e1s convincentemente que una inscripci\u00f3n mutilada hallada en P\u00e9rgamo, probablemente para ser fechada en el siglo segundo d.C., deber\u00eda ser le\u00edda \u00aba dioses no conocidos\u00bb. Di\u00f3genes Laertius (I. 110) cuenta la historia de c\u00f3mo en Atenas se extermin\u00f3 una plaga, siguiendo las advertencias de Epim\u00e9nides, qui\u00e9n dijo a los atenienses que soltaran ovejas en el Are\u00f3pago, y en cualquier lugar donde ellas se echaran, hicieran sacrificio \u00abal dios apropiado\u00bb, evidentemente que cualquier dios no conocido era responsable de haber enviado la plaga. Pablo pudo haber visto un altar actual con la inscripci\u00f3n \u00aba un dios no conocido\u00bb, aunque pudo haber adaptado el plural a singular de acuerdo al prop\u00f3sito de su alocuci\u00f3n al Are\u00f3pago. De todos modos \u00e9l emple\u00f3 el concepto de un dios desconocido como un punto de contacto m\u00e1s efectivo para presentar al Dios vivo y verdadero a los griegos.<\/p>\n<p style=\"text-align: justify;\">BIBLIOGRAF\u00cdA<\/p>\n<ol style=\"text-align: justify;\" start=\"23\">\n<li>Deissmann, <em>St. Paul<\/em>, Appendix II; <a href=\"#_ftn2\" name=\"_ftnref2\">Arndt<\/a>, bajo <em>agnwstos<\/em>; G.H.C. Macgregor en <em><a href=\"#_ftn3\" name=\"_ftnref3\">IB<\/a><\/em> sobre Acts 17:23.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Samuel A. Cartledge<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftn4\" name=\"_ftnref4\"><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\">AV <\/a>Authorized Version<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref2\" name=\"_ftn2\">Arndt <\/a>Arndt-Gingrich, <em>Greek-English Lexicon<\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref3\" name=\"_ftn3\"><em>IB <\/em><\/a><em>Interpreter\u2019s Bible<\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref4\" name=\"_ftn4\"><\/a>Harrison, E. F., Bromiley, G. W., &amp; Henry, C. F. H. (2006). <em>Diccionario de Teologi\u0301a<\/em> (179). Grand Rapids, MI: Libros Desafi\u0301o.<\/p>\n<\/p>\n<p><b>Fuente: Diccionario de Teolog\u00eda<\/b><\/p>\n<p><p style='text-align:justify;'><span lang=ES style=''>(gr. <\/span><span style=''>agn&#333;stos theos<\/span><span lang=ES style=''>). En Hch. 17.23 Pablo hace referencia a la dedicatoria en un altar ateniense, \u201cal Dios no conocido\u201d, frase que adopta como tema de su discurso en el *Are\u00f3pago. Pausanias (<i>Descripci\u00f3n de Grecia<\/i>, 1.1.4) dice que en Atenas hay \u201caltares de dioses denominados desconocidos\u201d, y Fil\u00f3strato (<i>Vida de Apolonio y Tiana<\/i>, 6.3.5) habla en forma semejante de \u201caltares de divinidades desconocidas\u201d que exist\u00edan all\u00ed. Frecuentemente se los asocia con el relato que hace Di\u00f3genes Laercio (<i>Vidas de fil\u00f3sofos<\/i>, 1.110) sobre la erecci\u00f3n de \u201caltares an\u00f3nimos\u201d en Atenas y los alrededores en cierta ocasi\u00f3n, con el fin de impedir una peste. Dedicaciones semejantes se han constatado en otras partes, en casos en que el nombre de alguna deidad local fuera incierto, o cuando se hab\u00eda perdido la inscripci\u00f3n de alguna dedicaci\u00f3n original.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=';text-transform:uppercase'>Bibliograf\u00eda.<\/span><span lang=ES style=''> H. Metzger, <i>Las rutas de san Pablo en el oriente griego<\/i>, 1962, pp. 36\u201341; G. B\u00e1ez Camargo, <i>Comentario arqueol\u00f3gico de la Biblia<\/i>, 1979, pp. 281; P. Esterlrich, \u201cDios desconocido\u201d, <i>\u00b0EBDM<\/i>, t(t). II, cols. 958\u2013960.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal style='margin-bottom:0cm;margin-bottom:.0001pt;text-indent: 18.0pt;line-height:normal'><span lang=ES style=''>E. Norden, <i>agnostos Theos<\/i>, 1912; K. Lake, \u201c<i>The Unknown God<\/i>\u201d, en <etiqueta id=\"#_ftn354\" name=\"_ftnref354\" title=\"\"><i>BC<\/i><\/etiqueta>, 5, pp. 240\u2013246; B. G\u00e4rtner, <i>The Aeropagus Speech and Natural Revelation<\/i>, 1955, pp. 242ss; E. Haenchen, <i>The Acts of the Apostles<\/i>, 1971, pp. 516ss.<\/span><\/p>\n<p style='text-align:justify;' class=MsoNormal align=right style='text-align:right;line-height:normal'><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><etiqueta id=\"#_ftn355\" name=\"_ftnref355\" title=\"\"><span lang=ES style='font-size:10.0pt; ;color:green'>F.F.B.<\/span><\/etiqueta><span lang=ES style='font-family:\"Tahoma\",sans-serif'>&#65279;<\/span><\/p>\n<p style='text-align:justify;'>Douglas, J. (2000). Nuevo diccionario Biblico : Primera Edicion. Miami: Sociedades B\u00edblicas Unidas.<\/p>\n<\/p>\n<p><b>Fuente: Nuevo Diccionario B\u00edblico<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estas palabras aparecen solo en Act 17:23. Este probablemente era un altar votivo, levantado por alg\u00fan adorador que no sab\u00ed\u00ada a qu\u00e9 dios agradecer por alg\u00fan beneficio que hab\u00ed\u00ada recibido. Fuente: Diccionario B\u00edblico Mundo Hispano (Griego agn\u014dstos zeos). Esta frase se encuentra s\u00f3lo una vez en el NT, en Hechos 17:23. Como en el griego &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/dios-no-conocido\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDIOS NO CONOCIDO\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5963","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/5963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=5963"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/5963\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=5963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=5963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=5963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}