{"id":5966,"date":"2016-02-05T02:17:19","date_gmt":"2016-02-05T07:17:19","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/diacono-diaconisa\/"},"modified":"2016-02-05T02:17:19","modified_gmt":"2016-02-05T07:17:19","slug":"diacono-diaconisa","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/diacono-diaconisa\/","title":{"rendered":"DIACONO, DIACONISA"},"content":{"rendered":"<p>(gr., diakonos, siervo, ministro). Pablo us\u00f3 la palabra gr. para referirse a s\u00ed\u00ad mismo (1Co 3:5; Eph 3:7). Se declar\u00f3 que Jes\u00fas era un diakonos de los jud\u00ed\u00ados (Rom 15:8). Los siervos dom\u00e9sticos eran diakonoi (Mat 22:13). Pablo le dijo a Timoteo c\u00f3mo ser un buen diakonos (1Ti 4:6).<\/p>\n<p>Se infiere el diaconado, como puesto eclesi\u00e1stico, de Act 6:1-8, pero por lo menos dos de los siete hombres eran evangelistas. Las calificaciones dadas en 1 Timoteo 3 muestran que no se consideraba que los di\u00e1conos fueran miembros laicos comunes de la iglesia. Pablo menciona a los di\u00e1conos en conexi\u00f3n con los obispos (Phi 1:1).<\/p>\n<p>Se utiliza la misma palabra gr. en relaci\u00f3n a Febe en Rom 16:1, traducida por \u2020\u0153sierva\u2020\u009d o diaconisa. Ciertas mujeres ministraron (diakonein) a Jes\u00fas (Luk 8:2-3). No parece por las Escrituras ni por la literatura temprana de la iglesia que las diaconisas hayan sido oficiales de la iglesia.<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Mundo Hispano<\/b><\/p>\n<p>(Servidor) Hec 6:1-8, Fil.l:l.<\/p>\n<p> &#8211; Cualidades.<\/p>\n<p> 1Ti 3:8-13.<\/p>\n<p> &#8211; Diaconisa Febe: Rom 16:1-3, 1Ti 3:11.<\/p>\n<p>Diccionario B\u00ed\u00adblico Cristiano<br \/>\nDr. J. Dominguez<\/p>\n<p>http:\/\/biblia.com\/diccionario\/<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Cristiano<\/b><\/p>\n<p>El t\u00e9rmino griego diakoneo significa servir, como en Mat 4:11 (\u2020\u0153&#8230; los \u00e1ngeles llegaron y le serv\u00ed\u00adan [diakoneo]\u2020\u009d) y en muchas otras partes del NT. Diakon\u00ed\u00ada, a su vez, significa \u2020\u0153servicio, ministerio\u2020\u009d. As\u00ed\u00ad, \u2020\u00a2Marta \u2020\u0153se preocupaba con muchos quehaceres [diakon\u00ed\u00ada]\u2020\u009d (Luc 10:40). Esta palabra es utilizada mayormente por Pablo para se\u00f1alar su ministerio, como en Hch 20:24 (\u2020\u0153el ministerio [diakon\u00ed\u00ada] que recib\u00ed\u00ad del Se\u00f1or\u2020\u009d). Al que serv\u00ed\u00ada en un banquete se le llamaba diakonos (servidor, ministro). El Se\u00f1or dijo: \u2020\u0153El que quiera hacerse grande entre vosotros ser\u00e1 vuestro servidor [diakonos]\u2020\u009d (Mat 20:26). Pablo usa esta palabra para referirse a s\u00ed\u00ad mismo (\u2020\u0153\u00bfQu\u00e9, pues, es Pablo, y qu\u00e9 es Apolos? Servidores [diakonos] por medio de los cuales hab\u00e9is cre\u00ed\u00addo\u2020\u009d (1Co 3:5). No hay ning\u00fan se\u00f1alamiento b\u00ed\u00adblico directo en relaci\u00f3n con una subordinaci\u00f3n jer\u00e1rquica de los llamados di\u00e1conos o ministros ante otros, como los obispos (gr.=episkopos). Los \u2020\u0153obispos y di\u00e1conos\u2020\u009d son oficios relacionados, como puede verse en Flp 1:1 y en 1Ti 3:1-13, pero no se habla de ellos con la idea de establecer una jeraqu\u00ed\u00ada en la cual uno sea superior al otro.<\/p>\n<p>Es opini\u00f3n de muchos que la elecci\u00f3n de siete hermanos en Hch. 6 para \u2020\u0153servir [diakoneo] a las mesas\u2020\u009d marca el principio de un oficio especial en la iglesia que \u00e9sta denomin\u00f3 \u2020\u0153d.,\u2020\u009d transliterando la palabra del griego. La pr\u00e1ctica posapost\u00f3lica sigui\u00f3 ese patr\u00f3n. La idea que prevalec\u00ed\u00ada era la de dedicar personas a trabajos administrativos que dejaran en libertad a otros para persistir \u2020\u0153en la oraci\u00f3n y en el ministerio [diakon\u00ed\u00ada] de la palabra\u2020\u009d (Hch 6:4). Hay que observar, sin embargo, que Esteban, que era uno de los siete, \u2020\u0153lleno de gracia y de poder, hac\u00ed\u00ada grandes prodigios y se\u00f1ales entre el pueblo\u2020\u009d, predic\u00f3 un magn\u00ed\u00adfico serm\u00f3n (Hch 6:8; Hch 7:2-60). De manera que no es claro que en el principio fuera la intenci\u00f3n el limitar los di\u00e1conos a servicios administrativos o de acci\u00f3n social. Pero en el desarrollo posterior en la iglesia esto parece que fue as\u00ed\u00ad, como se atestigua en documentos del Siglo I y II. Los requisitos para ser obispo y d. aparecen en 1Ti 3:1-13.<br \/>\n\u00fanico caso de una mujer di\u00e1cono de que se tiene noticia en la Biblia es el de \u2020\u00a2Febe. De ella dice Pablo en Rom 16:1 : \u2020\u0153Os recomiendo &#8230; nuestra hermana Febe, la cual es d. de la iglesia en Cencrea\u2020\u009d. Algunos piensan que esta referencia a Febe no se\u00f1ala ning\u00fan cargo oficial sino que es una simple declaraci\u00f3n de su car\u00e1cter y comportamiento como sierva. La palabra \u2020\u0153diaconisa\u2020\u009d no es usada en femenino, sino simplemente diakonos. El uso del t\u00e9rmino femenino fue un desarrollo posterior en la historia de la iglesia. Esta participaci\u00f3n de mujeres en el oficio de d. no prosper\u00f3 mucho en la iglesia cat\u00f3lica, pero s\u00ed\u00ad en otras tradiciones cristianas, especialmente en la oriental. Las mujeres d. eran nombradas, entre otras cosas, para instruir a otras mujeres en la fe, bautizarlas y visitar las casas dedicadas s\u00f3lo a mujeres.<\/p>\n<p><b>Fuente: Diccionario de la Biblia Cristiano<\/b><\/p>\n<p>tip, FUNC<\/p>\n<p>vet, Este nombre se aplica generalmente a los siete que fueron elegidos para supervisar la distribuci\u00f3n de los fondos de la iglesia en Hch. 6:3; pero all\u00ed\u00ad no se les llama di\u00e1conos; aunque el nombre pueda serles aplicado no puede quedar restringido a aquel servicio. El t\u00e9rmino se aplica a cualquier servicio no especificado. La palabra griega es mucho m\u00e1s frecuentemente traducida \u00absiervo\u00bb y \u00abministro\u00bb que \u00abdi\u00e1cono\u00bb. Se refiere dos veces a Cristo (Ro. 15:8; G\u00e1. 2:17), tambi\u00e9n a Pablo y a otros (Col. 1:7, 23, 25), a magistrados (Ro. 13:4) e incluso a los emisarios de Satan\u00e1s (2 Co. 11:15). La Ep\u00ed\u00adstola a los Filipenses fue dirigida a los santos y a los \u00abobispos y di\u00e1conos\u00bb, o supervisores y siervos. En 1 Ti. 3:8-13 se dan las calificaciones morales del di\u00e1cono o ministro, pero no se especifica cu\u00e1l fuera su obra; es evidente que llevaban a cabo sus funciones de una forma oficial. El servicio de un di\u00e1cono no debe ser confundido con un \u00abdon\u00bb. Febe era diaconisa de la asamblea de Cencrea (Ro. 16:1).<\/p>\n<p><b>Fuente: Nuevo Diccionario B\u00edblico Ilustrado<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(gr., diakonos, siervo, ministro). Pablo us\u00f3 la palabra gr. para referirse a s\u00ed\u00ad mismo (1Co 3:5; Eph 3:7). Se declar\u00f3 que Jes\u00fas era un diakonos de los jud\u00ed\u00ados (Rom 15:8). Los siervos dom\u00e9sticos eran diakonoi (Mat 22:13). Pablo le dijo a Timoteo c\u00f3mo ser un buen diakonos (1Ti 4:6). Se infiere el diaconado, como puesto &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/diacono-diaconisa\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDIACONO, DIACONISA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5966","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/5966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=5966"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/5966\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=5966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=5966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=5966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}