{"id":7737,"date":"2016-02-05T04:08:45","date_gmt":"2016-02-05T09:08:45","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/nabonido-nabunaid\/"},"modified":"2016-02-05T04:08:45","modified_gmt":"2016-02-05T09:08:45","slug":"nabonido-nabunaid","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/nabonido-nabunaid\/","title":{"rendered":"NABONIDO, NABUNAID"},"content":{"rendered":"<p>Nabonido o Nabunaid fue el \u00faltimo rey del imperio neobabil\u00f3nico (*caldeo), quien gobern\u00f3 desde el 555 hasta el 539  a. de J.C.  La as\u00ed\u00ad llamada cr\u00f3nica de Nabonido, publicada primero por T. G. Pinches en 1882, relata ciertos eventos desde el a\u00f1o de la ascensi\u00f3n de Nabonido hasta la ca\u00ed\u00adda de *Babilonia. En ella se dice que el rey estaba en Teima en Arabia durante los a\u00f1os s\u00e9ptimo, noveno, d\u00e9cimo y d\u00e9cimoprimero de su reinado y que su hijo Belsasar (Bel-sar-usur) qued\u00f3 a cargo del gobierno. Nabonido permaneci\u00f3 como rey, pero Belsasar sirvi\u00f3 como regente. En octubre de 539  a. de J.C. , Babilonia cay\u00f3 ante los persas cuando Gobryas (Ugbaru) y el ej\u00e9rcito de Ciro entraron en Babilonia sin una pelea. Nabonido fue arrestado cuando regres\u00f3 a Babilonia. El cap\u00ed\u00adtulo 5 de Daniel relata el suceso de la ca\u00ed\u00adda de Babilonia despu\u00e9s de la fiesta imp\u00ed\u00ada de Belsasar, quien fue ejecutado por los persas cuando entraron en la ciudad.<br \/>\nBIBLIOGRAFIA: J. V. Schiel, \u2020\u0153Inscription de Nabonide\u2020\u009d, Recueil de Travaux Relatifs a la Philologie et \u00e1 l\u2020\u2122archeologie egypiennes et assyriennes, XVIII, 1896, p\u00e1gs. 15\u201329. Raymond P. Dougherty, Nabonidus and Belshazzar, Yale University Press, New Haven, 1929. A. Leo Oppenheim,  ANET , p\u00e1gs. 305\u2013306. C. J. Gadd, \u2020\u0153The Haran Inscription of Nabonidus\u2020\u009d, Anatolian Studies, VIII, 1958, p\u00e1gs. 35\u201392.<\/p>\n<p><b>Fuente: Diccionario B\u00edblico Arqueol\u00f3gico<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nabonido o Nabunaid fue el \u00faltimo rey del imperio neobabil\u00f3nico (*caldeo), quien gobern\u00f3 desde el 555 hasta el 539 a. de J.C. La as\u00ed\u00ad llamada cr\u00f3nica de Nabonido, publicada primero por T. G. Pinches en 1882, relata ciertos eventos desde el a\u00f1o de la ascensi\u00f3n de Nabonido hasta la ca\u00ed\u00adda de *Babilonia. En ella se &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/nabonido-nabunaid\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abNABONIDO, NABUNAID\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-7737","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/7737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=7737"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/7737\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=7737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=7737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=7737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}