{"id":15788,"date":"2017-06-17T10:05:03","date_gmt":"2017-06-17T15:05:03","guid":{"rendered":"http:\/\/www.biblia.work\/noticias\/el-papa-nombra-nuevo-arzobispo-en-argentina-y-enviado-para-el-centenario-de-mons-romero\/"},"modified":"2017-06-17T10:05:03","modified_gmt":"2017-06-17T15:05:03","slug":"el-papa-nombra-nuevo-arzobispo-en-argentina-y-enviado-para-el-centenario-de-mons-romero","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/noticias\/el-papa-nombra-nuevo-arzobispo-en-argentina-y-enviado-para-el-centenario-de-mons-romero\/","title":{"rendered":"El Papa nombra nuevo Arzobispo en Argentina y enviado para el centenario de Mons. Romero"},"content":{"rendered":"<p> VATICANO, 17 Jun. 17 (ACI).-<br \/>\n\tEl Papa Francisco acept&oacute; la renuncia presentada por Mons. Alfonso Rogelio Delgado Evers como Arzobispo de San Juan de Cuyo, Argentina, al alcanzar los 75 a&ntilde;os de edad, y nombr&oacute; como sucesor a Mons. Jorge Eduardo Lozano, hasta ahora Obispo Coadjutor de la misma Archidi&oacute;cesis.<\/p>\n<p style=\"text-align: justify\">\n\tMons. Jorge Eduardo Lozano naci&oacute; en Buenos Aires el 10 de febrero de 1955. Recibi&oacute; la ordenaci&oacute;n sacerdotal el 3 de diciembre de 1982 y fue elegido Obispo de Fornos Mayor y auxiliar de la Archidi&oacute;cesis de Buenos Aires el 4 de enero de 2000. Fue ordenado Obispo el 25 de marzo de 2000 en la Catedral de Buenos Aires.<\/p>\n<p style=\"text-align: justify\">\n\tEl 22 de diciembre de 2005 fue trasladado como Obispo de Gualeguaych&uacute;, sede de la que tom&oacute; posesi&oacute;n el 11 de marzo de 2006. El 31 de agosto fue nombrado por el Papa Francisco Arzobispo Coadjutor de San Juan de Cuyo.<\/p>\n<p style=\"text-align: justify\">\n\tAsimismo, es responsable de la Secci&oacute;n de Pastoral Social del Departamento de Justicia y Solidaridad del Consejo Episcopal Latinoamericano (CELAM), y Presidente de la Comisi&oacute;n de Pastoral Social de la Conferencia Episcopal de Argentina.<\/p>\n<p style=\"text-align: justify\">\n\tCentenario del nacimiento de Mons. &Oacute;scar Romero<\/p>\n<p style=\"text-align: justify\">\n\tPor otro lado, el Santo Padre tambi&eacute;n nombr&oacute; al Cardenal Ricardo Ezzati Andrello, Arzobispo de Santiago de Chile como su Enviado Especial para la celebraci&oacute;n del centenario del nacimiento del Beato Obispo &Oacute;scar Romero, que tendr&aacute; lugar en la ciudad de San Salvador el 15 de agosto de 2017.<\/p>\n<p style=\"text-align: justify\">\n\tTambi&eacute;n te puede interesar:<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Beato Romero inspir\u00f3 la Jornada de oraci\u00f3n y ayuno por los Misioneros M\u00e1rtires https:\/\/t.co\/ViuKD6W6iP<\/p>\n<p>&mdash; ACI Prensa (@aciprensa) 24 de marzo de 2017<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VATICANO, 17 Jun. 17 (ACI).- El Papa Francisco acept&oacute; la renuncia presentada por Mons. Alfonso Rogelio Delgado Evers como Arzobispo de San Juan de Cuyo, Argentina, al alcanzar los 75 a&ntilde;os de edad, y nombr&oacute; como sucesor a Mons. Jorge Eduardo Lozano, hasta ahora Obispo Coadjutor de la misma Archidi&oacute;cesis. Mons. Jorge Eduardo Lozano naci&oacute; &hellip; <a href=\"https:\/\/www.biblia.work\/noticias\/el-papa-nombra-nuevo-arzobispo-en-argentina-y-enviado-para-el-centenario-de-mons-romero\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEl Papa nombra nuevo Arzobispo en Argentina y enviado para el centenario de Mons. Romero\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15788","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts\/15788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/comments?post=15788"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts\/15788\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/media?parent=15788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/categories?post=15788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/tags?post=15788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}