{"id":16739,"date":"2017-07-19T12:05:02","date_gmt":"2017-07-19T17:05:02","guid":{"rendered":"http:\/\/www.biblia.work\/noticias\/nino-invita-al-papa-a-una-peregrinacion-y-esta-es-la-respuesta-de-francisco\/"},"modified":"2017-07-19T12:05:02","modified_gmt":"2017-07-19T17:05:02","slug":"nino-invita-al-papa-a-una-peregrinacion-y-esta-es-la-respuesta-de-francisco","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/noticias\/nino-invita-al-papa-a-una-peregrinacion-y-esta-es-la-respuesta-de-francisco\/","title":{"rendered":"Ni\u00f1o invita al Papa a una peregrinaci\u00f3n y esta es la respuesta de Francisco"},"content":{"rendered":"<p> VATICANO, 19 Jul. 17 (ACI).-<br \/>\n\tEl peque&ntilde;o Andrea, un ni&ntilde;o italiano de 9 a&ntilde;os, escribi&oacute; una carta al Papa Francisco invit&aacute;ndole a peregrinar el pr&oacute;ximo a&ntilde;o al Santuario Mariano de Loreto, junto a &eacute;l y a otros ni&ntilde;os; un gesto que agradeci&oacute; el Santo Padre con el proverbio que dice &ldquo;nunca digas nunca&rdquo;.<\/p>\n<p style=\"text-align: justify\">\n\tEste ni&ntilde;o, que acudi&oacute; junto con 150 ni&ntilde;os al Santuario Mariano de Loreto en el contexto de la &ldquo;Peregrinaci&oacute;n de la alegr&iacute;a&rdquo; que se celebr&oacute; del 22 al 26 de junio, envi&oacute; la carta en nombre de todos sus compa&ntilde;eros. En ella, adem&aacute;s de invitar al Pont&iacute;fice a peregrinar con ellos en 2018, le envi&oacute; una fotograf&iacute;a de grupo de todos los ni&ntilde;os y le pidi&oacute; que les bendijera al mirarla.<\/p>\n<p style=\"text-align: justify\">\n\tLa peregrinaci&oacute;n es organizada por la secci&oacute;n Roma-Lazio de la Uni&oacute;n Nacional Italiana de Transporte de enfermos a Lourdes y a Santuarios Internacionales (UNITALSI) con el objetivo de ense&ntilde;ar a los m&aacute;s peque&ntilde;os la importancia de la oraci&oacute;n y de la cercan&iacute;a a Dios al mismo tiempo que juegan, se divierten y hacen nuevas amistades.<\/p>\n<p style=\"text-align: justify\">\n\t&ldquo;Somos m&aacute;s de 130 ni&ntilde;os y muchos est&aacute;n enfermos, otros en sillas de ruedas y otros acuden solos y les acompa&ntilde;a alguna religiosa&rdquo;, indica Andrea en su carta en la que asegura que cada d&iacute;a rezaban por &eacute;l.<\/p>\n<p style=\"text-align: justify\">\n\tEn su respuesta, Francisco le dijo que &ldquo;ha sido bello recibir tu carta y saber de tu enriquecedora aventura vivida junto a UNITALSI en la Peregrinaci&oacute;n de la Alegr&iacute;a a Loreto, para ni&ntilde;os&rdquo;.<\/p>\n<p style=\"text-align: justify\">\n\t&ldquo;Gracias tambi&eacute;n por la foto de grupo que me has mandado donde he podido ver que sois much&iacute;simos y muy simp&aacute;ticos. Mientras miraba cada rostro en la fotograf&iacute;a rezaba a la Virgen de Loreto por vosotros y os he bendecido de coraz&oacute;n junto con vuestros padres, voluntarios, sacerdotes y responsables de UNITALSI&rdquo;, afirm&oacute; el Papa.<\/p>\n<p style=\"text-align: justify\">\n\tAdem&aacute;s, finaliz&oacute; dejando la puerta abierta a la posibilidad de acompa&ntilde;arles durante la peregrinaci&oacute;n del pr&oacute;ximo a&ntilde;o a Loreto: &ldquo;Gracias por la invitaci&oacute;n que me hab&eacute;is hecho a acudir en peregrinaci&oacute;n junto a vosotros, acompa&ntilde;ar a los ni&ntilde;os me produce una gran alegr&iacute;a. Un proverbio dice: &lsquo;Nunca digas nunca&rsquo;. Por lo tanto, confiemos ese sue&ntilde;o a las manos de la Providencia&rdquo;, concluy&oacute;. &nbsp;<\/p>\n<p style=\"text-align: justify\">\n\tTambi&eacute;n te puede interesar:<\/p>\n<p style=\"text-align: justify\">\n\t&nbsp;<\/p>\n<p style=\"text-align: justify\">\n\t\tEl Papa llama a recolector de basura que perdi&oacute; las dos piernas en accidente https:\/\/t.co\/4aiJKQfE0c<\/p>\n<p>\t&mdash; ACI Prensa (@aciprensa) 18 de julio de 2017<\/p>\n<p style=\"text-align: justify\">\n\t&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VATICANO, 19 Jul. 17 (ACI).- El peque&ntilde;o Andrea, un ni&ntilde;o italiano de 9 a&ntilde;os, escribi&oacute; una carta al Papa Francisco invit&aacute;ndole a peregrinar el pr&oacute;ximo a&ntilde;o al Santuario Mariano de Loreto, junto a &eacute;l y a otros ni&ntilde;os; un gesto que agradeci&oacute; el Santo Padre con el proverbio que dice &ldquo;nunca digas nunca&rdquo;. Este ni&ntilde;o, &hellip; <a href=\"https:\/\/www.biblia.work\/noticias\/nino-invita-al-papa-a-una-peregrinacion-y-esta-es-la-respuesta-de-francisco\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abNi\u00f1o invita al Papa a una peregrinaci\u00f3n y esta es la respuesta de Francisco\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16739","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts\/16739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/comments?post=16739"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts\/16739\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/media?parent=16739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/categories?post=16739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/tags?post=16739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}