{"id":16740,"date":"2017-07-19T12:10:02","date_gmt":"2017-07-19T17:10:02","guid":{"rendered":"http:\/\/www.biblia.work\/noticias\/vice-presidente-pence-embajada-de-ee-uu-sera-trasladada-a-jerusalen\/"},"modified":"2017-07-19T12:10:02","modified_gmt":"2017-07-19T17:10:02","slug":"vice-presidente-pence-embajada-de-ee-uu-sera-trasladada-a-jerusalen","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/noticias\/vice-presidente-pence-embajada-de-ee-uu-sera-trasladada-a-jerusalen\/","title":{"rendered":"Vice presidente Pence: Embajada de EE.UU. ser\u00e1 trasladada a Jerusal\u00e9n"},"content":{"rendered":"<p style=\"text-align: justify\">WASHINGTON, EE.UU.- El vicepresidente Mike Pence ha declarado que el presidente Donald Trump trasladar\u00e1 eventualmente la embajada de los Estados Unidos de Tel Aviv a Jerusal\u00e9n, un gesto simb\u00f3lico destinado a transmitir que Jerusal\u00e9n es la capital de Israel.<\/p>\n<p style=\"text-align: justify\">El vicepresidente Pence asegur\u00f3 a los asistentes que el presidente Trump trasladar\u00eda la embajada pronto. &#8220;Te prometo que llegar\u00e1 el d\u00eda en que el presidente Donald Trump traslade la embajada estadounidense de Tel Aviv a Jerusal\u00e9n, pero no es cuesti\u00f3n de s\u00ed, es s\u00f3lo cuando&#8221;, dijo Pence, seg\u00fan inform\u00f3 Jewish News Service.<\/p>\n<p style=\"text-align: justify\">&#8220;Estando de pie en Jerusal\u00e9n, en esa ciudad antigua y santa, nuestro presidente declar\u00f3 para todo el mundo o\u00edr que bajo el liderazgo de [Trump], los Estados Unidos de Am\u00e9rica \u200b\u200bestar\u00e1n siempre con Israel &#8220;.<\/p>\n<p style=\"text-align: justify\">Los comentarios de Pence fueron parte de la cumbre de dos d\u00edas de CUFI, que tuvo lugar el lunes y martes en el Centro de Convenciones Walter E. Washington. En un comunicado publicado antes de la Cumbre, el CUFI describi\u00f3 el evento como &#8220;el principal evento pro-Israel del a\u00f1o&#8221;, implorando a los partidarios de &#8220;unirse a nosotros en la capital de nuestra naci\u00f3n para mantenerse con Israel y el pueblo jud\u00edo&#8221;.<\/p>\n<p style=\"text-align: justify\">&#8220;En s\u00f3lo dos d\u00edas, usted recibir\u00e1 un conocimiento de nivel maestro de la situaci\u00f3n m\u00e1s actualizada en Israel y el Medio Oriente de algunos de los expertos m\u00e1s convincentes en el campo&#8221;, dijo CUFI.<\/p>\n<p style=\"text-align: justify\">&#8220;No tenemos duda de que juntos podemos tomar una posici\u00f3n que har\u00e1 a Israel m\u00e1s fuerte y a su pueblo m\u00e1s seguro durante los pr\u00f3ximos a\u00f1os&#8221;. Adem\u00e1s de Pence, otros oradores notables de la Cumbre de este a\u00f1o incluyeron al ex embajador estadounidense John Bolton, al pastor de la Iglesia Cornerstone John Hagee, al congresista Trent Franks de Arizona, al senador John Cornyn de Texas y al primer ministro israel\u00ed Benjamin Netanyahu, entre otros. .<\/p>\n<p style=\"text-align: justify\">Las observaciones de Pence llegan un mes despu\u00e9s de que Trump firmara una renuncia retrasando el movimiento de la embajada a Jerusal\u00e9n, haciendo eco de las pr\u00e1cticas de los \u00faltimos presidentes recientes.<\/p>\n<p style=\"text-align: justify\">&#8220;Su predecesor, Barack Obama, firm\u00f3 la misma exenci\u00f3n de seis meses ocho veces durante su mandato, los ex presidentes Bill Clinton y George W. Bush tambi\u00e9n firmaron la exenci\u00f3n&#8221;, inform\u00f3 Politico.<\/p>\n<p style=\"text-align: justify\">&#8220;En 1995, el Congreso aprob\u00f3 una ley que ordenaba trasladar la embajada a Jerusal\u00e9n, pero los presidentes pueden firmar renuncias de seis meses para retrasar el traslado, y lo han hecho desde entonces&#8221;, ha publicado <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.christianpost.com\/news\/american-embassy-move-jerusalem-vice-president-pence-192402\/\">Christian Post.<\/a><\/p>\n<p style=\"text-align: justify\">La entrada <a rel=\"nofollow\" href=\"http:\/\/www.noticiacristiana.com\/iglesia\/israel\/2017\/07\/pence-embajada-ee-uu-jerusalen.html\">Vice presidente Pence: Embajada de EE.UU. ser\u00e1 trasladada a Jerusal\u00e9n<\/a> aparece primero en <a rel=\"nofollow\" href=\"http:\/\/www.noticiacristiana.com\">Noticias Cristianas Evang\u00e9licas<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WASHINGTON, EE.UU.- El vicepresidente Mike Pence ha declarado que el presidente Donald Trump trasladar\u00e1 eventualmente la embajada de los Estados Unidos de Tel Aviv a Jerusal\u00e9n, un gesto simb\u00f3lico destinado a transmitir que Jerusal\u00e9n es la capital de Israel. El vicepresidente Pence asegur\u00f3 a los asistentes que el presidente Trump trasladar\u00eda la embajada pronto. &#8220;Te &hellip; <a href=\"https:\/\/www.biblia.work\/noticias\/vice-presidente-pence-embajada-de-ee-uu-sera-trasladada-a-jerusalen\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abVice presidente Pence: Embajada de EE.UU. ser\u00e1 trasladada a Jerusal\u00e9n\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16740","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts\/16740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/comments?post=16740"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts\/16740\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/media?parent=16740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/categories?post=16740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/tags?post=16740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}