{"id":2400,"date":"2016-04-01T14:05:02","date_gmt":"2016-04-01T19:05:02","guid":{"rendered":"http:\/\/www.biblia.work\/noticias\/selena-gomez-interpreta-cancion-de-adoracion-en-concierto-de-hillsong\/"},"modified":"2016-04-01T14:05:02","modified_gmt":"2016-04-01T19:05:02","slug":"selena-gomez-interpreta-cancion-de-adoracion-en-concierto-de-hillsong","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/noticias\/selena-gomez-interpreta-cancion-de-adoracion-en-concierto-de-hillsong\/","title":{"rendered":"Selena G\u00f3mez interpreta canci\u00f3n de adoraci\u00f3n en concierto de Hillsong"},"content":{"rendered":"<p style=\"text-align: justify\">La actriz y cantante Selena G\u00f3mez interpret\u00f3 su canci\u00f3n \u201cNobody\u201d en la Iglesia Hillsong en Los \u00c1ngeles, California, y ha expresado su satisfacci\u00f3n por realizar una canci\u00f3n de adoraci\u00f3n. <\/p>\n<p style=\"text-align: justify\">The Christian Post informa que la joven de 23 a\u00f1os de edad, asiste regularmente a los servicios de la popular iglesia. La estrella de Hollywood sorprendi\u00f3 recientemente a la congregaci\u00f3n tras subir al altar e interpretar el tema musical, que seg\u00fan ella habla sobre Dios. <\/p>\n<p style=\"text-align: justify\">G\u00f3mez se identifica como cristiana y menciona con frecuencia pasajes de la Biblia y habla sobre Jes\u00fas en redes sociales. <\/p>\n<p style=\"text-align: justify\">\u00abLa primera vez que dirijo la adoraci\u00f3n\u00bb, escribi\u00f3 en un mensaje de Instagram, refiri\u00e9ndose al concierto de Hillsong. \u00abInterpret\u00e9 la primera canci\u00f3n de adoraci\u00f3n que yo misma escrib\u00ed. Estoy muy agradecida por su gracia y comprensi\u00f3n\u00bb.<\/p>\n<p style=\"text-align: justify\">Cuando ella subi\u00f3 al escenario para interpretar \u00abNobody\u00bb, G\u00f3mez dijo a la congregaci\u00f3n:  \u00abEsta noche es m\u00e1s que un concierto, es m\u00e1s que Hillsong, es m\u00e1s que yo venga al escenario y cante una canci\u00f3n para ustedes. Se trata de una relaci\u00f3n que es mayor que cualquier cosa garantizada\u00bb.<\/p>\n<p style=\"text-align: justify\">G\u00f3mez tambi\u00e9n ha declarado anteriormente que ella conoce personalmente a los integrantes de Hillsong y que ella ama su m\u00fasica. <\/p>\n<p style=\"text-align: justify\">\u00abAmo a Brooke Fraser, ella es mi favorita.. Y tengo el placer de conocerla y ella es incre\u00edble. Me encanta Hillsong, me encanta todo de su culto, soy una fan\u00e1tica de todo eso\u00bb, dijo. \u00abY el nuevo Hillsong Young &amp; Free es tan bueno que llegu\u00e9 a escuchar algo de su m\u00fasica, antes de que saliera\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actriz y cantante Selena G\u00f3mez interpret\u00f3 su canci\u00f3n \u201cNobody\u201d en la Iglesia Hillsong en Los \u00c1ngeles, California, y ha expresado su satisfacci\u00f3n por realizar una canci\u00f3n de adoraci\u00f3n. The Christian Post informa que la joven de 23 a\u00f1os de edad, asiste regularmente a los servicios de la popular iglesia. La estrella de Hollywood sorprendi\u00f3 &hellip; <a href=\"https:\/\/www.biblia.work\/noticias\/selena-gomez-interpreta-cancion-de-adoracion-en-concierto-de-hillsong\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abSelena G\u00f3mez interpreta canci\u00f3n de adoraci\u00f3n en concierto de Hillsong\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2400","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts\/2400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/comments?post=2400"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts\/2400\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/media?parent=2400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/categories?post=2400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/tags?post=2400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}