{"id":3265,"date":"2016-05-05T01:05:02","date_gmt":"2016-05-05T06:05:02","guid":{"rendered":"http:\/\/www.biblia.work\/noticias\/hoy-se-conmemora-a-san-angel-martir-de-los-carmelitas\/"},"modified":"2016-05-05T01:05:02","modified_gmt":"2016-05-05T06:05:02","slug":"hoy-se-conmemora-a-san-angel-martir-de-los-carmelitas","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/noticias\/hoy-se-conmemora-a-san-angel-martir-de-los-carmelitas\/","title":{"rendered":"Hoy se conmemora a San \u00c1ngel, M\u00e1rtir de los carmelitas"},"content":{"rendered":"<p> REDACCI\u00d3N CENTRAL, 05 May. 16 (ACI).-<br \/>\n\tSan &Aacute;ngel fue uno de los primeros sacerdotes miembros de la Orden de Nuestra Se&ntilde;ora del Monte Carmelo; convirti&oacute; a muchos con su predicaci&oacute;n y milagros, y fue martirizado hacia el 1226 en Sicilia, Italia.<\/p>\n<p style=\"text-align: justify\">\n\tEste santo naci&oacute; en Jerusal&eacute;n en el 1185. Seg&uacute;n la tradici&oacute;n, sus padres fueron jud&iacute;os convertidos al cristianismo despu&eacute;s de que la Sant&iacute;sima Virgen Mar&iacute;a se les apareciera.<\/p>\n<p style=\"text-align: justify\">\n\tDesde ni&ntilde;o se mostr&oacute; con extraordinarios dones espirituales e intelectuales. A los 15 a&ntilde;os hablaba ya el griego, lat&iacute;n y hebreo. Y a los 25 decidi&oacute; entrar a la orden los Carmelitas que habitaban en el convento de Santa Ana (Jerusal&eacute;n), lugar en el que realiz&oacute; su profesi&oacute;n de fe.<\/p>\n<p style=\"text-align: justify\">\n\tDurante cinco a&ntilde;os vivi&oacute; como ermita&ntilde;o en el Monte Carmelo, donde se le apareci&oacute; el mismo Jes&uacute;s mostr&aacute;ndole el mal que le esperaba a la Tierra Santa con la invasi&oacute;n de los musulmanes. Por ello el Se&ntilde;or le dijo que se dirija a Occidente para predicar y convertir a los pecadores.<\/p>\n<p style=\"text-align: justify\">\n\tAsimismo, tras ser ordenado sacerdote en 1218, recibi&oacute; de su Orden la misi&oacute;n de viajar a Roma y obtener la aprobaci&oacute;n de la nueva Regla del Carmelo de parte del Papa Honorio III, la cual conseguir&iacute;a en 1226.<\/p>\n<p style=\"text-align: justify\">\n\tTras predicar un tiempo en San Juan de Letr&aacute;n (Roma), fue enviado a hacer lo mismo en Sicilia y convertir a los seguidores del catarismo, una herej&iacute;a que condenaba el sacramento de matrimonio, negaban la resurrecci&oacute;n de la carne, etc. Tambi&eacute;n se le recuerda porque convirti&oacute; a m&aacute;s de 200 jud&iacute;os en Palermo.<\/p>\n<p style=\"text-align: justify\">\n\tSin embargo fue en la ciudad de Licata, cuando predicaba a una multitud, que fue acuchillado por una banda de malhechores. Herido de muerte, cay&oacute; de rodillas y or&oacute; por todo el pueblo y en particular por los que lo hab&iacute;an herido.<\/p>\n<p style=\"text-align: justify\">\n\tLa Orden del Carmen lo venera como santo por lo menos desde 1456. Algunos afirman que su culto fue oficialmente reconocido por el papa P&iacute;o II en 1459. Su fiesta se celebra el 5 de mayo.<\/p>\n<p style=\"text-align: justify\">\n\tM&aacute;s informaci&oacute;n en el siguiente enlace<\/p>\n<p style=\"text-align: justify\">\n\tTambi&eacute;n te puede interesar:<\/p>\n<p style=\"text-align: justify\">\n\t&nbsp;<\/p>\n<p style=\"text-align: justify\">\n\t\tOraci&oacute;n a San &Aacute;ngel #Santoral #5Mayo https:\/\/t.co\/GKZxpa7xf2<\/p>\n<p>\t&mdash; ACI Prensa (@aciprensa) 4 de mayo de 2016<\/p>\n<p style=\"text-align: justify\">\n\t&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REDACCI\u00d3N CENTRAL, 05 May. 16 (ACI).- San &Aacute;ngel fue uno de los primeros sacerdotes miembros de la Orden de Nuestra Se&ntilde;ora del Monte Carmelo; convirti&oacute; a muchos con su predicaci&oacute;n y milagros, y fue martirizado hacia el 1226 en Sicilia, Italia. Este santo naci&oacute; en Jerusal&eacute;n en el 1185. Seg&uacute;n la tradici&oacute;n, sus padres fueron &hellip; <a href=\"https:\/\/www.biblia.work\/noticias\/hoy-se-conmemora-a-san-angel-martir-de-los-carmelitas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abHoy se conmemora a San \u00c1ngel, M\u00e1rtir de los carmelitas\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3265","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts\/3265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/comments?post=3265"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts\/3265\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/media?parent=3265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/categories?post=3265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/tags?post=3265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}