{"id":457,"date":"2015-11-30T19:22:03","date_gmt":"2015-12-01T00:22:03","guid":{"rendered":"http:\/\/www.biblia.work\/noticias\/rezar-para-librarse-del-servicio-militar-en-israel\/"},"modified":"2015-11-30T19:22:03","modified_gmt":"2015-12-01T00:22:03","slug":"rezar-para-librarse-del-servicio-militar-en-israel","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/noticias\/rezar-para-librarse-del-servicio-militar-en-israel\/","title":{"rendered":"Rezar para librarse del servicio militar en Israel"},"content":{"rendered":"<p style=\"text-align: justify\">Pocas cosas irritan m\u00e1s a los israel\u00edes laicos que la exenci\u00f3n del servicio militar para los jud\u00edos ultraortodoxos, una prerrogativa que tiene su origen en el nacimiento del Estado jud\u00edo, en 1948. Los <em>haredim,<\/em>una peque\u00f1a minor\u00eda entonces, fueron excluidos de la obligaci\u00f3n de alistarse para que siguieran dedicando su vida a la oraci\u00f3n y el estudio de los textos sagrados, pero en la actualidad representan m\u00e1s del 10% de los ocho millones de habitantes de Israel y son la comunidad con mayor tasa de natalidad.<\/p>\n<p style=\"text-align: justify\">El anterior Gobierno del primer ministro Benjam\u00edn Netanyahu, en el que no estaban representados los partidos ultraortodoxos, aprob\u00f3 en 2014 una reforma legal para incorporar a filas de forma progresiva a los estudiantes de las <em>yeshiva<\/em> o escuelas rab\u00ednicas. Quien no acudiese al llamamiento a filas se enfrentar\u00eda a penas de c\u00e1rcel. La nueva normativa tendr\u00eda que haber entrado en vigor en 2017, pero la Knesset (Parlamento) la ha aplazado hasta 2020 y, de hecho, la ha vaciado de contenido al dejar al ministro de Defensa la potestad de dispensar del alistamiento militar obligatorio a los reclutas ultrarreligiosos.<\/p>\n<p style=\"text-align: justify\">En un nuevo ejercicio de oportunidad pol\u00edtica, Netanyahu ha salvado as\u00ed la actual coalici\u00f3n conservadora en el poder, en la que est\u00e1n integrados los ultraortodoxos de la Uni\u00f3n por la Tor\u00e1 y el Juda\u00edsmo y del Partido Shas, cuyos 13 votos sumados son clave para conservar la ajustada mayor\u00eda de 61 diputados en una C\u00e1mara de 120 esca\u00f1os que sostiene al primer ministro del Likud.<\/p>\n<p style=\"text-align: justify\">Los sectores laicos de la sociedad israel\u00ed, que cargan sobre sus hombros el peso del servicio militar \u2014de unos tres a\u00f1os de duraci\u00f3n para los hombres y dos a\u00f1os para las mujeres a partir de los 18 a\u00f1os\u2014 en plena ola de violencia contra la ocupaci\u00f3n de los territorios palestinos, rechazan la perpetuaci\u00f3n de los privilegios de los <em>haredim.<\/em> Una encuesta del Instituto para el Pluralismo Religioso citada por el diario <em>Haaretz<\/em> refleja que el 76% de los jud\u00edos israel\u00edes est\u00e1 en contra de la reforma legal del servicio militar, un porcentaje que se eleva al 82% entre los no <em>haredim.<\/em><\/p>\n<p style=\"text-align: justify\"><em>Fuente: <strong>www.elpais.com<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pocas cosas irritan m\u00e1s a los israel\u00edes laicos que la exenci\u00f3n del servicio militar para los jud\u00edos ultraortodoxos, una prerrogativa que tiene su origen en el nacimiento del Estado jud\u00edo, en 1948. Los haredim,una peque\u00f1a minor\u00eda entonces, fueron excluidos de la obligaci\u00f3n de alistarse para que siguieran dedicando su vida a la oraci\u00f3n y el &hellip; <a href=\"https:\/\/www.biblia.work\/noticias\/rezar-para-librarse-del-servicio-militar-en-israel\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abRezar para librarse del servicio militar en Israel\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-457","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts\/457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/comments?post=457"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts\/457\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/media?parent=457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/categories?post=457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/tags?post=457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}