{"id":462,"date":"2015-12-01T11:08:02","date_gmt":"2015-12-01T16:08:02","guid":{"rendered":"http:\/\/www.biblia.work\/noticias\/creyentes-llevan-consuelo-a-paris-en-medio-del-dolor\/"},"modified":"2015-12-01T11:08:02","modified_gmt":"2015-12-01T16:08:02","slug":"creyentes-llevan-consuelo-a-paris-en-medio-del-dolor","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/noticias\/creyentes-llevan-consuelo-a-paris-en-medio-del-dolor\/","title":{"rendered":"Creyentes llevan consuelo a Par\u00eds en medio del dolor"},"content":{"rendered":"<p style=\"text-align: justify\">Los parisinos buscan recuperarse despu\u00e9s de los brutales ataques que perpet\u00fao ISIS, dejando al menos 130 muertos. El presidente franc\u00e9s, Francois Hollande, dijo que su naci\u00f3n atacar\u00e1 al Estado Isl\u00e1mico sin misericordia. Mientras tanto, un grupo de creyentes est\u00e1 llevando consuelo a los afectados por el atentado. <\/p>\n<p style=\"text-align: justify\">Los parisinos intentan seguir adelante y volver a su rutina diaria. <\/p>\n<p style=\"text-align: justify\">Pero el ambiente en muchas oficinas no es el mismo. <\/p>\n<p style=\"text-align: justify\">\u00abTenemos canales de televisi\u00f3n por todas partes y vemos por todo lado y solo nos quedamos viendo el televisor\u00bb, dice una mujer. <\/p>\n<p style=\"text-align: justify\">Los habitantes de Par\u00eds intentan volver a su vida cotidiana, pero ahora que saben que los atacantes han crecido y nacido en Francia y en B\u00e9lgica, muchos se preguntan si es seguro seguir adelante. <\/p>\n<p style=\"text-align: justify\">\u00abSabemos que est\u00e1n aqu\u00ed, este hombre, o este hombre. No sabemos. Tengo miedo porque ahora es real\u00bb, indica Daniel, un residente. <\/p>\n<p style=\"text-align: justify\">Con todo lo que sucede, los cristianos franceses van a memoriales para ayudar a consolar a los afligidos, junto con los capellanes de habla francesa del Equipo de Respuesta R\u00e1pida de Billy Graham. <\/p>\n<p style=\"text-align: justify\">\u00abNuestra meta es solo dar esperanza en medio de la crisis\u00bb, asevera el capell\u00e1n Laurent. <\/p>\n<p style=\"text-align: justify\">Los d\u00edas de duelo han terminado, pero la gente de Par\u00eds a\u00fan sufre. El Equipo de Respuesta R\u00e1pida de Billy Graham ha enviado ocho capellanes para ministrar a la gente y brindar el amor de Dios en la ciudad durante este tiempo dif\u00edcil. <\/p>\n<p style=\"text-align: justify\">\u00abEstamos apoyando a las personas que sufren y orando con ellas cuando se da la oportunidad, as\u00ed como uniendo a las iglesias de todo Francia y anim\u00e1ndoles a responder\u00bb, comenta Laurent. <\/p>\n<p style=\"text-align: justify\">Los capellanes estar\u00e1n en Par\u00eds durante al menos dos semanas para orar con la gente y ayudar a las iglesias a planear vigilias, para alcanzar a la comunidad en este tiempo dif\u00edcil. <\/p>\n<p style=\"text-align: justify\">\u00abLa gente est\u00e1 respondiendo a esta iniciativa de orar por Par\u00eds. Lo que queremos hacer es animar a la Iglesia para que tomen ventaja de esto y realicen vigilias de oraci\u00f3n para que talvez vayan a orar en los sitios de los tiroteos, y estaremos all\u00ed para ministrar a las personas junto con la Iglesia\u00bb, relata Laurent. <\/p>\n<p style=\"text-align: justify\">\u00abVistiendo \u00e9sta camisa, invito a la gente a decir: &#8216;Ok, podemos orar juntos, es sencillo'\u00bb, comenta Damien. <\/p>\n<p style=\"text-align: justify\">El equipo pide oraci\u00f3n para que Dios los gu\u00ede a personas con corazones abiertos y que encuentren oportunidades para ministrar a las personas que est\u00e1n dispuestas a escuchar el mensaje de esperanza que Jes\u00fas les ofrece. <\/p>\n<p style=\"text-align: justify\"><em>Fuente: <strong>www.MundoCristiano.tv <\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los parisinos buscan recuperarse despu\u00e9s de los brutales ataques que perpet\u00fao ISIS, dejando al menos 130 muertos. El presidente franc\u00e9s, Francois Hollande, dijo que su naci\u00f3n atacar\u00e1 al Estado Isl\u00e1mico sin misericordia. Mientras tanto, un grupo de creyentes est\u00e1 llevando consuelo a los afectados por el atentado. Los parisinos intentan seguir adelante y volver a &hellip; <a href=\"https:\/\/www.biblia.work\/noticias\/creyentes-llevan-consuelo-a-paris-en-medio-del-dolor\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCreyentes llevan consuelo a Par\u00eds en medio del dolor\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-462","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts\/462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/comments?post=462"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/posts\/462\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/media?parent=462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/categories?post=462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/noticias\/wp-json\/wp\/v2\/tags?post=462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}