{"id":10082,"date":"2016-03-11T19:24:24","date_gmt":"2016-03-12T00:24:24","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/el-legado\/"},"modified":"2016-03-11T19:24:24","modified_gmt":"2016-03-12T00:24:24","slug":"el-legado","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/el-legado\/","title":{"rendered":"El legado"},"content":{"rendered":"<p style=\"text-align: justify;\">Mas a Jehov\u00e1 vuestro Dios seguir\u00e9is, como hab\u00e9is hecho hasta hoy. <strong>Josue 23:8<\/strong><\/p>\n<p style=\"text-align: justify;\">Para definir qu\u00e9 es un legado leamos: Joel 1:1 Palabra de Jehov\u00e1 que vino a Joel, hijo de Petuel. O\u00edd esto ancianos y escuchad, todos los moradores de la tierra. Ha acontecido esto en vuestros d\u00edas, o en los d\u00edas de vuestros padres? De esto contar\u00e9is a vuestros hijos, y vuestros Hijos a sus hijos, y sus hijos a la otra generaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">La pregunta va mas all\u00e1 de que les voy a dejar a mis hijos una buena cuenta en el banco, una casa paga o un auto ultimo modelo para que me recuerden. Por lo general el que es fiel en lo poco lo es en lo mucho, as\u00ed que el que es desagradecido lo ser\u00e1 con casa con cuenta en el banco,con auto nuevo, con lo que le pongan.<\/p>\n<p style=\"text-align: justify;\">Tres Ejemplos de personas que dejaron un legado.<\/p>\n<p><strong>1. El\u00edas. 2 Reyes 2:9-10<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 es lo que Eliseo m\u00e1s quer\u00eda de su padre espiritual?<\/p>\n<p style=\"text-align: justify;\">\u00bfAhora qu\u00e9 es lo que mas quieren tus hijos?<\/p>\n<p style=\"text-align: justify;\">\u00bfEliseo quer\u00eda una doble porci\u00f3n para qu\u00e9? \u00bfPara pararse en la esquina a d\u00e1rselas de agrandado? No, fue mas bien para continuar con la obra de su mentor, de su padre espiritual, continuar con ese legado que dej\u00f3 El\u00edas.<\/p>\n<p style=\"text-align: justify;\">As\u00ed debemos aprender que en nuestra vida no es sencillamente ocupar ox\u00edgeno, sino m\u00e1s bien que alguien contin\u00fae tu obra; alguien que aproveche por lo cual te reventaste tanto toda tu vida. Que no malgasten en un solo d\u00eda lo que te cost\u00f3 tanto tiempo lograr. Eclesiast\u00e9s 2:21 dice que no le dejes a uno que nunca trabaj\u00f3 en su vida.<\/p>\n<p style=\"text-align: justify;\"><strong>2. El legado de David. 2 Cr\u00f3nicas 29:25<\/strong><\/p>\n<p style=\"text-align: justify;\">Salom\u00f3n super\u00f3 la riqueza y el honor de su padre. El legado de David se origin\u00f3 en su relaci\u00f3n con Dios y dio sus valores espirituales como herencia a su hijo Salom\u00f3n. El dinero y el poder que dejamos a nuestros hijos son menos importantes que el legado espiritual que podemos darles.<\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 clase de herencia recibir\u00e1n tus hijos?<\/p>\n<p style=\"text-align: justify;\"><strong>3. El legado de Jes\u00fas. Mateo 28:18-20<\/strong><\/p>\n<p style=\"text-align: justify;\">Es el m\u00e1s importante por que \u00c9l dijo: estar\u00e9 con Uds. hasta el fin, id haced disc\u00edpulos mantengan esto que aprendieron de mi.<\/p>\n<p style=\"text-align: justify;\"><strong>Conclusi\u00f3n:<\/strong><\/p>\n<p style=\"text-align: justify;\">De eso se trata el legado mientras vivimos tenemos todas las posibilidades de mejorar.<\/p>\n<p style=\"text-align: justify;\">si hasta ahora solo hab\u00edas pensado en ti, te invito a que arregles cuentas con \u00c9L.<\/p>\n<p style=\"text-align: justify;\">DIOS TE BENDIGA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mas a Jehov\u00e1 vuestro Dios seguir\u00e9is, como hab\u00e9is hecho hasta hoy. Josue 23:8 Para definir qu\u00e9 es un legado leamos: Joel 1:1 Palabra de Jehov\u00e1 que vino a Joel, hijo de Petuel. O\u00edd esto ancianos y escuchad, todos los moradores de la tierra. Ha acontecido esto en vuestros d\u00edas, o en los d\u00edas de vuestros &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/el-legado\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEl legado\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10082","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/10082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=10082"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/10082\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=10082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=10082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=10082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}