{"id":24651,"date":"2016-05-19T12:44:15","date_gmt":"2016-05-19T17:44:15","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/olvidando-un-amor-que-no-pudo-ser\/"},"modified":"2016-05-19T12:44:15","modified_gmt":"2016-05-19T17:44:15","slug":"olvidando-un-amor-que-no-pudo-ser","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/olvidando-un-amor-que-no-pudo-ser\/","title":{"rendered":"Olvidando un amor que no pudo ser"},"content":{"rendered":"<p class=\"wp-caption-text\">No es bueno que pases la mayor\u00eda de tu tiempo llorando por algo que no pudo ser y que no estaba en los planes de Dios.<\/p>\n<p align=\"justify\">Parece un tema sacado de una novela, pero no podemos negar la realidad, vivimos un periodo en donde los fracasos sentimentales est\u00e1n a la orden del d\u00eda. En donde los valores del verdadero amor se han perdido y en donde el patr\u00f3n a establecer es la falta de sensibilidad entre la pareja.<\/p>\n<p align=\"justify\">\n<p align=\"justify\">A diario recibo correos de personas pidiendo consejer\u00eda para olvidar un amor que no pudo ser. Es triste ver como los jovencitos y j\u00f3venes mayores se embarcan en relaciones sentimentales dejados llevar m\u00e1s que por la voluntad de Dios, por sus propias emociones humanas, lo que conlleva a un casi seguro fracaso.<\/p>\n<p align=\"justify\">Y es que es hora de levantar la cabeza y dirigir nuestra mirada al Se\u00f1or, quien tendr\u00eda que ser Due\u00f1o y Se\u00f1or de nuestros sentimientos, los cuales se tendr\u00edan que canalizar por medio de su voluntad y no la nuestra. Mientras los j\u00f3venes no comprendan este principio, ser\u00e1 dif\u00edcil evitar que nuevos fracasos aparezcan en sus vidas sentimentales.<\/p>\n<p align=\"justify\">No hay que ir muy lejos para darnos cuenta que la mayor\u00eda de relaciones amorosas entre cristianos hoy en d\u00eda son impulsadas por \u201clo que creo que es de Dios\u201d y no por LO QUE REALMENTE DIOS QUIERE DE MI.<\/p>\n<p align=\"justify\">Realmente hay una gran diferencia entre \u201clo que yo pienso que es\u201d y lo que \u201cDios piensa que es lo mejor para mi\u201d, pero mientras no sepamos distinguir estas dos frases, seguiremos creyendo que lo que nosotros pensamos, es lo correcto, olvid\u00e1ndonos de esta manera de lo que realmente Dios quiere para m\u00ed.<\/p>\n<p align=\"justify\">Y es que el amor es ciego y la locura lo acompa\u00f1a, reza un dicho que algo de verdad ha de tener. Si el amor es ciego porque cuando no proviene de Dios te siega en sentimiento enga\u00f1osos que lo \u00fanico que hace es da\u00f1ar fuertemente tu coraz\u00f3n, y si que es locura, porque entre m\u00e1s te das cuenta que la relaci\u00f3n no funciona, mas intentas seguirla, para seguirte da\u00f1ando, s\u00ed que es un locura TOTAL.<\/p>\n<p align=\"justify\">Ahora bien, si por \u201ca\u201d o \u201cb\u201d motivo no te fue bien en el amor y hasta el d\u00eda de hoy no has podido superar ese incidente, el cual uno que otro d\u00eda al recordar te saca una lagrima o en donde vives esperanzado o esperanzada a que un d\u00eda volver\u00e1, tu desesperaci\u00f3n por ese amor que no fue te lleva a preguntar: \u00bfC\u00f3mo olvidarlo y superarlo?<\/p>\n<p align=\"justify\">A continuaci\u00f3n te doy algunas claves que personalmente considero que te ser\u00e1n de gran ayuda para tratar de olvidar el mal momento que viviste en el amor:<\/p>\n<p align=\"justify\"><strong>1. Tienes que entender que este ser\u00e1 un proceso:<\/strong> No hay una clave m\u00e1gica para levantarte el d\u00eda de ma\u00f1ana y creer que ya todo est\u00e1 olvidado. No te enga\u00f1es y no nos enga\u00f1emos, esto es UN PROCESO que comenzaras a partir de hoy. Lo que quiero decir con esto es que en el camino, vendr\u00e1n recuerdos, sentimientos encontrados, suspiros y de todo lo que te puedas imaginas en este proceso, pero no quiere decir que NO LO PODR\u00c1S OLVIDAR. Por esa raz\u00f3n no tienes que desanimarte en este proceso que te voy a tratar de explicar. Quiz\u00e1 un d\u00eda sentir\u00e1s el deseo casi imposible de controlar de llamar por tel\u00e9fono a ese amor que no pudo ser, de escribir un mensaje de texto o simplemente de ir y visitarlo, y en alg\u00fan momento quiz\u00e1 caer\u00e1s, pero no te desanimes, es parte del proceso. Es casi imposible que luego de estar acostumbrado a una persona y tener una rutina de vida, no vayas a sentir el deseo de saber de esa persona, pero trata de todas las formas posibles ir reduciendo estos deseos.<\/p>\n<p align=\"justify\"><strong>2. Es importante la DETERMINACION:<\/strong> Tu puedes decir que quiere olvidar, pero mientras no halla en ti una verdadera DETERMINACION de hacerlo, lo siento, tus palabras solo son eso: \u201cpalabras\u201d. Cuando hablo de determinaci\u00f3n hablo de QUERER y HACER lo imposible por tratar de olvidar, digo esto, porque la gran mayor\u00eda de personas dicen querer olvidar un amor que no fue, pero dentro de si saben muy bien que no quieren olvidarse. Por esa raz\u00f3n tu deseo de OLVIDAR tiene que salir de un coraz\u00f3n que tenga la convicci\u00f3n firme y la DETERMINACION TOTAL de querer olvidar de una vez por todas, pues mientras no halla esto, ser\u00e1 dif\u00edcil poder olvidar.<\/p>\n<p align=\"justify\"><strong>3. Tienes que valorarte:<\/strong> La mayor\u00eda de fracasos amorosos terminan con palabras y frases desagradables como: \u201cYo nunca te quise\u201d, \u201cno eres lo suficiente para mi\u201d, \u201cno me mereces\u201d, \u201cno eres tan bello o bella\u201d, \u201cestuve contigo por lastima\u201d, etc. Frases que crean en el coraz\u00f3n del receptor un concepto de si mismo(a) que vale poco. Realmente estas frases no pueden salir de un coraz\u00f3n que realmente ama a Dios, esas frases solo pueden salir de una vida influenciada por el enemigo, por lo que querr\u00e1 destrozarte. Recuerda que el enemigo odia la imagen de Dios en tu vida, por esa raz\u00f3n tratara por todos los medios posibles desanimarte y desvalorizarte para que acabes alej\u00e1ndote de Dios. Mas sin embargo tienes que saber que tu vales mucho ERES UN PR\u00cdNCIPE Y UNA PRINCESA DE DIOS, vales la SANGRE DE CRISTO, \u00bfEs poca cosa esto?, definitivamente NO. Por esa raz\u00f3n debes valorarte, si el amor que no pudo ser te trata mal cada vez que lo buscas o lo llamas, \u00bfPara que lo sigues haciendo?, la voluntad de Dios no es que te desvalorices, al contrario TU ERES LA PERLA DE GRAN PRECIO del Se\u00f1or, El te compro a precio de sangre, y no es posible que mientras El te de valor, tu te desvalorices sola o solo. No permitas que te sigan desvalorizando, te dignidad y sobre todo ENTIENDE que a Dios no le agradan esos episodios, por lo que no los busques mas.<\/p>\n<p align=\"justify\"><strong>4. Tienes que entender que NO ERA LA PERSONA PARA TI:<\/strong> Muchos se hacen la pregunta: \u00bfY si era el que Dios me quer\u00eda dar y lo perd\u00ed? No mi amado hermano o hermana, definitivamente NO ERA PARA TI, \u00bfC\u00f3mo vas a creer que Dios te iba a dar una persona que lejos de amarte, te desvaloriza, te hace sentir mal y para colmo te dice palabras que no son las de un hijo de Dios?, es descabellado pensar que si esa persona te trataba as\u00ed en el noviazgo, \u00bfC\u00f3mo te pudo tratar en un matrimonio?, no me vengas con el cuento que pod\u00eda cambiar, si ya no esta contigo, es porque a DIOS NO LE PARECIO esa relaci\u00f3n y por eso sucedi\u00f3 lo que sucedi\u00f3. Es que tienes que entender que a Dios nada se le escapa, una relaci\u00f3n que no se basa en amor, sino que en malos sentimientos JAM\u00c1S ser\u00e1 de Dios. Dios es amor y no desamor. No puedes pasarte la vida pensado que si era el que Dios te hab\u00eda dado, porque con convicci\u00f3n y Dios no me dejara mentir te digo: NO ERA PARA TI. No sigas queriendo descifrar cosas que est\u00e1n tan claras a simple vista. La voluntad de Dios no es que sufras en el amor, la voluntad de Dios es que encuentres en tu pareja la AYUDA ID\u00d3NEA, y no la ayuda err\u00f3nea. Dale gracias a Dios que te libro de un martirio con esa relaci\u00f3n y que gracias a El pronto volver\u00e1s a sonre\u00edr y de eso te quiero hablar en el quinto punto.<\/p>\n<p align=\"justify\"><strong>5. Tienes que entender que DIOS TIENE ALGUIEN PREPARADO(A) PARA TI:<\/strong> Es dif\u00edcil asimilarlo al corto tiempo de terminar una relaci\u00f3n, pues los sentimientos por el amor que no pudo ser tal vez siguen a flor de piel, pero aun cuando no lo entiendas en el momento, lo entender\u00e1s tarde o temprano y es que: DIOS YA TIENE A TU PR\u00cdNCIPE AZUL o TU PRINCESA DE LOS SUE\u00d1OS. As\u00ed es Dios, es que El no hace nada mal, TODO es perfecto y parte de su plan es darte a ti, la persona INDICADA, esa que te amara mas de lo que un d\u00eda te imaginaste que alguien te pod\u00eda amar, esa personas que respetara cada idea y plan tuyo y que sin duda te respaldara, esa personas que te aceptara tal y como eres sin importar tus errores y defectos, esa persona que al verla a los ojos sentir\u00e1s algo indescriptible y que solo los que nos hemos enamorado de verdad sentimos. Esa persona de la cual te enamoraras como nunca y la cual estar\u00e1 enamorado de ti como nunca, en donde la base de su relaci\u00f3n ser\u00e1 DIOS y en donde el amor que Dios ha depositado en sus vidas ser\u00e1 compartido entre los dos.<\/p>\n<p align=\"justify\">Amados, en este momento quiz\u00e1 no lo entiendes, pero CREEME que Dios ya tiene una persona preparada para ti, \u00bfCu\u00e1ndo?, no lo se, \u00bfC\u00f3mo ser\u00e1?, tampoco lo se, pero lo que si se es que ser\u00e1 en el TIEMPO PERFECTO de Dios y ser\u00e1 la PERSONA MAS BELLA que hallas visto en tu vida.<\/p>\n<p align=\"justify\">El amor no se busca por nuestra propia cuenta, es puesto por DIOS en el momento id\u00f3neo y de la manera menos pensada, solo basta con realizar las siguientes tres acciones con las cuales estar\u00e1s acercando mas ese momento:<\/p>\n<p align=\"justify\"><strong>1.<\/strong> <em>Del\u00e9itate asimismo en Jehov\u00e1, Y \u00e9l te conceder\u00e1 las peticiones de tu coraz\u00f3n.<\/em> (<strong>Salmos 37: 4<\/strong>)<\/p>\n<p align=\"justify\"><strong>2.<\/strong> <em>Mas buscad primeramente el reino de Dios y su justicia, y todas estas cosas os ser\u00e1n a\u00f1adidas<\/em>. (<strong>Mateo 6: 33<\/strong>)<\/p>\n<p align=\"justify\"><strong>3.<\/strong> <em>Encomienda a Jehov\u00e1 tu camino, Y conf\u00eda en \u00e9l; y \u00e9l har\u00e1.<\/em> (<strong>Salmos 37: 5<\/strong>)<\/p>\n<p align=\"justify\">No es bueno que pases la mayor\u00eda de tu tiempo llorando por algo que no pudo ser y que no estaba en los planes de Dios que fuera. Es momento de levantarte, lavar tu cara y entender que no puedes seguir derramando l\u00e1grimas, ni lament\u00e1ndote toda tu vida por algo que NO IBA A SER.<\/p>\n<p align=\"justify\">A partir de hoy tienes que comenzar a vivir cada d\u00eda para el Se\u00f1or, con la FE certera de que Dios te recompensara con una persona que SOBREPASARA TUS EXPECTATIVAS y en la cual encontraras TODAS las caracter\u00edsticas que siempre so\u00f1aste y de las cuales ni te imaginabas que podr\u00eda tener.<\/p>\n<p align=\"justify\">Es imp\u00f3rtate aclarar que no es la voluntad de Dios que andes probando varias relaciones haber cual funciona. No puedes andar prestando tu coraz\u00f3n a cualquiera que se te pare enfrente. Por esa raz\u00f3n trata la manera de hacer las cosas como a Dios le agradan, esto es en orden, no te dejes llevar por tus sentimientos, deposita tus decisiones en el Se\u00f1or y b\u00e1sate en su respuesta y su voluntad antes que en la tuya.<\/p>\n<p align=\"justify\">Espera en el Se\u00f1or TODO el tiempo que sea necesario, no le pongas candado a tu coraz\u00f3n creyendo que todos o todas son iguales, al contrario entr\u00e9gale tus emociones y sentimientos al Se\u00f1or para que El te gu\u00ede a tomar la mejor decisi\u00f3n en tu vida sentimental, si haces esto te aseguro que NO FRACASARAS.<\/p>\n<p align=\"justify\">\u00a1Vamos es hora de cambiar la hoja de esa horrible historia que acabas de pasar, y comprender que la siguiente hoja est\u00e1 llena de BELLOS PLANES de Dios especialmente para ti!<\/p>\n<p align=\"justify\">Dedicado a todos los que en alg\u00fan momento de sus vidas se equivocaron en el amor y que creyeron que jam\u00e1s volver\u00edan a encontrar a alguien que los amara.<\/p>\n<p align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\"><em>Autor: Enrique Monterroza &#8211; devocionaldiario.com<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No es bueno que pases la mayor\u00eda de tu tiempo llorando por algo que no pudo ser y que no estaba en los planes de Dios. Parece un tema sacado de una novela, pero no podemos negar la realidad, vivimos un periodo en donde los fracasos sentimentales est\u00e1n a la orden del d\u00eda. En donde &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/olvidando-un-amor-que-no-pudo-ser\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abOlvidando un amor que no pudo ser\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24651","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/24651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=24651"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/24651\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=24651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=24651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=24651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}