{"id":2599,"date":"2015-12-01T00:50:24","date_gmt":"2015-12-01T05:50:24","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/como-descubrir-su-estilo-de-liderazgo\/"},"modified":"2015-12-01T00:50:24","modified_gmt":"2015-12-01T05:50:24","slug":"como-descubrir-su-estilo-de-liderazgo","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/como-descubrir-su-estilo-de-liderazgo\/","title":{"rendered":"C\u00f3mo descubrir su estilo de liderazgo"},"content":{"rendered":"<p style=\"text-align: justify; font-style: italic; \">por Bill Hybles<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p class=\"copete\" style=\"text-align: justify;\">Diez maneras de guiar al pueblo de Dios. Textos b\u00edblicos: Romanos 12:8; Salmo 78:72.<\/p>\n<p class=\"texto\">\n<p><P align=justify>He notado que hay por lo menos diez maneras principales en las que los l\u00edderes dotados gu\u00edan a sus equipos:<\/P><\/p>\n<li style=\"text-align: justify;\">\nL\u00edder visionario. Estos l\u00edderes tienen una imagen bien clara de lo que quieren que suceda. Proyectan las visiones con poder. Est\u00e1n orientados al futuro. Por lo general, son idealistas y est\u00e1n llenos de fe.<\/LI><\/p>\n<li style=\"text-align: justify;\">\nL\u00edder director. En los puntos cr\u00edticos de una organizaci\u00f3n, este l\u00edder es capaz de evaluar los valores, misi\u00f3n, puntos fuertes y d\u00e9biles, recursos, personal y apertura al cambio de una organizaci\u00f3n; y luego, con sabidur\u00eda asombrosa, llevar a la organizaci\u00f3n en la direcci\u00f3n correcta.<\/LI><\/p>\n<li style=\"text-align: justify;\">\nL\u00edder estrat\u00e9gico. Esta persona puede descomponer una visi\u00f3n apasionante en pasos alcanzables, formando un plan de acci\u00f3n que todos pueden entender y en el que todos pueden participar.<\/LI><\/p>\n<li style=\"text-align: justify;\">\nL\u00edder administrador. Ciertos l\u00edderes poseen la habilidad particular de establecer mojones en el camino hacia la meta, y luego organizar a las personas, procesos y recursos para cumplir la misi\u00f3n.<\/LI><\/p>\n<li style=\"text-align: justify;\">\nL\u00edder motivador. Estos l\u00edderes poseen perspicacia para saber qui\u00e9n necesita un nuevo desaf\u00edo o una capacitaci\u00f3n adicional. Pueden percibir qui\u00e9n precisa reconocimiento p\u00fablico, una palabra de aliento o un d\u00eda de descanso.<\/LI><\/p>\n<li style=\"text-align: justify;\">\nL\u00edder protector. Este hombre o esta mujer ama a los miembros del equipo profundamente, los apoya en forma constante, y ora por ellos diligentemente, tanto que la misi\u00f3n del equipo se cumple.<\/LI><\/p>\n<li style=\"text-align: justify;\">\nL\u00edder edificador del equipo. Estos l\u00edderes encuentran o desarrollan l\u00edderes con car\u00e1cter, afinidad con los dem\u00e1s miembros del equipo y habilidades precisas. Colocan a las personas en los puestos apropiados por los motivos correctos, lo que luego producir\u00e1 los resultados adecuados.<\/LI><\/p>\n<li style=\"text-align: justify;\">\nL\u00edder empresario. Estos l\u00edderes poseen visi\u00f3n, energ\u00eda inagotable y esp\u00edritu aventurero. Funcionan mejor en una operaci\u00f3n de lanzamiento.<\/LI><\/p>\n<li style=\"text-align: justify;\">\nL\u00edder ingeniero. Estos l\u00edderes florecen en una situaci\u00f3n donde se ha perdido la visi\u00f3n o el enfoque. Descubren cu\u00e1l era la misi\u00f3n y lo que necesita hacerse ahora, y deciden c\u00f3mo se medir\u00e1 el progreso.<\/LI><\/p>\n<li style=\"text-align: justify;\">\nL\u00edder constructor de puentes. Este l\u00edder tiene una gran variedad de partes bajo un mismo techo, de modo que una organizaci\u00f3n compleja pueda cumplir con su misi\u00f3n. Esto requiere una enorme flexibilidad: habilidad de comprometerse y negociar, escuchar, entender y pensar fuera de lo ya establecido.<\/LI><\/p>\n<p><P align=justify>\u0097BILL HYBELS<\/P><\/p>\n<p><P align=justify>Usado con permiso de Willow Creek Association.<\/P><\/p>\n<p><P align=justify>Para comentar<\/P><br \/>\n<P align=justify>1. \u00bfCu\u00e1l es su principal estilo o estilos de liderazgo?<\/P><br \/>\n<P align=justify>2. \u00bfCu\u00e1n bien se adecua su estilo de liderazgo con los roles que desempe\u00f1a en la iglesia?<\/P><br \/>\n<P align=justify>3. \u00bfQu\u00e9 estilos de liderazgo faltan en su equipo?<\/P>\n                    <\/p>\n<p class=\"pie\" style=\"text-align: justify; font-style: italic; \"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>por Bill Hybles Diez maneras de guiar al pueblo de Dios. Textos b\u00edblicos: Romanos 12:8; Salmo 78:72. He notado que hay por lo menos diez maneras principales en las que los l\u00edderes dotados gu\u00edan a sus equipos: L\u00edder visionario. Estos l\u00edderes tienen una imagen bien clara de lo que quieren que suceda. Proyectan las visiones &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/como-descubrir-su-estilo-de-liderazgo\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abC\u00f3mo descubrir su estilo de liderazgo\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2599","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/2599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=2599"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/2599\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=2599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=2599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=2599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}