{"id":27486,"date":"2016-05-20T13:39:39","date_gmt":"2016-05-20T18:39:39","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/peligro-plantas-asesinas\/"},"modified":"2016-05-20T13:39:39","modified_gmt":"2016-05-20T18:39:39","slug":"peligro-plantas-asesinas","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/peligro-plantas-asesinas\/","title":{"rendered":"\u00a1Peligro! \u00a1Plantas asesinas!"},"content":{"rendered":"\n<p align=\"justify\" id=\"p1\" class=\"st\"><strong>\u00a1Peligro! <\/strong><strong>\u00a1Plantas asesinas!<\/strong><\/p>\n<p align=\"justify\" id=\"p2\" class=\"sa\">De nuestro corresponsal en Gran Breta\u00f1a<\/p>\n<p align=\"justify\" id=\"p3\" class=\"sb\">TODOS sabemos que los animales se alimentan de plantas. Pero \u00bfsab\u00eda usted que algunas plantas se alimentan de animales? Pues bien, se conocen unas quinientas cincuenta especies de plantas carn\u00edvoras \u2014tambi\u00e9n llamadas insect\u00edvoras\u2014, y siguen descubri\u00e9ndose otras. Aunque estas extraordinarias especies vegetales realizan la fotos\u00edntesis, las que crecen en terrenos pobres no\u00a0obtienen suficientes nitratos y otros nutrientes esenciales, por lo que recurren a los insectos como suplemento alimenticio.<\/p>\n<p align=\"justify\" id=\"p4\" class=\"sb\">Cada especie tiene su propio m\u00e9todo de atrapar presas. Unas disponen de cepos, otras de trampillas (una especie de puertecitas) y otras atraen a sus v\u00edctimas hacia trampas resbaladizas o superficies pegajosas de las que resulta imposible escapar. Examinemos las plantas carn\u00edvoras con m\u00e1s detalle.<\/p>\n<p align=\"justify\" id=\"p5\" class=\"ss\"><strong>Cepos y trampillas<\/strong><\/p>\n<p align=\"justify\" id=\"p6\" class=\"sb\">Con toda probabilidad, la\u00a0planta carn\u00edvora m\u00e1s conocida es la <strong>venus atrapamoscas, <\/strong>la cual alcanza unos 30\u00a0cent\u00edmetros de altura y crece en Norteam\u00e9rica, particularmente en las turberas de Carolina del Norte y del Sur. Sus hojas brillantes y de color vivo est\u00e1n bordeadas de gl\u00e1ndulas productoras de un l\u00edquido dulce que constituye una tentaci\u00f3n dif\u00edcil de resistir para los insectos. Y\u00a0ah\u00ed est\u00e1 el peligro, pues la venus atrapamoscas tiene tres pelos sensibles en el centro de cada limbo foliar que hacen que la hoja se cierre cuando un animalito desprevenido los toca. Las espinas que bordean las hojas quedan trabadas, como si fueran las piezas dentadas de un cepo de acero, e impiden que la presa escape.<\/p>\n<p align=\"justify\" id=\"p7\" class=\"sb\">Si cae en la trampa algo empujado por el viento \u2014como una ramita seca\u2014, la planta lo suelta al cabo de un par de d\u00edas. Pero cuando los pelos sensoriales de la hoja detectan la presencia de sustancias nitrogenadas, se liberan unas enzimas que descomponen el cuerpo del insecto capturado para que la planta absorba los nutrientes. Este proceso toma entre diez y treinta y cinco d\u00edas, dependiendo del tama\u00f1o de la presa.<\/p>\n<p align=\"justify\" id=\"p8\" class=\"sb\">Cabe se\u00f1alar que si solo se\u00a0excita un pelo sensorial, tal vez debido a una gota de lluvia, las hojas no\u00a0se cierran, pues estas solo reaccionan cuando se tocan dos o los tres pelos sensoriales, aunque sea a intervalos de hasta veinte segundos. La\u00a0velocidad con que se cierran las hojas depende de la temperatura y de la luz solar. En\u00a0ciertas condiciones, esto sucede en tres cent\u00e9simas de segundo.<\/p>\n<p align=\"justify\" id=\"p9\" class=\"sb\">Con todo, hay especies a\u00fan m\u00e1s veloces. Por ejemplo, las utricularias, mayormente acu\u00e1ticas, tienen hojas que crecen bajo el agua y que presentan numerosos utr\u00edculos, o vejigas, provistos de una trampilla y varios pelos largos. Cuando un animalito \u2014como una pulga de agua\u2014 toca los pelos, se abre la trampilla. Dado que la presi\u00f3n del agua dentro de la vejiga es inferior a la del exterior, la presa es succionada hacia dentro y la trampilla se cierra\u00a0tras ella. Y\u00a0esto sucede en menos de tres cent\u00e9simas de\u00a0segundo.<\/p>\n<p align=\"justify\" id=\"p10\" class=\"ss\"><strong>Trampas resbaladizas<\/strong><\/p>\n<p align=\"justify\" id=\"p11\" class=\"sb\">Entre las plantas carn\u00edvoras m\u00e1s grandes se cuentan las <strong>plantas odre colgantes. <\/strong>Algunas de ellas, como las del sudeste asi\u00e1tico, son trepadoras y crecen hasta llegar a las copas de los \u00e1rboles. Las trampas que utilizan pueden acumular hasta dos litros de l\u00edquido y son capaces de atrapar criaturas del tama\u00f1o de una rana. Al\u00a0parecer, algunas incluso han apresado ratas. Pero \u00bfc\u00f3mo lo hacen?<\/p>\n<p align=\"justify\" id=\"p12\" class=\"sb\">Las hojas de la planta odre parecen una jarra, u odre, y tienen una tapadera para que no\u00a0entre la lluvia. Los insectos son atra\u00eddos por el brillante color y el abundante n\u00e9ctar del interior. Pero cuando uno de ellos trata de llegar al n\u00e9ctar y se posa en el reborde superior, que es resbaladizo, cae dentro del l\u00edquido acumulado en el fondo.\u00a0Como las paredes est\u00e1n revestidas de pelos orientados hacia abajo, le resulta imposible escapar. Adem\u00e1s, el n\u00e9ctar de algunas plantas odre contiene un narc\u00f3tico que adormece a la presa.<\/p>\n<p align=\"justify\" id=\"p13\" class=\"sb\">La m\u00e1s llamativa de todas seguramente es la planta odre de California, conocida tambi\u00e9n como <strong>planta cobra, <\/strong>la cual crece en las monta\u00f1as de California y Oreg\u00f3n (EE.UU.). El\u00a0\u201codre\u201d de la planta se parece mucho a una cobra en posici\u00f3n de ataque. Cuando un insecto se introduce por la boca de la planta, se desorienta con la luz que parece entrar por unas ventanitas. El\u00a0insecto vuela hacia la luz tratando in\u00fatilmente de escapar. Exhausto, cae en el l\u00edquido del fondo y se ahoga.<\/p>\n<p align=\"justify\" id=\"p14\" class=\"ss\"><strong>Valor dom\u00e9stico y comercial<\/strong><\/p>\n<p align=\"justify\" id=\"p15\" class=\"sb\">Las <strong>grasillas <\/strong>tienen hojas pegajosas que atraen a la mosca esci\u00e1rida y a la mosquita blanca de los invernaderos. Estos insectos son una plaga tanto para las plantas comerciales de invernadero como para las plantas dom\u00e9sticas de interior. Los sistemas artificiales para atrapar moscas son eficaces pero indiscriminados, pues tambi\u00e9n eliminan las abejas y las moscas de las flores. En\u00a0cambio, las grasillas son mejores porque solo se adhieren a ellas los peque\u00f1os insectos perjudiciales.<\/p>\n<p align=\"justify\" id=\"p16\" class=\"sb\">Las <strong>plantas odre de Norteam\u00e9rica <\/strong>est\u00e1n ganando popularidad entre los jardineros. Sus hermosas flores y la elegante forma de sus hojas las hacen m\u00e1s atractivas que otras especies, y son f\u00e1ciles de cultivar. Adem\u00e1s, consumen una inmensa cantidad de moscas. De\u00a0hecho, cada planta puede terminar con miles de moscas en una estaci\u00f3n. Las abejas no\u00a0corren peligro, pues parece que no\u00a0se sienten atra\u00eddas por este tipo de planta. Pero \u00bfc\u00f3mo se fecundan las flores sin atrapar a los insectos que las polinizan? Las flores aparecen primero, mientras las hojas todav\u00eda no\u00a0han terminado de adoptar la forma de odres. Para cuando estos ya est\u00e1n formados, las flores han muerto y los insectos polinizadores se han ido.<\/p>\n<p align=\"justify\" id=\"p17\" class=\"sb\">Una variedad f\u00e1cil de cultivar y que tolera una gran diferencia de temperaturas es la <strong><em>Drosera dichotoma, <\/em><\/strong>natural de Australia. \u201cEs una planta ideal para quienes no\u00a0pueden sentarse afuera por las noches debido a los mosquitos\u201d, dice Chris Heath, especialista en plantas carn\u00edvoras del Walworth Garden Farm Environmental Education Centre, una organizaci\u00f3n educativa y ben\u00e9fica de Londres. Su\u00a0consejo es: \u201cPl\u00e1ntela en una cesta colgante para que sus brillantes gotitas atraigan a los mosquitos\u201d. Cuando estos rozan una hoja, quedan adheridos a ella por sus pegajosos pelos, los cuales se curvan hacia dentro y aprietan al insecto contra la superficie de la hoja.<\/p>\n<p align=\"justify\" id=\"p18\" class=\"ss\"><strong>La conservaci\u00f3n de las plantas carn\u00edvoras<\/strong><\/p>\n<p align=\"justify\" id=\"p19\" class=\"sb\">Lamentablemente, muchas plantas carn\u00edvoras crecen en h\u00e1bitats que el hombre est\u00e1 destrozando. Por ejemplo, la planta odre colgante del sudeste asi\u00e1tico est\u00e1 en peligro de extinci\u00f3n debido a la agricultura itinerante de tala y quema. En\u00a0otros lugares se desecan los pantanos con fines urban\u00edsticos. Debido a ello, algunas especies ya se han extinguido.*<\/p>\n<div id=\"p20\">\n<p align=\"justify\" class=\"sb\">\u00bfLe gustar\u00eda tener una planta carn\u00edvora? No\u00a0tiene que arrancarla del campo, pues muchas de ellas se pueden obtener f\u00e1cilmente en establecimientos que las multiplican a trav\u00e9s de semillas o mediante la t\u00e9cnica de cultivo de tejidos. Las instrucciones para su cuidado son sencillas: mantener la planta h\u00fameda en todo momento con agua de lluvia. Adem\u00e1s, a las plantas carn\u00edvoras les beneficia la luz solar, pero a las especies de zonas templadas es mejor mantenerlas en un lugar fresco durante el invierno.<\/p>\n<p align=\"justify\" class=\"sb\">Eso s\u00ed, hace falta paciencia, pues algunas de estas plantas necesitan hasta tres a\u00f1os para alcanzar la madurez. Pero por lo menos no\u00a0hay que darles alimento, \u00a1ellas mismas se lo buscan!<\/p>\n<\/div>\n<p align=\"justify\" id=\"p21\" class=\"sf\"><strong>[Nota]<\/strong><\/p>\n<div id=\"fn1\" class=\"fcc\">\n<p align=\"justify\" id=\"p22\">Ciertas plantas insect\u00edvoras est\u00e1n protegidas por la Convenci\u00f3n sobre el Comercio Internacional de Especies Amenazadas.<\/p>\n<\/div>\n<p align=\"justify\" id=\"p23\" class=\"se\"><strong>[Recuadro de la p\u00e1gina 27]<\/strong><\/p>\n<p align=\"justify\" id=\"p24\" class=\"sc\">\u25aa  <strong>Hongos carn\u00edvoros<\/strong><\/p>\n<p align=\"justify\" id=\"p25\" class=\"sc\">  Las plantas carn\u00edvoras m\u00e1s peque\u00f1as son unos hongos que cazan gusanos nematodos microsc\u00f3picos que viven en la tierra. Algunos de estos hongos poseen unos nudos pegajosos sobre ped\u00fanculos, y otros tienen unos ap\u00e9ndices con tres lazadas de tan solo 25 micras de grosor que se cierran alrededor de cualquier nematodo que se introduzca en ellas sin darse cuenta. Tan pronto como el gusano queda atrapado, es invadido por los filamentos del hongo y muere. Estos hongos son objeto de estudio por su potencial como pesticidas, ya que los da\u00f1os que los nematodos causan a los cultivos ascienden todos los a\u00f1os a centenares de millones de d\u00f3lares.<\/p>\n<p align=\"justify\" id=\"p26\" class=\"se\"><strong>[Recuadro de la p\u00e1gina 27]<\/strong><\/p>\n<p align=\"justify\" id=\"p27\" class=\"sc\">\u25aa  <strong>\u00a1Los insectos contraatacan!<\/strong><\/p>\n<p align=\"justify\" id=\"p28\" class=\"sc\">  No todos los insectos sucumben a las tretas de las plantas insect\u00edvoras. La\u00a0mosca de la carne, por ejemplo, tiene un ap\u00e9ndice en cada pie que le permite trepar por los pelos orientados hacia el fondo de la planta odre como si fuera un escalador. Cuando sus huevos eclosionan, las larvas se alimentan de los insectos en descomposici\u00f3n. Luego, cuando est\u00e1n a punto de convertirse en pupa, agujerean las paredes del odre y escapan. Las orugas de una peque\u00f1a polilla tejen una tela con la que cubren los molestos pelos de la planta odre. Algunas ara\u00f1as tejen sus telas astutamente sobre las plantas odre para acceder primero a los insectos curiosos que se le acercan, y por lo menos en el caso de una especie, la piel de la ara\u00f1a es de tales caracter\u00edsticas que le permite refugiarse en los jugos g\u00e1stricos de la planta si se ve amenazada.<\/p>\n<p align=\"justify\" id=\"p29\" class=\"se\"><strong>[Ilustraci\u00f3n de la p\u00e1gina 24]<\/strong><\/p>\n<p align=\"justify\" id=\"p30\" class=\"sc\">Hoja de planta odre colgante<\/p>\n<p align=\"justify\" id=\"p31\" class=\"se\"><strong>[Ilustraci\u00f3n de las p\u00e1ginas 24 y 25]<\/strong><\/p>\n<p align=\"justify\" id=\"p32\" class=\"sc\">Venus atrapamoscas:<\/p>\n<p align=\"justify\" id=\"p33\" class=\"sk\">en la hoja de la izquierda se ve una mosca atrapada; en la de la derecha, los pelos sensoriales<\/p>\n<p align=\"justify\" id=\"p34\" class=\"sc\"><strong>[Reconocimiento]<\/strong><\/p>\n<p align=\"justify\" id=\"p35\" class=\"sc\">Plantas: Copyright Chris Heath, Kentish Town City Farm, London<\/p>\n<p align=\"justify\" id=\"p36\" class=\"se\"><strong>[Ilustraci\u00f3n de la p\u00e1gina 25]<\/strong><\/p>\n<p align=\"justify\" id=\"p37\" class=\"sc\">Flor y hoja (a\u00fan sin forma de odre) de la\u00a0planta cobra<\/p>\n<p align=\"justify\" id=\"p38\" class=\"sc\"><strong>[Reconocimiento]<\/strong><\/p>\n<p align=\"justify\" id=\"p39\" class=\"sc\">Copyright Chris Heath, Kentish Town City Farm, London<\/p>\n<p align=\"justify\" id=\"p40\" class=\"se\"><strong>[Ilustraci\u00f3n de la p\u00e1gina 26]<\/strong><\/p>\n<p align=\"justify\" id=\"p41\" class=\"sc\">Planta odre de\u00a0Norteam\u00e9rica:<\/p>\n<p align=\"justify\" id=\"p42\" class=\"sk\">su flor es del tama\u00f1o de una naranja<\/p>\n<p align=\"justify\" id=\"p43\" class=\"se\"><strong>[Ilustraci\u00f3n de la p\u00e1gina 26]<\/strong><\/p>\n<p align=\"justify\" id=\"p44\" class=\"sc\">Grasilla:<\/p>\n<p align=\"justify\" id=\"p45\" class=\"sk\">en sus pegajosas hojas quedan atrapadas las moscas esci\u00e1ridas y las\u00a0mosquitas blancas de los invernaderos<\/p>\n<p align=\"justify\" id=\"p46\" class=\"se\"><strong>[Ilustraciones de la p\u00e1gina 26]<\/strong><\/p>\n<p align=\"justify\" id=\"p47\" class=\"sc\">Hojas de la planta odre\u00a0de Norteam\u00e9rica;<\/p>\n<p align=\"justify\" id=\"p48\" class=\"sk\">arriba: mosca tomando n\u00e9ctar que la deja adormilada<\/p>\n<p align=\"justify\" id=\"p49\" class=\"se\"><strong>[Ilustraci\u00f3n de la p\u00e1gina 26]<\/strong><\/p>\n<p align=\"justify\" id=\"p50\" class=\"sc\"><em>Drosera dichotoma:<\/em><\/p>\n<p align=\"justify\" id=\"p51\" class=\"sk\">insecto atrapado por los pelos pegajosos de la hoja<\/p>\n<p align=\"justify\" id=\"p52\" class=\"sc\"><strong>[Reconocimiento]<\/strong><\/p>\n<p align=\"justify\" id=\"p53\" class=\"sc\">Plantas: Copyright Chris Heath, Kentish\u00a0Town City Farm, London<\/p>\n<p align=\"justify\" id=\"p54\" class=\"sb\">\n<p>Fuente: \u00a1Despertad!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Peligro! \u00a1Plantas asesinas! De nuestro corresponsal en Gran Breta\u00f1a TODOS sabemos que los animales se alimentan de plantas. Pero \u00bfsab\u00eda usted que algunas plantas se alimentan de animales? Pues bien, se conocen unas quinientas cincuenta especies de plantas carn\u00edvoras \u2014tambi\u00e9n llamadas insect\u00edvoras\u2014, y siguen descubri\u00e9ndose otras. Aunque estas extraordinarias especies vegetales realizan la fotos\u00edntesis, las &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/peligro-plantas-asesinas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00a1Peligro! \u00a1Plantas asesinas!\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27486","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/27486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=27486"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/27486\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=27486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=27486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=27486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}