{"id":27555,"date":"2016-05-20T13:43:11","date_gmt":"2016-05-20T18:43:11","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/observando-el-mundo-110\/"},"modified":"2016-05-20T13:43:11","modified_gmt":"2016-05-20T18:43:11","slug":"observando-el-mundo-110","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/observando-el-mundo-110\/","title":{"rendered":"Observando el mundo"},"content":{"rendered":"\n<p align=\"justify\" id=\"p1\" class=\"st\"><strong>Observando el mundo<\/strong><\/p>\n<p align=\"justify\" id=\"p2\" class=\"ss\"><strong>Nubes y elefantes<\/strong><\/p>\n<p align=\"justify\" id=\"p3\" class=\"sb\">\u00bfQu\u00e9 peso alcanza una nube? Seg\u00fan la agencia ABC News, un c\u00famulo viene a contener 550 toneladas de agua. \u201cPara visualizarlo mejor \u2014recomend\u00f3 la meteor\u00f3loga Peggy LeMone\u2014,\u00a0[&#8230;] tomemos como referencia a los elefantes.\u201d Tomando como base para estos animales un promedio de seis toneladas, el agua de un c\u00famulo normal equivaldr\u00eda a 100 espec\u00edmenes. Todo ese l\u00edquido se encuentra en gotas diminutas que flotan en el aire c\u00e1lido ascendente. A\u00a0diferencia del algodonoso c\u00famulo, el nubarr\u00f3n de tormenta es comparable a 200.000 de tales paquidermos. \u00bfY\u00a0las nubes de hurac\u00e1n? LeMone calcul\u00f3 el peso del agua en un metro c\u00fabico de tales nubes y lo multiplic\u00f3 por el volumen total, con lo que obtuvo un resultado equiparable a 40.000.000 de ejemplares. \u201cDe esto se desprende que el agua transportada por un hurac\u00e1n pesa m\u00e1s que todos los elefantes que existen \u2014y tal vez m\u00e1s que todos los que han existido\u2014 en el planeta\u201d, concluye el informe.<\/p>\n<p align=\"justify\" id=\"p4\" class=\"ss\"><strong>El mejor momento para lavarse los dientes<\/strong><\/p>\n<p align=\"justify\" id=\"p5\" class=\"sb\">Seg\u00fan el peri\u00f3dico <em>Milenio, <\/em>de la ciudad de M\u00e9xico, cepillarse los dientes justo despu\u00e9s de haber consumido bebidas o alimentos \u00e1cidos puede da\u00f1ar el esmalte. Bas\u00e1ndose en un informe de la Universidad de Gotinga (Alemania), el diario advierte que los alimentos \u00e1cidos debilitan temporalmente el esmalte dental, por lo que el cepillado nada m\u00e1s acabar el almuerzo tal vez sea nocivo. As\u00ed pues, es conveniente esperar unos minutos para que los dientes recuperen su fuerza.<\/p>\n<p align=\"justify\" id=\"p6\" class=\"ss\"><strong>Ave reci\u00e9n descubierta pierde su h\u00e1bitat<\/strong><\/p>\n<p align=\"justify\" id=\"p7\" class=\"sb\">De acuerdo con el rotativo caraque\u00f1o <em>Daily Journal, <\/em>cuando los constructores de una represa venezolana deforestaron el islote deshabitado de Carrizal, ubicado en el r\u00edo Caron\u00ed, se descubri\u00f3 un p\u00e1jaro desconocido. Entre los espec\u00edmenes retirados antes de eliminar la vegetaci\u00f3n apareci\u00f3 un peque\u00f1o pinz\u00f3n con manchas azules que viv\u00eda en la impenetrable espesura de los bamb\u00faes. Los naturalistas esperan encontrar en las cercan\u00edas m\u00e1s ejemplares de esta especie reci\u00e9n catalogada. \u201cLa alegr\u00eda del descubrimiento del semillero de Carrizal\u00a0[&#8230;] se ve empa\u00f1ada por el reconocimiento de que hemos destruido el lugar donde por tanto tiempo se escondi\u00f3 de nosotros esta ave\u201d, indica el investigador Robin Restall.<\/p>\n<p align=\"justify\" id=\"p8\" class=\"ss\"><strong>La limpieza de las tablas de cocina<\/strong><\/p>\n<p align=\"justify\" id=\"p9\" class=\"sb\">\u00bfQu\u00e9 tablas de cortar son m\u00e1s higi\u00e9nicas: las de madera, o las de pl\u00e1stico? \u201cLas dos son adecuadas siempre que est\u00e9n muy limpias \u2014afirma el bolet\u00edn <em>UC Berkeley Wellness Letter<\/em>\u2014. Sin importar el material, deben fregarse a fondo con agua jabonosa caliente despu\u00e9s de cortar carne cruda.\u201d Si tienen muchos surcos o est\u00e1n grasientas, conviene extremar la limpieza. \u201cPueden desinfectarse con una soluci\u00f3n de una cucharadita de blanqueador en un litro de agua\u201d, indica el bolet\u00edn. Tambi\u00e9n deben lavarse y secarse bien las manos y los cuchillos.<\/p>\n<p align=\"justify\" id=\"p10\" class=\"ss\"><strong>Los preescolares y la inform\u00e1tica<\/strong><\/p>\n<p align=\"justify\" id=\"p11\" class=\"sb\">El peri\u00f3dico <em>The Vancouver Sun <\/em>dice que, de acuerdo con ciertos peritos, \u201cel uso prolongado de computadoras como sustituto de los juegos tradicionales\u201d reporta pocas ventajas a los preescolares y \u201cpuede ocasionarles aislamiento social, problemas de concentraci\u00f3n, p\u00e9rdida de creatividad e incluso depresi\u00f3n y ansiedad\u201d. La\u00a0computadora traslada al ni\u00f1o de un mundo \u201ctridimensional y experiencial a otro bidimensional y virtual\u201d, afirma la psic\u00f3loga Sharna Olfman. Los investigadores destacan la importancia de \u201clos juegos de imitaci\u00f3n supervisados por los padres\u201d como medio de ense\u00f1arles \u201cpalabras, colores, formas, n\u00fameros, modales y aspectos de la vida cotidiana\u201d. La\u00a0psic\u00f3loga Jane Healy asegura que los juegos tradicionales revisten especial importancia durante los primeros siete a\u00f1os de vida. Tales actividades ayudan al peque\u00f1o a prestar atenci\u00f3n, mientras que es posible que los est\u00edmulos inform\u00e1ticos produzcan el efecto contrario.<\/p>\n<p align=\"justify\" id=\"p12\" class=\"ss\"><strong>La televisi\u00f3n como \u201cdroga dura\u201d<\/strong><\/p>\n<p align=\"justify\" id=\"p13\" class=\"sb\">\u201cLos ni\u00f1os que ven m\u00e1s de dos horas de televisi\u00f3n rinden menos en el colegio\u201d, indica el diario espa\u00f1ol <em>La Vanguardia. <\/em>Tras afirmar que la peque\u00f1a pantalla puede ser un magn\u00edfico instrumento pedag\u00f3gico, el pediatra Francisco Mu\u00f1oz denuncia los efectos de pasar demasiado tiempo con ella. En\u00a0su opini\u00f3n, los rendimientos m\u00e1s bajos de quienes abusan de este medio se deben al \u201cretraso del proceso madurativo y a una menor capacidad de abstracci\u00f3n\u201d. Adem\u00e1s agrega: \u201cExiste una relaci\u00f3n clara entre la visi\u00f3n de ciertos programas, publicidad y v\u00eddeos musicales con el consumo de alcohol, tabaco y drogas entre los adolescentes\u201d. Si bien admite que no\u00a0todos los menores van a imitar la mala conducta que ven en la pantalla, el psiquiatra infantil Paulino Castells cataloga a la televisi\u00f3n de \u201cdroga dura\u201d por los \u201cperniciosos efectos que causa en las mentes m\u00e1s fr\u00e1giles\u201d.<\/p>\n<p align=\"justify\" id=\"p14\" class=\"ss\"><strong>Aulas ruidosas<\/strong><\/p>\n<p align=\"justify\" id=\"p15\" class=\"sb\">Los ecos y ruidos de fondo que se producen en las aulas dificultan la buena audici\u00f3n de los alumnos, de acuerdo con la revista alemana <em>Der Spiegel. <\/em>\u201cCuanto m\u00e1s dif\u00edcil le resulta al ni\u00f1o entender algo, menos capaz ser\u00e1 de retenerlo\u201d, asegura la psic\u00f3loga Maria Klatte. En\u00a0algunos centros educativos de Alemania se registraron niveles de sonido de 70 a 90 decibeles (dB). \u201cEn los empleos donde se realiza una intensa labor intelectual, el l\u00edmite es de 55 dB\u201d, indica el investigador especializado en ruido Gerhart Tiesler, quien a\u00f1adi\u00f3: \u201cEn la industria se recomienda protegerse los o\u00eddos cuando se superan los 85 dB\u201d. Adem\u00e1s, cuanto m\u00e1s reverbera el sonido en un sal\u00f3n de clases \u2014sean palabras, movimiento de sillas o toses\u2014, m\u00e1s dif\u00edcil es concentrarse. Los techos ac\u00fasticos reducen el ruido y el eco, con el consiguiente alivio para los nervios y las gargantas de maestros y estudiantes, pero muchas escuelas no\u00a0tienen medios para costearlos.<\/p>\n<p align=\"justify\" id=\"p16\" class=\"ss\"><strong>Los supermercados desplazan a los comercios tradicionales<\/strong><\/p>\n<p align=\"justify\" id=\"p17\" class=\"sb\">\u201cLa proliferaci\u00f3n de supermercados en el este y sur de \u00c1frica amenaza a los mercados locales y, por ende, a los medios de subsistencia de los agricultores y ganaderos de las regiones rurales\u201d, se\u00f1ala el bolet\u00edn cient\u00edfico alem\u00e1n <em>wissenschaft-online. <\/em>En\u00a0la actualidad, el 30% de las ventas minoristas de alimentos en Kenia tienen lugar en 200 supermercados y diez hipermercados, lo que equivale al volumen conjunto de 90.000 comercios peque\u00f1os. En\u00a0opini\u00f3n de Kostas Stamoulis \u2014de la Organizaci\u00f3n de las Naciones Unidas para la Agricultura y la Alimentaci\u00f3n\u2014, la globalizaci\u00f3n y la r\u00e1pida urbanizaci\u00f3n \u201cimpondr\u00e1n a \u00c1frica cambios m\u00e1s radicales en el sistema de distribuci\u00f3n de alimentos que los que hemos visto en los pa\u00edses desarrollados\u201d. Los expertos esperan que se evite la cat\u00e1strofe creando cooperativas que ofrezcan un mercado para los productos locales y capacitando a los agricultores y ganaderos para facilitarles la transici\u00f3n.<\/p>\n<p align=\"justify\" id=\"p18\" class=\"sb\">\n<p>Fuente: \u00a1Despertad!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Observando el mundo Nubes y elefantes \u00bfQu\u00e9 peso alcanza una nube? Seg\u00fan la agencia ABC News, un c\u00famulo viene a contener 550 toneladas de agua. \u201cPara visualizarlo mejor \u2014recomend\u00f3 la meteor\u00f3loga Peggy LeMone\u2014,\u00a0[&#8230;] tomemos como referencia a los elefantes.\u201d Tomando como base para estos animales un promedio de seis toneladas, el agua de un c\u00famulo &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/observando-el-mundo-110\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abObservando el mundo\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27555","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/27555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=27555"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/27555\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=27555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=27555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=27555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}