{"id":27556,"date":"2016-05-20T13:43:15","date_gmt":"2016-05-20T18:43:15","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/de-nuestros-lectores-110\/"},"modified":"2016-05-20T13:43:15","modified_gmt":"2016-05-20T18:43:15","slug":"de-nuestros-lectores-110","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/de-nuestros-lectores-110\/","title":{"rendered":"De nuestros lectores"},"content":{"rendered":"\n<p align=\"justify\" id=\"p1\" class=\"st\"><strong>De nuestros lectores<\/strong><\/p>\n<p align=\"justify\" id=\"p2\" class=\"sb\"><strong>El mundo agropecuario  <\/strong>Les escribo para expresarles mi reconocimiento por el reportaje \u201c\u00bfA qu\u00e9 se debe la crisis del campo?\u201d (8 de octubre de\u00a02003). Pertenezco a una comunidad rural en la que muchos est\u00e1n vendiendo sus tierras por los problemas econ\u00f3micos y otras razones. Da\u00a0la impresi\u00f3n de que cada d\u00eda surgen nuevas urbanizaciones en donde hab\u00eda cultivos. A\u00a0veces me pregunto si quedar\u00e1 espacio para la agricultura. Lo\u00a0que m\u00e1s me conforta es saber que Jehov\u00e1 solucionar\u00e1 definitivamente la crisis del campo.<\/p>\n<p align=\"justify\" id=\"p3\" class=\"sj\">V. A., Estados Unidos<\/p>\n<p align=\"justify\" id=\"p4\" class=\"sb\"><strong>Mosaicos  <\/strong>Quer\u00eda darles las gracias por el art\u00edculo \u201cEl mosaico: el arte de pintar con piedras\u201d (8 de octubre de\u00a02003), cuyas p\u00e1ginas incluyen la foto de uno de los mosaicos de un parque estatal cercano. He vivido cerca de all\u00ed por m\u00e1s de una d\u00e9cada y nunca los hab\u00eda visto. Fui a contemplarlos y qued\u00e9 muy impresionada. Ahora tengo en mayor estima este arte.<\/p>\n<p align=\"justify\" id=\"p5\" class=\"sj\">E. D., Estados Unidos<\/p>\n<p align=\"justify\" id=\"p6\" class=\"sb\">Ten\u00eda la intenci\u00f3n de informarme mejor sobre los mosaicos, particularmente desde que en\u00a01993 asistimos a las asambleas que celebraron los testigos de Jehov\u00e1 en Rusia. En\u00a0San Petersburgo y Mosc\u00fa pudimos admirar muchos bellos ejemplos. Deseo expresar mi agradecimiento a los artistas, por dedicar tantos a\u00f1os a este arte, y a ustedes, por publicar un reportaje tan instructivo.<\/p>\n<p align=\"justify\" id=\"p7\" class=\"sj\">B. Z., Alemania<\/p>\n<p align=\"justify\" id=\"p8\" class=\"sb\"><strong>Estilos de vida alternativos  <\/strong>Muchas gracias por el art\u00edculo \u201cEl punto de vista b\u00edblico: \u00bfAprueba Dios los estilos de vida alternativos?\u201d (8 de octubre de\u00a02003). Tengo 17\u00a0a\u00f1os y me he criado en un hogar cristiano. No\u00a0obstante, siento deseos homosexuales desde muy joven. Aunque me cuesta mucho entender esos impulsos, me tranquiliza saber que Jehov\u00e1 comprende mi lucha interna. A\u00a0quienes hagan frente a tales emociones, les doy este consejo: \u00a1No\u00a0se rindan!<\/p>\n<p align=\"justify\" id=\"p9\" class=\"sj\">J. M., Estados Unidos<\/p>\n<p align=\"justify\" id=\"p10\" class=\"sb\">Llevo toda la vida atormentada por la atracci\u00f3n sexual pervertida, as\u00ed que me he visto reflejada en su art\u00edculo. En\u00a0mi caso, sufro los terribles efectos de haber visto pornograf\u00eda desde muy peque\u00f1a y de haber padecido abusos sexuales. Gracias por la ayuda para entenderme a m\u00ed misma.<\/p>\n<p align=\"justify\" id=\"p11\" class=\"sj\">J. B.\u00a0M., Estados Unidos<\/p>\n<p align=\"justify\" id=\"p12\" class=\"sb\">En el campo de las inclinaciones sexuales, conviene tener presente la influencia de la gen\u00e9tica, las hormonas, la crianza y muchos otros factores. Ciertamente, quienes luchan con sus tendencias homosexuales pueden recibir apoyo en la congregaci\u00f3n cristiana.<\/p>\n<p align=\"justify\" id=\"p13\" class=\"sj\">D. L., Gran Breta\u00f1a<\/p>\n<p align=\"justify\" id=\"p14\" class=\"si\"><strong>\u00a1Despertad! <em>responde: <\/em><\/strong>Nos condolemos sinceramente de quienes luchan con sus tendencias sexuales. Como se indic\u00f3 en el art\u00edculo, las causas de tales dificultades pueden ser complejas. Ahora bien, mientras la persona no\u00a0cultive deliberadamente los deseos inmorales ni\u00a0los lleve a la pr\u00e1ctica, puede seguir pura a los ojos de Jehov\u00e1 Dios y estar segura de que a \u00e9l le complacen los esfuerzos que haga por mantener la limpieza moral (Proverbios 27:11).<\/p>\n<p align=\"justify\" id=\"p15\" class=\"sb\"><strong>Molinos  <\/strong>Me encant\u00f3 el reportaje \u201cLos molinos de viento: elegantes recuerdos de tiempos pasados\u201d (8 de octubre de\u00a02003). Aprend\u00ed que no\u00a0solo se utilizaban para moler grano, sino para muchos otros fines. No\u00a0soy m\u00e1s que un chico de campo, y me siento incapaz de expresar cu\u00e1nto agradezco la informaci\u00f3n que me dan.<\/p>\n<p align=\"justify\" id=\"p16\" class=\"sj\">S. A., Rusia<\/p>\n<p align=\"justify\" id=\"p17\" class=\"sb\"><strong>Aprecio por <em>\u00a1Despertad!  <\/em><\/strong>Gracias por el n\u00famero del 8 de octubre de\u00a02003. Fue el primero que le\u00ed entero. Me estoy dando cuenta de que deber\u00eda haberme beneficiado de todo lo que nos provee Jehov\u00e1. La\u00a0verdad es que me sorprendi\u00f3 lo interesante que era. Es\u00a0una l\u00e1stima que a pesar de contar con una revista tan magn\u00edfica, no\u00a0la hubiera le\u00eddo de cabo a rabo hasta ahora.<\/p>\n<p align=\"justify\" id=\"p18\" class=\"sj\">R. K., Jap\u00f3n<\/p>\n<p align=\"justify\" id=\"p19\" class=\"sb\">\n<p>Fuente: \u00a1Despertad!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De nuestros lectores El mundo agropecuario Les escribo para expresarles mi reconocimiento por el reportaje \u201c\u00bfA qu\u00e9 se debe la crisis del campo?\u201d (8 de octubre de\u00a02003). Pertenezco a una comunidad rural en la que muchos est\u00e1n vendiendo sus tierras por los problemas econ\u00f3micos y otras razones. Da\u00a0la impresi\u00f3n de que cada d\u00eda surgen nuevas &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/de-nuestros-lectores-110\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDe nuestros lectores\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27556","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/27556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=27556"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/27556\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=27556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=27556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=27556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}