{"id":29168,"date":"2016-06-07T12:36:27","date_gmt":"2016-06-07T17:36:27","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/valoran-el-amor-de-dios\/"},"modified":"2016-06-07T12:36:27","modified_gmt":"2016-06-07T17:36:27","slug":"valoran-el-amor-de-dios","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/valoran-el-amor-de-dios\/","title":{"rendered":"Valoran el amor de Dios"},"content":{"rendered":"\n<p align=\"justify\" id=\"p1\" data-pid=\"1\" class=\"st\"><strong>Valoran el amor de Dios<\/strong><\/p>\n<p align=\"justify\" id=\"p2\" data-pid=\"2\" class=\"sn\">\u25cf Jes\u00fas nos ense\u00f1\u00f3 a valorar el amor de Dios. Dijo: \u201cTanto am\u00f3 Dios al mundo que dio a su Hijo unig\u00e9nito [Jes\u00fas], para que todo el que ejerce fe en \u00e9l no\u00a0sea destruido, sino que tenga vida eterna\u201d (Juan 3:16). El\u00a0amor que Dios nos tiene y el gran porvenir que nos espera gracias a que nos dio a su Hijo son algunos de los temas que destaca el libro <em>Acerqu\u00e9monos a Jehov\u00e1.<\/em><\/p>\n<p align=\"justify\" id=\"p3\" data-pid=\"3\" class=\"sb\">Una mujer de Florida (Estados Unidos) escribi\u00f3: \u201cCuando le\u00ed el cap\u00edtulo 5, no\u00a0pude sino sentirme asombrada por el amor, la sabidur\u00eda y el inmenso poder de Jehov\u00e1. Meditar sobre sus creaciones me ha hecho amarlo a\u00fan m\u00e1s\u201d. Otra mujer, de Dakota del Sur (Estados Unidos), relat\u00f3: \u201cPor m\u00e1s de treinta a\u00f1os he encontrado muy dif\u00edcil expresar amor o sentirme amada. Ning\u00fan otro libro me ha ayudado tanto como este\u201d.<\/p>\n<p align=\"justify\" id=\"p4\" data-pid=\"4\" class=\"sb\">El libro <em>Acerqu\u00e9monos a Jehov\u00e1, <\/em>de 320 p\u00e1ginas, analiza las cualidades primordiales de Dios, que son el poder, la justicia, la sabidur\u00eda y el amor. Para solicitarlo, llene el cup\u00f3n adjunto y env\u00edelo a la direcci\u00f3n indicada o a la que corresponda de las que aparecen en la p\u00e1gina 5 de esta revista.<\/p>\n<p align=\"justify\" id=\"p5\" data-pid=\"5\" class=\"su\">\u25a1 Deseo recibir este libro sin compromiso alguno.<\/p>\n<p align=\"justify\" id=\"p6\" data-pid=\"6\" class=\"su\">\u25a1 Deseo que me informen sobre sus cursos b\u00edblicos gratuitos a domicilio.<\/p>\n<p align=\"justify\" id=\"p7\" data-pid=\"7\" class=\"sb\">\n<p>Fuente: \u00a1Despertad!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valoran el amor de Dios \u25cf Jes\u00fas nos ense\u00f1\u00f3 a valorar el amor de Dios. Dijo: \u201cTanto am\u00f3 Dios al mundo que dio a su Hijo unig\u00e9nito [Jes\u00fas], para que todo el que ejerce fe en \u00e9l no\u00a0sea destruido, sino que tenga vida eterna\u201d (Juan 3:16). El\u00a0amor que Dios nos tiene y el gran porvenir &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/valoran-el-amor-de-dios\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abValoran el amor de Dios\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29168","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/29168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=29168"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/29168\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=29168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=29168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=29168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}