{"id":29170,"date":"2016-06-07T12:36:38","date_gmt":"2016-06-07T17:36:38","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/todos-quieren-estar-conectados\/"},"modified":"2016-06-07T12:36:38","modified_gmt":"2016-06-07T17:36:38","slug":"todos-quieren-estar-conectados","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/todos-quieren-estar-conectados\/","title":{"rendered":"Todos quieren estar conectados"},"content":{"rendered":"\n<p align=\"justify\" id=\"p1\" data-pid=\"1\" class=\"st\"><strong>Todos quieren estar conectados<\/strong><\/p>\n<p align=\"justify\" id=\"p2\" data-pid=\"2\" class=\"sn\">\u25cf Imagine la siguiente situaci\u00f3n. Sam se ha resistido por a\u00f1os a la idea de utilizar la tecnolog\u00eda moderna para mantenerse en comunicaci\u00f3n con sus familiares y amigos. Lo\u00a0llaman el Anticuado. Todo el mundo \u2014hasta sus hijos adolescentes\u2060\u2014 quiere estar conectado. En\u00a0cierta ocasi\u00f3n le dice a su hija de 16 a\u00f1os: \u201c\u00a1Echo mucho de menos los d\u00edas en que uno hablaba con la gente cara a cara!\u201d.<\/p>\n<p align=\"justify\" id=\"p3\" data-pid=\"3\" class=\"sb\">Con el tiempo, Sam comienza a reconsiderar su postura. Piensa en los amigos a los que no\u00a0ha visto o con los que no\u00a0ha hablado por a\u00f1os. Piensa tambi\u00e9n en aquellos parientes con los que no\u00a0tiene mucha relaci\u00f3n porque viven muy ocupados. \u201cSi quiero mantenerme en contacto \u2014dice\u2060\u2014, voy a tener que empezar a usar el nuevo sistema.\u201d La\u00a0escena se sit\u00faa en una zona rural de Estados Unidos a mediados del siglo\u00a0XX. El\u00a0anticuado de Sam al fin se decide a conseguir un tel\u00e9fono.<\/p>\n<p align=\"justify\" id=\"p4\" data-pid=\"4\" class=\"sb\">Avancemos ahora al a\u00f1o\u00a02012. Nathan,\u00a0nieto\u00a0de Sam, acaba de hablar por tel\u00e9fono con Roberto y \u00c1ngela, dos amigos \u00edntimos que se mudaron al otro lado del mundo. \u201c\u00a1Hace ya diez a\u00f1os que se fueron!\u201d, murmura, asombrado de lo r\u00e1pido que ha pasado el tiempo.<\/p>\n<p align=\"justify\" id=\"p5\" data-pid=\"5\" class=\"sb\">A lo largo de los a\u00f1os, Nathan se ha conformado con recibir ocasionalmente una llamada de familiares y amigos que se han mudado lejos. Pero ahora parece que todo el mundo \u2014hasta sus hijos adolescentes\u2060\u2014 utiliza una red social para estar en contacto.<\/p>\n<p align=\"justify\" id=\"p6\" data-pid=\"6\" class=\"sb\">La gente llama a Nathan anticuado porque se resiste a subir al tren de la t\u00e9cnica. \u201cEcho mucho de menos los d\u00edas en que uno hablaba por tel\u00e9fono y o\u00eda la voz de la persona\u201d, se lamenta. Entonces comienza a reconsiderar su postura. \u201cSi quiero mantenerme en contacto \u2014dice\u2060\u2014, voy a tener que empezar a usar el nuevo sistema.\u201d<\/p>\n<p align=\"justify\" id=\"p7\" data-pid=\"7\" class=\"sb\">\u00bfSe ha sentido usted como Nathan? Los\u00a0seres\u00a0humanos somos sociales por naturaleza y necesitamos comunicarnos (G\u00e9nesis 2:18; Proverbios 17:17). En\u00a0vista de que tantas personas lo hacen hoy mediante las redes sociales, \u00bfqu\u00e9 cosas le conviene saber acerca de esta moderna herramienta?<\/p>\n<p align=\"justify\" id=\"p8\" data-pid=\"8\" class=\"sb\">\n<p>Fuente: \u00a1Despertad!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos quieren estar conectados \u25cf Imagine la siguiente situaci\u00f3n. Sam se ha resistido por a\u00f1os a la idea de utilizar la tecnolog\u00eda moderna para mantenerse en comunicaci\u00f3n con sus familiares y amigos. Lo\u00a0llaman el Anticuado. Todo el mundo \u2014hasta sus hijos adolescentes\u2060\u2014 quiere estar conectado. En\u00a0cierta ocasi\u00f3n le dice a su hija de 16 a\u00f1os: &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/todos-quieren-estar-conectados\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abTodos quieren estar conectados\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29170","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/29170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=29170"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/29170\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=29170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=29170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=29170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}