{"id":29177,"date":"2016-06-07T12:36:59","date_gmt":"2016-06-07T17:36:59","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/que-hago-para-que-me-guste-estudiar-la-biblia\/"},"modified":"2016-06-07T12:36:59","modified_gmt":"2016-06-07T17:36:59","slug":"que-hago-para-que-me-guste-estudiar-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/que-hago-para-que-me-guste-estudiar-la-biblia\/","title":{"rendered":"\u00bfQu\u00e9 hago para que me guste estudiar la Biblia?"},"content":{"rendered":"\n<p align=\"justify\" id=\"p1\" data-pid=\"1\" class=\"st\"><strong>Los j\u00f3venes preguntan<\/strong><\/p>\n<p align=\"justify\" id=\"p2\" data-pid=\"2\" class=\"st\"><strong>\u00bfQu\u00e9 hago para que me guste estudiar la Biblia?<\/strong><\/p>\n<p align=\"justify\" id=\"p3\" data-pid=\"3\" class=\"sa\"><strong>\u00bfPara qu\u00e9 estudiar la Biblia? Velo de esta manera:<\/strong><\/p>\n<p align=\"justify\" id=\"p4\" data-pid=\"4\" class=\"si\">La Biblia es un <em>best seller <\/em>que puede ayudarte a desenterrar un <em>tesoro<\/em>. \u00bfC\u00f3mo?<\/p>\n<p align=\"justify\" id=\"p5\" data-pid=\"5\" class=\"s6\">\u25cf Prepar\u00e1ndote para vivir la mejor vida posible<\/p>\n<p align=\"justify\" id=\"p6\" data-pid=\"6\" class=\"s6\">\u25cf Cont\u00e1ndote cosas sobre el pasado y el futuro que no\u00a0podr\u00edas aprender de ning\u00fan otro modo<\/p>\n<p align=\"justify\" id=\"p7\" data-pid=\"7\" class=\"s6\">\u25cf Ense\u00f1\u00e1ndote a conocerte a ti mismo y a ser mejor persona*<\/p>\n<p align=\"justify\" id=\"p8\" data-pid=\"8\" class=\"sb\">ESTUDIAR la Biblia requiere esfuerzo, \u00a1pero la recompensa es enorme! \u00bfQuieres saber c\u00f3mo est\u00e1n haci\u00e9ndolo otros j\u00f3venes? En\u00a0la siguiente hoja te mostramos c\u00f3mo algunos est\u00e1n venciendo sus obst\u00e1culos y sac\u00e1ndole todo el jugo a su estudio personal de la Biblia. Rec\u00f3rtala y d\u00f3blala; as\u00ed tendr\u00e1s una \u00fatil fuente de consulta de cuatro p\u00e1ginas.<\/p>\n<p align=\"justify\" id=\"p9\" data-pid=\"9\" class=\"sb\"><em>\u201cEn la Biblia hay de todo para todos. Las posibilidades de estudio son infinitas.\u201d (Valerie.)<\/em>*<\/p>\n<p align=\"justify\" id=\"p10\" data-pid=\"10\" class=\"sd\">Encontrar\u00e1s m\u00e1s art\u00edculos de la secci\u00f3n \u201cLos j\u00f3venes preguntan\u201d en www.watchtower.org\/yps<\/p>\n<p align=\"justify\" id=\"p11\" data-pid=\"11\" class=\"sf\"><strong>[Notas]<\/strong><\/p>\n<div id=\"fn1\" class=\"fcc\">\n<p align=\"justify\" id=\"p12\" data-pid=\"12\">Si quieres entender mejor c\u00f3mo logra todas estas cosas la Biblia, busca a los testigos de Jehov\u00e1 de tu zona, escribe a la direcci\u00f3n que corresponda de la p\u00e1gina 5 o visita el sitio www.watchtower.org\/s.<\/p>\n<\/div>\n<div id=\"fn2\" class=\"fcc\">\n<p align=\"justify\" id=\"p13\" data-pid=\"13\">Se han cambiado algunos nombres.<\/p>\n<\/div>\n<p align=\"justify\" id=\"p14\" data-pid=\"14\" class=\"se\"><strong>[Ilustraciones y recuadro de las p\u00e1ginas 19 y 20]<\/strong><\/p>\n<p align=\"justify\" id=\"p15\" data-pid=\"15\" class=\"sc\"><strong>C\u00d3MO ESTUDIAR LA BIBLIA<\/strong><\/p>\n<p align=\"justify\" id=\"p16\" data-pid=\"16\" class=\"sc\"><strong>El problema: FALTA DE MOTIVACI\u00d3N<\/strong><\/p>\n<p align=\"justify\" id=\"p17\" data-pid=\"17\" class=\"sc\">\u201cA veces, lo que menos quiero es sentarme a estudiar toda una hora.\u201d (Lena)<\/p>\n<p align=\"justify\" id=\"p18\" data-pid=\"18\" class=\"sc\"><strong>La soluci\u00f3n: UN BUEN INCENTIVO<\/strong><\/p>\n<p align=\"justify\" id=\"p19\" data-pid=\"19\" class=\"sc\">  Para tomarle el gusto al estudio de la Biblia, primero debes preguntarte: \u201c\u00bfMe va a servir de algo?\u201d. Bueno, \u00bfte gustar\u00eda ser amigo de Dios, comprender mejor la situaci\u00f3n mundial o mejorar tu personalidad? La\u00a0Biblia puede ayudarte a lograr estas cosas, \u00a1y muchas m\u00e1s!<\/p>\n<p align=\"justify\" id=\"p20\" data-pid=\"20\" class=\"sc\">  <em>\u201cNo lo veas como un trabajo o como estudiar para el colegio. M\u00edralo como una manera de estrechar tu amistad con el mejor Amigo que podr\u00edas tener: Jehov\u00e1 Dios.\u201d (Bethany.)<\/em><\/p>\n<p align=\"justify\" id=\"p21\" data-pid=\"21\" class=\"sc\">  <em>\u201cEstudiar es como pasar un rato a solas con Jehov\u00e1. Si\u00a0tus padres siempre est\u00e1n presentes cuando est\u00e1s en compa\u00f1\u00eda de alguien, \u00bfdir\u00edas que ese alguien es tu amigo, o el de ellos? Si\u00a0estudias por tu cuenta, Jehov\u00e1 llegar\u00e1 a ser amigo <strong>tuyo.\u201d <\/strong>(Bianca.)<\/em><\/p>\n<p align=\"justify\" id=\"p22\" data-pid=\"22\" class=\"sc\">  <strong>Recuerda: <\/strong>\u201cTodo lo que est\u00e1 escrito en la Biblia es el mensaje de Dios, y es \u00fatil para ense\u00f1ar a la gente, para ayudarla y corregirla, y para mostrarle c\u00f3mo debe vivir\u201d (2\u00a0Timoteo 3:16, <em>Traducci\u00f3n en lenguaje actual<\/em>). La\u00a0Biblia tambi\u00e9n puede serte \u00fatil de esas maneras.<\/p>\n<p align=\"justify\" id=\"p23\" data-pid=\"23\" class=\"sc\">  <em>\u201cTrato de concentrarme en los beneficios. Si\u00a0hay algo de mi personalidad que no\u00a0me gusta, tomo el estudio como una oportunidad para abordar el problema y mejorar.\u201d (Max.)<\/em><\/p>\n<p align=\"justify\" id=\"p24\" data-pid=\"24\" class=\"sk\"><strong>\u00bfY t\u00fa?<\/strong><\/p>\n<p align=\"justify\" id=\"p25\" data-pid=\"25\" class=\"sk\">\u00bfQu\u00e9 incentivo necesitas para estudiar?<\/p>\n<p align=\"justify\" id=\"p26\" data-pid=\"26\" class=\"se\"><strong>El problema: ES ABURRIDO<\/strong><\/p>\n<p align=\"justify\" id=\"p27\" data-pid=\"27\" class=\"sc\">\u201cA los diez minutos de estudiar empiezo a cansarme; a los veinte, ya quiero acabar, y a la media hora estoy que me muero de aburrimiento.\u201d (Allison)<\/p>\n<p align=\"justify\" id=\"p28\" data-pid=\"28\" class=\"sc\"><strong>La soluci\u00f3n: SER CREATIVO<\/strong><\/p>\n<p align=\"justify\" id=\"p29\" data-pid=\"29\" class=\"sc\">  Echa a volar la imaginaci\u00f3n. \u00bfQu\u00e9 vas a estudiar? \u00bfC\u00f3mo lo vas a hacer? \u00bfD\u00f3nde?<\/p>\n<p align=\"justify\" id=\"p30\" data-pid=\"30\" class=\"sc\">  <em>\u201cInvestiga las dudas que tengas. Cuando encuentras la respuesta a algo que te est\u00e1 dando vueltas en la cabeza, te sientes satisfecho, hasta contento.\u201d (Richard.)<\/em><\/p>\n<p align=\"justify\" id=\"p31\" data-pid=\"31\" class=\"sc\">  <em>\u201cCuando leas un pasaje, visualiza la escena. Piensa que t\u00fa eres el personaje principal o que eres un observador. Mira la historia con los ojos de la imaginaci\u00f3n.\u201d (Steven.)<\/em><\/p>\n<p align=\"justify\" id=\"p32\" data-pid=\"32\" class=\"sc\">  <em>\u201cHaz que el estudio sea agradable. Si\u00e9ntate en el patio y t\u00f3mate una limonada. A\u00a0m\u00ed me gusta tener algo ligero de comer. \u00bfA\u00a0qui\u00e9n no?\u201d (Alexandra.)<\/em><\/p>\n<p align=\"justify\" id=\"p33\" data-pid=\"33\" class=\"sc\">  <strong>Recuerda: <\/strong>El\u00a0aburrimiento es una percepci\u00f3n que no\u00a0siempre coincide con la realidad. As\u00ed que en vez de decir: <em>\u201cEstudiar <\/em>es aburrido\u201d, di: <em>\u201cEstoy <\/em>aburrido\u201d. Decide t\u00fa c\u00f3mo vas a ver las cosas. Eso te dar\u00e1 el control y la capacidad para hacer los cambios necesarios (Proverbios 2:10,\u00a011).<\/p>\n<p align=\"justify\" id=\"p34\" data-pid=\"34\" class=\"sc\">  <em>\u201cEl estudio personal no\u00a0tiene por qu\u00e9 ser aburrido. Puede ser lo que t\u00fa quieras que sea.\u201d (Vanessa.)<\/em><\/p>\n<p align=\"justify\" id=\"p35\" data-pid=\"35\" class=\"sk\"><strong>\u00bfY t\u00fa?<\/strong><\/p>\n<p align=\"justify\" id=\"p36\" data-pid=\"36\" class=\"sk\">\u00bfQu\u00e9 ideas se te ocurren para hacer m\u00e1s interesante el estudio?<\/p>\n<p align=\"justify\" id=\"p37\" data-pid=\"37\" class=\"sc\"><strong>El problema: FALTA DE TIEMPO<\/strong><\/p>\n<p align=\"justify\" id=\"p38\" data-pid=\"38\" class=\"sc\">\u201cMe gustar\u00eda estudiar m\u00e1s la Biblia, pero estoy tan ocupada que me cuesta mucho encontrar momentos para sentarme y hacerlo.\u201d (Mar\u00eda)<\/p>\n<p align=\"justify\" id=\"p39\" data-pid=\"39\" class=\"sc\"><strong>La soluci\u00f3n: FIJAR PRIORIDADES<\/strong><\/p>\n<p align=\"justify\" id=\"p40\" data-pid=\"40\" class=\"sc\">  Convertirse en adulto implica aprender a distinguir \u201clas cosas m\u00e1s importantes\u201d (Filipenses 1:10).<\/p>\n<p align=\"justify\" id=\"p41\" data-pid=\"41\" class=\"sc\">  <em>\u201cMi mam\u00e1 me ayud\u00f3 a entender que el tiempo nunca me va a sobrar y que tengo que buscarlo. As\u00ed que, una vez que me propuse estudiar, segu\u00ed su consejo.\u201d (Natanya.)<\/em><\/p>\n<p align=\"justify\" id=\"p42\" data-pid=\"42\" class=\"sc\">  <em>\u201cHe aprendido que tengo que fijar una hora para el estudio. Cuando llega el momento, dejo cualquier cosa que est\u00e9 haciendo y me pongo a estudiar.\u201d (Yolanda.)<\/em><\/p>\n<p align=\"justify\" id=\"p43\" data-pid=\"43\" class=\"sc\">  <em>\u201cSi pones el estudio antes que el entretenimiento, te aseguro que disfrutar\u00e1s a\u00fan m\u00e1s del estudio y luego podr\u00e1s divertirte sin remordimientos.\u201d (Diana.)<\/em><\/p>\n<p align=\"justify\" id=\"p44\" data-pid=\"44\" class=\"sc\">  <strong>Recuerda: <\/strong>Si\u00a0no tienes prioridades, perder\u00e1s el control sobre tu tiempo y te convertir\u00e1s en su esclavo. Es\u00a0mucho mejor hacerle espacio al estudio y no\u00a0dejarlo a la casualidad (Efesios 5:15,\u00a016).<\/p>\n<p align=\"justify\" id=\"p45\" data-pid=\"45\" class=\"sc\">  <em>\u201cCuando uno va a la escuela, hay mil cosas que\u00a0atender. Sin embargo, hago un esfuerzo consciente por incluir en mi horario el estudio de la Biblia; esa es una de mis prioridades.\u201d (Jordan.)<\/em><\/p>\n<p align=\"justify\" id=\"p46\" data-pid=\"46\" class=\"sk\"><strong>\u00bfY t\u00fa?<\/strong><\/p>\n<p align=\"justify\" id=\"p47\" data-pid=\"47\" class=\"sk\">\u00bfQu\u00e9 horario de estudio podr\u00edas elaborar?<\/p>\n<p align=\"justify\" id=\"p48\" data-pid=\"48\" class=\"se\"><strong>[Ilustraciones y recuadro de la p\u00e1gina 19]<\/strong><\/p>\n<p align=\"justify\" id=\"p49\" data-pid=\"49\" class=\"sc\"><strong>CONSEJOS DE OTROS J\u00d3VENES<\/strong><\/p>\n<p align=\"justify\" id=\"p50\" data-pid=\"50\" class=\"sc\"><strong>Zachary: <\/strong>\u201cNo\u00a0estudies \u00fanicamente lo que tus padres o los dem\u00e1s estudian. Para que sea realmente personal, elige algo que <em>t\u00fa <\/em>quieras aprender\u201d.<\/p>\n<p align=\"justify\" id=\"p51\" data-pid=\"51\" class=\"se\"><strong>Kaley: <\/strong>\u201cComienza poco a poco. Si\u00a0es necesario, empieza estudiando solo cinco minutos, pero todos los d\u00edas. Luego sube a diez, luego a quince&#8230; Ver\u00e1s que con el tiempo te gusta\u201d.<\/p>\n<p align=\"justify\" id=\"p52\" data-pid=\"52\" class=\"se\"><strong>Daniela: <\/strong>\u201cLos detalles cuentan mucho. Consigue bol\u00edgrafos de colores y una libreta bonita, o crea en tu computadora una carpeta llamada \u2018Estudio personal\u2019\u201d.<\/p>\n<p align=\"justify\" id=\"p53\" data-pid=\"53\" class=\"se\"><strong>Jordan: <\/strong>\u201cCuando yo mismo escojo el tema, estudio durante m\u00e1s tiempo. Adem\u00e1s, necesito estar en un lugar tranquilo. No\u00a0puedo concentrarme si hay mucho ruido\u201d.<\/p>\n<p align=\"justify\" id=\"p54\" data-pid=\"54\" class=\"se\"><strong>[Ilustraci\u00f3n de la p\u00e1gina 18]<\/strong><\/p>\n<p align=\"justify\" id=\"p55\" data-pid=\"55\" class=\"sc\">(Para ver el texto en su formato original, consulte la publicaci\u00f3n)<\/p>\n<p align=\"justify\" id=\"p56\" data-pid=\"56\" class=\"sc\">Recorta<\/p>\n<p align=\"justify\" id=\"p57\" data-pid=\"57\" class=\"sc\">Dobla<\/p>\n<p align=\"justify\" id=\"p58\" data-pid=\"58\" class=\"sb\">\n<p>Fuente: \u00a1Despertad!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los j\u00f3venes preguntan \u00bfQu\u00e9 hago para que me guste estudiar la Biblia? \u00bfPara qu\u00e9 estudiar la Biblia? Velo de esta manera: La Biblia es un best seller que puede ayudarte a desenterrar un tesoro. \u00bfC\u00f3mo? \u25cf Prepar\u00e1ndote para vivir la mejor vida posible \u25cf Cont\u00e1ndote cosas sobre el pasado y el futuro que no\u00a0podr\u00edas aprender &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/que-hago-para-que-me-guste-estudiar-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfQu\u00e9 hago para que me guste estudiar la Biblia?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29177","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/29177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=29177"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/29177\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=29177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=29177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=29177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}