{"id":29190,"date":"2016-06-07T12:37:38","date_gmt":"2016-06-07T17:37:38","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/es-malo-ser-popular\/"},"modified":"2016-06-07T12:37:38","modified_gmt":"2016-06-07T17:37:38","slug":"es-malo-ser-popular","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/es-malo-ser-popular\/","title":{"rendered":"\u00bfEs malo ser popular?"},"content":{"rendered":"\n<p align=\"justify\" class=\"contextTtl\" id=\"p1\" data-pid=\"1\"><strong>Los j\u00f3venes preguntan<\/strong><\/p>\n<p><strong>\u00bfEs malo ser popular?<\/strong><\/p>\n<div class=\"groupSurvey\">\n<p align=\"justify\" id=\"p3\" data-pid=\"3\" class=\"si\"><strong>Completa la siguiente oraci\u00f3n:<\/strong><\/p>\n<p align=\"justify\" id=\"p4\" data-pid=\"4\" class=\"si\">\u2024\u2024\u2024\u2024\u2024 es bueno ser popular.<\/p>\n<li class=\"listSingleChoice\">\n<p align=\"justify\" id=\"p5\" data-pid=\"5\" class=\"s6\">A. Siempre<\/p>\n<\/li>\n<li class=\"listSingleChoice\">\n<p align=\"justify\" id=\"p6\" data-pid=\"6\" class=\"s6\">B. A\u00a0veces<\/p>\n<\/li>\n<li class=\"listSingleChoice\">\n<p align=\"justify\" id=\"p7\" data-pid=\"7\" class=\"s6\">C. Nunca<\/p>\n<\/li>\n<\/div>\n<div class=\"bodyTxt\">\n<div id=\"section1\" class=\"section\">\n<div class=\"pGroup\">\n<p align=\"justify\" id=\"p8\" data-pid=\"8\" class=\"sb\">SI ELEGISTE la opci\u00f3n <strong>B, <\/strong>has contestado correctamente, pues quien goza de popularidad es admirado por muchas personas, y eso a veces es bueno. La\u00a0Biblia predijo que los cristianos ser\u00edan la \u201cluz de las naciones\u201d y que muchos se sentir\u00edan atra\u00eddos a ellos (Isa\u00edas 42:6; Hechos 13:47). De\u00a0modo que, en este sentido, puede decirse que los cristianos son populares.<\/p>\n<\/div>\n<\/div>\n<div id=\"section2\" class=\"section\"><strong>\u00bfSab\u00edas esto?<\/strong><\/p>\n<div class=\"pGroup\">\n<p align=\"justify\" data-pid=\"9\" class=\"p9 sb\"> Jes\u00fas tambi\u00e9n fue popular. De\u00a0jovencito se gan\u00f3 el favor de Dios y de los hombres (Lucas 2:52). Adem\u00e1s, la Biblia dice que cuando se hizo adulto, \u201cgrandes muchedumbres le siguieron de Galilea y de Dec\u00e1polis y de Jerusal\u00e9n y de Judea y del otro lado del Jord\u00e1n\u201d (Mateo 4:25).<\/p>\n<\/div>\n<\/div>\n<div id=\"section3\" class=\"section\"><strong>\u00bfEstuvo mal?<\/strong><\/p>\n<div class=\"pGroup\">\n<p align=\"justify\" data-pid=\"10\" class=\"p10 sb\"> No, porque Jes\u00fas <em>no\u00a0buscaba <\/em>esa fama. Tampoco se mor\u00eda por que los dem\u00e1s lo aceptaran. \u00c9l\u00a0simplemente hac\u00eda lo que era correcto, y eso llamaba la atenci\u00f3n de las personas (Juan 8:29,\u00a030). No\u00a0obstante, Jes\u00fas sab\u00eda que la gente suele cambiar de opini\u00f3n y que la aceptaci\u00f3n de la que disfrutaba era temporal. De\u00a0hecho, hasta sab\u00eda que terminar\u00edan asesin\u00e1ndolo (Lucas 9:22).<\/p>\n<\/div>\n<\/div>\n<div id=\"section4\" class=\"section\"><strong>Conclusi\u00f3n:<\/strong><\/p>\n<div class=\"pGroup\">\n<p align=\"justify\" data-pid=\"11\" class=\"p11 sb\"> La popularidad es como el dinero. Tener dinero no\u00a0es necesariamente malo. La\u00a0cuesti\u00f3n es lo que uno est\u00e1 dispuesto a hacer para obtenerlo o para no\u00a0perderlo. Lo\u00a0mismo sucede con la popularidad.<\/p>\n<\/div>\n<\/div>\n<div id=\"section5\" class=\"section\"><strong>\u00a1Cuidado!<\/strong><\/p>\n<div class=\"pGroup\">\n<p align=\"justify\" data-pid=\"12\" class=\"p12 sb\"> Muchos j\u00f3venes est\u00e1n dispuestos a hacer lo que sea con tal de ser populares. Algunos intentan complacer a todo el mundo y se dejan llevar por los dem\u00e1s. Y\u00a0hay quienes <em>obligan <\/em>a sus compa\u00f1eros a aceptarlos por medio de abusos y amenazas.*<\/p>\n<p align=\"justify\" id=\"p13\" data-pid=\"13\" class=\"sb\">En las siguientes p\u00e1ginas examinaremos dos caminos que, equivocadamente, muchos siguen para ser populares. Pero tambi\u00e9n veremos una mejor alternativa.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"relatedContent\">\n<p align=\"justify\" id=\"p14\" data-pid=\"14\" class=\"sd\">Encontrar\u00e1s m\u00e1s art\u00edculos de la secci\u00f3n \u201cLos j\u00f3venes preguntan\u201d en www.watchtower.org\/yps<\/p>\n<\/div>\n<div class=\"groupFootnote\">\n<div>\n<p align=\"justify\" id=\"p16\" data-pid=\"16\">La Biblia dice que \u201clos nefilim\u201d \u2014unos abusones de la antig\u00fcedad\u2060\u2014 eran \u201chombres de fama\u201d (G\u00e9nesis 6:4). A\u00a0ellos solo les interesaba fomentar su propia gloria.<\/p>\n<\/div>\n<\/div>\n<div class=\"boxSupplement\">\n<div class=\"boxContent\">\n<div id=\"p18\" data-pid=\"18\" class=\"boxTtl\">\n<div><strong>CAMINOS PARA SER POPULAR<\/strong><\/div>\n<\/div>\n<p><strong>COMPLACER A\u00a0LOS DEM\u00c1S<\/strong><\/p>\n<ul>\n<li>\n<p align=\"justify\" id=\"p20\" data-pid=\"20\" class=\"sw\">Necesitas que otros te acepten.<\/p>\n<\/li>\n<li>\n<p align=\"justify\" id=\"p21\" data-pid=\"21\" class=\"sw\">Para lograrlo, te esfuerzas por ser como ellos.<\/p>\n<\/li>\n<\/ul>\n<p align=\"justify\" id=\"p22\" data-pid=\"22\" class=\"sw\">\u201cTrat\u00e9 de cambiar mi forma de ser para que los dem\u00e1s me aceptaran. Al\u00a0principio funcion\u00f3, pero despu\u00e9s me di cuenta de que nunca debes dejar de ser quien eres solo para caer bien.\u201d (Nicole)<\/p>\n<p align=\"justify\" id=\"p23\" data-pid=\"23\" class=\"sw\"><strong>La Biblia dice: <\/strong>\u201cNo sigas a la mayor\u00eda en su maldad.\u00a0[&#8230;] No\u00a0te dejes llevar por la mayor\u00eda, inclin\u00e1ndote por lo que no\u00a0es justo\u201d (\u00c9xodo 23:2, <em>Dios habla hoy<\/em>).<\/p>\n<p><strong>OBLIGAR A\u00a0LOS DEM\u00c1S<\/strong><\/p>\n<ul>\n<li>\n<p align=\"justify\" id=\"p25\" data-pid=\"25\" class=\"sw\">Todos te admiran, y t\u00fa mismo te encargar\u00e1s de que eso no\u00a0cambie.<\/p>\n<\/li>\n<li>\n<p align=\"justify\" id=\"p26\" data-pid=\"26\" class=\"sw\">Har\u00e1s lo que sea para mantenerte en la cima, aunque tengas que pisotear a los dem\u00e1s.<\/p>\n<\/li>\n<\/ul>\n<p align=\"justify\" id=\"p27\" data-pid=\"27\" class=\"sw\">\u201cLos chicos suelen ser crueles. Adem\u00e1s, como los abusones son m\u00e1s populares, alguien t\u00edmido podr\u00eda pensar que siempre tienen la raz\u00f3n.\u201d (Raquel)<\/p>\n<p align=\"justify\" id=\"p28\" data-pid=\"28\" class=\"sw\"><strong>La Biblia dice: <\/strong>\u201cAs\u00ed como quieren que los hombres les hagan a ustedes, h\u00e1ganles de igual manera a ellos\u201d (Lucas 6:31).<\/p>\n<p><strong>UNA MEJOR ALTERNATIVA<\/strong><\/p>\n<div class=\"boxSupplement\">\n<div class=\"boxContent\">\n<div class=\"blockTxt floatEast\">\n<p align=\"justify\" id=\"p33\" data-pid=\"33\" class=\"sw\"><strong>Seguir los consejos de la izquierda tal vez te haga menos popular a los ojos de algunos, pero te har\u00e1 m\u00e1s popular entre aquellos a quienes Dios ama.<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<li>\n<p align=\"justify\" id=\"p30\" data-pid=\"30\" class=\"sw\">              <strong>Define tus principios. <\/strong>La Biblia dice que las personas maduras son capaces de \u201cdistinguir tanto lo correcto como lo incorrecto\u201d (Hebreos 5:14).<\/p>\n<\/li>\n<li>\n<p align=\"justify\" id=\"p31\" data-pid=\"31\" class=\"sw\">              <strong>Af\u00e9rrate a tus convicciones. <\/strong>S\u00e9 como Josu\u00e9, un l\u00edder del antiguo Israel que afirm\u00f3: \u201cEsc\u00f3janse hoy a qui\u00e9n quieren servir\u00a0[&#8230;]. Pero en cuanto a m\u00ed y a mi casa, nosotros serviremos a Jehov\u00e1\u201d (Josu\u00e9 24:15).<\/p>\n<\/li>\n<li>\n<p align=\"justify\" id=\"p32\" data-pid=\"32\" class=\"sw\">              <strong>Conf\u00eda en que has escogido el mejor camino. <\/strong>El ap\u00f3stol Pablo le dijo a Timoteo: \u201cDios no\u00a0nos dio un esp\u00edritu de\u00a0cobard\u00eda, sino de poder\u201d (2\u00a0Timoteo 1:7).<\/p>\n<\/li>\n<\/div>\n<\/div>\n<div class=\"boxSupplement\">\n<div id=\"p35\" data-pid=\"35\" class=\"boxTtl\">\n<div><strong>LO QUE OPINAN OTROS J\u00d3VENES<\/strong><\/div>\n<\/div>\n<div class=\"boxContent\">\n<p align=\"justify\" id=\"p36\" data-pid=\"36\" class=\"sc\"><strong>Melissa: <\/strong>\u201cClaro, puedes intentar ser como cualquiera que anda por los pasillos de la escuela. Pero \u00bfqu\u00e9 tendr\u00eda eso de especial? Ser cristiano te hace diferente en un buen sentido. No\u00a0te hace raro, te hace agradable\u201d.<\/p>\n<p align=\"justify\" id=\"p38\" data-pid=\"38\" class=\"se\"><strong>Ashley: <\/strong>\u201cEn\u00a0la escuela no\u00a0era muy popular. Pero en las reuniones cristianas, donde los hermanos me quer\u00edan tal como era, se me iba cualquier inter\u00e9s que tuviera por ganarme la aprobaci\u00f3n de mis compa\u00f1eros de clase\u201d.<\/p>\n<p align=\"justify\" id=\"p40\" data-pid=\"40\" class=\"se\"><strong>Phillip: <\/strong>\u201cLa\u00a0clave para que otros te acepten es mostrar inter\u00e9s personal. \u00daltimamente me he esforzado por hacer peque\u00f1os favores a mis amigos, y eso me ha acercado m\u00e1s a ellos\u201d.<\/p>\n<\/div>\n<\/div>\n<p>Fuente: \u00a1Despertad!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los j\u00f3venes preguntan \u00bfEs malo ser popular? Completa la siguiente oraci\u00f3n: \u2024\u2024\u2024\u2024\u2024 es bueno ser popular. A. Siempre B. A\u00a0veces C. Nunca SI ELEGISTE la opci\u00f3n B, has contestado correctamente, pues quien goza de popularidad es admirado por muchas personas, y eso a veces es bueno. La\u00a0Biblia predijo que los cristianos ser\u00edan la \u201cluz de &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/es-malo-ser-popular\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfEs malo ser popular?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29190","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/29190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=29190"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/29190\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=29190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=29190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=29190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}