{"id":32332,"date":"2016-06-13T12:01:37","date_gmt":"2016-06-13T17:01:37","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/ana-tijan-y-luka-brajnovic-fe-y-amor-en-la-guerra-mundial\/"},"modified":"2016-06-13T12:01:37","modified_gmt":"2016-06-13T17:01:37","slug":"ana-tijan-y-luka-brajnovic-fe-y-amor-en-la-guerra-mundial","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/ana-tijan-y-luka-brajnovic-fe-y-amor-en-la-guerra-mundial\/","title":{"rendered":"Ana Tijan y Luka Brajnovic, fe y amor en la Guerra&nbsp;Mundial"},"content":{"rendered":"<p><b>Por: Aleteia Team<\/b><\/p>\n<p align=\"justify\">Naci&oacute; el a&ntilde;o 1920 en Croacia, tiene ya casi un siglo de vida y en todo instante transmite vitalidad y esperanza. Ana Tij&aacute;n es una mujer cuyos a&ntilde;os e historia hablan del poder aut&eacute;ntico de la fe, espont&aacute;nea, que se conf&iacute;a por entero a Dios, pudiendo sobrevivir a guerras, persecuciones y matanzas\u2026<br \/> &nbsp;<br \/> -Recuerdo que ten&iacute;a catorce a&ntilde;os. Yo viv&iacute;a en Senj. Era mayo del 1935, el mes de la Virgen -comienza relatando en una entrevista que publica el portal web Amarantho-, y se celebraba una fiesta eucar&iacute;stica. Hab&iacute;a una misa en la plaza en la que ven&iacute;a much&iacute;sima gente, sobre todo j&oacute;venes que bajaban de los montes especialmente para la celebraci&oacute;n. En aquella &eacute;poca no hab&iacute;a autobuses, as&iacute; que esa gente se mov&iacute;a en camiones. Todo estaba preparado para la ocasi&oacute;n\u2026<br \/> &nbsp;<br \/> &raquo;Decid&iacute; quedarme un rato m&aacute;s rezando. Cuando sal&iacute; me encontr&eacute; con el bullicio de la gente. En una de las plazuelas por las que ten&iacute;a que pasar hab&iacute;a un cami&oacute;n distinto a los otros. De todas las callejuelas salieron un mont&oacute;n de gendarmes que empezaron, sin m&aacute;s, a dispararnos. Yo no sab&iacute;a qu&eacute; hacer. Estaba asustad&iacute;sima. Apuntaban m&aacute;s bien hacia arriba y hacia los otros camiones y yo, como era peque&ntilde;a, me met&iacute; por debajo de las piernas de un gendarme y empec&eacute; a correr.<\/p>\n<p align=\"justify\"> Tuve la suerte de que no me alcanz&oacute; ninguna bala, pero ve&iacute;a caer a mucha gente delante de m&iacute;. Hab&iacute;a incluso chicos que intentaban escapar con la tripa abierta. Fue una gran carnicer&iacute;a\u2026&nbsp; As&iacute; empez&oacute; mi juventud, con este recuerdo tan tremendo. La ciudad de repente se qued&oacute; muda. En silencio. Fue un shock. Despu&eacute;s de tanto tiempo, todav&iacute;a no lo he olvidado.<br \/> &nbsp;<br \/> Ana naci&oacute; justo cuando Europa y el mundo buscaban sanar las heridas de la Primera Guerra Mundial. Por entonces su natal Croacia inici&oacute; una aventura uni&eacute;ndose a otras comunidades eslavas de los Balcanes para formar el Reino de los Serbios, Croatas y Eslovenos. Pero fue imposible la armon&iacute;a en esa diversidad y tras instaurarse en 1929 un r&eacute;gimen dictatorial surgi&oacute; el Reino de Yugoslavia.<br \/> &nbsp;<br \/> La Segunda Guerra Mundial trajo el descalabro suficiente que el dictador comunista \u2018Mariscal\u2019 Tito aprovech&oacute; para apoderase de Yugoslavia\u2026 Ana entonces vivi&oacute; sus primeros a&ntilde;os en medio de un campo de batalla<br \/> &nbsp;<br \/><strong>-&iquest;C&oacute;mo enfrenta una ni&ntilde;a todo este dolor?<\/strong><\/p>\n<p align=\"justify\"> -Si volvemos al recuerdo de aquel mes de mayo, cuando ten&iacute;a catorce a&ntilde;os, pienso: &iquest;Por qu&eacute; me qued&eacute; yo en esa iglesia mientras los dem&aacute;s sal&iacute;an a la calle a disfrutar de la fiesta? La verdad es que hab&iacute;a una imagen de la Virgen, muy venerada en Senj, y quise quedarme un rato m&aacute;s a rezar. Ahora estoy segura de que fue Ella quien hizo que no me tocase ninguna bala. Estoy segura de que Ella me salv&oacute; la vida ese d&iacute;a. Y en realidad todos, porque es un milagro que haya llegado hasta los 94 a&ntilde;os despu&eacute;s de todos los peligros que me han tocado vivir.<br \/> &nbsp;<br \/><strong>-Estudi&oacute; Filosof&iacute;a y Letras en la rama de Eslav&iacute;stica en la Universidad de Zagreb y se mud&oacute; a esa ciudad en 1939. &iquest;C&oacute;mo fueron esos a&ntilde;os?<\/strong><\/p>\n<p align=\"justify\"> -Cuando yo empec&eacute; la universidad ya se o&iacute;an tambores de guerra. Los alemanes se iban acercando poco a poco a nuestra tierra. Nunca pudimos tener clases normales\u2026<br \/> &nbsp;<br \/><strong>-No deb&iacute;a de ser f&aacute;cil ir a la Universidad en aquella &eacute;poca.<\/strong><\/p>\n<p align=\"justify\"> -Era muy dif&iacute;cil, pero de todo lo malo siempre se saca algo bueno. Conoc&iacute; al que despu&eacute;s ha sido mi marido y con &eacute;l parec&iacute;a que los problemas se suavizaban\u2026 De peque&ntilde;a ten&iacute;a dos metas: ir a la universidad y formar una familia. Una ya la hab&iacute;a conseguido y tambi&eacute;n hab&iacute;a conocido a Luka. En realidad no se pod&iacute;an tener metas. La &uacute;nica preocupaci&oacute;n era sobrevivir d&iacute;a a d&iacute;a\u2026 la muerte estaba constantemente presente. Por eso ten&iacute;amos que estar preparados siempre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Aleteia Team Naci&oacute; el a&ntilde;o 1920 en Croacia, tiene ya casi un siglo de vida y en todo instante transmite vitalidad y esperanza. Ana Tij&aacute;n es una mujer cuyos a&ntilde;os e historia hablan del poder aut&eacute;ntico de la fe, espont&aacute;nea, que se conf&iacute;a por entero a Dios, pudiendo sobrevivir a guerras, persecuciones y matanzas\u2026 &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/ana-tijan-y-luka-brajnovic-fe-y-amor-en-la-guerra-mundial\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abAna Tijan y Luka Brajnovic, fe y amor en la Guerra&nbsp;Mundial\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32332","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32332"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32332\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}