{"id":32342,"date":"2016-06-13T12:02:01","date_gmt":"2016-06-13T17:02:01","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/mi-matrimonio-se-rompio-por-culpa-de-facebook\/"},"modified":"2016-06-13T12:02:01","modified_gmt":"2016-06-13T17:02:01","slug":"mi-matrimonio-se-rompio-por-culpa-de-facebook","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/mi-matrimonio-se-rompio-por-culpa-de-facebook\/","title":{"rendered":"Mi matrimonio se rompi\u00f3 \u00bfpor culpa de&nbsp;Facebook?"},"content":{"rendered":"<p><b>Por: PSICONLINEWS<\/b><\/p>\n<p align=\"justify\">Si has llegado a esta pregunta, imagino que est&aacute;s buscando una soluci&oacute;n a un problema que perturba a los matrimonios desde la &eacute;poca de Orkut: los celos desencadenados por las relaciones en las redes sociales. El famoso Facebook es la estrella del momento. Vamos a dejar el whatsapp para despu&eacute;s.<br \/> &nbsp;<br \/> Es habitual o&iacute;r frases del tipo: \u201cFacebook acab&oacute; con mi relaci&oacute;n\u201d, o \u201cLo que el amor construy&oacute;, Facebook lo destruy&oacute;\u201d.<br \/> &nbsp;<br \/> No se pueden contar la cantidad de desenga&ntilde;os amorosos relacionados con la red social. Pero con celos o no, la mayor&iacute;a no renuncia a su perfil. Pensando en esto, dar&iacute;a algunas estrategias b&aacute;sicas que pueden evitar mucha confusi&oacute;n.<br \/> &nbsp;<br \/><strong>1) Llega a acuerdos<\/strong><br \/> &nbsp;<br \/> Todas las relaciones humanas son regidas por acuerdos, aunque no sean expl&iacute;citos. Por ejemplo: Cuando una pareja decide la fecha, se sobreentiende que no va a buscarse otra pareja.<br \/> &nbsp;<br \/> Adem&aacute;s, cuando se trata de redes sociales, la cuesti&oacute;n se complica un poco. Mientras que para uno es absolutamente normal aceptar personas desconocidas, ex-novios (as), y compartir cualquier tipo de fotos, para esto puede ser considerado como una gran falta de respeto. &iexcl;Y llega la confusi&oacute;n!<br \/> &nbsp;<br \/> La mejor manera de lidiar con esta situaci&oacute;n siempre es un buen di&aacute;logo. Es importante que te intereses por saber los motivos que llevaron al otro a pensar y actuar de determinada manera. Ponerse en el lugar del ser amado por algunos instantes puede marcar la diferencia.<br \/> &nbsp;<br \/><strong>2) Intenta no generalizar<\/strong><br \/> &nbsp;<br \/> Si est&aacute;s celoso\/a de determinada persona de la lista de amigos de tu c&oacute;nyuge, explica tus motivos para que el otro pueda entender y saber c&oacute;mo actuar.<br \/> &nbsp;<br \/> En lugar de decir: \u201cExijo que quites a fulano (a) de tu Facebook\u201d, di: \u201cLa presencia de esa persona en tu lista de amigos me causa un gran malestar. &iquest;Podemos hablar sobre ello?\u201d.<br \/> &nbsp;<br \/> A partir de un di&aacute;logo tranquilo y respetuoso, podr&eacute;is llegar a un acuerdo. Quiz&aacute;s percibas que la persona en cuesti&oacute;n no representa amenaza real alguna para tu relaci&oacute;n, y a partir de ah&iacute; consigas vivir en paz. O tal vez tu c&oacute;nyuge perciba que tus argumentos son v&aacute;lidos y tienen fundamento, y simplemente rompa la amistad con esa persona. Independientemente del resultado, habr&eacute;is establecido un di&aacute;logo adulto, es decir, el primer paso para una relaci&oacute;n saludable.<br \/> &nbsp;<br \/><strong>3) Espere a que pase el enfado<\/strong><br \/> &nbsp;<br \/> Cuando sentimos celos, tendemos a enfadarnos con nuestro c&oacute;nyuge, y es en este momento cuando se produce un ciclo de falta de respeto. El ofendido y dolido quiere tambi&eacute;n ofender y hacer da&ntilde;o, l&oacute;gicamente el otro reacciona contra las ofensas, y entonces el problema toma proporciones gigantescas.<br \/> &nbsp;<br \/> Una buena estrategia es no hablar mientras estas nervioso\/a, espera un poco, si es posible incluso a otro d&iacute;a, y cr&eacute;eme, la mayor&iacute;a de las veces te dar&aacute;s cuenta de que la cosa no era tan grave.<br \/> &nbsp;<br \/> Cuando tu c&oacute;nyuge se comporta de manera que consideras reprobable en las redes sociales, de ninguna manera intentes provocarlo haciendo lo mismo, o creando situaciones para darle celos, pues con esto est&aacute;s cerrando puertas a la soluci&oacute;n del problema. Lo que quieres es vivir paz junto a la persona que amas, &iquest;no? Por tanto, no entres en un ciclo de provocaciones.<br \/> &nbsp;<br \/><strong>4) Habla cara a cara<\/strong><br \/> &nbsp;<br \/> Jam&aacute;s discutas sobre tu relaci&oacute;n a trav&eacute;s de mensajes. Adem&aacute;s de los malentendidos, la falta de una mirada comprensiva, de un gesto que diga: estoy aqu&iacute; por ti, o incluso de un abrazo reconciliador, marcan una enorme diferencia. Adem&aacute;s, es muy probable que despu&eacute;s de la conversaci&oacute;n virtual, cuando os encontr&eacute;is en persona, quer&aacute;is aclarar algo que no qued&oacute; claro en los mensajes, lo que empeorar&aacute; las cosas.<br \/> &nbsp;<br \/><strong>5) Date cuenta de cu&aacute;ndo los celos sobrepasan los l&iacute;mites<\/strong><br \/> &nbsp;<br \/> Los celos son algo inherente a los seres humanos, y estar&aacute;n siempre presente en las relaciones. Cuando est&aacute;n fundamentados por motivos l&oacute;gicos son s&oacute;lo un aspecto de la fascinante relaci&oacute;n del hombre con sus iguales. Si se llevan con respeto y buen humor, puede incluso ser beneficioso en el fortalecimiento de las relaciones.<br \/> &nbsp;<br \/> Pero cuando causa sufrimiento profundo y prejuicios en otros aspectos de la vida diaria, como por ejemplo: trabajo y estudios, es hora de reflexionar y buscar ayuda.<br \/> &nbsp;<br \/> Las relaciones mediadas por internet son una realidad con la cual tenemos que lidiar, directa o indirectamente. La mejor manera de sacar provecho de ese tipo de relaci&oacute;n es conocer nuestros miedos y flaquezas para poder enfrentarlos, y respetar no s&oacute;lo los l&iacute;mites del otro, sino sobre todo los nuestros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: PSICONLINEWS Si has llegado a esta pregunta, imagino que est&aacute;s buscando una soluci&oacute;n a un problema que perturba a los matrimonios desde la &eacute;poca de Orkut: los celos desencadenados por las relaciones en las redes sociales. El famoso Facebook es la estrella del momento. Vamos a dejar el whatsapp para despu&eacute;s. &nbsp; Es habitual &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/mi-matrimonio-se-rompio-por-culpa-de-facebook\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abMi matrimonio se rompi\u00f3 \u00bfpor culpa de&nbsp;Facebook?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32342","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32342"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32342\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}