{"id":32355,"date":"2016-06-13T12:02:32","date_gmt":"2016-06-13T17:02:32","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/5-cosas-que-desearia-haber-sabido-antes-de-casarme\/"},"modified":"2016-06-13T12:02:32","modified_gmt":"2016-06-13T17:02:32","slug":"5-cosas-que-desearia-haber-sabido-antes-de-casarme","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/5-cosas-que-desearia-haber-sabido-antes-de-casarme\/","title":{"rendered":"5 cosas que desear\u00eda haber sabido antes de&nbsp;casarme"},"content":{"rendered":"<p><b>Por: La Opci\u00f3n V<\/b><\/p>\n<p align=\"justify\">Nos pasa muy seguido que mi esposa y yo recibimos comentarios sobre nuestro matrimonio que nos hacen sonre&iacute;r. \u201cSe ven tan felices\u201d, \u201cse portan como reci&eacute;n casados\u201d, \u201cno entender&iacute;an nuestros problemas porque su matrimonio es excelente\u201d, \u201custedes nunca discuten\u201d.<br \/> &nbsp;<br \/><strong>No sonre&iacute;mos porque esto que nos dicen nos hace felices, sino porque muy pocas personas conocen nuestra verdadera historia.<\/strong> Y todas las parejas tienen una, incluso nosotros.<br \/> &nbsp;<br \/> Hace no mucho tiempo, Consuela y yo estuvimos a punto de divorciarnos. Las cosas no iban bien y nuestro matrimonio estaba en crisis. No digo esto a la ligera. Est&aacute;bamos en el punto de no retorno \u2013 o por lo menos eso pens&aacute;bamos.<br \/> &nbsp;<br \/> Asistimos a terapia matrimonial con sacerdotes y consejeros matrimoniales que trataban de ayudarnos a restaurar lo que alguna vez fue nuestro matrimonio. Fue uno de los momentos m&aacute;s dolorosos por los que he pasado personalmente.<br \/> &nbsp;<br \/> Al reflexionar de nuevo en ese momento de mi vida, hay algunas cosas que s&eacute; que si yo ya las hubiera entendido plenamente cuando me cas&eacute;, la crisis en la que nos encontr&aacute;bamos se hubiese podido haber evitado. Aqu&iacute; est&aacute;n cinco de ellas:<br \/> &nbsp;<br \/><strong>1. No existe un plan B<\/strong><br \/> &nbsp;<br \/> Mi matrimonio es para toda la vida y s&oacute;lo termina con la muerte. Suena un poco l&uacute;gubre, pero es verdad. Cuando hice la promesa de amar a mi esposa de por vida, me compromet&iacute; a hacer que nuestro matrimonio funcionara sin importar la situaci&oacute;n en que nos encontr&aacute;ramos.<br \/> &nbsp;<br \/> Mi mentalidad era que iba a dejar mis opciones abiertas. Si estar casado no funcionaba o si estar con Consuela no duraba o si ella no me hac&iacute;a feliz, yo quer&iacute;a estar seguro de que ten&iacute;a una salida o, peor a&uacute;n, otra opci&oacute;n. Pero, en el matrimonio no hay un plan B. El tener un plan B y mantener abierta la puerta para escapar u otras posibilidades me privaban de comprometerme y dedicarme totalmente a mi esposa y a nuestro matrimonio.<br \/> &nbsp;<br \/><strong>2. El matrimonio no se trata de mi felicidad<\/strong><br \/> &nbsp;<br \/> Muchas parejas cometen este error. Lo escucho todo el tiempo. Y yo mismo lo cre&iacute;a en el a&ntilde;o 2000 cuando caminamos por el pasillo el d&iacute;a de nuestra boda. En mi mente pensaba: \u201cConsuelo es mi esposa y su deber es hacerme feliz. Eso es lo que hacen las esposas. Y si ella no me hace feliz, entonces tendr&eacute; que encontrar a alguien o algo que s&iacute; lo haga\u201d.<br \/> &nbsp;<br \/> La verdad es que el matrimonio se trata de mucho m&aacute;s que solo mi felicidad. Y ella no tiene toda la responsabilidad de mi felicidad. La felicidad es subjetiva y relativa y, como hombre, mi definici&oacute;n de la felicidad cambia tanto que no hay manera de que ella pudiera mantenerse al d&iacute;a con todas mis exigencias. El matrimonio es sobre el amor y el respeto mutuo y honrar a Dios por medio de nuestra fidelidad. No se trata de mi felicidad.<br \/> &nbsp;<br \/><strong>3. La comunicaci&oacute;n es m&aacute;s eficaz que el silencio<\/strong><br \/> &nbsp;<br \/> Soy una persona introvertida. Tambi&eacute;n soy un hombre. Por lo tanto, hablar de mis sentimientos es tan extra&ntilde;o e inc&oacute;modo para m&iacute; como pilotear un avi&oacute;n. Autom&aacute;ticamente, cuando algo me molesta o me hace enojar me a&iacute;slo y me quedo callado. Llega un punto en que reprimo tanto esos sentimientos, que empiezo a buscar formas perjudiciales de canalizar mi enojo, depresi&oacute;n o lo que sea que me est&aacute; molestando.<br \/> &nbsp;<br \/> De lo que me he dado cuenta es que nadie me ama y cuida de m&iacute; y nadie puede atenderme como mi esposa lo hace. Puedo estar seguro de que ella va a tratar mis inseguridades y emociones con delicadeza. Y si estoy molesto con ella, ella es la &uacute;nica persona que puede arreglarlo \u2014entonces &iquest;por qu&eacute; no hablar con ella?<br \/> &nbsp;<br \/><strong>4. Ayudarla a ella me beneficia a m&iacute;<\/strong><br \/> &nbsp;<br \/> Siempre recomiendo el libro \u201cLos 5 lenguajes del amor\u201d a los que se van a casar o a los que ya est&aacute;n casados. Cambi&oacute; la forma en que ve&iacute;a mi relaci&oacute;n con mi esposa. Como es natural, tratamos de amar a los dem&aacute;s como queremos ser amados \u2014pero si ese no es su lenguaje de amor, nuestros esfuerzos son en vano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: La Opci\u00f3n V Nos pasa muy seguido que mi esposa y yo recibimos comentarios sobre nuestro matrimonio que nos hacen sonre&iacute;r. \u201cSe ven tan felices\u201d, \u201cse portan como reci&eacute;n casados\u201d, \u201cno entender&iacute;an nuestros problemas porque su matrimonio es excelente\u201d, \u201custedes nunca discuten\u201d. &nbsp;No sonre&iacute;mos porque esto que nos dicen nos hace felices, sino porque &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/5-cosas-que-desearia-haber-sabido-antes-de-casarme\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab5 cosas que desear\u00eda haber sabido antes de&nbsp;casarme\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32355","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32355"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32355\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}