{"id":32371,"date":"2016-06-13T12:03:11","date_gmt":"2016-06-13T17:03:11","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/es-valido-el-matrimonio-por-la-iglesia-entre-dos-personas-ateas\/"},"modified":"2016-06-13T12:03:11","modified_gmt":"2016-06-13T17:03:11","slug":"es-valido-el-matrimonio-por-la-iglesia-entre-dos-personas-ateas","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/es-valido-el-matrimonio-por-la-iglesia-entre-dos-personas-ateas\/","title":{"rendered":"\u00bfEs v\u00e1lido el matrimonio por la Iglesia entre dos personas&nbsp;ateas?"},"content":{"rendered":"<p><b>Por: Aleteia Team<\/b><\/p>\n<p align=\"justify\"><em>Quisiera plantear una pregunta sobre el matrimonio y su validez. Si un matrimonio se celebra en la Iglesia entre dos personas ateas, porque es tradici&oacute;n y se hace por contentar a las familias, &iquest;es v&aacute;lido? &iquest;Se vuelve v&aacute;lido despu&eacute;s de alg&uacute;n a&ntilde;o de matrimonio o cuando nacen los hijos? La pregunta se refiere a ateos declarados, aunque bautizados.<\/em><br \/> &nbsp;<br \/><strong>La respuesta est&aacute; basada en la <a target=\"_blank\" href=\"\/\/it.aleteia.org\/religione\/contenuti-aggregati\/valido-matrimonio-persone-atee-5811270372556800\">original<\/a>, mucho m&aacute;s detallada, del padre Francesco Romano, Profesor de Derecho can&oacute;nico de la Facultad teol&oacute;gica de Italia Central. <\/strong><br \/> &nbsp;<br \/> Es dif&iacute;cil dar una respuesta un&iacute;voca a la pregunta, como dijo Benedicto XVI el 25 de julio de 2005 hablando al clero de Valle d\u2019Aosta: recordaba que cuando era Prefecto de la Congregaci&oacute;n para la Doctrina de la Fe, personalmente consideraba que <strong>un matrimonio celebrado sin fe pod&iacute;a tener \u201cun indicio de invalidez\u201d<\/strong>, reconociendo que era \u201c<strong>un problema muy dif&iacute;cil que deb&iacute;a ser profundizado a&uacute;n m&aacute;s\u201d.<\/strong><br \/> &nbsp;<br \/> La cuesti&oacute;n es que, <strong>en la doctrina de la Iglesia, la fe de los contrayentes no es imprescindible para la validez del sacramento, siempre y cuando estos tengan recta intenci&oacute;n de casarse conforme a la ley de la Iglesia.<\/strong><br \/> &nbsp;<br \/> Juan Pablo II tambi&eacute;n hab&iacute;a abordado el tema en la Alocuci&oacute;n a la Rota Romana del 30 de enero de 2003, diciendo que \u201c<strong>una actitud de los contrayentes que no tenga en cuenta la dimensi&oacute;n sobrenatural del matrimonio puede hacerlo nulo si afecta a su validez en el plano natural<\/strong>\u201d (por ejemplo, si no tienen intenci&oacute;n de contraer matrimonio para toda la vida).<br \/> &nbsp;<br \/> El Papa polaco quer&iacute;a decir que la falta de fe no anula necesariamente el matrimonio si hay recta intenci&oacute;n de casarse conforme a lo que dice la Iglesia (es decir, matrimonio sacramental indisoluble, fiel y abierto a la vida), y que por tanto, la validez del matrimonio no depende de la existencia o no de la fe, sino de esa recta intenci&oacute;n.<br \/> &nbsp;<br \/> Ahora bien, <strong>cuando no hay fe como tal, ni deseo de la gracia y de la salvaci&oacute;n, el problema que se plantea es saber si existe esa recta intenci&oacute;n de contraer matrimonio sacramental.<\/strong><br \/> &nbsp;<br \/> Como ya advert&iacute;a la Comisi&oacute;n teol&oacute;gica Internacional en un pronunciamiento del 6 de diciembre de 1977, s&iacute;: es verdad que \u201c<strong>la ausencia de la fe personal puede comprometer la validez del matrimonio\u201d, pues un cristiano que abandona la fe est&aacute; rechazando el sacramento como tal<\/strong>, por tanto, es dif&iacute;cil que exista recta intenci&oacute;n \u201cde contraer matrimonio como dice la Iglesia\u201d. <strong>No es imposible, pero s&iacute; muy dif&iacute;cil.<\/strong><br \/> &nbsp;<br \/> Hay que tener en cuenta que el C&oacute;digo de Derecho Can&oacute;nico dice que <strong>entre bautizados no puede existir un matrimonio que no sea sacramental<\/strong> (can. 1055 &sect;2), es decir, no puede existir el matrimonio \u201cnatural\u201d sin m&aacute;s.<br \/> &nbsp;<br \/> Es decir, los contrayentes bautizados, que son ministros del matrimonio, <strong>pueden actuar \u201cen nombre de Cristo\u201d s&oacute;lo si quieren hacer lo que Cristo instituy&oacute; y la Iglesia hace. Quien celebra \u201cen su propio nombre\u201d no quiere entrar en la sacramentalidad del matrimonio, y por tanto, &eacute;ste no se produce.<\/strong><br \/> &nbsp;<br \/> Pero si esos dos bautizados vuelven a la fe, &iquest;qu&eacute; sucede con ese matrimonio? &iquest;O si esos dos bautizados se casaron por lo civil? Pues bien, <strong>si ese matrimonio ten&iacute;a al menos las propiedades esenciales, por ejemplo unidad e indisolubilidad, no ser&iacute;a necesario casarse de nuevo: se podr&iacute;a \u201csanar de ra&iacute;z\u201d o \u201cconvalidar\u201d<\/strong> (depende del caso) ese&nbsp; matrimonio (leer m&aacute;s sobre esto <a target=\"_blank\" href=\"http:\/\/www.iuscanonicum.org\/index.php\/derecho-matrimonial\/convalidacion-y-sanacion\/45-la-convalidacion-y-la-sanacion-en-la-raiz-en-el-matrimonio.html\">aqu&iacute;<\/a>)<br \/> &nbsp;<br \/> Respecto a la segunda parte de la pregunta, la respuesta es negativa: <strong>Si un matrimonio no fue contra&iacute;do v&aacute;lidamente, no se convierte en v&aacute;lido con el paso del tiempo. Tampoco el nacimiento de los hijos lo vuelve v&aacute;lido, pues no modifica el modo como se contrajo ese matrimonio.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Aleteia Team Quisiera plantear una pregunta sobre el matrimonio y su validez. Si un matrimonio se celebra en la Iglesia entre dos personas ateas, porque es tradici&oacute;n y se hace por contentar a las familias, &iquest;es v&aacute;lido? &iquest;Se vuelve v&aacute;lido despu&eacute;s de alg&uacute;n a&ntilde;o de matrimonio o cuando nacen los hijos? La pregunta se &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/es-valido-el-matrimonio-por-la-iglesia-entre-dos-personas-ateas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfEs v\u00e1lido el matrimonio por la Iglesia entre dos personas&nbsp;ateas?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32371","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32371"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32371\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}